{"id":85454,"date":"2024-07-01T16:57:13","date_gmt":"2024-07-01T14:57:13","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/aussichtspunkte-von-bergamo\/"},"modified":"2024-10-15T12:10:55","modified_gmt":"2024-10-15T10:10:55","slug":"aussichtspunkte-von-bergamo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/aussichtspunkte-von-bergamo\/","title":{"rendered":"Aussichtspunkte von Bergamo"},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"template":"","categories":[],"tags":[],"aggr":[],"area":[],"kind":[18685],"zona":[],"class_list":["post-85454","oggetto","type-oggetto","status-publish","hentry","kind-itinerario-de"],"acf":{"featured_video":false,"is_an_ambassador":false,"slides":[{"image":{"ID":68910,"id":68910,"title":"CREATOR: gd-jpeg v1.0 (using IJG JPEG v62), quality = 95","filename":"itinerario-punti-panoramici.jpg","filesize":674364,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/itinerario-punti-panoramici.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/aussichtspunkte-von-bergamo\/creator-gd-jpeg-v1-0-using-ijg-jpeg-v62-quality-95-2-2\/","alt":"","author":"8","description":"","caption":"CREATOR: gd-jpeg v1.0 (using IJG JPEG v62), quality = 95","name":"creator-gd-jpeg-v1-0-using-ijg-jpeg-v62-quality-95-2-2","status":"inherit","uploaded_to":85454,"date":"2024-07-01 14:44:46","modified":"2024-10-07 10:09:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/itinerario-punti-panoramici-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/itinerario-punti-panoramici-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/itinerario-punti-panoramici-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/itinerario-punti-panoramici-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/itinerario-punti-panoramici-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/itinerario-punti-panoramici.jpg","2048x2048-width":1920,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/itinerario-punti-panoramici.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/itinerario-punti-panoramici.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/itinerario-punti-panoramici.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"modules":[{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":""},"tcm_ui":[{"label":"Geeignet f\u00fcr","value":"Kinder, Erwachsene, \u00e4ltere Menschen"},{"label":"Modus","value":"zu Fu\u00df, mit \u00f6ffentlichen Verkehrsmitteln"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p>Wenn Sie Panoramablicke, atemberaubende 360\u00b0-Aussichten lieben &#8230; ist Bergamo genau das Richtige f\u00fcr Sie!<br \/>\nSie f\u00fchrt Sie von der Stadt in die Natur auf einer Route, die Geschichte, Kunst und das Spektrum der sch\u00f6nsten Emotionen miteinander verbindet &#8211; und das alles in luftiger H\u00f6he. Auf dieser Route besichtigen Sie <strong>die Wahrzeichen der Stadt<\/strong>, vom <strong>Torre dei Caduti<\/strong> bis zu den pr\u00e4chtigen <strong>venezianischen Mauern<\/strong> aus dem 16. Jahrhundert, von der <strong>Rocca<\/strong> aus dem 14. Jahrhundert bis zum tausendj\u00e4hrigen <strong>Torre del Gombito<\/strong>, bis zum legend\u00e4ren <strong>Campanone<\/strong> auf der Piazza Vecchia und enden in der Sch\u00f6nheit des H\u00fcgels von <strong>San Vigilio<\/strong>, der ganz Bergamo und den gr\u00fcnen Parco dei Colli \u00fcberragt.<\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Von Largo Porta Nuova nach Piazza Vittorio Veneto"},"tcm_ui":[{"label":"Empfohlene Dauer","value":"von 9:00 Uhr bis 10:00 Uhr."}],"tcm_content":[{"acf_fc_layout":"text","text":"<p>Wenn Sie die Propilei di <strong>Porta Nuova<\/strong> hinter sich lassen und in Richtung Viale Roma gehen, erreichen Sie in wenigen Minuten die <strong>Piazza Vittorio Veneto<\/strong>, das Herz der modernen Stadt, die vom <strong>Chiostro di Santa Marta<\/strong>, dem <strong>Centro Piacentiniano<\/strong> und einigen der ber\u00fchmtesten Lokale Bergamos \u00fcberragt wird.<br \/>\nNach einem Kaffee und einer Pause, um die sch\u00f6nen Arkaden zu erkunden, betreten Sie den <strong>Torre dei Caduti<\/strong>: die sechs Treppenstufen &#8211; entweder zu Fu\u00df oder mit dem Aufzug &#8211; werden durch den atemberaubenden Blick auf die Unterstadt von der Terrasse oben belohnt. Wenn Sie nach S\u00fcdosten blicken, sehen Sie das<strong>Donizetti-Theater<\/strong>, im Osten den <strong>Quadriportico del <\/strong><strong>Sentierone <\/strong>mit dem Centro Piacentiniano, im Westen <strong>den Palazzo Frizzoni<\/strong> (Sitz des Rathauses) und nat\u00fcrlich im Nord-Nordwesten die herrliche Skyline der <strong>Oberstadt<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-68914\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/torre-dei-caduti-1024x689.jpg\" alt=\"\" width=\"1024\" height=\"689\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/torre-dei-caduti-1024x689.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/torre-dei-caduti-300x202.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/torre-dei-caduti-768x516.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/torre-dei-caduti-1536x1033.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/torre-dei-caduti.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Von der Unterstadt zur Oberstadt"},"tcm_ui":[{"label":"Empfohlene Dauer","value":"von 10:00 bis 11:30"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p>Sobald Sie den Turm verlassen haben, ist es an der Zeit, Bergamo Alta zu erreichen, und Sie k\u00f6nnen dies tun, w\u00e4hrend Sie die Skyline der Stadt auf dem H\u00fcgel immer vor sich haben. Gehen Sie weiter die Viale Roma entlang und gehen Sie die gesamte L\u00e4nge der Viale Vittorio Emanuele II entlang, bis Sie die<strong>untere Station der Standseilbahn<\/strong> erreichen. Nehmen Sie in einem der Waggons Platz und erleben Sie den Nervenkitzel des Aufstiegs auf den H\u00fcgel dank der Gleise, die seit \u00fcber hundert Jahren die beiden Bergamo miteinander verbinden und zwischen Villen und G\u00e4rten hindurchf\u00fchren. Von der <strong>Oberen Station<\/strong> aus haben Sie einen weiten Blick auf die Unterstadt und gelangen zur <strong>Piazza Mercato delle Scarpe<\/strong>; biegen Sie links ab und gehen Sie die Via S. Giacomo hinunter. Vorbei an alten Adelspal\u00e4sten erreichen Sie dann die <strong>Porta San Giacomo<\/strong> und genie\u00dfen einen langen Spaziergang entlang der <strong>venezianischen<\/strong> Stadtmauern. Von hier aus schweift Ihr Blick \u00fcber ein herrliches neues Panorama von Bergamo, seiner Provinz, den Alpen und an einem klaren Tag sogar \u00fcber die Ebene bis nach Mailand.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-68920\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/veduta-delle-mura-da-porta-s.-giacomo-1024x621.jpg\" alt=\"\" width=\"1024\" height=\"621\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/veduta-delle-mura-da-porta-s.-giacomo-1024x621.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/veduta-delle-mura-da-porta-s.-giacomo-300x182.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/veduta-delle-mura-da-porta-s.-giacomo-768x466.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/veduta-delle-mura-da-porta-s.-giacomo-1536x931.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/veduta-delle-mura-da-porta-s.-giacomo.jpg 1580w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Von der Festung zum Gombito-Turm"},"tcm_ui":[{"label":"Empfohlene Dauer","value":"von 11:30 Uhr bis 12:30 Uhr."}],"tcm_content":[{"acf_fc_layout":"text","text":"<p style=\"font-weight: 400;\">Wenn Sie die Viale delle Mura in der N\u00e4he der<strong> Porta S. Agostino<\/strong> verlassen und die <strong>ehemalige Kirche<\/strong><strong>S. Agostino<\/strong> zu Ihrer Rechten sehen, biegen Sie links ab und nehmen die <strong>Via Porta Dipinta<\/strong>.<br \/>\nZwischen antiken Schildern und Geb\u00e4uden von gro\u00dfem historischem Wert wie <strong>S. Michele al Pozzo Bianco<\/strong> gelangen Sie zur\u00fcck zur Piazza Mercato delle Scarpe, dem Platz der Standseilbahn.<br \/>\nNehmen Sie die Via alla Rocca, die erste Stra\u00dfe rechts, und in f\u00fcnf Minuten erreichen Sie die <strong>Rocca di Bergamo<\/strong>, die von dem herrlichen Parco delle Rimembranze umgeben ist.<br \/>\nAuch hier k\u00f6nnen Sie einen atemberaubenden Blick auf die Umgebung genie\u00dfen, sowohl von den Festungsmauern als auch vom Turm aus.<br \/>\nDer Spaziergang durch die Geschichte setzt sich auch im Garten fort, der mit zahlreichen Relikten aus den beiden Weltkriegen \u00fcbers\u00e4t ist.<\/p>\n<p style=\"font-weight: 400;\">Zur\u00fcck auf der Piazza Mercato delle Scarpe ist es an der Zeit, das Herz des Dorfes zu betreten.<br \/>\nVerlassen Sie die Via alla Rocca, biegen Sie rechts ab und gehen Sie die <strong>Via del Gombito<\/strong> entlang, inmitten von Gesch\u00e4ften und typischen Restaurants.<br \/>\nNach etwa 5 Minuten, vorbei an der <strong>Kirche S. Pancrazio<\/strong>, finden Sie zu Ihrer Linken den <strong>Torre del Gombito<\/strong>, hinter dem sich der <strong>Antico Lavatoio <\/strong>di Via Mario Lupo befindet, der jetzt restauriert wurde und wieder mit Wasser gef\u00fcllt ist.<br \/>\nAm Eingang des Turms befindet sich auch die Touristeninformation von Citt\u00e0 Alta.<br \/>\nBuchen Sie hier Ihren Besuch, steigen Sie hinauf und genie\u00dfen Sie ein 360\u00b0-Panorama \u00fcber ganz Ober-Bergamo &#8211; 263 Stufen f\u00fcr einen wahrhaft privilegierten Aussichtspunkt!<br \/>\nDer Turm ist eine Sehensw\u00fcrdigkeit, die Sie sich nicht entgehen lassen sollten: Er strahlt schon von au\u00dfen seinen tausendj\u00e4hrigen Charme aus, ist hoch und streng und bewacht noch immer die Kreuzung der beiden Verkehrsadern der Stadt, die in der r\u00f6mischen Antike der cardo und der decumanus waren.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-68926\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/gombito-1024x591.jpg\" alt=\"\" width=\"1024\" height=\"591\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/gombito-1024x591.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/gombito-300x173.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/gombito-768x443.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/gombito-1536x886.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/gombito.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Vom Campanone nach San Vigilio"},"tcm_ui":[{"label":"Empfohlene Dauer","value":"von 14:30 bis 16:00"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p style=\"font-weight: 400;\">Nach einer leckeren Mittagspause mit bergamasker Spezialit\u00e4ten erwartet Sie auf der <strong>Piazza Vecchia<\/strong> der <strong>Stadtturm<\/strong>, Bergamos geliebter &#8216;Campanone&#8217;, der sich an der Ecke von <strong>Palazzo della Ragione<\/strong> und <strong>Palazzo del Podest\u00e0<\/strong> befindet.<br \/>\nMit dem Aufzug &#8211; oder zu Fu\u00df, wenn Sie n\u00fcchtern bleiben wollen &#8211; k\u00f6nnen Sie die Spitze des Turms erreichen, der einst hundert Glockenschl\u00e4ge zum Schlie\u00dfen der Tore der Oberstadt erklingen lie\u00df, und unerwartete Ausblicke auf die <strong>Piazza Duomo<\/strong>, die Oberstadt und die Orobischen Berge genie\u00dfen.<br \/>\nDer perfekte Ort f\u00fcr unvergessliche Fotos!<\/p>\n<p style=\"font-weight: 400;\">Aber das gro\u00dfe Finale erwartet Sie an der alten Burg, die die ganze Stadt \u00fcberblickt. Verlassen Sie die Piazza Vecchia und biegen Sie links in die <strong>Via Colleoni<\/strong> ein, vorbei an der <strong>Piazza Mascheroni<\/strong> und der <strong>Piazza della Cittadella<\/strong>, bis Sie zum <strong>Largo Colle Aperto<\/strong> kommen. Hinter dem Kreisverkehr sehen Sie einen monumentalen Bogen: es ist eines der vier Tore von Citt\u00e0 Alta aus dem 16. Jahrhundert, <strong>Porta S. Alessandro<\/strong>.<br \/>\nGehen Sie hindurch, und auf der rechten Seite befindet sich die <strong>Standseilbahn von S. Vigilio<\/strong> &#8211; eine dreimin\u00fctige, schwindelerregende Auffahrt auf den Gipfel des H\u00fcgels, zwischen Stadt, Himmel und terrassenf\u00f6rmig angelegten G\u00e4rten, wo Sie sich wie auf dem Gipfel der Welt f\u00fchlen werden. F\u00fcr einen noch spezielleren Abschluss erreichen Sie das<strong>Schloss S. Vigilio<\/strong>, in dessen Garten Sie eine Tafel finden, die Ihnen die Namen der Berge nennt, \u00fcber die Sie Ihren Blick schweifen lassen k\u00f6nnen. Danach k\u00f6nnen Sie, wenn Sie m\u00f6chten, eine der Stra\u00dfen oder Treppen nehmen, die den H\u00fcgel hinunterf\u00fchren, und die Aussichten entdecken, die das <a href=\"https:\/\/visit.valueservice.cloud\/oggetto\/la-citta-verde\/?_gl=1*tafguv*_up*MQ..*_ga*MjI1NjM2ODkzLjE3Mjg5NzcxNTA.*_ga_S3VC5W948H*MTcyODk4NjcxNS4yLjAuMTcyODk4NjcxNS4wLjAuMA..\">City Trekking<\/a> im <strong>Parco dei Colli<\/strong> bietet.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-68932\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/san-vigilio.jpg\" alt=\"\" width=\"915\" height=\"528\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/san-vigilio.jpg 915w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/san-vigilio-300x173.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/san-vigilio-768x443.jpg 768w\" sizes=\"auto, (max-width: 915px) 100vw, 915px\" \/><\/p>\n"}]}],"filotto_layout":"scroll","filotto_fill":"manual","hero_title":"Aussichtspunkte von Bergamo","hero_text":"<p>Fast in den Wolken zwischen St\u00e4dten, Ebenen und Bergen<\/p>\n","size":"full","filotto_title":"","filotto_sub":"","filotto_items":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"related":false,"hero_type":"images","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85454\/revisions"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=85454"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=85454"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=85454"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=85454"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=85454"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=85454"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=85454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}