{"id":85480,"date":"2024-08-19T13:56:42","date_gmt":"2024-08-19T11:56:42","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/die-meile-der-schoenheit\/"},"modified":"2024-10-08T15:14:01","modified_gmt":"2024-10-08T13:14:01","slug":"die-meile-der-schoenheit","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/","title":{"rendered":"Die Meile der Sch\u00f6nheit"},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":74806,"template":"","categories":[],"tags":[],"aggr":[],"area":[868],"kind":[18685],"zona":[18760],"class_list":["post-85480","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","area-bergamo-area","kind-itinerario-de","zona-bergamo-de"],"acf":{"featured_video":false,"slides":[{"image":{"ID":74806,"id":74806,"title":"miglio","filename":"miglio.jpg","filesize":661136,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/miglio.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/miglio-2\/","alt":"","author":"8","description":"","caption":"","name":"miglio-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:07:49","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":908,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/miglio-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/miglio-300x172.jpg","medium-width":300,"medium-height":172,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/miglio-768x441.jpg","medium_large-width":768,"medium_large-height":441,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/miglio-1024x588.jpg","large-width":1024,"large-height":588,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/miglio-1536x883.jpg","1536x1536-width":1536,"1536x1536-height":883,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/miglio.jpg","2048x2048-width":1580,"2048x2048-height":908,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/miglio.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":172,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/miglio.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":230,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/miglio.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":345}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":74855,"id":74855,"title":"_PQD6196","filename":"PQD6196-scaled.jpg","filesize":922470,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6196-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_pqd6196-2\/","alt":"","author":"8","description":"","caption":"","name":"_pqd6196-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:18:35","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6196-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6196-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6196-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6196-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6196-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6196-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6196-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6196-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6196-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":74849,"id":74849,"title":"_PQD6163_cittadella","filename":"PQD6163_cittadella-scaled.jpg","filesize":1199757,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_pqd6163_cittadella-2\/","alt":"","author":"8","description":"","caption":"","name":"_pqd6163_cittadella-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:18:21","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":74885,"id":74885,"title":"DSC_0885","filename":"DSC_0885-scaled.jpg","filesize":1726123,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_0885-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/dsc_0885-2\/","alt":"","author":"8","description":"","caption":"","name":"dsc_0885-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:20:44","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_0885-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_0885-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_0885-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_0885-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_0885-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_0885-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_0885-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_0885-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_0885-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":74819,"id":74819,"title":"_44G0322","filename":"44G0322-scaled.jpg","filesize":1536791,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_44g0322-2\/","alt":"","author":"8","description":"","caption":"","name":"_44g0322-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:16:37","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":74825,"id":74825,"title":"_44G0338","filename":"44G0338-scaled.jpg","filesize":1449178,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_44g0338-2\/","alt":"","author":"8","description":"","caption":"","name":"_44g0338-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:16:52","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":37398,"id":37398,"title":"Vista dell'ingresso di Palazzo Terzi","filename":"Vista-dellingresso-di-Palazzo-Terzi.png","filesize":2627057,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/top-5-luoghi-instagrammabili-a-bergamo\/vista-dellingresso-di-palazzo-terzi-2\/","alt":"","author":"7","description":"","caption":"","name":"vista-dellingresso-di-palazzo-terzi-2","status":"inherit","uploaded_to":80226,"date":"2024-06-03 11:05:09","modified":"2024-08-19 13:53:29","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":940,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi-300x182.png","medium-width":300,"medium-height":182,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi-768x466.png","medium_large-width":768,"medium_large-height":466,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi-1024x621.png","large-width":1024,"large-height":621,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi-1536x932.png","1536x1536-width":1536,"1536x1536-height":932,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi.png","2048x2048-width":1550,"2048x2048-height":940,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":182,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":243,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":364}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":621,"id":621,"title":"Palazzo Moroni","filename":"Palazzo-Moroni.jpg","filesize":613765,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/palazzo-moroni-2\/","alt":"","author":"4","description":"","caption":"","name":"palazzo-moroni-2","status":"inherit","uploaded_to":85480,"date":"2024-04-12 15:46:13","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1512,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni-300x214.jpg","medium-width":300,"medium-height":214,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni-768x549.jpg","medium_large-width":768,"medium_large-height":549,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni-1024x731.jpg","large-width":1024,"large-height":731,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni.jpg","1536x1536-width":1512,"1536x1536-height":1080,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni.jpg","2048x2048-width":1512,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":214,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":286,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":429}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":74879,"id":74879,"title":"Accademia Carrara museum, Lower Bergamo","filename":"Accademia-Carrara-museum-Lower-Bergamo-scaled.jpg","filesize":589126,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/accademia-carrara-museum-lower-bergamo-2\/","alt":"","author":"8","description":"","caption":"","name":"accademia-carrara-museum-lower-bergamo-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:19:31","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1709,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-2048x1367.jpg","2048x2048-width":2048,"2048x2048-height":1367,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":74831,"id":74831,"title":"_DSC5030","filename":"DSC5030-scaled.jpg","filesize":1046748,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC5030-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_dsc5030-2\/","alt":"","author":"8","description":"","caption":"","name":"_dsc5030-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:16:58","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1704,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC5030-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC5030-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC5030-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC5030-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC5030-1536x1022.jpg","1536x1536-width":1536,"1536x1536-height":1022,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC5030-2048x1363.jpg","2048x2048-width":2048,"2048x2048-height":1363,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC5030-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC5030-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC5030-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"modules":[{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":""},"tcm_ui":[{"label":"Abreise","value":"Largo Colle Aperto"},{"label":"Ankunft","value":"Piazza Giacomo Carrara"},{"label":"Erreichbar in","value":"Auto, Bus  "},{"label":"Dauer","value":"1 h 10''"},{"label":"L\u00e4nge","value":"2,5 km"},{"label":"Geeignet f\u00fcr","value":"Erwachsene, Kinder"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p style=\"text-align: justify;\">Lassen Sie sich auf eine einzigartige Reise entlang der Meile der Sch\u00f6nheit entf\u00fchren, eine Autorenroute, um die <strong>Kulturhauptstadt Bergamo Brescia 2023<\/strong> von ihrer besten Seite zu feiern.<br \/>\nSchritt f\u00fcr Schritt werden Sie alle Merkmale der Sch\u00f6nheit kennenlernen, um Bergamo aus einer anderen Perspektive zu erleben. Lassen Sie sich durch eine ungew\u00f6hnliche Route zwischen<strong>noblen Residenzen<\/strong>, <strong>Kunstwerken<\/strong>, <strong>Gassen, Treppen<\/strong> und vielem mehr f\u00fchren und vergessen Sie dabei nat\u00fcrlich nicht einen der sch\u00f6nsten Pl\u00e4tze Italiens. Entdecken Sie voller Neugier eine Stadt, die nur darauf wartet, ihre besten Geheimnisse zu enth\u00fcllen und Sie mit offenen M\u00fcndern zur\u00fcckzulassen.  <\/p>\n<p style=\"text-align: justify;\">Wir empfehlen Ihnen, von der <strong>Cittadella Viscontea<\/strong> in der Oberstadt bis zum Fu\u00df der <strong>venezianischen Mauern<\/strong> zu gehen, aber es gibt keine feste Regel: Ihre Meile der Sch\u00f6nheit funktioniert auch in umgekehrter Richtung!<\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":""},"tcm_ui":[{"label":"H\u00f6henunterschied","value":"+10 m"},{"label":"Schwierigkeiten","value":"einfach"},{"label":"Route Typ","value":"Gehen, linear"}],"tcm_content":[{"acf_fc_layout":"googlemap_embed","map":{"locations":false,"file_kml":false}},{"acf_fc_layout":"buttons","buttons":[{"style":"primary","text":"gpx-Track herunterladen  ","icon":{"button_icon":"none"},"function":"link","url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/1-Miglio-della-bellezza.gpx","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}]}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Zitadellenplatz"},"tcm_ui":[{"label":"Dauer (ohne Museumsbesuche)","value":"10'"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p dir=\"ltr\" style=\"text-align: justify;\">Das erste Kapitel der Meile beginnt auf der <strong>Piazza della Cittadella<\/strong>: einem der charakteristischen Pl\u00e4tze der Oberstadt, dessen facettenreiche Vergangenheit Spuren hinterlassen hat, die noch deutlich sichtbar sind.<br \/>\nK\u00f6nnen Sie sie erkennen?<br \/>\nNur wenige Meter voneinander entfernt finden Sie ein St\u00fcck r\u00f6mische Stra\u00dfe, einen Pfeiler der alten mittelalterlichen Stadtmauer und S\u00e4ulen aus der romanischen Zeit, um nur einige zu nennen.  <\/p>\n<p dir=\"ltr\" style=\"text-align: justify;\">Auch das gesamte historisch-wissenschaftliche Wissen Bergamos wird hier bewahrt: Sie sollten sich einen interaktiven Besuch im <strong>Naturwissenschaftlichen Museum &#8216;E. Caffi&#8217;<\/strong> nicht entgehen lassen, in dem Mineralien, Fossilien, Tiere und Insekten eifers\u00fcchtig aufbewahrt werden, und im<strong> St\u00e4dtischen Arch\u00e4ologischen Museum<\/strong>, das sich von einer einfachen und anf\u00e4nglichen &#8216;Antikensammlung&#8217; zu einer Sammlung von unsch\u00e4tzbarem Wert entwickelt hat.<\/p>\n<p dir=\"ltr\">\n"},{"acf_fc_layout":"gallery","gallery_items":[{"description":"","image":{"ID":74849,"id":74849,"title":"_PQD6163_cittadella","filename":"PQD6163_cittadella-scaled.jpg","filesize":1199757,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_pqd6163_cittadella-2\/","alt":"","author":"8","description":"","caption":"","name":"_pqd6163_cittadella-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:18:21","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6163_cittadella-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"url_youtube":""},{"description":"","image":{"ID":74929,"id":74929,"title":"_PQD6160_cittadella","filename":"PQD6160_cittadella-scaled.jpg","filesize":968002,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6160_cittadella-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_pqd6160_cittadella-2\/","alt":"","author":"8","description":"","caption":"","name":"_pqd6160_cittadella-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:45:02","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6160_cittadella-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6160_cittadella-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6160_cittadella-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6160_cittadella-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6160_cittadella-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6160_cittadella-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6160_cittadella-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6160_cittadella-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6160_cittadella-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"url_youtube":""},{"description":"","image":{"ID":74923,"id":74923,"title":"_PQD6128_cittadella","filename":"PQD6128_cittadella-scaled.jpg","filesize":1051927,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6128_cittadella-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_pqd6128_cittadella-2\/","alt":"","author":"8","description":"","caption":"","name":"_pqd6128_cittadella-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:44:41","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6128_cittadella-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6128_cittadella-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6128_cittadella-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6128_cittadella-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6128_cittadella-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6128_cittadella-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6128_cittadella-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6128_cittadella-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6128_cittadella-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"url_youtube":""}]}]},{"acf_fc_layout":"filotto","filotto_title":"Interessante Punkte","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":[{"object":20053,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19894,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19972,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""}],"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Von der Piazza Mascheroni zum Teatro Sociale"},"tcm_ui":[{"label":"Dauer","value":"15'"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p style=\"text-align: justify;\">Nehmen Sie den S\u00e4ulengang am Fu\u00dfe des <strong>Campanella-Turms<\/strong>, erreichen Sie die <strong>Piazza Mascheroni<\/strong> (fr\u00fcher Piazza Nuova genannt) und gehen Sie weiter auf der Via Colleoni, besser bekannt als <strong>Corsarola<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Fast versteckt vor der Hektik der <em>Einheimischen<\/em>, Touristen und Studenten sowie der Enge der Stra\u00dfe \u00f6ffnen sich auf magische Weise die Eing\u00e4nge zu den wichtigsten Zentren der kulturellen Aktivit\u00e4ten in der Oberstadt: das<strong> Teatro Sociale<\/strong> und das<strong>Ex-monastero del Carmine<\/strong>, das immer noch in vollem Gange ist und ein reichhaltiges Programm an Auff\u00fchrungen und Veranstaltungen bietet, die Sie nicht verpassen sollten.<\/p>\n"},{"acf_fc_layout":"gallery","gallery_items":[{"description":"","image":{"ID":74954,"id":74954,"title":"_MAU0411 piazza mascheroni","filename":"MAU0411-piazza-mascheroni-scaled.jpg","filesize":1002048,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0411-piazza-mascheroni-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_mau0411-piazza-mascheroni-2\/","alt":"","author":"8","description":"","caption":"","name":"_mau0411-piazza-mascheroni-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:56:14","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1682,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0411-piazza-mascheroni-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0411-piazza-mascheroni-300x197.jpg","medium-width":300,"medium-height":197,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0411-piazza-mascheroni-768x504.jpg","medium_large-width":768,"medium_large-height":504,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0411-piazza-mascheroni-1024x673.jpg","large-width":1024,"large-height":673,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0411-piazza-mascheroni-1536x1009.jpg","1536x1536-width":1536,"1536x1536-height":1009,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0411-piazza-mascheroni-2048x1345.jpg","2048x2048-width":2048,"2048x2048-height":1345,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0411-piazza-mascheroni-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":197,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0411-piazza-mascheroni-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":263,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0411-piazza-mascheroni-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":394}},"url_youtube":""},{"description":"","image":{"ID":74936,"id":74936,"title":"_MAU0433piazza mascheroni","filename":"MAU0433piazza-mascheroni-scaled.jpg","filesize":1027719,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0433piazza-mascheroni-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_mau0433piazza-mascheroni-2\/","alt":"","author":"8","description":"","caption":"","name":"_mau0433piazza-mascheroni-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:55:02","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1691,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0433piazza-mascheroni-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0433piazza-mascheroni-300x198.jpg","medium-width":300,"medium-height":198,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0433piazza-mascheroni-768x507.jpg","medium_large-width":768,"medium_large-height":507,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0433piazza-mascheroni-1024x676.jpg","large-width":1024,"large-height":676,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0433piazza-mascheroni-1536x1015.jpg","1536x1536-width":1536,"1536x1536-height":1015,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0433piazza-mascheroni-2048x1353.jpg","2048x2048-width":2048,"2048x2048-height":1353,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0433piazza-mascheroni-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":198,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0433piazza-mascheroni-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":264,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0433piazza-mascheroni-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":396}},"url_youtube":""},{"description":"","image":{"ID":74960,"id":74960,"title":"_MAU0427piazza mascheroni","filename":"MAU0427piazza-mascheroni-scaled.jpg","filesize":1610769,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0427piazza-mascheroni-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_mau0427piazza-mascheroni-2\/","alt":"","author":"8","description":"","caption":"","name":"_mau0427piazza-mascheroni-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:56:45","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1592,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0427piazza-mascheroni-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0427piazza-mascheroni-300x187.jpg","medium-width":300,"medium-height":187,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0427piazza-mascheroni-768x478.jpg","medium_large-width":768,"medium_large-height":478,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0427piazza-mascheroni-1024x637.jpg","large-width":1024,"large-height":637,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0427piazza-mascheroni-1536x955.jpg","1536x1536-width":1536,"1536x1536-height":955,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0427piazza-mascheroni-2048x1274.jpg","2048x2048-width":2048,"2048x2048-height":1274,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0427piazza-mascheroni-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":187,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0427piazza-mascheroni-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":249,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0427piazza-mascheroni-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":373}},"url_youtube":""},{"description":"","image":{"ID":74942,"id":74942,"title":"_MAU0432cisterna piazza mascheroni","filename":"MAU0432cisterna-piazza-mascheroni-scaled.jpg","filesize":1774364,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0432cisterna-piazza-mascheroni-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_mau0432cisterna-piazza-mascheroni-2\/","alt":"","author":"8","description":"","caption":"","name":"_mau0432cisterna-piazza-mascheroni-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:55:32","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1723,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0432cisterna-piazza-mascheroni-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0432cisterna-piazza-mascheroni-300x202.jpg","medium-width":300,"medium-height":202,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0432cisterna-piazza-mascheroni-768x517.jpg","medium_large-width":768,"medium_large-height":517,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0432cisterna-piazza-mascheroni-1024x689.jpg","large-width":1024,"large-height":689,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0432cisterna-piazza-mascheroni-1536x1034.jpg","1536x1536-width":1536,"1536x1536-height":1034,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0432cisterna-piazza-mascheroni-2048x1378.jpg","2048x2048-width":2048,"2048x2048-height":1378,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0432cisterna-piazza-mascheroni-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":202,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0432cisterna-piazza-mascheroni-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":269,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/MAU0432cisterna-piazza-mascheroni-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":404}},"url_youtube":""},{"description":"","image":{"ID":75002,"id":75002,"title":"via Colleoni (1)","filename":"via-Colleoni-1-scaled.jpg","filesize":842727,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/via-Colleoni-1-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/via-colleoni-1-2\/","alt":"","author":"8","description":"","caption":"","name":"via-colleoni-1-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 17:02:21","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/via-Colleoni-1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/via-Colleoni-1-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/via-Colleoni-1-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/via-Colleoni-1-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/via-Colleoni-1-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/via-Colleoni-1-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/via-Colleoni-1-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/via-Colleoni-1-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/via-Colleoni-1-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"url_youtube":""},{"description":"","image":{"ID":75008,"id":75008,"title":"Chiesa S. Agata del Carmine e via Colleoni (1)","filename":"Chiesa-S.-Agata-del-Carmine-e-via-Colleoni-1-scaled.jpg","filesize":1240528,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Chiesa-S.-Agata-del-Carmine-e-via-Colleoni-1-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/chiesa-s-agata-del-carmine-e-via-colleoni-1-2\/","alt":"","author":"8","description":"","caption":"","name":"chiesa-s-agata-del-carmine-e-via-colleoni-1-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 17:02:41","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Chiesa-S.-Agata-del-Carmine-e-via-Colleoni-1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Chiesa-S.-Agata-del-Carmine-e-via-Colleoni-1-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Chiesa-S.-Agata-del-Carmine-e-via-Colleoni-1-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Chiesa-S.-Agata-del-Carmine-e-via-Colleoni-1-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Chiesa-S.-Agata-del-Carmine-e-via-Colleoni-1-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Chiesa-S.-Agata-del-Carmine-e-via-Colleoni-1-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Chiesa-S.-Agata-del-Carmine-e-via-Colleoni-1-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Chiesa-S.-Agata-del-Carmine-e-via-Colleoni-1-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Chiesa-S.-Agata-del-Carmine-e-via-Colleoni-1-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"url_youtube":""},{"description":"","image":{"ID":74996,"id":74996,"title":"S17_2715","filename":"S17_2715.jpg","filesize":372145,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2715.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/s17_2715-2\/","alt":"","author":"8","description":"","caption":"","name":"s17_2715-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 17:02:04","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2000,"height":1335,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2715-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2715-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2715-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2715-1024x684.jpg","large-width":1024,"large-height":684,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2715-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2715.jpg","2048x2048-width":2000,"2048x2048-height":1335,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2715.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2715.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2715.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"url_youtube":""},{"description":"","image":{"ID":74990,"id":74990,"title":"S17_2710","filename":"S17_2710.jpg","filesize":489234,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2710.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/s17_2710-2\/","alt":"","author":"8","description":"","caption":"","name":"s17_2710-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 17:02:02","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2000,"height":1335,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2710-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2710-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2710-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2710-1024x684.jpg","large-width":1024,"large-height":684,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2710-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2710.jpg","2048x2048-width":2000,"2048x2048-height":1335,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2710.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2710.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/S17_2710.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"url_youtube":""},{"description":"","image":{"ID":74984,"id":74984,"title":"DSC_4844","filename":"DSC_4844-scaled.jpg","filesize":898738,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_4844-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/dsc_4844-2\/","alt":"","author":"8","description":"","caption":"","name":"dsc_4844-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 17:01:56","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1709,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_4844-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_4844-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_4844-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_4844-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_4844-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_4844-2048x1367.jpg","2048x2048-width":2048,"2048x2048-height":1367,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_4844-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_4844-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_4844-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"url_youtube":""},{"description":"","image":{"ID":75014,"id":75014,"title":"Via Colleoni","filename":"Via-Colleoni.jpg","filesize":8632062,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Via-Colleoni.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/via-colleoni-2\/","alt":"","author":"8","description":"","caption":"","name":"via-colleoni-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 17:03:01","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":8256,"height":5504,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Via-Colleoni-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Via-Colleoni-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Via-Colleoni-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Via-Colleoni-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Via-Colleoni-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Via-Colleoni.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Via-Colleoni.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Via-Colleoni.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Via-Colleoni.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"url_youtube":""},{"description":"","image":{"ID":74978,"id":74978,"title":"teatro sociale","filename":"teatro-sociale.jpg","filesize":850166,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/teatro-sociale.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/teatro-sociale-2\/","alt":"","author":"8","description":"","caption":"","name":"teatro-sociale-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 17:01:40","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1066,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/teatro-sociale-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/teatro-sociale-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/teatro-sociale-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/teatro-sociale-1024x682.jpg","large-width":1024,"large-height":682,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/teatro-sociale-1536x1023.jpg","1536x1536-width":1536,"1536x1536-height":1023,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/teatro-sociale.jpg","2048x2048-width":1600,"2048x2048-height":1066,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/teatro-sociale.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/teatro-sociale.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/teatro-sociale.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"url_youtube":""},{"description":"","image":{"ID":74972,"id":74972,"title":"sociale","filename":"sociale.jpg","filesize":273735,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/sociale.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/sociale-2\/","alt":"","author":"8","description":"","caption":"","name":"sociale-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 17:01:37","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1282,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/sociale-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/sociale-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/sociale-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/sociale-1024x684.jpg","large-width":1024,"large-height":684,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/sociale-1536x1026.jpg","1536x1536-width":1536,"1536x1536-height":1026,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/sociale.jpg","2048x2048-width":1920,"2048x2048-height":1282,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/sociale.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/sociale.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/sociale.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"url_youtube":""}]}]},{"acf_fc_layout":"filotto","filotto_title":"Interessante Punkte","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":[{"object":20159,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19799,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19957,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":20070,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19878,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""}],"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Piazza Vecchia und Piazza Duomo"},"tcm_ui":[{"label":"Dauer","value":"20'"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p style=\"text-align: justify;\">Fahren Sie weiter geradeaus, bis sich einer der sch\u00f6nsten Pl\u00e4tze Italiens vor Ihnen auftut: die <strong>Piazza Vecchia<\/strong>.<br \/>\nEs ist an der Zeit, das Herz von Bergamo Alta zu entdecken! <\/p>\n<p style=\"text-align: justify;\">Die grandiosen Monumente werden Sie in Atem halten &#8211; aber vergessen Sie nicht, aufzupassen, wo Sie hintreten, denn unter dem<strong> Palazzo della Ragione<\/strong> finden Sie eine seltene, antike Sonnenuhr in einer dunklen Kammer, die Sie zur Piazza Duomo f\u00fchrt.<br \/>\nIn der N\u00e4he des <strong>Baptisteriums<\/strong> k\u00f6nnen Sie die Gr\u00f6\u00dfe der angeblich gr\u00f6\u00dften Glocke der Lombardei bewundern, der Glocke des <strong>Stadtturms<\/strong>, die als &#8216;Campanone&#8217; bekannt ist. <\/p>\n"},{"acf_fc_layout":"gallery","gallery_items":[{"description":"","image":{"ID":37151,"id":37151,"title":"Piazza Vecchia,","filename":"Piazza-Vecchia-1.jpg","filesize":306789,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/10-cose\/piazza-vecchia-3-2\/","alt":"Vista di Piazza Vecchia","author":"7","description":"Vista di Piazza Vecchia","caption":"","name":"piazza-vecchia-3-2","status":"inherit","uploaded_to":37337,"date":"2024-05-31 10:06:05","modified":"2025-03-20 15:10:48","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":900,"height":650,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-1-300x217.jpg","medium-width":300,"medium-height":217,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-1-768x555.jpg","medium_large-width":768,"medium_large-height":555,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-1.jpg","large-width":900,"large-height":650,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-1.jpg","1536x1536-width":900,"1536x1536-height":650,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-1.jpg","2048x2048-width":900,"2048x2048-height":650,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":217,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":289,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":433}},"url_youtube":""},{"description":"","image":{"ID":37138,"id":37138,"title":"Piazza Vecchia _","filename":"Piazza-Vecchia-_.jpg","filesize":347375,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-_.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/10-cose\/piazza-vecchia-_-2\/","alt":"Vista di Piazza Vecchia dall'alto","author":"7","description":"Vista di Piazza Vecchia dall'alto","caption":"","name":"piazza-vecchia-_-2","status":"inherit","uploaded_to":37337,"date":"2024-05-31 10:03:09","modified":"2025-03-20 15:10:23","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":900,"height":650,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-_-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-_-300x217.jpg","medium-width":300,"medium-height":217,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-_-768x555.jpg","medium_large-width":768,"medium_large-height":555,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-_.jpg","large-width":900,"large-height":650,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-_.jpg","1536x1536-width":900,"1536x1536-height":650,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-_.jpg","2048x2048-width":900,"2048x2048-height":650,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-_.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":217,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-_.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":289,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-_.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":433}},"url_youtube":""},{"description":"","image":{"ID":37132,"id":37132,"title":"Piazza Vecchia","filename":"Piazza-Vecchia.jpg","filesize":352265,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/10-cose\/piazza-vecchia-2\/","alt":"Fontana Contarini - Piazza Vecchia","author":"7","description":"Fontana Contarini - Piazza Vecchia","caption":"","name":"piazza-vecchia-2","status":"inherit","uploaded_to":37337,"date":"2024-05-31 10:02:37","modified":"2025-03-20 15:09:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":900,"height":650,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-300x217.jpg","medium-width":300,"medium-height":217,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia-768x555.jpg","medium_large-width":768,"medium_large-height":555,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia.jpg","large-width":900,"large-height":650,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia.jpg","1536x1536-width":900,"1536x1536-height":650,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia.jpg","2048x2048-width":900,"2048x2048-height":650,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":217,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":289,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Piazza-Vecchia.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":433}},"url_youtube":""},{"description":"","image":{"ID":74861,"id":74861,"title":"_PQD6204","filename":"PQD6204-scaled.jpg","filesize":989308,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6204-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_pqd6204-2\/","alt":"","author":"8","description":"","caption":"","name":"_pqd6204-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:18:48","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6204-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6204-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6204-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6204-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6204-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6204-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6204-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6204-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6204-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"url_youtube":""},{"description":"","image":{"ID":68131,"id":68131,"title":"_DSC1524 piazza vecchia_portici_cappella colleoni","filename":"DSC1524-piazza-vecchia_portici_cappella-colleoni.jpg","filesize":838926,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/DSC1524-piazza-vecchia_portici_cappella-colleoni.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/citta-alta\/_dsc1524-piazza-vecchia_portici_cappella-colleoni-2\/","alt":"Scorcio di piazza Vecchia a Bergamo con vista sulla Cappella Colleoni","author":"7","description":"Scorcio di piazza Vecchia a Bergamo con vista sulla Cappella Colleoni","caption":"","name":"_dsc1524-piazza-vecchia_portici_cappella-colleoni-2","status":"inherit","uploaded_to":80775,"date":"2024-06-26 12:56:10","modified":"2025-03-21 19:17:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1281,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/DSC1524-piazza-vecchia_portici_cappella-colleoni-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/DSC1524-piazza-vecchia_portici_cappella-colleoni-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/DSC1524-piazza-vecchia_portici_cappella-colleoni-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/DSC1524-piazza-vecchia_portici_cappella-colleoni-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/DSC1524-piazza-vecchia_portici_cappella-colleoni-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/DSC1524-piazza-vecchia_portici_cappella-colleoni.jpg","2048x2048-width":1920,"2048x2048-height":1281,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/DSC1524-piazza-vecchia_portici_cappella-colleoni.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/DSC1524-piazza-vecchia_portici_cappella-colleoni.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/DSC1524-piazza-vecchia_portici_cappella-colleoni.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"url_youtube":""}]}]},{"acf_fc_layout":"filotto","filotto_title":"Interessante Punkte","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":[{"object":20033,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19846,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19812,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19896,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":20019,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":20073,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19820,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19817,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":20092,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""}],"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Altes Waschhaus - Palazzo Terzi"},"tcm_ui":[{"label":"Dauer","value":"10'"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p style=\"text-align: justify;\">\nNachdem Sie sich an der Sch\u00f6nheit sattgesehen haben, suchen Sie die Arkade der<strong> Via Ca&#8217; Longa<\/strong> in der N\u00e4he des Palazzo della Ragione auf, direkt neben dem Platz, der bereits im 15. Jahrhundert eine Taverne war: Diese kleine Abk\u00fcrzung f\u00fchrt Sie direkt zu einer der beliebtesten Aussichten von Bergamo Alta. Am Ende finden Sie einen charmanten, von B\u00e4umen ges\u00e4umten Platz, an dem der<strong>Antico Lavatoio<\/strong> und der h\u00f6chste Turm der Stadt, der mittelalterliche <strong>Gombito-Turm<\/strong>, stehen. Von hier aus k\u00f6nnen Sie, wenn Sie m\u00f6chten, einen kleinen Abstecher machen: Biegen Sie rechts ab, gehen Sie die <strong>Via Mario Lupo<\/strong> hinauf und Sie werden schon bald mit einem der ikonischsten Ausblicke \u00fcberhaupt belohnt, n\u00e4mlich dem des eleganten <strong>Palazzo Terzi<\/strong>, dessen Eingang sich auf die ber\u00fchmte Terrasse mit ihren Statuen \u00f6ffnet, die die Unterstadt \u00fcberblickt. <\/p>\n<p style=\"text-align: justify;\">Gehen Sie wieder zur\u00fcck, \u00fcberqueren Sie den kleinen Platz des Antico Lavatoio und nehmen Sie die letzte Abk\u00fcrzung nach rechts, zwischen den Blumenbeeten und den Stufen der <strong>Piazzetta Angelini<\/strong>, bis Sie die <strong>Piazza Mercato delle Scarpe<\/strong> erreichen <strong>.<\/strong><br \/>\nDieser Platz, an dem sich die Hauptzufahrtsstra\u00dfen der Stadt kreuzen, war einst ein Ort des Handels und ist auch heute noch ein wichtiger Knotenpunkt voller Charme und Geheimnisse, die es zu entdecken gilt. <\/p>\n"},{"acf_fc_layout":"gallery","gallery_items":[{"description":"","image":{"ID":74825,"id":74825,"title":"_44G0338","filename":"44G0338-scaled.jpg","filesize":1449178,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_44g0338-2\/","alt":"","author":"8","description":"","caption":"","name":"_44g0338-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:16:52","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0338-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"url_youtube":""},{"description":"","image":{"ID":74819,"id":74819,"title":"_44G0322","filename":"44G0322-scaled.jpg","filesize":1536791,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_44g0322-2\/","alt":"","author":"8","description":"","caption":"","name":"_44g0322-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:16:37","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0322-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"url_youtube":""},{"description":"","image":{"ID":37264,"id":37264,"title":"Vista dal Campanone - Torre del Gombito - Duomo","filename":"Vista-dal-Campanone-Torre-del-Gombito-Duomo.jpg","filesize":304072,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Vista-dal-Campanone-Torre-del-Gombito-Duomo.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/10-cose\/vista-dal-campanone-torre-del-gombito-duomo-2\/","alt":"Vista dal Campanone - Torre del Gombito - Duomo","author":"7","description":"Vista dal Campanone - Torre del Gombito - Duomo","caption":"","name":"vista-dal-campanone-torre-del-gombito-duomo-2","status":"inherit","uploaded_to":37337,"date":"2024-06-03 07:57:54","modified":"2025-03-20 15:49:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":900,"height":650,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Vista-dal-Campanone-Torre-del-Gombito-Duomo-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Vista-dal-Campanone-Torre-del-Gombito-Duomo-300x217.jpg","medium-width":300,"medium-height":217,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Vista-dal-Campanone-Torre-del-Gombito-Duomo-768x555.jpg","medium_large-width":768,"medium_large-height":555,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Vista-dal-Campanone-Torre-del-Gombito-Duomo.jpg","large-width":900,"large-height":650,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Vista-dal-Campanone-Torre-del-Gombito-Duomo.jpg","1536x1536-width":900,"1536x1536-height":650,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Vista-dal-Campanone-Torre-del-Gombito-Duomo.jpg","2048x2048-width":900,"2048x2048-height":650,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Vista-dal-Campanone-Torre-del-Gombito-Duomo.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":217,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Vista-dal-Campanone-Torre-del-Gombito-Duomo.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":289,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Vista-dal-Campanone-Torre-del-Gombito-Duomo.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":433}},"url_youtube":""},{"description":"","image":{"ID":37398,"id":37398,"title":"Vista dell'ingresso di Palazzo Terzi","filename":"Vista-dellingresso-di-Palazzo-Terzi.png","filesize":2627057,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi.png","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/top-5-luoghi-instagrammabili-a-bergamo\/vista-dellingresso-di-palazzo-terzi-2\/","alt":"","author":"7","description":"","caption":"","name":"vista-dellingresso-di-palazzo-terzi-2","status":"inherit","uploaded_to":80226,"date":"2024-06-03 11:05:09","modified":"2024-08-19 13:53:29","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":940,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi-300x182.png","medium-width":300,"medium-height":182,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi-768x466.png","medium_large-width":768,"medium_large-height":466,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi-1024x621.png","large-width":1024,"large-height":621,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi-1536x932.png","1536x1536-width":1536,"1536x1536-height":932,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi.png","2048x2048-width":1550,"2048x2048-height":940,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":182,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":243,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/Vista-dellingresso-di-Palazzo-Terzi.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":364}},"url_youtube":""},{"description":"","image":{"ID":2659,"id":2659,"title":"1be3b3016c6e3887e6233825253d2086_fc074d36.jpg","filename":"1be3b3016c6e3887e6233825253d2086_fc074d36.jpg","filesize":169643,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1be3b3016c6e3887e6233825253d2086_fc074d36.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/palazzo-terzi\/1be3b3016c6e3887e6233825253d2086_fc074d36-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1be3b3016c6e3887e6233825253d2086_fc074d36-jpg-2","status":"inherit","uploaded_to":19805,"date":"2024-05-08 08:34:32","modified":"2024-05-08 12:24:26","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":915,"height":528,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1be3b3016c6e3887e6233825253d2086_fc074d36-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1be3b3016c6e3887e6233825253d2086_fc074d36-300x173.jpg","medium-width":300,"medium-height":173,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1be3b3016c6e3887e6233825253d2086_fc074d36-768x443.jpg","medium_large-width":768,"medium_large-height":443,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1be3b3016c6e3887e6233825253d2086_fc074d36.jpg","large-width":915,"large-height":528,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1be3b3016c6e3887e6233825253d2086_fc074d36.jpg","1536x1536-width":915,"1536x1536-height":528,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1be3b3016c6e3887e6233825253d2086_fc074d36.jpg","2048x2048-width":915,"2048x2048-height":528,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1be3b3016c6e3887e6233825253d2086_fc074d36.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":173,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1be3b3016c6e3887e6233825253d2086_fc074d36.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":231,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1be3b3016c6e3887e6233825253d2086_fc074d36.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":346}},"url_youtube":""},{"description":"","image":{"ID":2617,"id":2617,"title":"582156492afd66b77ecd12abb5d791f6_374cc9d1.jpg","filename":"582156492afd66b77ecd12abb5d791f6_374cc9d1.jpg","filesize":801447,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/582156492afd66b77ecd12abb5d791f6_374cc9d1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/palazzo-terzi\/582156492afd66b77ecd12abb5d791f6_374cc9d1-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"582156492afd66b77ecd12abb5d791f6_374cc9d1-jpg-2","status":"inherit","uploaded_to":19805,"date":"2024-05-08 08:34:29","modified":"2024-05-08 12:24:26","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1281,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/582156492afd66b77ecd12abb5d791f6_374cc9d1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/582156492afd66b77ecd12abb5d791f6_374cc9d1-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/582156492afd66b77ecd12abb5d791f6_374cc9d1-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/582156492afd66b77ecd12abb5d791f6_374cc9d1-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/582156492afd66b77ecd12abb5d791f6_374cc9d1-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/582156492afd66b77ecd12abb5d791f6_374cc9d1.jpg","2048x2048-width":1920,"2048x2048-height":1281,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/582156492afd66b77ecd12abb5d791f6_374cc9d1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/582156492afd66b77ecd12abb5d791f6_374cc9d1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/582156492afd66b77ecd12abb5d791f6_374cc9d1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"url_youtube":""},{"description":"","image":{"ID":2635,"id":2635,"title":"6f44df57ee18bf4f5bd0da500a654bf6_92f3bc16.jpg","filename":"6f44df57ee18bf4f5bd0da500a654bf6_92f3bc16.jpg","filesize":203492,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f44df57ee18bf4f5bd0da500a654bf6_92f3bc16.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/palazzo-terzi\/6f44df57ee18bf4f5bd0da500a654bf6_92f3bc16-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6f44df57ee18bf4f5bd0da500a654bf6_92f3bc16-jpg-2","status":"inherit","uploaded_to":19805,"date":"2024-05-08 08:34:31","modified":"2024-05-08 12:24:26","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":915,"height":528,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f44df57ee18bf4f5bd0da500a654bf6_92f3bc16-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f44df57ee18bf4f5bd0da500a654bf6_92f3bc16-300x173.jpg","medium-width":300,"medium-height":173,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f44df57ee18bf4f5bd0da500a654bf6_92f3bc16-768x443.jpg","medium_large-width":768,"medium_large-height":443,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f44df57ee18bf4f5bd0da500a654bf6_92f3bc16.jpg","large-width":915,"large-height":528,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f44df57ee18bf4f5bd0da500a654bf6_92f3bc16.jpg","1536x1536-width":915,"1536x1536-height":528,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f44df57ee18bf4f5bd0da500a654bf6_92f3bc16.jpg","2048x2048-width":915,"2048x2048-height":528,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f44df57ee18bf4f5bd0da500a654bf6_92f3bc16.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":173,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f44df57ee18bf4f5bd0da500a654bf6_92f3bc16.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":231,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/6f44df57ee18bf4f5bd0da500a654bf6_92f3bc16.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":346}},"url_youtube":""},{"description":"","image":{"ID":74867,"id":74867,"title":"_PQD6301","filename":"PQD6301-scaled.jpg","filesize":931733,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6301-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_pqd6301-2\/","alt":"","author":"8","description":"","caption":"","name":"_pqd6301-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:19:00","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6301-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6301-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6301-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6301-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6301-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6301-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6301-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6301-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/PQD6301-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"url_youtube":""},{"description":"","image":{"ID":2119,"id":2119,"title":"1d5023a55308d830b2efbaa284cc8865_39cf5b01.jpg","filename":"1d5023a55308d830b2efbaa284cc8865_39cf5b01.jpg","filesize":462087,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1d5023a55308d830b2efbaa284cc8865_39cf5b01.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/zisterne-der-piazza-mercato-delle-scarpe\/1d5023a55308d830b2efbaa284cc8865_39cf5b01-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1d5023a55308d830b2efbaa284cc8865_39cf5b01-jpg-2","status":"inherit","uploaded_to":19789,"date":"2024-05-08 08:33:50","modified":"2024-05-08 12:24:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1d5023a55308d830b2efbaa284cc8865_39cf5b01-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1d5023a55308d830b2efbaa284cc8865_39cf5b01-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1d5023a55308d830b2efbaa284cc8865_39cf5b01-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1d5023a55308d830b2efbaa284cc8865_39cf5b01-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1d5023a55308d830b2efbaa284cc8865_39cf5b01-1536x595.jpg","1536x1536-width":1536,"1536x1536-height":595,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1d5023a55308d830b2efbaa284cc8865_39cf5b01.jpg","2048x2048-width":1550,"2048x2048-height":600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1d5023a55308d830b2efbaa284cc8865_39cf5b01.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1d5023a55308d830b2efbaa284cc8865_39cf5b01.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1d5023a55308d830b2efbaa284cc8865_39cf5b01.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"url_youtube":""}]}]},{"acf_fc_layout":"filotto","filotto_title":"Interessante Punkte","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":[{"object":19864,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":20055,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19805,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19833,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19789,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""}],"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Moroni Palast und G\u00e4rten - Porta S. Agostino"},"tcm_ui":[{"label":"Dauer","value":"20'"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p style=\"text-align: justify;\">Beginnen Sie Ihren Abstieg!<br \/>\nNehmen Sie die <strong>Via Porta Dipinta<\/strong> nach links und lassen Sie sich von den verborgenen Sch\u00e4tzen in den Bann ziehen: vom <strong>Palazzo und den Giardini Moroni<\/strong>, einem FAI-Kulturerbe, \u00fcber die scheinbar schlichte <strong>Kirche Sant&#8217;Andrea<\/strong> bis hin zur Kunstgeschichtsstunde mit den Werken von Lotto in der kleinen Kirche <strong>San Michele al Pozzo Bianco<\/strong>. <\/p>\n<p style=\"text-align: justify;\">Ganz am Ende sehen Sie bereits den<strong>ehemaligen Sant&#8217;Agostino-Komplex<\/strong>, der dem monumentalen Ortseingang seinen Namen gibt und heute Sitz der Universit\u00e4t von Bergamo ist.<br \/>\nFolgen Sie ihm, durchqueren Sie die <strong>Porta Sant&#8217;Agostino<\/strong>, gehen Sie ein St\u00fcck bergab, halten Sie sich links und biegen Sie am Anfang der Via Pignolo sofort links in die <strong>Via della Noca<\/strong> ein. So lassen Sie das monumentale Tor mit dem charakteristischen venezianischen L\u00f6wen hinter sich und gehen eine der typischen mittelalterlichen Treppen der Stadt entlang. <\/p>\n"},{"acf_fc_layout":"gallery","gallery_items":[{"description":"","image":{"ID":2515,"id":2515,"title":"2a9643049a4449d1c130c0199b018188_ab9ef7f3.jpg","filename":"2a9643049a4449d1c130c0199b018188_ab9ef7f3.jpg","filesize":206521,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2a9643049a4449d1c130c0199b018188_ab9ef7f3.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/palazzo-e-giardini-moroni\/2a9643049a4449d1c130c0199b018188_ab9ef7f3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"2a9643049a4449d1c130c0199b018188_ab9ef7f3-jpg-2","status":"inherit","uploaded_to":19803,"date":"2024-05-08 08:34:22","modified":"2024-05-08 12:24:25","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":915,"height":528,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2a9643049a4449d1c130c0199b018188_ab9ef7f3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2a9643049a4449d1c130c0199b018188_ab9ef7f3-300x173.jpg","medium-width":300,"medium-height":173,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2a9643049a4449d1c130c0199b018188_ab9ef7f3-768x443.jpg","medium_large-width":768,"medium_large-height":443,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2a9643049a4449d1c130c0199b018188_ab9ef7f3.jpg","large-width":915,"large-height":528,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2a9643049a4449d1c130c0199b018188_ab9ef7f3.jpg","1536x1536-width":915,"1536x1536-height":528,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2a9643049a4449d1c130c0199b018188_ab9ef7f3.jpg","2048x2048-width":915,"2048x2048-height":528,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2a9643049a4449d1c130c0199b018188_ab9ef7f3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":173,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2a9643049a4449d1c130c0199b018188_ab9ef7f3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":231,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2a9643049a4449d1c130c0199b018188_ab9ef7f3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":346}},"url_youtube":""},{"description":"","image":{"ID":621,"id":621,"title":"Palazzo Moroni","filename":"Palazzo-Moroni.jpg","filesize":613765,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/palazzo-moroni-2\/","alt":"","author":"4","description":"","caption":"","name":"palazzo-moroni-2","status":"inherit","uploaded_to":85480,"date":"2024-04-12 15:46:13","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1512,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni-300x214.jpg","medium-width":300,"medium-height":214,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni-768x549.jpg","medium_large-width":768,"medium_large-height":549,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni-1024x731.jpg","large-width":1024,"large-height":731,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni.jpg","1536x1536-width":1512,"1536x1536-height":1080,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni.jpg","2048x2048-width":1512,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":214,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":286,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/04\/Palazzo-Moroni.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":429}},"url_youtube":""},{"description":"","image":{"ID":2545,"id":2545,"title":"abd2f0c22ed0bd29d473203563d4ca07_e2ccc289.jpg","filename":"abd2f0c22ed0bd29d473203563d4ca07_e2ccc289.jpg","filesize":163589,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/abd2f0c22ed0bd29d473203563d4ca07_e2ccc289.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/palazzo-e-giardini-moroni\/abd2f0c22ed0bd29d473203563d4ca07_e2ccc289-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"abd2f0c22ed0bd29d473203563d4ca07_e2ccc289-jpg-2","status":"inherit","uploaded_to":19803,"date":"2024-05-08 08:34:23","modified":"2024-05-08 12:24:25","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":915,"height":528,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/abd2f0c22ed0bd29d473203563d4ca07_e2ccc289-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/abd2f0c22ed0bd29d473203563d4ca07_e2ccc289-300x173.jpg","medium-width":300,"medium-height":173,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/abd2f0c22ed0bd29d473203563d4ca07_e2ccc289-768x443.jpg","medium_large-width":768,"medium_large-height":443,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/abd2f0c22ed0bd29d473203563d4ca07_e2ccc289.jpg","large-width":915,"large-height":528,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/abd2f0c22ed0bd29d473203563d4ca07_e2ccc289.jpg","1536x1536-width":915,"1536x1536-height":528,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/abd2f0c22ed0bd29d473203563d4ca07_e2ccc289.jpg","2048x2048-width":915,"2048x2048-height":528,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/abd2f0c22ed0bd29d473203563d4ca07_e2ccc289.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":173,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/abd2f0c22ed0bd29d473203563d4ca07_e2ccc289.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":231,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/abd2f0c22ed0bd29d473203563d4ca07_e2ccc289.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":346}},"url_youtube":""},{"description":"","image":{"ID":2842,"id":2842,"title":"d81de8acbb8933099332994d78c0eb74_17b71d04.jpg","filename":"d81de8acbb8933099332994d78c0eb74_17b71d04.jpg","filesize":760363,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d81de8acbb8933099332994d78c0eb74_17b71d04.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/ex-monastero-di-santagostino\/d81de8acbb8933099332994d78c0eb74_17b71d04-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d81de8acbb8933099332994d78c0eb74_17b71d04-jpg-2","status":"inherit","uploaded_to":19811,"date":"2024-05-08 08:35:02","modified":"2024-05-08 12:24:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1285,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d81de8acbb8933099332994d78c0eb74_17b71d04-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d81de8acbb8933099332994d78c0eb74_17b71d04-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d81de8acbb8933099332994d78c0eb74_17b71d04-768x514.jpg","medium_large-width":768,"medium_large-height":514,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d81de8acbb8933099332994d78c0eb74_17b71d04-1024x685.jpg","large-width":1024,"large-height":685,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d81de8acbb8933099332994d78c0eb74_17b71d04-1536x1028.jpg","1536x1536-width":1536,"1536x1536-height":1028,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d81de8acbb8933099332994d78c0eb74_17b71d04.jpg","2048x2048-width":1920,"2048x2048-height":1285,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d81de8acbb8933099332994d78c0eb74_17b71d04.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d81de8acbb8933099332994d78c0eb74_17b71d04.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d81de8acbb8933099332994d78c0eb74_17b71d04.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":402}},"url_youtube":""},{"description":"","image":{"ID":2848,"id":2848,"title":"264d17555cd5101366aeaca22a8f7383_56371a2b.jpg","filename":"264d17555cd5101366aeaca22a8f7383_56371a2b.jpg","filesize":606832,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/264d17555cd5101366aeaca22a8f7383_56371a2b.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/ex-monastero-di-santagostino\/264d17555cd5101366aeaca22a8f7383_56371a2b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"264d17555cd5101366aeaca22a8f7383_56371a2b-jpg-2","status":"inherit","uploaded_to":19811,"date":"2024-05-08 08:35:02","modified":"2024-05-08 12:24:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":598,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/264d17555cd5101366aeaca22a8f7383_56371a2b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/264d17555cd5101366aeaca22a8f7383_56371a2b-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/264d17555cd5101366aeaca22a8f7383_56371a2b-768x296.jpg","medium_large-width":768,"medium_large-height":296,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/264d17555cd5101366aeaca22a8f7383_56371a2b-1024x395.jpg","large-width":1024,"large-height":395,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/264d17555cd5101366aeaca22a8f7383_56371a2b-1536x593.jpg","1536x1536-width":1536,"1536x1536-height":593,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/264d17555cd5101366aeaca22a8f7383_56371a2b.jpg","2048x2048-width":1550,"2048x2048-height":598,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/264d17555cd5101366aeaca22a8f7383_56371a2b.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/264d17555cd5101366aeaca22a8f7383_56371a2b.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":154,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/264d17555cd5101366aeaca22a8f7383_56371a2b.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":231}},"url_youtube":""},{"description":"","image":{"ID":74813,"id":74813,"title":"_44G0029","filename":"44G0029-scaled.jpg","filesize":1052493,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0029-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/_44g0029-2\/","alt":"","author":"8","description":"","caption":"","name":"_44g0029-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:16:20","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1651,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0029-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0029-300x193.jpg","medium-width":300,"medium-height":193,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0029-768x495.jpg","medium_large-width":768,"medium_large-height":495,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0029-1024x660.jpg","large-width":1024,"large-height":660,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0029-1536x991.jpg","1536x1536-width":1536,"1536x1536-height":991,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0029-2048x1321.jpg","2048x2048-width":2048,"2048x2048-height":1321,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0029-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":193,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0029-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":258,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/44G0029-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":387}},"url_youtube":""},{"description":"","image":{"ID":2860,"id":2860,"title":"d3b8a63738282638d7274199ba5d1c94_12b47dee.jpg","filename":"d3b8a63738282638d7274199ba5d1c94_12b47dee.jpg","filesize":614313,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d3b8a63738282638d7274199ba5d1c94_12b47dee.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/ex-monastero-di-santagostino\/d3b8a63738282638d7274199ba5d1c94_12b47dee-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d3b8a63738282638d7274199ba5d1c94_12b47dee-jpg-2","status":"inherit","uploaded_to":19811,"date":"2024-05-08 08:35:03","modified":"2024-05-08 12:24:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d3b8a63738282638d7274199ba5d1c94_12b47dee-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d3b8a63738282638d7274199ba5d1c94_12b47dee-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d3b8a63738282638d7274199ba5d1c94_12b47dee-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d3b8a63738282638d7274199ba5d1c94_12b47dee-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d3b8a63738282638d7274199ba5d1c94_12b47dee-1536x595.jpg","1536x1536-width":1536,"1536x1536-height":595,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d3b8a63738282638d7274199ba5d1c94_12b47dee.jpg","2048x2048-width":1550,"2048x2048-height":600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d3b8a63738282638d7274199ba5d1c94_12b47dee.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d3b8a63738282638d7274199ba5d1c94_12b47dee.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d3b8a63738282638d7274199ba5d1c94_12b47dee.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"url_youtube":""}]}]},{"acf_fc_layout":"filotto","filotto_title":"Interessante Punkte","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":[{"object":19831,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19803,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":20059,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19923,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":20056,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19784,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":20141,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19811,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":20027,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""}],"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Zwischen GAMeC und Accademia Carrara"},"tcm_ui":[{"label":"Dauer (ohne Museumsbesuch)","value":"10'"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p style=\"text-align: justify;\">Letzter Halt auf Ihrer Meile der Sch\u00f6nheit.<br \/>\nLassen Sie sich nicht von dem<em>&#8216;non latius<\/em>&#8216; (&#8216;nicht weiter&#8217;) einsch\u00fcchtern, das auf der kleinen Stele am Fu\u00dfe der Noca eingraviert ist und erreichen Sie die <strong>Piazza Giacomo Carrara<\/strong>.<br \/>\nDort finden Sie sich inmitten der H\u00f6hepunkte des k\u00fcnstlerischen Ausdrucks Bergamos wieder: Innovation, Kreativit\u00e4t, einzigartige Sammlungen und Perspektiven sind nur einige der Dinge, die die<strong>Accademia Carrara<\/strong> und die <strong>Galleria d&#8217;Arte Moderna<\/strong> zu bieten haben.<br \/>\nEntdecken Sie die unverzichtbaren Dauerausstellungen und lassen Sie sich von den Neuheiten faszinieren, die diese beiden Museen immer f\u00fcr Sie bereithalten!   <\/p>\n<p style=\"text-align: justify;\">Zu sch\u00f6n f\u00fcr eine einzelne Tour?<br \/>\nSie k\u00f6nnen auch die Piazza Carrara zu Ihrem Ausgangspunkt machen und die Meile hinauflaufen, um die Sch\u00f6nheit der Stadt vom Fu\u00dfe der Mauern bis zur Spitze der H\u00fcgel zu entdecken. <\/p>\n"},{"acf_fc_layout":"gallery","gallery_items":[{"description":"","image":{"ID":41622,"id":41622,"title":"_PQD5703_accademia carrara_esterno","filename":"PQD5703_accademia-carrara_esterno-scaled.jpg","filesize":1002244,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/PQD5703_accademia-carrara_esterno-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/i-musei-accademia-carrara-e-gamec\/_pqd5703_accademia-carrara_esterno-2\/","alt":"","author":"7","description":"","caption":"","name":"_pqd5703_accademia-carrara_esterno-2","status":"inherit","uploaded_to":80503,"date":"2024-06-20 10:19:46","modified":"2024-08-19 13:53:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/PQD5703_accademia-carrara_esterno-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/PQD5703_accademia-carrara_esterno-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/PQD5703_accademia-carrara_esterno-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/PQD5703_accademia-carrara_esterno-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/PQD5703_accademia-carrara_esterno-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/PQD5703_accademia-carrara_esterno-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/PQD5703_accademia-carrara_esterno-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/PQD5703_accademia-carrara_esterno-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/PQD5703_accademia-carrara_esterno-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"url_youtube":""},{"description":"","image":{"ID":74879,"id":74879,"title":"Accademia Carrara museum, Lower Bergamo","filename":"Accademia-Carrara-museum-Lower-Bergamo-scaled.jpg","filesize":589126,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/accademia-carrara-museum-lower-bergamo-2\/","alt":"","author":"8","description":"","caption":"","name":"accademia-carrara-museum-lower-bergamo-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:19:31","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1709,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-2048x1367.jpg","2048x2048-width":2048,"2048x2048-height":1367,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/Accademia-Carrara-museum-Lower-Bergamo-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"url_youtube":""},{"description":"","image":{"ID":74891,"id":74891,"title":"DSC_5822","filename":"DSC_5822-scaled.jpg","filesize":892399,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_5822-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/die-meile-der-schoenheit\/dsc_5822-2\/","alt":"","author":"8","description":"","caption":"","name":"dsc_5822-2","status":"inherit","uploaded_to":85480,"date":"2024-08-12 16:20:54","modified":"2024-10-08 10:33:33","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1709,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_5822-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_5822-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_5822-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_5822-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_5822-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_5822-2048x1367.jpg","2048x2048-width":2048,"2048x2048-height":1367,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_5822-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_5822-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/08\/DSC_5822-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"url_youtube":""}]}]},{"acf_fc_layout":"filotto","filotto_title":"Interessante Punkte","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":[{"object":20032,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":19903,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""}],"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},{"acf_fc_layout":"one_column_module","ctac_title":"Bereit f\u00fcr mehr Reiserouten?","ctac_text":"<p>Entdecken Sie die sch\u00f6nsten Routen in der Rubrik <strong>Where To Go<\/strong> der Website!<\/p>\n","ctac_buttons":{"buttons":false},"ctac_buttons_new":false}],"filotto_layout":"scroll","hero_title":"Die Meile der Sch\u00f6nheit","hero_text":"<p>Die Reiseroute des Autors, um die authentische Sch\u00f6nheit von Bergamo zu entdecken<\/p>\n","size":"full","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"filotto_fill":"manual","filotto_items":false,"hero_type":"images","filotto_title":"","filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"hero_buttons":false,"is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/74806"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=85480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=85480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=85480"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=85480"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=85480"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=85480"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=85480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}