{"id":85547,"date":"2024-09-18T12:00:57","date_gmt":"2024-09-18T10:00:57","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/trekking-von-bueggio-zum-gleno-staudamm\/"},"modified":"2024-10-08T15:21:50","modified_gmt":"2024-10-08T13:21:50","slug":"trekking-von-bueggio-zum-gleno-staudamm","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/trekking-von-bueggio-zum-gleno-staudamm\/","title":{"rendered":"Trekking von Bueggio zum Gleno-Staudamm"},"excerpt":{"rendered":"","protected":false},"author":35,"featured_media":79151,"template":"","categories":[],"tags":[],"aggr":[],"area":[],"kind":[18685],"zona":[],"class_list":["post-85547","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","kind-itinerario-de"],"acf":{"featured_video":false,"slides":[{"image":{"ID":79114,"id":79114,"title":"G6","filename":"G6-5.jpg","filesize":433101,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-5.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/trekking-von-bueggio-zum-gleno-staudamm\/g6-6-2\/","alt":"","author":"35","description":"","caption":"","name":"g6-6-2","status":"inherit","uploaded_to":85547,"date":"2024-09-18 10:24:59","modified":"2024-10-07 10:13:55","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1275,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-5-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-5-768x510.jpg","medium_large-width":768,"medium_large-height":510,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-5-1024x680.jpg","large-width":1024,"large-height":680,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-5-1536x1020.jpg","1536x1536-width":1536,"1536x1536-height":1020,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-5.jpg","2048x2048-width":1920,"2048x2048-height":1275,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-5.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-5.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-5.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":398}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":79120,"id":79120,"title":"G7","filename":"G7-5.jpg","filesize":373794,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-5.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/trekking-von-bueggio-zum-gleno-staudamm\/g7-6-2\/","alt":"","author":"35","description":"","caption":"","name":"g7-6-2","status":"inherit","uploaded_to":85547,"date":"2024-09-18 10:25:01","modified":"2024-10-07 10:13:55","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1275,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-5-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-5-768x510.jpg","medium_large-width":768,"medium_large-height":510,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-5-1024x680.jpg","large-width":1024,"large-height":680,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-5-1536x1020.jpg","1536x1536-width":1536,"1536x1536-height":1020,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-5.jpg","2048x2048-width":1920,"2048x2048-height":1275,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-5.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-5.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-5.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":398}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":79157,"id":79157,"title":"G13","filename":"G13.jpg","filesize":411829,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G13.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/trekking-von-bueggio-zum-gleno-staudamm\/g13-2\/","alt":"","author":"35","description":"","caption":"","name":"g13-2","status":"inherit","uploaded_to":85547,"date":"2024-09-18 10:25:10","modified":"2024-10-07 10:13:55","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1263,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G13-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G13-300x197.jpg","medium-width":300,"medium-height":197,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G13-768x505.jpg","medium_large-width":768,"medium_large-height":505,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G13-1024x674.jpg","large-width":1024,"large-height":674,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G13-1536x1010.jpg","1536x1536-width":1536,"1536x1536-height":1010,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G13.jpg","2048x2048-width":1920,"2048x2048-height":1263,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G13.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":197,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G13.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":263,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G13.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":395}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":79132,"id":79132,"title":"G9","filename":"G9-6.jpg","filesize":504001,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-6.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/trekking-von-bueggio-zum-gleno-staudamm\/g9-7-2\/","alt":"","author":"35","description":"","caption":"","name":"g9-7-2","status":"inherit","uploaded_to":85547,"date":"2024-09-18 10:25:04","modified":"2024-10-07 10:13:55","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1275,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-6-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-6-768x510.jpg","medium_large-width":768,"medium_large-height":510,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-6-1024x680.jpg","large-width":1024,"large-height":680,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-6-1536x1020.jpg","1536x1536-width":1536,"1536x1536-height":1020,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-6.jpg","2048x2048-width":1920,"2048x2048-height":1275,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":398}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":79126,"id":79126,"title":"G8","filename":"G8-4.jpg","filesize":428470,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-4.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/trekking-von-bueggio-zum-gleno-staudamm\/g8-5-2\/","alt":"","author":"35","description":"","caption":"","name":"g8-5-2","status":"inherit","uploaded_to":85547,"date":"2024-09-18 10:25:02","modified":"2024-10-07 10:13:55","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1275,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-4-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-4-768x510.jpg","medium_large-width":768,"medium_large-height":510,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-4-1024x680.jpg","large-width":1024,"large-height":680,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-4-1536x1020.jpg","1536x1536-width":1536,"1536x1536-height":1020,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-4.jpg","2048x2048-width":1920,"2048x2048-height":1275,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":398}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":79138,"id":79138,"title":"G10","filename":"G10-6.jpg","filesize":432619,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-6.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/trekking-von-bueggio-zum-gleno-staudamm\/g10-7-2\/","alt":"","author":"35","description":"","caption":"","name":"g10-7-2","status":"inherit","uploaded_to":85547,"date":"2024-09-18 10:25:05","modified":"2024-10-07 10:13:55","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1275,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-6-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-6-768x510.jpg","medium_large-width":768,"medium_large-height":510,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-6-1024x680.jpg","large-width":1024,"large-height":680,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-6-1536x1020.jpg","1536x1536-width":1536,"1536x1536-height":1020,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-6.jpg","2048x2048-width":1920,"2048x2048-height":1275,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":398}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":79145,"id":79145,"title":"G11","filename":"G11-5.jpg","filesize":356885,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G11-5.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/trekking-von-bueggio-zum-gleno-staudamm\/g11-6-2\/","alt":"","author":"35","description":"","caption":"","name":"g11-6-2","status":"inherit","uploaded_to":85547,"date":"2024-09-18 10:25:07","modified":"2024-10-07 10:13:55","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1275,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G11-5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G11-5-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G11-5-768x510.jpg","medium_large-width":768,"medium_large-height":510,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G11-5-1024x680.jpg","large-width":1024,"large-height":680,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G11-5-1536x1020.jpg","1536x1536-width":1536,"1536x1536-height":1020,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G11-5.jpg","2048x2048-width":1920,"2048x2048-height":1275,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G11-5.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G11-5.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G11-5.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":398}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":79151,"id":79151,"title":"G12","filename":"G12-4.jpg","filesize":380834,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G12-4.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/trekking-von-bueggio-zum-gleno-staudamm\/g12-5-2\/","alt":"","author":"35","description":"","caption":"","name":"g12-5-2","status":"inherit","uploaded_to":85547,"date":"2024-09-18 10:25:08","modified":"2024-10-07 10:13:55","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1273,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G12-4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G12-4-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G12-4-768x509.jpg","medium_large-width":768,"medium_large-height":509,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G12-4-1024x679.jpg","large-width":1024,"large-height":679,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G12-4-1536x1018.jpg","1536x1536-width":1536,"1536x1536-height":1018,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G12-4.jpg","2048x2048-width":1920,"2048x2048-height":1273,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G12-4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G12-4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":265,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G12-4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":398}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"modules":[{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":""},"tcm_ui":[{"label":"ABFAHRT:","value":"Bueggio, Vilminore"},{"label":"ANKOMMEN:","value":"Bueggio, Vilminore"},{"label":"ERREICHBAR IN:","value":"Auto - nehmen Sie die SP 35 Bergamo - Nembro und die SP35dir in Richtung SS671 in Nembro in Richtung Colere.\nFolgen Sie der SP294, SP61 und SP58 in Richtung der Via San Gottardo in Vilminore di Scalve "},{"label":"BUSVERBINDUNGEN:","value":"der Bus S70A aus Bergamo kommt in 2 Stunden in Vilminore im Stadtzentrum an.\nVon Vilminore aus m\u00fcssen Sie Pianezza erreichen (5 Minuten mit dem Auto, 50 Minuten zu Fu\u00df).\nIm Sommer gibt es einen Shuttle-Bus von Vilminore nach Pianezza.  "}],"tcm_content":[{"acf_fc_layout":"text","text":"<p>          <span style=\"font-weight: 400;\">Wenn Sie auf der Suche nach einem Abenteuer sind, das Natursch\u00f6nheiten und Geschichte miteinander verbindet, ist Bueggio, ein Ortsteil von Vilminore di Scalve, der ideale Ausgangspunkt.<br \/>\nAuf diesem Rundweg k\u00f6nnen Sie den menschlichen Erfindungsreichtum und die Kraft der Natur entdecken und gleichzeitig in die Erinnerungen an eine tragische Katastrophe eintauchen. <\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-78948 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-5-1024x680.jpg\" alt=\"\" width=\"1024\" height=\"680\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-5-1024x680.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-5-300x199.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-5-768x510.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-5-1536x1020.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-5.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":""},"tcm_ui":[{"label":"L\u00c4NGE:","value":"8.8 km"},{"label":"DAUER:","value":"4 Stunden"},{"label":"OFFENLEGUNG:","value":"+510 m"},{"label":"SCHWIERIGKEIT:","value":"E - Wandern"},{"label":"REISEROUTEN-TYPOLOGIE:","value":"zu Fu\u00df, in einer Schleife"}],"tcm_content":[{"acf_fc_layout":"googlemap_embed","map":{"locations":false,"file_kml":false}},{"acf_fc_layout":"buttons","buttons":[{"style":"primary","text":"Laden Sie das GPX herunter  ","icon":{"button_icon":"none"},"function":"link","url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/8-Gleno-escursione-traccia-17-1.gpx","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}]}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Start der Route"},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"text","text":"<p>          <span style=\"font-weight: 400;\">Von Bueggio aus, auf einer H\u00f6he von 1.052 Metern, folgen Sie der Beschilderung des Weges Nr. 410, der links vom Dorf den Bach Povo hinauff\u00fchrt.<br \/>\nDer erste Halt ist bei Ponte del Gleno, wo Sie einen Picknickplatz finden, der ideal f\u00fcr eine Pause ist.<br \/>\nHier k\u00f6nnen Sie die Zeit nutzen, um die &#8216;Marmitte dei giganti&#8217; (Schlagl\u00f6cher der Giganten) zu besichtigen, besondere felsige Hohlr\u00e4ume, die durch die erosive Wirkung von Wasser und Gletschern entstanden sind.<br \/>\nDiese L\u00f6cher, die gro\u00dfen T\u00f6pfen \u00e4hneln, hei\u00dfen so, weil man im Volksmund glaubte, dass sie von Riesen zum Kochen benutzt wurden.<br \/>\nLassen Sie sich von diesem Naturschauspiel verzaubern und setzen Sie dann Ihren Spaziergang im Wald fort, wo der Schatten der B\u00e4ume Ihnen eine angenehme K\u00fchle bietet.    <\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-78936 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-5-1024x680.jpg\" alt=\"\" width=\"1024\" height=\"680\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-5-1024x680.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-5-300x199.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-5-768x510.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-5-1536x1020.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-5.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Der Gleno-Damm und seine Geschichte"},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"text","text":"<p>          <span style=\"font-weight: 400;\">Wenn Sie dem Weg weiter folgen, erreichen Sie eine H\u00f6he von etwa 1.550 Metern, wo die \u00dcberreste des Gleno-Staudamms stehen.<br \/>\nDieses Bauwerk, das vor \u00fcber f\u00fcnfzig Jahren schwer besch\u00e4digt wurde, wird Sie mit seiner imposanten Mauer beeindrucken.<br \/>\nUm das Ausma\u00df der Katastrophe, die sich am 1. Dezember 1923 ereignete, zu verstehen, sollten Sie sich die Erkl\u00e4rungstafeln in der N\u00e4he ansehen.<br \/>\nBeim Anblick der B\u00f6gen des Staudamms, der 6 Millionen Kubikmeter Wasser fassen soll, werden Sie sich angesichts der Gr\u00f6\u00dfe des Bauwerks und der Naturgewalten klein f\u00fchlen.   <\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-78930 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G3-5-1024x676.jpg\" alt=\"\" width=\"1024\" height=\"676\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G3-5-1024x676.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G3-5-300x198.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G3-5-768x507.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G3-5-1536x1014.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G3-5.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Der Belviso-Pass und kontrastreiche Landschaften"},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"text","text":"<p><span style=\"font-weight: 400;\">Wenn Sie den Weg fortsetzen, k\u00f6nnte der gut trainierte Wanderer nach weiteren drei Stunden guten Gehens den Belviso-Pass auf 2516 Metern H\u00f6he erreichen, von wo aus Sie die Unermesslichkeit des gesamten Tals bewundern k\u00f6nnen. Wir hingegen erreichen kurz darauf die saisonale Rastst\u00e4tte oberhalb, wo Sie eine kurze Pause einlegen oder ein komplettes Mittagessen genie\u00dfen k\u00f6nnen, w\u00e4hrend Sie das umliegende Panorama bewundern.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Zur\u00fcck auf dem Weg erreichen Sie den n\u00f6rdlichsten Punkt des Gleno-Beckens und gehen \u00fcber die kleine Holzbr\u00fccke am linken orographischen Ufer des Sees entlang bis zu den Ruinen der Staumauer. <\/span> <\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-78924 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G2-5-1024x680.jpg\" alt=\"\" width=\"1024\" height=\"680\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G2-5-1024x680.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G2-5-300x199.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G2-5-768x510.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G2-5-1536x1020.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G2-5.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Die R\u00fcckkehr \u00fcber den Pfad 411"},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"text","text":"<p>          <span style=\"font-weight: 400;\">F\u00fcr den R\u00fcckweg nehmen Sie den Weg 411 nach Pianezza, der Teil des Via Decia Weges ist.<br \/>\nDiese Route ist bekannt f\u00fcr ihren Weg durch Eisenholzw\u00e4lder.<br \/>\nNachdem Sie einen kleinen Staudamm passiert haben, der noch in Betrieb ist, wird der Weg flach und ist stellenweise in den Fels gehauen.<br \/>\nNach den Wasserrohren wird der Abstieg steil.<br \/>\nWenn Sie den kleinen Platz in Pianezza erreichen, folgen Sie der Stra\u00dfe ein paar hundert Meter bis zur ersten Haarnadelkurve, wo Sie den Weg nach Bueggio wieder aufnehmen k\u00f6nnen.<br \/>\nDiese Wanderung bietet eine faszinierende Mischung aus Natur und Geschichte, zwischen den Ruinen des Gleno-Staudamms und der unber\u00fchrten Sch\u00f6nheit der Berglandschaft.<br \/>\nIch hoffe, Sie genie\u00dfen diesen Ausflug und nehmen unvergessliche Erinnerungen an diese herrliche Gegend des Gebiets von Bergamo mit.<br \/>\nViel Spa\u00df bei Ihrem Ausflug!       <\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-78918 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G1-6-1024x680.jpg\" alt=\"\" width=\"1024\" height=\"680\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G1-6-1024x680.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G1-6-300x199.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G1-6-768x510.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G1-6-1536x1020.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G1-6.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]}],"filotto_layout":"scroll","hero_title":"Trekking von Bueggio zum Gleno-Staudamm","hero_text":"<p>          <span style=\"font-weight: 400;\">Die Mutter, die 50 Tage lebte<\/span><\/p>\n","size":"full","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"filotto_fill":"manual","filotto_items":false,"hero_type":"images","filotto_title":"","filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"hero_buttons":false,"is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85547","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/35"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85547\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/79151"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=85547"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=85547"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=85547"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=85547"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=85547"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=85547"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=85547"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}