{"id":85572,"date":"2024-09-18T10:23:53","date_gmt":"2024-09-18T08:23:53","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/von-piazzo-nach-rifugio-gremei\/"},"modified":"2024-10-08T15:22:32","modified_gmt":"2024-10-08T13:22:32","slug":"von-piazzo-nach-rifugio-gremei","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-piazzo-nach-rifugio-gremei\/","title":{"rendered":"Von Piazzo nach Rifugio Gremei"},"excerpt":{"rendered":"","protected":false},"author":35,"featured_media":78554,"template":"","categories":[],"tags":[],"aggr":[],"area":[],"kind":[18685],"zona":[],"class_list":["post-85572","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","kind-itinerario-de"],"acf":{"featured_video":false,"slides":[{"image":{"ID":78578,"id":78578,"title":"G10","filename":"G10-4.jpg","filesize":349580,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-4.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-piazzo-nach-rifugio-gremei\/g10-5-2\/","alt":"","author":"35","description":"","caption":"","name":"g10-5-2","status":"inherit","uploaded_to":85572,"date":"2024-09-18 08:51:57","modified":"2024-10-07 10:15:11","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-4-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-4-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-4-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-4-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-4.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G10-4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":78572,"id":78572,"title":"G9","filename":"G9-4.jpg","filesize":485988,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-4.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-piazzo-nach-rifugio-gremei\/g9-5-2\/","alt":"","author":"35","description":"","caption":"","name":"g9-5-2","status":"inherit","uploaded_to":85572,"date":"2024-09-18 08:51:56","modified":"2024-10-07 10:15:11","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-4-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-4-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-4-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-4-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-4.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G9-4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":78548,"id":78548,"title":"G5","filename":"G5-3.jpg","filesize":362930,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-3.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-piazzo-nach-rifugio-gremei\/g5-4-2\/","alt":"","author":"35","description":"","caption":"","name":"g5-4-2","status":"inherit","uploaded_to":85572,"date":"2024-09-18 08:51:50","modified":"2024-10-07 10:15:11","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-3-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-3-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-3-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-3-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-3.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G5-3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":78554,"id":78554,"title":"G6","filename":"G6-3.jpg","filesize":277447,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-3.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-piazzo-nach-rifugio-gremei\/g6-4-2\/","alt":"","author":"35","description":"","caption":"","name":"g6-4-2","status":"inherit","uploaded_to":85572,"date":"2024-09-18 08:51:51","modified":"2024-10-07 10:15:11","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-3-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-3-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-3-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-3-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-3.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G6-3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":78560,"id":78560,"title":"G7","filename":"G7-3.jpg","filesize":486027,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-3.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-piazzo-nach-rifugio-gremei\/g7-4-2\/","alt":"","author":"35","description":"","caption":"","name":"g7-4-2","status":"inherit","uploaded_to":85572,"date":"2024-09-18 08:51:53","modified":"2024-10-07 10:15:11","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-3-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-3-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-3-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-3-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-3.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G7-3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":78566,"id":78566,"title":"G8","filename":"G8-2.jpg","filesize":575135,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-2.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-piazzo-nach-rifugio-gremei\/g8-3-2\/","alt":"","author":"35","description":"","caption":"","name":"g8-3-2","status":"inherit","uploaded_to":85572,"date":"2024-09-18 08:51:54","modified":"2024-10-07 10:15:11","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-2-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-2-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-2-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-2-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-2.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G8-2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":78542,"id":78542,"title":"G4","filename":"G4-3.jpg","filesize":373478,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-3.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-piazzo-nach-rifugio-gremei\/g4-4-2\/","alt":"","author":"35","description":"","caption":"","name":"g4-4-2","status":"inherit","uploaded_to":85572,"date":"2024-09-18 08:51:48","modified":"2024-10-07 10:15:11","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-3-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-3-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-3-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-3-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-3.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G4-3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"modules":[{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":""},"tcm_ui":[{"label":"ABFAHRT:","value":"Ortschaft Piazzo - Piazzatorre  "},{"label":"ANKOMMEN:","value":"Ortschaft Piazzo - Piazzatorre"},{"label":"ERREICHBAR IN:","value":"SS470 Valle Brembana bis Piazza Brembana und nehmen Sie die SP1 nach Piazzatorre"},{"label":"BUSVERBINDUNGEN:","value":"Der Bus B50 aus Bergamo kommt in etwa 2 Stunden in Piazzatorre an.\nVon Piazzatorre aus gehen Sie 1,5 km (ca. 30 Minuten) bis nach Piazzo, dem Ausgangspunkt der Wanderung "},{"label":"PARKEN:","value":"Gro\u00dfer Parkplatz am Sessellift Gremei  "}],"tcm_content":[{"acf_fc_layout":"text","text":"<p>          <span style=\"font-weight: 400;\">Die Wanderung von Piazzo zum Rifugio Gremei im Herzen des oberen Brembana-Tals bietet eine beeindruckende Route durch \u00fcppige W\u00e4lder und atemberaubende Aussichten.<br \/>\nAusgehend von dem malerischen Dorf Piazzo verbindet diese Route die Herausforderung der Anstiege mit der Ruhe der Almen und gipfelt in der einladenden Gremei-H\u00fctte. <\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-78482 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G2-3-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G2-3-1024x683.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G2-3-300x200.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G2-3-768x512.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G2-3-1536x1024.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G2-3.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":""},"tcm_ui":[{"label":"L\u00c4NGE:","value":"9 km"},{"label":"DAUER:","value":"4 Stunden"},{"label":"OFFENLEGUNG:","value":"+640 m"},{"label":"SCHWIERIGKEIT:","value":"EE - Erfahrene Wanderer"},{"label":"REISEROUTEN-TYPOLOGIE:","value":"zu Fu\u00df, in einer Schleife"}],"tcm_content":[{"acf_fc_layout":"googlemap_embed","map":{"locations":false,"file_kml":false}},{"acf_fc_layout":"buttons","buttons":[{"style":"primary","text":"GPX HERUNTERLADEN  ","icon":{"button_icon":"none"},"function":"link","url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/5-percorso_5___percorso-3-BIS-gremei-cortissimo.gpx","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}]}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"In Richtung Torcola Vaga"},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"text","text":"<p>          <span style=\"font-weight: 400;\">Piazzatorre, das von Bergamo aus leicht mit der Buslinie B50 oder mit dem Auto durch Parken an den Skiliften zu erreichen ist, ist der ideale Ausgangspunkt f\u00fcr dieses Bergabenteuer.<br \/>\nDer Start der Route ist in Piazzo, das auf einer H\u00f6he von 1.105 Metern liegt.<br \/>\nVon hier aus nehmen Sie den Weg Nummer 121, der sich links zwischen der Eisbahn und dem Sessellift nach Gremei befindet.<br \/>\nDie Landstra\u00dfe steigt mit einer Reihe von steilen Kehren am Wald entlang an und folgt dem Lauf des Piazzatorre-Bachs bis zu einem Falsopiano.<br \/>\nSobald Sie den Bach hinter sich gelassen haben, geht es mit m\u00e4\u00dfigeren Steigungen weiter und Sie erreichen die K\u00e4serei Torcola Vaga auf einer H\u00f6he von 1.486 Metern.<br \/>\nHier verwandelt sich die Landschaft in eine m\u00e4rchenhafte Umgebung, die von Weiden und sp\u00e4rlichen Tannen umgeben ist. Ein paar H\u00fctten zeugen von der einst h\u00e4ufigen sommerlichen Weidet\u00e4tigkeit.     <\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-78488 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G3-3-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G3-3-1024x683.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G3-3-300x200.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G3-3-768x512.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G3-3-1536x1024.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G3-3.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Von Corna dei Bagoli nach Rifugio Gremei"},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"text","text":"<p>          <span style=\"font-weight: 400;\">Gleich hinter der Casera verlassen Sie den Feldweg und steigen links \u00fcber die gr\u00fcnen Weiden hinauf, bis Sie den Sattel der Corna dei Bagoli erreichen, eine der landschaftlich sch\u00f6nsten Etappen der Route.<br \/>\nVon Baita Alta aus nehmen Sie den Weg 119 auf der rechten Seite, der zur Kammlinie f\u00fchrt.<br \/>\nDieser Teil der Route stellt den H\u00f6hepunkt der Anstrengung dar, bietet aber auch die besten Aussichten, da Sie das Tal unter Ihnen aus jedem Winkel bewundern k\u00f6nnen.  <\/span><\/p>\n<p>          <span style=\"font-weight: 400;\">Nach dem Erreichen des Gipfels der Corna dei Bagoli, am f\u00fcnften Kilometer, k\u00f6nnen die trainierteren Wanderer leicht zum nahegelegenen Gipfel des Monte Torcola Soliva weitergehen, an dessen Spitze die ehemalige Torcole-H\u00fctte steht, ein privilegierter Aussichtspunkt \u00fcber einen Gro\u00dfteil des Valle Brembana.<br \/>\nAndernfalls setzen Sie den Weg fort und biegen scharf nach rechts hinunter zum Rifugio Gremei ab. 1.550 Meter \u00fcber dem Meeresspiegel und in der N\u00e4he der Skilifte gelegen, ist die H\u00fctte ein beliebter Treffpunkt f\u00fcr Bergfreunde und Gelegenheitswanderer.<br \/>\nHier k\u00f6nnen Sie sich im Solarium entspannen und eine gute Mahlzeit genie\u00dfen, was das Erlebnis nach der anstrengenden Wanderung noch lohnender macht.  <\/span><\/p>\n<p>          <span style=\"font-weight: 400;\">F\u00fcr den R\u00fcckweg gehen Sie unterhalb der Ankunftsstation des Sessellifts Gremei 1 vorbei.<br \/>\nNach etwa 400 Metern im Wald trifft der Weg wieder auf die K\u00e4serei Torcola Vaga und bietet Ihnen eine Route, die Sie bereits von der Hinfahrt her kennen.<br \/>\nAlternativ k\u00f6nnen Sie sich auch f\u00fcr eine entspannte Abfahrt mit dem Sessellift entscheiden, bei der Sie die herrliche Naturlandschaft der Region von oben bewundern k\u00f6nnen.  <\/span><\/p>\n<p>          <span style=\"font-weight: 400;\">Diese Route bietet zwischen anspruchsvollen Anstiegen und malerischen Abfahrten ein komplettes und lohnendes Wandererlebnis inmitten der nat\u00fcrlichen Sch\u00f6nheit des oberen Brembana-Tals.<\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-78476 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G1-4-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G1-4-1024x683.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G1-4-300x200.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G1-4-768x512.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G1-4-1536x1024.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/G1-4.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]}],"filotto_layout":"scroll","hero_title":"Von Piazzo nach Rifugio Gremei","hero_text":"<p>          <span style=\"font-weight: 400;\">Die H\u00f6hen und Tiefen des Torcole<\/span><\/p>\n","size":"full","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"filotto_fill":"manual","filotto_items":false,"hero_type":"images","filotto_title":"","filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"hero_buttons":false,"is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/35"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/78554"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=85572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=85572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=85572"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=85572"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=85572"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=85572"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=85572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}