{"id":85597,"date":"2024-09-16T16:17:21","date_gmt":"2024-09-16T14:17:21","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/von-der-cespedosio-huette-zu-den-gipfeln\/"},"modified":"2024-10-08T15:23:10","modified_gmt":"2024-10-08T13:23:10","slug":"von-der-cespedosio-huette-zu-den-gipfeln","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-der-cespedosio-huette-zu-den-gipfeln\/","title":{"rendered":"Von der Cespedosio-H\u00fctte zu den Gipfeln"},"excerpt":{"rendered":"","protected":false},"author":35,"featured_media":78450,"template":"","categories":[],"tags":[],"aggr":[],"area":[],"kind":[18685],"zona":[],"class_list":["post-85597","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","kind-itinerario-de"],"acf":{"featured_video":false,"slides":[{"image":{"ID":78414,"id":78414,"title":"C5","filename":"C5-1.jpg","filesize":357533,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C5-1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-der-cespedosio-huette-zu-den-gipfeln\/c5-2-2\/","alt":"","author":"35","description":"","caption":"","name":"c5-2-2","status":"inherit","uploaded_to":85597,"date":"2024-09-18 08:17:19","modified":"2024-10-07 10:16:14","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1267,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C5-1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C5-1-300x198.jpg","medium-width":300,"medium-height":198,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C5-1-768x507.jpg","medium_large-width":768,"medium_large-height":507,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C5-1-1024x676.jpg","large-width":1024,"large-height":676,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C5-1-1536x1014.jpg","1536x1536-width":1536,"1536x1536-height":1014,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C5-1.jpg","2048x2048-width":1920,"2048x2048-height":1267,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C5-1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":198,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C5-1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":264,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C5-1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":396}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":78420,"id":78420,"title":"C6","filename":"C6-1.jpg","filesize":442598,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C6-1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-der-cespedosio-huette-zu-den-gipfeln\/c6-2-2\/","alt":"","author":"35","description":"","caption":"","name":"c6-2-2","status":"inherit","uploaded_to":85597,"date":"2024-09-18 08:17:21","modified":"2024-10-07 10:16:14","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1268,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C6-1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C6-1-300x198.jpg","medium-width":300,"medium-height":198,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C6-1-768x507.jpg","medium_large-width":768,"medium_large-height":507,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C6-1-1024x676.jpg","large-width":1024,"large-height":676,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C6-1-1536x1014.jpg","1536x1536-width":1536,"1536x1536-height":1014,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C6-1.jpg","2048x2048-width":1920,"2048x2048-height":1268,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C6-1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":198,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C6-1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":264,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C6-1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":396}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":78450,"id":78450,"title":"C12","filename":"C12-1.jpg","filesize":551191,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C12-1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-der-cespedosio-huette-zu-den-gipfeln\/c12-2-2\/","alt":"","author":"35","description":"","caption":"","name":"c12-2-2","status":"inherit","uploaded_to":85597,"date":"2024-09-18 08:17:29","modified":"2024-10-07 10:16:14","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1284,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C12-1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C12-1-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C12-1-768x514.jpg","medium_large-width":768,"medium_large-height":514,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C12-1-1024x685.jpg","large-width":1024,"large-height":685,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C12-1-1536x1027.jpg","1536x1536-width":1536,"1536x1536-height":1027,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C12-1.jpg","2048x2048-width":1920,"2048x2048-height":1284,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C12-1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C12-1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C12-1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":78426,"id":78426,"title":"C7","filename":"C7-1.jpg","filesize":397357,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C7-1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-der-cespedosio-huette-zu-den-gipfeln\/c7-2-2\/","alt":"","author":"35","description":"","caption":"","name":"c7-2-2","status":"inherit","uploaded_to":85597,"date":"2024-09-18 08:17:23","modified":"2024-10-07 10:16:14","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1277,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C7-1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C7-1-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C7-1-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C7-1-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C7-1-1536x1022.jpg","1536x1536-width":1536,"1536x1536-height":1022,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C7-1.jpg","2048x2048-width":1920,"2048x2048-height":1277,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C7-1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C7-1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C7-1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":78438,"id":78438,"title":"C10","filename":"C10-1.jpg","filesize":528815,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C10-1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-der-cespedosio-huette-zu-den-gipfeln\/c10-2-2\/","alt":"","author":"35","description":"","caption":"","name":"c10-2-2","status":"inherit","uploaded_to":85597,"date":"2024-09-18 08:17:26","modified":"2024-10-07 10:16:14","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C10-1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C10-1-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C10-1-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C10-1-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C10-1-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C10-1.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C10-1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C10-1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C10-1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":78432,"id":78432,"title":"C8","filename":"C8-1.jpg","filesize":439906,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C8-1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-der-cespedosio-huette-zu-den-gipfeln\/c8-2-2\/","alt":"","author":"35","description":"","caption":"","name":"c8-2-2","status":"inherit","uploaded_to":85597,"date":"2024-09-18 08:17:24","modified":"2024-10-07 10:16:14","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1270,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C8-1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C8-1-300x198.jpg","medium-width":300,"medium-height":198,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C8-1-768x508.jpg","medium_large-width":768,"medium_large-height":508,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C8-1-1024x677.jpg","large-width":1024,"large-height":677,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C8-1-1536x1016.jpg","1536x1536-width":1536,"1536x1536-height":1016,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C8-1.jpg","2048x2048-width":1920,"2048x2048-height":1270,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C8-1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":198,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C8-1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":265,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C8-1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":397}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":78444,"id":78444,"title":"C11","filename":"C11-1.jpg","filesize":426372,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C11-1.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/von-der-cespedosio-huette-zu-den-gipfeln\/c11-2-2\/","alt":"","author":"35","description":"","caption":"","name":"c11-2-2","status":"inherit","uploaded_to":85597,"date":"2024-09-18 08:17:28","modified":"2024-10-07 10:16:14","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1269,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C11-1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C11-1-300x198.jpg","medium-width":300,"medium-height":198,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C11-1-768x508.jpg","medium_large-width":768,"medium_large-height":508,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C11-1-1024x677.jpg","large-width":1024,"large-height":677,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C11-1-1536x1015.jpg","1536x1536-width":1536,"1536x1536-height":1015,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C11-1.jpg","2048x2048-width":1920,"2048x2048-height":1269,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C11-1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":198,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C11-1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":264,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C11-1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":397}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"modules":[{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":""},"tcm_ui":[{"label":"ABFAHRT:","value":"Cespedosio Zuflucht, Camerata Cornello"},{"label":"ANKOMMEN:","value":"Baita Campo, Piazza Brembana"},{"label":"ERREICHBAR IN:","value":"Auto - SS470 Valle Brembana bis Lenna und nehmen Sie die Gemeindestra\u00dfe nach Camerata Cornello  "},{"label":"","value":""}],"tcm_content":[{"acf_fc_layout":"text","text":"<p>          <span style=\"font-weight: 400;\">Die Cespedosio-H\u00fctte liegt \u00fcber tausend Meter \u00fcber dem Meeresspiegel am Osthang des Monte Venturosa.<br \/>\nDie H\u00fctte ist der ideale Ausgangspunkt f\u00fcr die Erkundung der hohen Gipfel der Region und bietet Wanderern atemberaubende Aussichten und ein v\u00f6lliges Eintauchen in die Natur. <\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-78352 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C4-1024x682.jpg\" alt=\"\" width=\"1024\" height=\"682\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C4-1024x682.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C4-300x200.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C4-768x512.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C4-1536x1023.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C4.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":""},"tcm_ui":[{"label":"L\u00c4NGE:","value":"4.2 km"},{"label":"DAUER:","value":"1 h 30 min"},{"label":"OFFENLEGUNG:","value":"+380 m"},{"label":"SCHWIERIGKEIT:","value":"E - Wandern"},{"label":"REISEROUTEN-TYPOLOGIE:","value":"Gehen, linear"}],"tcm_content":[{"acf_fc_layout":"googlemap_embed","map":{"locations":false,"file_kml":false}},{"acf_fc_layout":"buttons","buttons":[{"style":"primary","text":"GPX HERUNTERLADEN","icon":{"button_icon":"none"},"function":"link","url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/4-Cespedosio.gpx","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}]}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Standort \u00c4ra"},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"text","text":"<p>          <span style=\"font-weight: 400;\">Um die H\u00fctte zu erreichen, haben Sie zwei M\u00f6glichkeiten.<br \/>\nWenn Sie das Auto bevorzugen, k\u00f6nnen Sie die Valle Brembana Staatsstra\u00dfe 470 nehmen.<br \/>\nAuf dem Weg dorthin kommen Sie an einem beeindruckenden Marmorsteinbruch vorbei, der Ihnen anzeigt, dass Sie auf der richtigen Stra\u00dfe sind.<br \/>\nFolgen Sie den Schildern und Sie werden in k\u00fcrzester Zeit das Rifugio Cespedosio erreichen.<br \/>\nWenn Sie hingegen ein abenteuerlicheres und intensiveres Erlebnis w\u00fcnschen, k\u00f6nnen Sie von der Kirche von Camerata Cornello aus zu Fu\u00df losgehen.<br \/>\nParken Sie Ihr Auto auf dem Sportplatz in der N\u00e4he der Kirche und machen Sie sich auf den Weg.<br \/>\nDer etwa eineinhalbst\u00fcndige Spaziergang f\u00fchrt Sie durch eine bezaubernde Landschaft bis zur H\u00fctte.      <\/span><\/p>\n<p>          <span style=\"font-weight: 400;\">Die Route ist landschaftlich besonders reizvoll und beeindruckend. Sie f\u00fchrt Sie auf eine H\u00f6he von \u00fcber 1.400 Metern mit Steigungen von nicht mehr als 10\u00b0.<br \/>\nAuf dem Weg nach oben kommen Sie an malerischen D\u00f6rfern wie Era vorbei.<br \/>\nIn diesem Dorf mit seinen Bergh\u00e4usern und seiner altert\u00fcmlichen Atmosph\u00e4re werden Sie sich in die Vergangenheit zur\u00fcckversetzt f\u00fchlen und einen Eindruck vom traditionellen Leben im Tal gewinnen.  <\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-78346 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C3-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C3-1024x683.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C3-300x200.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C3-768x512.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C3-1536x1024.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C3.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Mit den Schafhirten inmitten der Aromen des Brembana-Tals"},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"text","text":"<p>          <span style=\"font-weight: 400;\">Entlang der Route wird es keinen Mangel an Gelegenheiten f\u00fcr angenehme Pausen geben.<br \/>\nEs gibt zahlreiche Aussichtspunkte, die spektakul\u00e4re Ausblicke auf das Valle Brembana bieten.<br \/>\nAu\u00dferdem treffen Sie vielleicht auf einheimische Hirten, die oft ihre typischen Produkte zum Verkauf anbieten.<br \/>\nDarunter ist auch der K\u00e4se, der f\u00fcr seine Qualit\u00e4t und Tradition bekannt ist.<br \/>\nDas Brembana-Tal, das auch als Cheese Valley bekannt ist, erhielt 2019 die Anerkennung als UNESCO Creative City for Gastronomy, was seine Bedeutung in der K\u00e4seszene unterstreicht.    <\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-78340 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C2-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C2-1024x683.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C2-300x200.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C2-768x512.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C2-1536x1024.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C2.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Ankunft an der Cespedosio-H\u00fctte"},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"text","text":"<p>          <span style=\"font-weight: 400;\">An der Cespedosio-H\u00fctte angekommen, geht es auf der asphaltierten Stra\u00dfe leicht bergab bis zur Ortschaft Era.<br \/>\nFolgen Sie nun der Via Era, die mit m\u00e4\u00dfiger Steigung ansteigt und dann nach rechts abbiegt. Sie wird zu einer sch\u00f6nen Agro-Sylvo-Hirtenstra\u00dfe am Rande des Waldes und der gr\u00fcnen Weiden, die von der Baita Campelli herabf\u00fchren.<br \/>\nVon der Baita aus geht es weiter bergauf und Sie kommen aus dem Wald heraus. Dabei k\u00f6nnen Sie die gr\u00fcnen Wiesen, den blauen Himmel und das Panorama genie\u00dfen, das sich nun \u00fcber das gesamte Valle Brembana erstreckt, alles umh\u00fcllt von dem f\u00fcr die Hochebene typischen intensiven Heuduft.<br \/>\nFahren Sie weiter leicht bergauf und erreichen Sie nach einer letzten Haarnadelkurve Baita Campo auf einer H\u00f6he von 1440 Metern, den H\u00f6hepunkt dieses besonderen Brembana-Ausflugs.   <\/span><\/p>\n<p>          <span style=\"font-weight: 400;\">F\u00fcr erfahrenere Wanderer gibt es weitere Abenteuer, die Sie unternehmen k\u00f6nnen, bis Sie die Baita Maffenoli erreichen, die auf einer H\u00f6he von 1.367 Metern liegt, mit einem zus\u00e4tzlichen Spaziergang von etwa 20 Minuten.<br \/>\nAlternativ k\u00f6nnen Sie auch dem Weg 128 folgen, der Sie bis zur Piazza Brembana f\u00fchrt und eine weitere Herausforderung f\u00fcr Sie darstellt. <\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-78334 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C1-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C1-1024x683.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C1-300x200.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C1-768x512.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C1-1536x1024.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/C1.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]}],"filotto_layout":"scroll","hero_title":"Von der Cespedosio-H\u00fctte zu den Gipfeln","hero_text":"<p>          <span style=\"font-weight: 400;\">Auf den Spuren der Schafhirten<\/span><\/p>\n","size":"full","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"filotto_fill":"manual","filotto_items":false,"hero_type":"images","filotto_title":"","filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"hero_buttons":false,"is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/35"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85597\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/78450"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=85597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=85597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=85597"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=85597"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=85597"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=85597"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=85597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}