{"id":85627,"date":"2024-09-13T10:16:51","date_gmt":"2024-09-13T08:16:51","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/am-maresana-pass\/"},"modified":"2024-10-08T15:23:43","modified_gmt":"2024-10-08T13:23:43","slug":"am-maresana-pass","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/am-maresana-pass\/","title":{"rendered":"Am Maresana-Pass"},"excerpt":{"rendered":"","protected":false},"author":35,"featured_media":77333,"template":"","categories":[],"tags":[],"aggr":[],"area":[],"kind":[18685],"zona":[],"class_list":["post-85627","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","kind-itinerario-de"],"acf":{"featured_video":false,"slides":[{"image":{"ID":77339,"id":77339,"title":"M11","filename":"M11.jpg","filesize":442693,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M11.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/am-maresana-pass\/m11-2\/","alt":"","author":"35","description":"","caption":"","name":"m11-2","status":"inherit","uploaded_to":85627,"date":"2024-09-13 08:58:46","modified":"2024-10-07 10:17:27","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M11-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M11-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M11-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M11-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M11-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M11.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M11.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M11.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M11.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":77315,"id":77315,"title":"M7","filename":"M7.jpg","filesize":606126,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M7.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/am-maresana-pass\/m7-2\/","alt":"","author":"35","description":"","caption":"","name":"m7-2","status":"inherit","uploaded_to":85627,"date":"2024-09-13 08:58:40","modified":"2024-10-07 10:17:27","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M7-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M7-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M7-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M7-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M7.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":77297,"id":77297,"title":"M4","filename":"M4.jpg","filesize":448458,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M4.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/am-maresana-pass\/m4-2\/","alt":"","author":"35","description":"","caption":"","name":"m4-2","status":"inherit","uploaded_to":85627,"date":"2024-09-13 08:58:35","modified":"2024-10-07 10:17:27","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M4-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M4-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M4-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M4-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M4.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":77333,"id":77333,"title":"M10","filename":"M10.jpg","filesize":465471,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M10.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/am-maresana-pass\/m10-2\/","alt":"","author":"35","description":"","caption":"","name":"m10-2","status":"inherit","uploaded_to":85627,"date":"2024-09-13 08:58:44","modified":"2024-10-07 10:17:27","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M10-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M10-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M10-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M10-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M10-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M10.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M10.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M10.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M10.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":77346,"id":77346,"title":"M12","filename":"M12.jpg","filesize":382295,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M12.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/am-maresana-pass\/m12-2\/","alt":"","author":"35","description":"","caption":"","name":"m12-2","status":"inherit","uploaded_to":85627,"date":"2024-09-13 09:07:29","modified":"2024-10-07 10:17:27","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M12-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M12-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M12-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M12-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M12-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M12.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M12.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M12.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M12.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":77327,"id":77327,"title":"M9","filename":"M9.jpg","filesize":385049,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M9.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/am-maresana-pass\/m9-2\/","alt":"","author":"35","description":"","caption":"","name":"m9-2","status":"inherit","uploaded_to":85627,"date":"2024-09-13 08:58:43","modified":"2024-10-07 10:17:27","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M9-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M9-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M9-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M9-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M9.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":77321,"id":77321,"title":"M8","filename":"M8.jpg","filesize":527729,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M8.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/am-maresana-pass\/m8-2\/","alt":"","author":"35","description":"","caption":"","name":"m8-2","status":"inherit","uploaded_to":85627,"date":"2024-09-13 08:58:41","modified":"2024-10-07 10:17:27","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M8-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M8-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M8-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M8-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M8.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":77303,"id":77303,"title":"M5","filename":"M5.jpg","filesize":473588,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M5.jpg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/am-maresana-pass\/m5-2\/","alt":"","author":"35","description":"","caption":"","name":"m5-2","status":"inherit","uploaded_to":85627,"date":"2024-09-13 08:58:37","modified":"2024-10-07 10:17:27","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1280,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M5-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M5-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M5-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M5-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M5.jpg","2048x2048-width":1920,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M5.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M5.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M5.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"modules":[{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":""},"tcm_ui":false,"tcm_content":false},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":""},"tcm_ui":[{"label":"ABFAHRT:","value":"\u00fcber Quintino Alto, 31"},{"label":"ANKOMMEN:","value":"Maresana H\u00fcgel, Kirche von San Marco"},{"label":"ERREICHBAR IN:","value":"auto"},{"label":"BUSVERBINDUNGEN:","value":"ATB Linie 6 - Haltestelle Via Leonardo Da Vinci"}],"tcm_content":[{"acf_fc_layout":"text","text":"<p>          <span style=\"font-weight: 400;\">Die vollst\u00e4ndig von Gr\u00fcn umgebene Route ist bei Kindern sehr beliebt, da sie in v\u00f6lliger Freiheit laufen und rennen k\u00f6nnen.<br \/>\nSie erfordert geeignetes Schuhwerk und besondere Vorsicht in einigen Abschnitten wegen der vorhandenen Felsen, gilt aber in ihrer Komplexit\u00e4t als kurze und mittelschwere Route mit 15% Steigung. <\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-77281 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M2-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M2-1024x683.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M2-300x200.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M2-768x512.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M2-1536x1024.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M2.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":""},"tcm_ui":[{"label":"L\u00c4NGE:","value":"1,4 km"},{"label":"DAUER:","value":"45 min"},{"label":"OFFENLEGUNG:","value":"+210 m"},{"label":"SCHWIERIGKEIT:","value":"Medien  "},{"label":"REISEROUTEN-TYPOLOGIE:","value":"Gehen, linear"}],"tcm_content":[{"acf_fc_layout":"googlemap_embed","map":{"locations":false,"file_kml":false}},{"acf_fc_layout":"buttons","buttons":[{"style":"primary","text":"gpx herunterladen  ","icon":{"button_icon":"none"},"function":"link","url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/10-Monterosso-Maresana.gpx","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}]}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Die gr\u00fcne Route"},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"text","text":"<p>          <span style=\"font-weight: 400;\">Der Start erfolgt in der Via Quintino Alto in Bergamo. Von Anfang an werden Sie zwischen den Parks zweier sch\u00f6ner Privatvillen begleitet, wo die rot-wei\u00dfe Fahne mit der Nummer 533 den CAI-Pfad markiert, der am Fu\u00dfe der ersten Stufen sichtbar ist.<br \/>\nSie folgen dem Weg, der immer auf das Ziel hinweist: Colle della Maresana.<br \/>\nAuf dem Weg dorthin sind Sie von einer Landschaft voller Stille und Ruhe umgeben, ideal, um das Panorama im S\u00fcden der Stadt zu bewundern.<br \/>\nW\u00e4hrend des Aufstiegs werden die Ausblicke immer spektakul\u00e4rer, besonders im Fr\u00fchling, wenn sich die Felsen entlang des Weges mit den fuchsiafarbenen Bl\u00fctenbl\u00e4ttern und gelben Spitzen der Polygala f\u00e4rben.   <\/span><\/p>\n<p>          <span style=\"font-weight: 400;\">Der Maresana-Pass, der sich jenseits des nord\u00f6stlichen Stadtrandes entlang des Bergr\u00fcckens befindet, der den Beginn des Seriana-Tals definiert, ist ein Zufluchtsort f\u00fcr Liebhaber von Stille und Gr\u00fcn.<br \/>\nDer 546 Meter hohe Maresana ist von Kastanienw\u00e4ldern gepr\u00e4gt und bietet einen atemberaubenden Blick auf die Unterstadt und die umliegende Ebene. <\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-77287 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M3-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M3-1024x683.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M3-300x200.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M3-768x512.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M3-1536x1024.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M3.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]},{"acf_fc_layout":"two_columns_module","tcm_title":{"title_text":"Das kinderfreundliche Maresana"},"tcm_ui":false,"tcm_content":[{"acf_fc_layout":"text","text":"<p>          <span style=\"font-weight: 400;\">F\u00fcr die Kleinen wird der Spaziergang zu einem lustigen Abenteuer.<br \/>\nOben angekommen, bietet der Ca&#8217; Matta Park botanische und sensorische Pfade im Wald, einen kleinen k\u00fcnstlichen Teich und eine gro\u00dfe Wiese, auf der Sie sich entspannen und die Sonne genie\u00dfen k\u00f6nnen.<br \/>\nDer Park l\u00e4dt Sie ein, die biologische Vielfalt zu entdecken und bietet verschiedene Aktivit\u00e4ten und Workshops an, die auf den Schutz der Umwelt und die Entwicklung eines Umweltbewusstseins ausgerichtet sind.<br \/>\nAu\u00dferdem gibt es in der N\u00e4he der Kirche S. Marco in Maresana einen kleinen Spielplatz, der zus\u00e4tzliche Erholung f\u00fcr Kinder bietet.<br \/>\nErwachsene hingegen k\u00f6nnen die Geschichte des 1520 erbauten und im 16. Jahrhundert erweiterten religi\u00f6sen Geb\u00e4udes erkunden oder sich in dem nahe gelegenen historischen Restaurant entspannen.      <\/span><br \/>\n          <span style=\"font-weight: 400;\">Der Colle della Maresana belohnt die Anstrengung eines jeden, ob jung oder alt, mit dem Gef\u00fchl, auf dem gr\u00f6\u00dften Panoramabalkon \u00fcber Bergamo zu stehen.<br \/>\nDer Blick auf die darunter liegende Ebene ist atemberaubend und eine echte Belohnung f\u00fcr den Aufstieg.<br \/>\nGehen ist Glauben.  <\/span><\/p>\n<p>          <img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-77275 size-large\" src=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M1-1024x683.jpg\" alt=\"\" width=\"1024\" height=\"683\" srcset=\"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M1-1024x683.jpg 1024w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M1-300x200.jpg 300w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M1-768x512.jpg 768w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M1-1536x1024.jpg 1536w, https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/M1.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n"}]}],"filotto_layout":"scroll","hero_title":"Am Maresana-Pass","hero_text":"<p>          <span style=\"font-weight: 400;\">Blick auf Bergamo vom Balkon aus<\/span><\/p>\n","size":"full","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"filotto_fill":"manual","filotto_items":false,"hero_type":"images","filotto_title":"","filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"hero_buttons":false,"is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85627","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/users\/35"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/85627\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/77333"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=85627"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=85627"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=85627"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=85627"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=85627"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=85627"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=85627"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}