{"id":99967,"date":"2025-05-12T11:16:21","date_gmt":"2025-05-12T09:16:21","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/gusto-lee-2\/"},"modified":"2025-05-12T20:17:33","modified_gmt":"2025-05-12T18:17:33","slug":"gusto-lee","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/gusto-lee\/","title":{"rendered":"Gusto Lee"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":99968,"template":"","categories":[854],"tags":[],"aggr":[],"area":[],"kind":[18720],"zona":[],"class_list":["post-99967","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-essen","kind-ristorante-de"],"acf":{"buttons":false,"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Gusto Lee","hero_text":"","slides":[{"image":{"ID":99968,"id":99968,"title":"ecom_2912_general.jpeg","filename":"ecom_2912_general.jpeg","filesize":116893,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_2912_general.jpeg","link":"https:\/\/visit.valueservice.cloud\/de\/oggetto\/gusto-lee\/ecom_2912_general-jpeg-2\/","alt":"","author":"0","description":"","caption":"","name":"ecom_2912_general-jpeg-2","status":"inherit","uploaded_to":99967,"date":"2024-11-06 07:15:29","modified":"2025-05-12 18:17:34","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_2912_general-150x150.jpeg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_2912_general-300x225.jpeg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_2912_general-768x576.jpeg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_2912_general.jpeg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_2912_general.jpeg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_2912_general.jpeg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_2912_general.jpeg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_2912_general.jpeg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/ecom_2912_general.jpeg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Gusto Lee","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Gusto Lee ist ein familiengef\u00fchrtes Sushi-Restaurant und vieles mehr: Bestellen Sie ihre hochwertigen Maki oder Sashimi und probieren Sie ihre frisch zubereiteten Teigtaschen.&#13;<br \/>\nIhr Motto ist: Gesundes Essen f\u00fcr gl\u00fcckliche Menschen.<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.6934854","longitude":"9.6753067","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Angelo Maj, 10d","iu_addr_postalcode":"24121","iu_addr_city":"Bergamo","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"gustoleesas@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"","id_east":"","id_ristora":"166","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/99967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/oggetto\/99967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media\/99968"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/media?parent=99967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/categories?post=99967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/tags?post=99967"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/aggr?post=99967"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/area?post=99967"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/kind?post=99967"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/de\/wp-json\/wp\/v2\/zona?post=99967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}