{"id":158847,"date":"2025-04-18T13:03:12","date_gmt":"2025-04-18T11:03:12","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/il-giardino-di-berbech\/"},"modified":"2025-04-18T13:42:42","modified_gmt":"2025-04-18T11:42:42","slug":"il-giardino-di-berbech","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-giardino-di-berbech\/","title":{"rendered":"IL GIardino di berbech"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":147590,"template":"","categories":[997],"tags":[],"aggr":[],"area":[],"kind":[18723],"zona":[],"class_list":["post-158847","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sleep","kind-strutturaricettiva-en"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"IL GIardino di berbech","hero_text":"","buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.714892","longitude":"9.652117","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"LUCA BELLOLI","registered_office":"Via castagneta 14","iu_addr_streetnumber":"Via Castagneta, 14","iu_addr_postalcode":"24123","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 3208330530","iu_cell":"+39 3208330530","iu_website":"https:\/\/berbech.it\/","iu_email":"Info@berbech.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"5","iu_rooms":"2","iu_beds":"7","id_madeep":"","id_visit_manza":"10496","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"slides":[{"image":{"ID":147590,"id":147590,"title":"8876d87b1f1c7d95e496ff0bc975fc2b_ca459db7.jpg","filename":"8876d87b1f1c7d95e496ff0bc975fc2b_ca459db7.jpg","filesize":1160988,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8876d87b1f1c7d95e496ff0bc975fc2b_ca459db7.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-giardino-di-berbech\/8876d87b1f1c7d95e496ff0bc975fc2b_ca459db7-jpg-2\/","alt":"","author":"3","description":"","caption":"","name":"8876d87b1f1c7d95e496ff0bc975fc2b_ca459db7-jpg-2","status":"inherit","uploaded_to":158847,"date":"2025-04-17 14:25:27","modified":"2025-04-18 11:42:43","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8876d87b1f1c7d95e496ff0bc975fc2b_ca459db7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8876d87b1f1c7d95e496ff0bc975fc2b_ca459db7-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8876d87b1f1c7d95e496ff0bc975fc2b_ca459db7-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8876d87b1f1c7d95e496ff0bc975fc2b_ca459db7-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8876d87b1f1c7d95e496ff0bc975fc2b_ca459db7-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8876d87b1f1c7d95e496ff0bc975fc2b_ca459db7.jpg","2048x2048-width":1920,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8876d87b1f1c7d95e496ff0bc975fc2b_ca459db7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8876d87b1f1c7d95e496ff0bc975fc2b_ca459db7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8876d87b1f1c7d95e496ff0bc975fc2b_ca459db7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":147597,"id":147597,"title":"319c07f297889551d9f67ede1954507d_98e41ef6.jpg","filename":"319c07f297889551d9f67ede1954507d_98e41ef6.jpg","filesize":1369516,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/319c07f297889551d9f67ede1954507d_98e41ef6.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-giardino-di-berbech\/319c07f297889551d9f67ede1954507d_98e41ef6-jpg-2\/","alt":"","author":"3","description":"","caption":"","name":"319c07f297889551d9f67ede1954507d_98e41ef6-jpg-2","status":"inherit","uploaded_to":158847,"date":"2025-04-17 14:25:29","modified":"2025-04-18 11:42:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/319c07f297889551d9f67ede1954507d_98e41ef6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/319c07f297889551d9f67ede1954507d_98e41ef6-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/319c07f297889551d9f67ede1954507d_98e41ef6-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/319c07f297889551d9f67ede1954507d_98e41ef6-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/319c07f297889551d9f67ede1954507d_98e41ef6-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/319c07f297889551d9f67ede1954507d_98e41ef6.jpg","2048x2048-width":1920,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/319c07f297889551d9f67ede1954507d_98e41ef6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/319c07f297889551d9f67ede1954507d_98e41ef6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/319c07f297889551d9f67ede1954507d_98e41ef6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":147604,"id":147604,"title":"4a63426edbbf64c2af4899bf3c0b04ef_9d19a925.jpg","filename":"4a63426edbbf64c2af4899bf3c0b04ef_9d19a925.jpg","filesize":748342,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4a63426edbbf64c2af4899bf3c0b04ef_9d19a925.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-giardino-di-berbech\/4a63426edbbf64c2af4899bf3c0b04ef_9d19a925-jpg-2\/","alt":"","author":"3","description":"","caption":"","name":"4a63426edbbf64c2af4899bf3c0b04ef_9d19a925-jpg-2","status":"inherit","uploaded_to":158847,"date":"2025-04-17 14:25:30","modified":"2025-04-18 11:42:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4a63426edbbf64c2af4899bf3c0b04ef_9d19a925-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4a63426edbbf64c2af4899bf3c0b04ef_9d19a925-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4a63426edbbf64c2af4899bf3c0b04ef_9d19a925-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4a63426edbbf64c2af4899bf3c0b04ef_9d19a925-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4a63426edbbf64c2af4899bf3c0b04ef_9d19a925-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4a63426edbbf64c2af4899bf3c0b04ef_9d19a925.jpg","2048x2048-width":1920,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4a63426edbbf64c2af4899bf3c0b04ef_9d19a925.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4a63426edbbf64c2af4899bf3c0b04ef_9d19a925.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4a63426edbbf64c2af4899bf3c0b04ef_9d19a925.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":147611,"id":147611,"title":"6048f20b99f4ec65f0fcd1614dccefa0_1e887627.jpg","filename":"6048f20b99f4ec65f0fcd1614dccefa0_1e887627.jpg","filesize":757447,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6048f20b99f4ec65f0fcd1614dccefa0_1e887627.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-giardino-di-berbech\/6048f20b99f4ec65f0fcd1614dccefa0_1e887627-jpg-2\/","alt":"","author":"3","description":"","caption":"","name":"6048f20b99f4ec65f0fcd1614dccefa0_1e887627-jpg-2","status":"inherit","uploaded_to":158847,"date":"2025-04-17 14:25:32","modified":"2025-04-18 11:42:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6048f20b99f4ec65f0fcd1614dccefa0_1e887627-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6048f20b99f4ec65f0fcd1614dccefa0_1e887627-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6048f20b99f4ec65f0fcd1614dccefa0_1e887627-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6048f20b99f4ec65f0fcd1614dccefa0_1e887627-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6048f20b99f4ec65f0fcd1614dccefa0_1e887627-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6048f20b99f4ec65f0fcd1614dccefa0_1e887627.jpg","2048x2048-width":1920,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6048f20b99f4ec65f0fcd1614dccefa0_1e887627.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6048f20b99f4ec65f0fcd1614dccefa0_1e887627.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6048f20b99f4ec65f0fcd1614dccefa0_1e887627.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":147618,"id":147618,"title":"edccc742b3a63ada83077c399d1bd208_2ab976bd.jpg","filename":"edccc742b3a63ada83077c399d1bd208_2ab976bd.jpg","filesize":524858,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/edccc742b3a63ada83077c399d1bd208_2ab976bd.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-giardino-di-berbech\/edccc742b3a63ada83077c399d1bd208_2ab976bd-jpg-2\/","alt":"","author":"3","description":"","caption":"","name":"edccc742b3a63ada83077c399d1bd208_2ab976bd-jpg-2","status":"inherit","uploaded_to":158847,"date":"2025-04-17 14:25:33","modified":"2025-04-18 11:42:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/edccc742b3a63ada83077c399d1bd208_2ab976bd-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/edccc742b3a63ada83077c399d1bd208_2ab976bd-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/edccc742b3a63ada83077c399d1bd208_2ab976bd-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/edccc742b3a63ada83077c399d1bd208_2ab976bd-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/edccc742b3a63ada83077c399d1bd208_2ab976bd-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/edccc742b3a63ada83077c399d1bd208_2ab976bd.jpg","2048x2048-width":1920,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/edccc742b3a63ada83077c399d1bd208_2ab976bd.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/edccc742b3a63ada83077c399d1bd208_2ab976bd.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/edccc742b3a63ada83077c399d1bd208_2ab976bd.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":147625,"id":147625,"title":"4271d7336c66a88abbe5f60d4130fe44_8b4cac59.jpg","filename":"4271d7336c66a88abbe5f60d4130fe44_8b4cac59.jpg","filesize":531059,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4271d7336c66a88abbe5f60d4130fe44_8b4cac59.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-giardino-di-berbech\/4271d7336c66a88abbe5f60d4130fe44_8b4cac59-jpg-2\/","alt":"","author":"3","description":"","caption":"","name":"4271d7336c66a88abbe5f60d4130fe44_8b4cac59-jpg-2","status":"inherit","uploaded_to":158847,"date":"2025-04-17 14:25:35","modified":"2025-04-18 11:42:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4271d7336c66a88abbe5f60d4130fe44_8b4cac59-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4271d7336c66a88abbe5f60d4130fe44_8b4cac59-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4271d7336c66a88abbe5f60d4130fe44_8b4cac59-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4271d7336c66a88abbe5f60d4130fe44_8b4cac59-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4271d7336c66a88abbe5f60d4130fe44_8b4cac59-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4271d7336c66a88abbe5f60d4130fe44_8b4cac59.jpg","2048x2048-width":1920,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4271d7336c66a88abbe5f60d4130fe44_8b4cac59.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4271d7336c66a88abbe5f60d4130fe44_8b4cac59.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4271d7336c66a88abbe5f60d4130fe44_8b4cac59.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":147632,"id":147632,"title":"e8dddf75b105bce9bbce6822eb222c2a_0822733b.jpg","filename":"e8dddf75b105bce9bbce6822eb222c2a_0822733b.jpg","filesize":522371,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8dddf75b105bce9bbce6822eb222c2a_0822733b.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-giardino-di-berbech\/e8dddf75b105bce9bbce6822eb222c2a_0822733b-jpg-2\/","alt":"","author":"3","description":"","caption":"","name":"e8dddf75b105bce9bbce6822eb222c2a_0822733b-jpg-2","status":"inherit","uploaded_to":158847,"date":"2025-04-17 14:25:36","modified":"2025-04-18 11:42:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8dddf75b105bce9bbce6822eb222c2a_0822733b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8dddf75b105bce9bbce6822eb222c2a_0822733b-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8dddf75b105bce9bbce6822eb222c2a_0822733b-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8dddf75b105bce9bbce6822eb222c2a_0822733b-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8dddf75b105bce9bbce6822eb222c2a_0822733b-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8dddf75b105bce9bbce6822eb222c2a_0822733b.jpg","2048x2048-width":1920,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8dddf75b105bce9bbce6822eb222c2a_0822733b.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8dddf75b105bce9bbce6822eb222c2a_0822733b.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8dddf75b105bce9bbce6822eb222c2a_0822733b.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":147639,"id":147639,"title":"d2025abc7ba8ee9994391ca4ac9f4931_118a2142.jpg","filename":"d2025abc7ba8ee9994391ca4ac9f4931_118a2142.jpg","filesize":396725,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2025abc7ba8ee9994391ca4ac9f4931_118a2142.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-giardino-di-berbech\/d2025abc7ba8ee9994391ca4ac9f4931_118a2142-jpg-2\/","alt":"","author":"3","description":"","caption":"","name":"d2025abc7ba8ee9994391ca4ac9f4931_118a2142-jpg-2","status":"inherit","uploaded_to":158847,"date":"2025-04-17 14:25:38","modified":"2025-04-18 11:42:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2025abc7ba8ee9994391ca4ac9f4931_118a2142-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2025abc7ba8ee9994391ca4ac9f4931_118a2142-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2025abc7ba8ee9994391ca4ac9f4931_118a2142-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2025abc7ba8ee9994391ca4ac9f4931_118a2142-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2025abc7ba8ee9994391ca4ac9f4931_118a2142-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2025abc7ba8ee9994391ca4ac9f4931_118a2142.jpg","2048x2048-width":1920,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2025abc7ba8ee9994391ca4ac9f4931_118a2142.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2025abc7ba8ee9994391ca4ac9f4931_118a2142.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d2025abc7ba8ee9994391ca4ac9f4931_118a2142.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":147646,"id":147646,"title":"44ca2f3cbe1b1ecf4fee93867391e4ca_9dff0e32.jpg","filename":"44ca2f3cbe1b1ecf4fee93867391e4ca_9dff0e32.jpg","filesize":561564,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/44ca2f3cbe1b1ecf4fee93867391e4ca_9dff0e32.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-giardino-di-berbech\/44ca2f3cbe1b1ecf4fee93867391e4ca_9dff0e32-jpg-2\/","alt":"","author":"3","description":"","caption":"","name":"44ca2f3cbe1b1ecf4fee93867391e4ca_9dff0e32-jpg-2","status":"inherit","uploaded_to":158847,"date":"2025-04-17 14:25:39","modified":"2025-04-18 11:42:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/44ca2f3cbe1b1ecf4fee93867391e4ca_9dff0e32-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/44ca2f3cbe1b1ecf4fee93867391e4ca_9dff0e32-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/44ca2f3cbe1b1ecf4fee93867391e4ca_9dff0e32-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/44ca2f3cbe1b1ecf4fee93867391e4ca_9dff0e32-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/44ca2f3cbe1b1ecf4fee93867391e4ca_9dff0e32-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/44ca2f3cbe1b1ecf4fee93867391e4ca_9dff0e32.jpg","2048x2048-width":1920,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/44ca2f3cbe1b1ecf4fee93867391e4ca_9dff0e32.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/44ca2f3cbe1b1ecf4fee93867391e4ca_9dff0e32.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/44ca2f3cbe1b1ecf4fee93867391e4ca_9dff0e32.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":338}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"safe","label":"safe"},{"value":"laundry","label":"Lavanderia"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"solarium","label":"Solarium"},{"value":"wifi","label":"Wi-Fi"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"tv_room","label":"TV in camera"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/158847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/158847\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media\/147590"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media?parent=158847"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/categories?post=158847"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/tags?post=158847"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/aggr?post=158847"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/area?post=158847"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/kind?post=158847"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/zona?post=158847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}