{"id":158887,"date":"2025-04-18T13:04:38","date_gmt":"2025-04-18T11:04:38","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/bb-san-francesco-class\/"},"modified":"2025-04-18T13:44:11","modified_gmt":"2025-04-18T11:44:11","slug":"bb-san-francesco-class","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-san-francesco-class\/","title":{"rendered":"B&#038;B SAN FRANCESCO CLASS"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":148714,"template":"","categories":[997],"tags":[],"aggr":[],"area":[],"kind":[18723],"zona":[],"class_list":["post-158887","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sleep","kind-strutturaricettiva-en"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"B&B SAN FRANCESCO CLASS","hero_text":"<p dir='ltr'><span>Stylish new B&#038;B, conveniently located after a 6 minute walk from the funicular and an 8 minute walk from the QC Terme spa. Nearby shops for all needs.<\/span><\/p>\n<p>&#13;<\/p>\n<p><span>\u00a0<\/span><\/p>\n","slides":[{"image":{"ID":148714,"id":148714,"title":"f9277359b5ca34beae4bf82dd77d74f9_a3b096ef.jpg","filename":"f9277359b5ca34beae4bf82dd77d74f9_a3b096ef.jpg","filesize":559154,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-san-francesco-class\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"f9277359b5ca34beae4bf82dd77d74f9_a3b096ef-jpg-2","status":"inherit","uploaded_to":158887,"date":"2025-04-17 14:39:51","modified":"2025-04-18 11:44:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1152,"height":2048,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef-169x300.jpg","medium-width":169,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef-768x1365.jpg","medium_large-width":768,"medium_large-height":1365,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef-576x1024.jpg","large-width":576,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef-864x1536.jpg","1536x1536-width":864,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef.jpg","2048x2048-width":1152,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef.jpg","gform-image-choice-sm-width":169,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef.jpg","gform-image-choice-md-width":225,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef.jpg","gform-image-choice-lg-width":338,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148721,"id":148721,"title":"cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","filename":"cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","filesize":130289,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-san-francesco-class\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488-jpg-2","status":"inherit","uploaded_to":158887,"date":"2025-04-17 14:39:52","modified":"2025-04-18 11:44:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148728,"id":148728,"title":"9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","filename":"9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","filesize":116686,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-san-francesco-class\/9acfcfbe54398a525299b4b24b588b22_d2244fd3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"9acfcfbe54398a525299b4b24b588b22_d2244fd3-jpg-2","status":"inherit","uploaded_to":158887,"date":"2025-04-17 14:39:53","modified":"2025-04-18 11:44:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148735,"id":148735,"title":"8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","filename":"8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","filesize":112218,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-san-francesco-class\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"8d9355bd02b7c311ad10fa9826f01158_7a985d3a-jpg-2","status":"inherit","uploaded_to":158887,"date":"2025-04-17 14:39:54","modified":"2025-04-18 11:44:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148742,"id":148742,"title":"5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de.jpg","filename":"5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de.jpg","filesize":277737,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-san-francesco-class\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de-jpg-2","status":"inherit","uploaded_to":158887,"date":"2025-04-17 14:39:55","modified":"2025-04-18 11:44:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":900,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de-169x300.jpg","medium-width":169,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de-768x1365.jpg","medium_large-width":768,"medium_large-height":1365,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de-576x1024.jpg","large-width":576,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de-864x1536.jpg","1536x1536-width":864,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de.jpg","2048x2048-width":900,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de.jpg","gform-image-choice-sm-width":169,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de.jpg","gform-image-choice-md-width":225,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de.jpg","gform-image-choice-lg-width":338,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148749,"id":148749,"title":"3c78e9861a0a123e06217d69263d568d_45745c24.jpg","filename":"3c78e9861a0a123e06217d69263d568d_45745c24.jpg","filesize":139322,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-san-francesco-class\/3c78e9861a0a123e06217d69263d568d_45745c24-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3c78e9861a0a123e06217d69263d568d_45745c24-jpg-2","status":"inherit","uploaded_to":158887,"date":"2025-04-17 14:39:56","modified":"2025-04-18 11:44:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148756,"id":148756,"title":"c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","filename":"c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","filesize":200484,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-san-francesco-class\/c15af13143f5ea124fa282d477ea64ca_c71cecdc-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c15af13143f5ea124fa282d477ea64ca_c71cecdc-jpg-2","status":"inherit","uploaded_to":158887,"date":"2025-04-17 14:39:57","modified":"2025-04-18 11:44:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148763,"id":148763,"title":"27f95e83868ef558f9172416bed60717_29080259.jpg","filename":"27f95e83868ef558f9172416bed60717_29080259.jpg","filesize":462973,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-san-francesco-class\/27f95e83868ef558f9172416bed60717_29080259-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"27f95e83868ef558f9172416bed60717_29080259-jpg-2","status":"inherit","uploaded_to":158887,"date":"2025-04-17 14:39:58","modified":"2025-04-18 11:44:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":942,"height":628,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259.jpg","large-width":942,"large-height":628,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259.jpg","1536x1536-width":942,"1536x1536-height":628,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259.jpg","2048x2048-width":942,"2048x2048-height":628,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148770,"id":148770,"title":"65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","filename":"65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","filesize":85949,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-san-francesco-class\/65dc678186e843de51a1cade5e09a93a_5b77e816-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"65dc678186e843de51a1cade5e09a93a_5b77e816-jpg-2","status":"inherit","uploaded_to":158887,"date":"2025-04-17 14:39:59","modified":"2025-04-18 11:44:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148777,"id":148777,"title":"063467b628d5723bee3c66434054386e_f3518747.jpg","filename":"063467b628d5723bee3c66434054386e_f3518747.jpg","filesize":259703,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-san-francesco-class\/063467b628d5723bee3c66434054386e_f3518747-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"063467b628d5723bee3c66434054386e_f3518747-jpg-2","status":"inherit","uploaded_to":158887,"date":"2025-04-17 14:39:59","modified":"2025-04-18 11:44:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":800,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747.jpg","1536x1536-width":1200,"1536x1536-height":800,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747.jpg","2048x2048-width":1200,"2048x2048-height":800,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148784,"id":148784,"title":"dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","filename":"dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","filesize":156093,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-san-francesco-class\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b-jpg-2","status":"inherit","uploaded_to":158887,"date":"2025-04-17 14:40:00","modified":"2025-04-18 11:44:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Two rooms with private bathroom, welcome and courtesy kit, internal parking for motorbikes and bicycles, use of kitchen, TV, wifi, air conditioning, breakfast, tourist tax and final cleaning all included.&#13;<br \/>\n\u00a0<\/p>\n","indepth":"<p>Historic Art Nouveau buildings, world-famous San Pellegrino water spring, starting point for many hiking and biking tours; the casino and Gran Hotel can be visited by appointment. Possibility of sports activities such as horse riding, canoeing, climbing, tennis.&#13;<br \/>\n\u00a0<\/p>\n","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"<p>Arlecchino Room: euro 128.00 (possibility for third bed euro 50.00)&#13;<br \/>\nP\u00f2ta Room: euro 118.00 (doppia con possibilit\u00e0 di dividere il letto)<\/p>\n","services":"","parking":"<p>Free parking or hourly pay parking in front of the structure<\/p>\n","restaurant":"<p>Not foreseen<\/p>\n","breakfast":"<p>Excellent, hearty breakfast<\/p>\n","internet":"<p>Wifi available<\/p>\n","children":"","pets":"<p>not allowed<\/p>\n","latitude":"45.833123","longitude":"9.665365","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"B&B SAN FRANCESCO CLASS","registered_office":"MANNELLO ANDREA VIA MONTE ZUCCO 1 SAN PELLEGRINO TERME (BG)","iu_addr_streetnumber":"Via Monte Zucco, 1","iu_addr_postalcode":"24016","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"3402584538","iu_cell":"3402584538","iu_website":"http:\/\/www.bebsanfrancescoclass.it","iu_email":"sanfrancescobeb@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"2","iu_beds":"5","id_madeep":"","id_visit_manza":"10506","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","time":"<p>Check in ore 14:00\/16:00&#13;<br \/>\nCheck out ore 10:00&#13;<br \/>\nSolitamente sempre aperto, bisogna informarsi per\u00f2 sui periodi di chiusura obbligatori per legge.<\/p>\n","service_icons":[{"value":"laundry","label":"Lavanderia"},{"value":"tv_lounge","label":"Sala TV"},{"value":"tennis","label":"Tennis"},{"value":"wifi","label":"Wi-Fi"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"balcony","label":"Balcone"},{"value":"tv_room","label":"TV in camera"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/158887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/158887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media\/148714"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media?parent=158887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/categories?post=158887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/tags?post=158887"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/aggr?post=158887"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/area?post=158887"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/kind?post=158887"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/zona?post=158887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}