{"id":163887,"date":"2025-04-18T13:25:25","date_gmt":"2025-04-18T11:25:25","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/civico-13-immobili-e-soluzioni-rent\/"},"modified":"2025-04-18T14:06:18","modified_gmt":"2025-04-18T12:06:18","slug":"civico-13-immobili-e-soluzioni-rent","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/civico-13-immobili-e-soluzioni-rent\/","title":{"rendered":"Civico 13 &#8211; Immobili e Soluzioni Rent"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":163888,"template":"","categories":[997],"tags":[],"aggr":[],"area":[],"kind":[18723],"zona":[],"class_list":["post-163887","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sleep","kind-strutturaricettiva-en"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Civico 13 - Immobili e Soluzioni Rent","hero_text":"<p>Properties &#038; Solutions &#8211; Rent is aimed at those who travel for work, necessity or leisure and have decided to no longer settle for an anonymous hotel room. Thanks to a large portfolio of furnished and equipped apartments, it offers a special stay, characterized by efficiency and seriousness.<\/p>\n","slides":[{"image":{"ID":163888,"id":163888,"title":"7ecbfa12a728be47df06c175f077bcd2_9eed9dcb.png","filename":"7ecbfa12a728be47df06c175f077bcd2_9eed9dcb.png","filesize":541826,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ecbfa12a728be47df06c175f077bcd2_9eed9dcb.png","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/civico-13-immobili-e-soluzioni-rent\/7ecbfa12a728be47df06c175f077bcd2_9eed9dcb-png\/","alt":"","author":"0","description":"","caption":"","name":"7ecbfa12a728be47df06c175f077bcd2_9eed9dcb-png","status":"inherit","uploaded_to":163887,"date":"2025-04-18 08:44:42","modified":"2025-04-18 12:06:20","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":847,"height":636,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ecbfa12a728be47df06c175f077bcd2_9eed9dcb-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ecbfa12a728be47df06c175f077bcd2_9eed9dcb-300x225.png","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ecbfa12a728be47df06c175f077bcd2_9eed9dcb-768x577.png","medium_large-width":768,"medium_large-height":577,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ecbfa12a728be47df06c175f077bcd2_9eed9dcb.png","large-width":847,"large-height":636,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ecbfa12a728be47df06c175f077bcd2_9eed9dcb.png","1536x1536-width":847,"1536x1536-height":636,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ecbfa12a728be47df06c175f077bcd2_9eed9dcb.png","2048x2048-width":847,"2048x2048-height":636,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ecbfa12a728be47df06c175f077bcd2_9eed9dcb.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ecbfa12a728be47df06c175f077bcd2_9eed9dcb.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7ecbfa12a728be47df06c175f077bcd2_9eed9dcb.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":451}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163895,"id":163895,"title":"40dbc7468990a09b7c15c0c843dce449_34015486.png","filename":"40dbc7468990a09b7c15c0c843dce449_34015486.png","filesize":619722,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40dbc7468990a09b7c15c0c843dce449_34015486.png","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/civico-13-immobili-e-soluzioni-rent\/40dbc7468990a09b7c15c0c843dce449_34015486-png\/","alt":"","author":"0","description":"","caption":"","name":"40dbc7468990a09b7c15c0c843dce449_34015486-png","status":"inherit","uploaded_to":163887,"date":"2025-04-18 08:44:44","modified":"2025-04-18 12:06:20","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":849,"height":633,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40dbc7468990a09b7c15c0c843dce449_34015486-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40dbc7468990a09b7c15c0c843dce449_34015486-300x224.png","medium-width":300,"medium-height":224,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40dbc7468990a09b7c15c0c843dce449_34015486-768x573.png","medium_large-width":768,"medium_large-height":573,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40dbc7468990a09b7c15c0c843dce449_34015486.png","large-width":849,"large-height":633,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40dbc7468990a09b7c15c0c843dce449_34015486.png","1536x1536-width":849,"1536x1536-height":633,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40dbc7468990a09b7c15c0c843dce449_34015486.png","2048x2048-width":849,"2048x2048-height":633,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40dbc7468990a09b7c15c0c843dce449_34015486.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":224,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40dbc7468990a09b7c15c0c843dce449_34015486.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":298,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/40dbc7468990a09b7c15c0c843dce449_34015486.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":447}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163902,"id":163902,"title":"2c6b34203934bdca21be88d5c43aed9d_d5b0ee7e.png","filename":"2c6b34203934bdca21be88d5c43aed9d_d5b0ee7e.png","filesize":757212,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2c6b34203934bdca21be88d5c43aed9d_d5b0ee7e.png","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/civico-13-immobili-e-soluzioni-rent\/2c6b34203934bdca21be88d5c43aed9d_d5b0ee7e-png\/","alt":"","author":"0","description":"","caption":"","name":"2c6b34203934bdca21be88d5c43aed9d_d5b0ee7e-png","status":"inherit","uploaded_to":163887,"date":"2025-04-18 08:44:46","modified":"2025-04-18 12:06:20","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":848,"height":634,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2c6b34203934bdca21be88d5c43aed9d_d5b0ee7e-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2c6b34203934bdca21be88d5c43aed9d_d5b0ee7e-300x224.png","medium-width":300,"medium-height":224,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2c6b34203934bdca21be88d5c43aed9d_d5b0ee7e-768x574.png","medium_large-width":768,"medium_large-height":574,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2c6b34203934bdca21be88d5c43aed9d_d5b0ee7e.png","large-width":848,"large-height":634,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2c6b34203934bdca21be88d5c43aed9d_d5b0ee7e.png","1536x1536-width":848,"1536x1536-height":634,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2c6b34203934bdca21be88d5c43aed9d_d5b0ee7e.png","2048x2048-width":848,"2048x2048-height":634,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2c6b34203934bdca21be88d5c43aed9d_d5b0ee7e.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":224,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2c6b34203934bdca21be88d5c43aed9d_d5b0ee7e.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":299,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2c6b34203934bdca21be88d5c43aed9d_d5b0ee7e.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":449}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163909,"id":163909,"title":"6fdeec36f24c1054376b3224009389c4_52092efe.png","filename":"6fdeec36f24c1054376b3224009389c4_52092efe.png","filesize":797622,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fdeec36f24c1054376b3224009389c4_52092efe.png","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/civico-13-immobili-e-soluzioni-rent\/6fdeec36f24c1054376b3224009389c4_52092efe-png\/","alt":"","author":"0","description":"","caption":"","name":"6fdeec36f24c1054376b3224009389c4_52092efe-png","status":"inherit","uploaded_to":163887,"date":"2025-04-18 08:44:48","modified":"2025-04-18 12:06:20","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":843,"height":637,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fdeec36f24c1054376b3224009389c4_52092efe-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fdeec36f24c1054376b3224009389c4_52092efe-300x227.png","medium-width":300,"medium-height":227,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fdeec36f24c1054376b3224009389c4_52092efe-768x580.png","medium_large-width":768,"medium_large-height":580,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fdeec36f24c1054376b3224009389c4_52092efe.png","large-width":843,"large-height":637,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fdeec36f24c1054376b3224009389c4_52092efe.png","1536x1536-width":843,"1536x1536-height":637,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fdeec36f24c1054376b3224009389c4_52092efe.png","2048x2048-width":843,"2048x2048-height":637,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fdeec36f24c1054376b3224009389c4_52092efe.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":227,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fdeec36f24c1054376b3224009389c4_52092efe.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":302,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fdeec36f24c1054376b3224009389c4_52092efe.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":453}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163916,"id":163916,"title":"9e87424316aeae5d9a0a916ea6d17192_a87b6d03.png","filename":"9e87424316aeae5d9a0a916ea6d17192_a87b6d03.png","filesize":465918,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e87424316aeae5d9a0a916ea6d17192_a87b6d03.png","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/civico-13-immobili-e-soluzioni-rent\/9e87424316aeae5d9a0a916ea6d17192_a87b6d03-png\/","alt":"","author":"0","description":"","caption":"","name":"9e87424316aeae5d9a0a916ea6d17192_a87b6d03-png","status":"inherit","uploaded_to":163887,"date":"2025-04-18 08:44:50","modified":"2025-04-18 12:06:20","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":848,"height":638,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e87424316aeae5d9a0a916ea6d17192_a87b6d03-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e87424316aeae5d9a0a916ea6d17192_a87b6d03-300x226.png","medium-width":300,"medium-height":226,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e87424316aeae5d9a0a916ea6d17192_a87b6d03-768x578.png","medium_large-width":768,"medium_large-height":578,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e87424316aeae5d9a0a916ea6d17192_a87b6d03.png","large-width":848,"large-height":638,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e87424316aeae5d9a0a916ea6d17192_a87b6d03.png","1536x1536-width":848,"1536x1536-height":638,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e87424316aeae5d9a0a916ea6d17192_a87b6d03.png","2048x2048-width":848,"2048x2048-height":638,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e87424316aeae5d9a0a916ea6d17192_a87b6d03.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":226,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e87424316aeae5d9a0a916ea6d17192_a87b6d03.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":301,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9e87424316aeae5d9a0a916ea6d17192_a87b6d03.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":451}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":163923,"id":163923,"title":"41ec520a9560a160b7bbf33e555c996f_15aaf6ae.png","filename":"41ec520a9560a160b7bbf33e555c996f_15aaf6ae.png","filesize":483116,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ec520a9560a160b7bbf33e555c996f_15aaf6ae.png","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/civico-13-immobili-e-soluzioni-rent\/41ec520a9560a160b7bbf33e555c996f_15aaf6ae-png\/","alt":"","author":"0","description":"","caption":"","name":"41ec520a9560a160b7bbf33e555c996f_15aaf6ae-png","status":"inherit","uploaded_to":163887,"date":"2025-04-18 08:44:52","modified":"2025-04-18 12:06:21","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":840,"height":635,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ec520a9560a160b7bbf33e555c996f_15aaf6ae-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ec520a9560a160b7bbf33e555c996f_15aaf6ae-300x227.png","medium-width":300,"medium-height":227,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ec520a9560a160b7bbf33e555c996f_15aaf6ae-768x581.png","medium_large-width":768,"medium_large-height":581,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ec520a9560a160b7bbf33e555c996f_15aaf6ae.png","large-width":840,"large-height":635,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ec520a9560a160b7bbf33e555c996f_15aaf6ae.png","1536x1536-width":840,"1536x1536-height":635,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ec520a9560a160b7bbf33e555c996f_15aaf6ae.png","2048x2048-width":840,"2048x2048-height":635,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ec520a9560a160b7bbf33e555c996f_15aaf6ae.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":227,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ec520a9560a160b7bbf33e555c996f_15aaf6ae.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":302,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/41ec520a9560a160b7bbf33e555c996f_15aaf6ae.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":454}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>Welcome to our lovely apartment located in the city center, Civico 13 is furnished with attention to detail to guarantee you a comfortable and relaxing stay. The spaces are distributed in a functional way, the living room has a comfortable sofa bed, perfect for relaxing after a day of exploring the city, fully equipped kitchenette, bathroom and a lovely mezzanine with a double bedroom.<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"<p>The municipality of Bergamo requests payment of the tourist tax&#13;<br \/>\nThe apartment is on the 2nd floor, the kitchen is fully equipped but by law we cannot serve food and drinks, fill out the online check-in before your arrival to receive all the information on how to access the apartment.<\/p>\n","parking":"<p>Paid parking in the immediate vicinity<\/p>\n","restaurant":"","breakfast":"","internet":"<p>Free Wifi connection<\/p>\n","children":"","pets":"<p>Animals are not allowed<\/p>\n","latitude":"45.694140","longitude":"9.664288","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"Lct Management Srl","registered_office":"Via Vittorio Gasparini, 109 Bergamo","iu_addr_streetnumber":"Via Sant'Alessandro, 13","iu_addr_postalcode":"24122","iu_addr_city":"","iu_addr_province":"","iu_phone":"","iu_cell":"3519624337","iu_website":"https:\/\/immobiliesoluzioni.beddy.io\/#\/(beddy:home)?lang=it","iu_email":"rent@immobiliesoluzioni.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"10895","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"time":"<p>Check-in dalle 16:00 &#8211; Check-out entro le 10:00\u00a0<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"wifi","label":"Wi-Fi"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"satellite_tv","label":"TV satellitare"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"},{"value":"amex","label":"American Express"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/163887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/163887\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media\/163888"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media?parent=163887"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/categories?post=163887"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/tags?post=163887"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/aggr?post=163887"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/area?post=163887"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/kind?post=163887"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/zona?post=163887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}