{"id":166452,"date":"2025-04-18T13:29:04","date_gmt":"2025-04-18T11:29:04","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/mimosa-charm-e-relax-holistic-harmony-in-pedrengo-near-bergamo\/"},"modified":"2025-04-18T14:10:46","modified_gmt":"2025-04-18T12:10:46","slug":"mimosa-charm-e-relax-holistic-harmony-in-pedrengo-near-bergamo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/mimosa-charm-e-relax-holistic-harmony-in-pedrengo-near-bergamo\/","title":{"rendered":"MIMOSA CHARM E RELAX &#8211; HOLISTIC HARMONY in Pedrengo near Bergamo"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":166453,"template":"","categories":[997],"tags":[],"aggr":[],"area":[],"kind":[18723],"zona":[],"class_list":["post-166452","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sleep","kind-strutturaricettiva-en"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"MIMOSA CHARM E RELAX - HOLISTIC HARMONY in Pedrengo near Bergamo","hero_text":"<p>New little house near Bergamo, in an ideal location to reach important places.<\/p>\n<p>&#13;<\/p>\n<p>It is in a truly UNIQUE and SPECIAL place.<\/p>\n<p>&#13;<\/p>\n<p>Located in a quiet area, with a garden and terraces facing the river and a sunset view. Independent entrance.<\/p>\n<p>&#13;<\/p>\n<p>With a covered parking space.<\/p>\n","slides":[{"image":{"ID":166453,"id":166453,"title":"451eb11c152889352c988fec6f0f51fa_28f9ef2e.png","filename":"451eb11c152889352c988fec6f0f51fa_28f9ef2e.png","filesize":1280924,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/451eb11c152889352c988fec6f0f51fa_28f9ef2e.png","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/mimosa-charm-e-relax-holistic-harmony-in-pedrengo-near-bergamo\/451eb11c152889352c988fec6f0f51fa_28f9ef2e-png\/","alt":"","author":"0","description":"","caption":"","name":"451eb11c152889352c988fec6f0f51fa_28f9ef2e-png","status":"inherit","uploaded_to":166452,"date":"2025-04-18 08:55:30","modified":"2025-04-18 12:10:48","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1706,"height":1136,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/451eb11c152889352c988fec6f0f51fa_28f9ef2e-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/451eb11c152889352c988fec6f0f51fa_28f9ef2e-300x200.png","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/451eb11c152889352c988fec6f0f51fa_28f9ef2e-768x511.png","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/451eb11c152889352c988fec6f0f51fa_28f9ef2e-1024x682.png","large-width":1024,"large-height":682,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/451eb11c152889352c988fec6f0f51fa_28f9ef2e-1536x1023.png","1536x1536-width":1536,"1536x1536-height":1023,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/451eb11c152889352c988fec6f0f51fa_28f9ef2e.png","2048x2048-width":1706,"2048x2048-height":1136,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/451eb11c152889352c988fec6f0f51fa_28f9ef2e.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/451eb11c152889352c988fec6f0f51fa_28f9ef2e.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/451eb11c152889352c988fec6f0f51fa_28f9ef2e.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":166460,"id":166460,"title":"ad0fd6f3accde0d8cb6c572659ee4c24_cdda2e41.png","filename":"ad0fd6f3accde0d8cb6c572659ee4c24_cdda2e41.png","filesize":1555665,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ad0fd6f3accde0d8cb6c572659ee4c24_cdda2e41.png","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/mimosa-charm-e-relax-holistic-harmony-in-pedrengo-near-bergamo\/ad0fd6f3accde0d8cb6c572659ee4c24_cdda2e41-png\/","alt":"","author":"0","description":"","caption":"","name":"ad0fd6f3accde0d8cb6c572659ee4c24_cdda2e41-png","status":"inherit","uploaded_to":166452,"date":"2025-04-18 08:55:35","modified":"2025-04-18 12:10:48","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1712,"height":1166,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ad0fd6f3accde0d8cb6c572659ee4c24_cdda2e41-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ad0fd6f3accde0d8cb6c572659ee4c24_cdda2e41-300x204.png","medium-width":300,"medium-height":204,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ad0fd6f3accde0d8cb6c572659ee4c24_cdda2e41-768x523.png","medium_large-width":768,"medium_large-height":523,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ad0fd6f3accde0d8cb6c572659ee4c24_cdda2e41-1024x697.png","large-width":1024,"large-height":697,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ad0fd6f3accde0d8cb6c572659ee4c24_cdda2e41-1536x1046.png","1536x1536-width":1536,"1536x1536-height":1046,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ad0fd6f3accde0d8cb6c572659ee4c24_cdda2e41.png","2048x2048-width":1712,"2048x2048-height":1166,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ad0fd6f3accde0d8cb6c572659ee4c24_cdda2e41.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":204,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ad0fd6f3accde0d8cb6c572659ee4c24_cdda2e41.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":272,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ad0fd6f3accde0d8cb6c572659ee4c24_cdda2e41.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":409}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":166467,"id":166467,"title":"a50e5030230e093a17788b1bd2a53ab3_ae12889d.png","filename":"a50e5030230e093a17788b1bd2a53ab3_ae12889d.png","filesize":1213629,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a50e5030230e093a17788b1bd2a53ab3_ae12889d.png","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/mimosa-charm-e-relax-holistic-harmony-in-pedrengo-near-bergamo\/a50e5030230e093a17788b1bd2a53ab3_ae12889d-png\/","alt":"","author":"0","description":"","caption":"","name":"a50e5030230e093a17788b1bd2a53ab3_ae12889d-png","status":"inherit","uploaded_to":166452,"date":"2025-04-18 08:55:41","modified":"2025-04-18 12:10:48","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1694,"height":1092,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a50e5030230e093a17788b1bd2a53ab3_ae12889d-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a50e5030230e093a17788b1bd2a53ab3_ae12889d-300x193.png","medium-width":300,"medium-height":193,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a50e5030230e093a17788b1bd2a53ab3_ae12889d-768x495.png","medium_large-width":768,"medium_large-height":495,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a50e5030230e093a17788b1bd2a53ab3_ae12889d-1024x660.png","large-width":1024,"large-height":660,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a50e5030230e093a17788b1bd2a53ab3_ae12889d-1536x990.png","1536x1536-width":1536,"1536x1536-height":990,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a50e5030230e093a17788b1bd2a53ab3_ae12889d.png","2048x2048-width":1694,"2048x2048-height":1092,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a50e5030230e093a17788b1bd2a53ab3_ae12889d.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":193,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a50e5030230e093a17788b1bd2a53ab3_ae12889d.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":258,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a50e5030230e093a17788b1bd2a53ab3_ae12889d.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":387}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":166474,"id":166474,"title":"23985a4ad96b36450a1d07e4754a72b0_685e365a.png","filename":"23985a4ad96b36450a1d07e4754a72b0_685e365a.png","filesize":1778984,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23985a4ad96b36450a1d07e4754a72b0_685e365a.png","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/mimosa-charm-e-relax-holistic-harmony-in-pedrengo-near-bergamo\/23985a4ad96b36450a1d07e4754a72b0_685e365a-png\/","alt":"","author":"0","description":"","caption":"","name":"23985a4ad96b36450a1d07e4754a72b0_685e365a-png","status":"inherit","uploaded_to":166452,"date":"2025-04-18 08:55:45","modified":"2025-04-18 12:10:48","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1552,"height":932,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23985a4ad96b36450a1d07e4754a72b0_685e365a-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23985a4ad96b36450a1d07e4754a72b0_685e365a-300x180.png","medium-width":300,"medium-height":180,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23985a4ad96b36450a1d07e4754a72b0_685e365a-768x461.png","medium_large-width":768,"medium_large-height":461,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23985a4ad96b36450a1d07e4754a72b0_685e365a-1024x615.png","large-width":1024,"large-height":615,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23985a4ad96b36450a1d07e4754a72b0_685e365a-1536x922.png","1536x1536-width":1536,"1536x1536-height":922,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23985a4ad96b36450a1d07e4754a72b0_685e365a.png","2048x2048-width":1552,"2048x2048-height":932,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23985a4ad96b36450a1d07e4754a72b0_685e365a.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":180,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23985a4ad96b36450a1d07e4754a72b0_685e365a.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":240,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23985a4ad96b36450a1d07e4754a72b0_685e365a.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":360}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":166481,"id":166481,"title":"e5dd2b475f060ee581ad943fad1fdeaf_77ba0a63.png","filename":"e5dd2b475f060ee581ad943fad1fdeaf_77ba0a63.png","filesize":1064217,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e5dd2b475f060ee581ad943fad1fdeaf_77ba0a63.png","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/mimosa-charm-e-relax-holistic-harmony-in-pedrengo-near-bergamo\/e5dd2b475f060ee581ad943fad1fdeaf_77ba0a63-png\/","alt":"","author":"0","description":"","caption":"","name":"e5dd2b475f060ee581ad943fad1fdeaf_77ba0a63-png","status":"inherit","uploaded_to":166452,"date":"2025-04-18 08:55:51","modified":"2025-04-18 12:10:48","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1738,"height":1124,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e5dd2b475f060ee581ad943fad1fdeaf_77ba0a63-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e5dd2b475f060ee581ad943fad1fdeaf_77ba0a63-300x194.png","medium-width":300,"medium-height":194,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e5dd2b475f060ee581ad943fad1fdeaf_77ba0a63-768x497.png","medium_large-width":768,"medium_large-height":497,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e5dd2b475f060ee581ad943fad1fdeaf_77ba0a63-1024x662.png","large-width":1024,"large-height":662,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e5dd2b475f060ee581ad943fad1fdeaf_77ba0a63-1536x993.png","1536x1536-width":1536,"1536x1536-height":993,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e5dd2b475f060ee581ad943fad1fdeaf_77ba0a63.png","2048x2048-width":1738,"2048x2048-height":1124,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e5dd2b475f060ee581ad943fad1fdeaf_77ba0a63.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":194,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e5dd2b475f060ee581ad943fad1fdeaf_77ba0a63.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":259,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e5dd2b475f060ee581ad943fad1fdeaf_77ba0a63.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":388}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":166488,"id":166488,"title":"04972d8d5c1150e89da2713ed74d3d78_41461cdb.png","filename":"04972d8d5c1150e89da2713ed74d3d78_41461cdb.png","filesize":2676404,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04972d8d5c1150e89da2713ed74d3d78_41461cdb.png","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/mimosa-charm-e-relax-holistic-harmony-in-pedrengo-near-bergamo\/04972d8d5c1150e89da2713ed74d3d78_41461cdb-png\/","alt":"","author":"0","description":"","caption":"","name":"04972d8d5c1150e89da2713ed74d3d78_41461cdb-png","status":"inherit","uploaded_to":166452,"date":"2025-04-18 08:55:58","modified":"2025-04-18 12:10:48","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1690,"height":1146,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04972d8d5c1150e89da2713ed74d3d78_41461cdb-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04972d8d5c1150e89da2713ed74d3d78_41461cdb-300x203.png","medium-width":300,"medium-height":203,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04972d8d5c1150e89da2713ed74d3d78_41461cdb-768x521.png","medium_large-width":768,"medium_large-height":521,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04972d8d5c1150e89da2713ed74d3d78_41461cdb-1024x694.png","large-width":1024,"large-height":694,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04972d8d5c1150e89da2713ed74d3d78_41461cdb-1536x1042.png","1536x1536-width":1536,"1536x1536-height":1042,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04972d8d5c1150e89da2713ed74d3d78_41461cdb.png","2048x2048-width":1690,"2048x2048-height":1146,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04972d8d5c1150e89da2713ed74d3d78_41461cdb.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":203,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04972d8d5c1150e89da2713ed74d3d78_41461cdb.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":271,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/04972d8d5c1150e89da2713ed74d3d78_41461cdb.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":407}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":166495,"id":166495,"title":"618f267ffaeb41d133be1191edc46cfd_a770e4b5.png","filename":"618f267ffaeb41d133be1191edc46cfd_a770e4b5.png","filesize":1078456,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/618f267ffaeb41d133be1191edc46cfd_a770e4b5.png","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/mimosa-charm-e-relax-holistic-harmony-in-pedrengo-near-bergamo\/618f267ffaeb41d133be1191edc46cfd_a770e4b5-png\/","alt":"","author":"0","description":"","caption":"","name":"618f267ffaeb41d133be1191edc46cfd_a770e4b5-png","status":"inherit","uploaded_to":166452,"date":"2025-04-18 08:56:04","modified":"2025-04-18 12:10:48","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":924,"height":780,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/618f267ffaeb41d133be1191edc46cfd_a770e4b5-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/618f267ffaeb41d133be1191edc46cfd_a770e4b5-300x253.png","medium-width":300,"medium-height":253,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/618f267ffaeb41d133be1191edc46cfd_a770e4b5-768x648.png","medium_large-width":768,"medium_large-height":648,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/618f267ffaeb41d133be1191edc46cfd_a770e4b5.png","large-width":924,"large-height":780,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/618f267ffaeb41d133be1191edc46cfd_a770e4b5.png","1536x1536-width":924,"1536x1536-height":780,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/618f267ffaeb41d133be1191edc46cfd_a770e4b5.png","2048x2048-width":924,"2048x2048-height":780,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/618f267ffaeb41d133be1191edc46cfd_a770e4b5.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":253,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/618f267ffaeb41d133be1191edc46cfd_a770e4b5.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":338,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/618f267ffaeb41d133be1191edc46cfd_a770e4b5.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":506}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>Relax and recharge in this place of peace and elegance.&#13;<br \/>\nMimosa Charme e Relax is a truly unique and special place, both for its type of construction and for its location: situated in a quiet area, with a private garden and terraces, in front of the river, with a sunset view.&#13;<br \/>\nNewly built two-room house, located on the elevator level (access via an external staircase) near the river, in a very quiet area. It features an independent entrance, spacious terraces, and a garden with a sunset view.&#13;<br \/>\nIt consists of:&#13;<br \/>\n&#13;<br \/>\nA double bedroom with a large wardrobe and terrace;&#13;<br \/>\nA living area with a sofa, a terrace for outdoor dining, a double bed for 2 extra guests, a fully equipped kitchen with an oven, fridge, TV, kettle, coffee machine, and toaster; vacuum cleaner, fire extinguisher.&#13;<br \/>\nA bathroom with a shower, sink, hairdryer, and welcome kit.&#13;<br \/>\nCovered parking space in the garage.&#13;<br \/>\n&#13;<br \/>\nThe house accommodates up to 4 people + a baby in a crib (provided upon request).&#13;<br \/>\nPets are allowed (as long as they do not get on the beds and sofa).&#13;<br \/>\nWe provide our guests with:&#13;<br \/>\n&#13;<br \/>\nHerbal tea&#13;<br \/>\nCoffee pod&#13;<br \/>\nSugar&#13;<br \/>\nOil, vinegar, salt&#13;<br \/>\nDetergent&#13;<br \/>\nSoaps&#13;<br \/>\nTablecloth and napkins&#13;<br \/>\nInformational material&#13;<br \/>\n&#13;<br \/>\nAll this just a few minutes from the center of Bergamo.<\/p>\n","indepth":"<p>FULL PAYMENT IN ADVANCE, AT THE TIME OF BOOKING (by bank transfer or PayPal).&#13;<br \/>\nMANDATORY SUBMISSION OF ALL GUESTS&#8217; DOCUMENTS AT LEAST 2 DAYS BEFORE ARRIVAL!&#13;<br \/>\nIn an optimal location to reach important places:&#13;<br \/>\n&#13;<br \/>\nIn front of the bus stop (ATB line 5, from Bergamo city center) (for schedules, check the website atb.bergamo.it, line 5).&#13;<br \/>\n3 km from Seriate train station, 6 km from Bergamo train station.&#13;<br \/>\n5-10 minutes from Bergamo city center and its famous medieval walls (UNESCO World Heritage Site).&#13;<br \/>\n10 minutes from Bergamo Airport (Orio al Serio).&#13;<br \/>\n10 minutes from the Bergamo Exhibition Center.&#13;<br \/>\n45 minutes from Milan city center.&#13;<\/p>\n","howtogetthere":"<p>In an ideal location to reach important places.&#13;<br \/>\nMimosa Charme e Relax is located:&#13;<br \/>\n&#13;<br \/>\nOn the border between Pedrengo and Scanzorosciate&#13;<br \/>\nIn front of the bus stop&#13;<br \/>\n3 km from Seriate train station, 6 km from Bergamo train station&#13;<br \/>\n10 minutes from Bergamo city center (with its famous medieval walls, a UNESCO World Heritage Site)&#13;<br \/>\n10 minutes from Orio al Serio\/Bergamo Airport&#13;<br \/>\n10 minutes from the Bergamo Exhibition Center&#13;<br \/>\n45 minutes from Milan city center&#13;<br \/>\n&#13;<br \/>\nThe &#8216;Mimosa Charme e Relax&#8217; house is in Pedrengo (BG), on the border between Pedrengo and Scanzorosciate, at Via Piave 13 A, inside the large ARMONIA OLISTICA building, right at the intersection with Via 25 Aprile in Scanzorosciate. (It is visible from the road because the name is engraved in large letters on the building).&#13;<br \/>\nThe house is located above THE LONGEVITY SUITE. The entrance is through a small gate to the right of the building, where the sign &#8216;Casa Vacanze Mimosa Charme e Relax&#8217; is displayed.<\/p>\n","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"<p>The average price varies depending on the number of people, pets, and season.&#13;<br \/>\nStarting from \u20ac85 per day.<\/p>\n","services":"<p>No tourist tax<\/p>\n","parking":"<p>Possibility to park vehicles in the covered garage or outside (with a parking disc).<\/p>\n","restaurant":"<p>Restaurants nearby, listed in the informational material available in the house.<\/p>\n","breakfast":"","internet":"<p>Possibility of WiFi<\/p>\n","children":"","pets":"<p>Pets are allowed, as long as they do not climb on sofas and beds!! And please pick up their waste from the grass!<\/p>\n","latitude":"45.704293","longitude":"9.724383","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"GIPI HOLDING SRL","registered_office":"via Bettera, 22 Gandino, Bg","iu_addr_streetnumber":"Via Piave, 13","iu_addr_postalcode":"24066","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"3332745242","iu_cell":"3355750795","iu_website":"https:\/\/www.airbnb.it\/rooms\/999134799099132406?adults=1&children=0&enable_m3_private_room=true&infants=0&pets=0&search_mode=regular_search&check_in=2025-01-24&check_out=2025-01-25&source_impression_id=p3_1737634852_P3DPHrMhfb0GTMqZ&previous_page_section_n","iu_email":"armoniaolisticapedrengo@gmail.com","iu_vat":"04232940165","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"11175","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"time":"<p>CHECK-IN dalle ore 14&#13;<br \/>\nCHECK-OUT entro le ore 10<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"audiovisual_equipment","label":"Impianti audiovisivi"},{"value":"solarium","label":"Solarium"},{"value":"wifi","label":"Wi-Fi"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"tv_room","label":"TV in camera"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"balcony","label":"Balcone"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"shower","label":"Bagni con doccia"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/166452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/166452\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media\/166453"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media?parent=166452"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/categories?post=166452"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/tags?post=166452"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/aggr?post=166452"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/area?post=166452"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/kind?post=166452"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/zona?post=166452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}