{"id":167990,"date":"2025-04-18T13:30:36","date_gmt":"2025-04-18T11:30:36","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/residenza-corallo\/"},"modified":"2025-04-18T14:12:50","modified_gmt":"2025-04-18T12:12:50","slug":"residenza-corallo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-corallo\/","title":{"rendered":"Residenza Corallo"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":167991,"template":"","categories":[997],"tags":[],"aggr":[],"area":[],"kind":[18723],"zona":[],"class_list":["post-167990","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sleep","kind-strutturaricettiva-en"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Residenza Corallo","hero_text":"<p>The house has been recently renovated, with simple and modern design furniture.<\/p>\n","slides":[{"image":{"ID":167991,"id":167991,"title":"45467c496e55391a079659de396bd042_3a27844d.jpg","filename":"45467c496e55391a079659de396bd042_3a27844d.jpg","filesize":290171,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45467c496e55391a079659de396bd042_3a27844d.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-corallo\/45467c496e55391a079659de396bd042_3a27844d-jpg\/","alt":"","author":"0","description":"","caption":"","name":"45467c496e55391a079659de396bd042_3a27844d-jpg","status":"inherit","uploaded_to":167990,"date":"2025-04-18 09:02:32","modified":"2025-04-18 12:12:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45467c496e55391a079659de396bd042_3a27844d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45467c496e55391a079659de396bd042_3a27844d-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45467c496e55391a079659de396bd042_3a27844d-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45467c496e55391a079659de396bd042_3a27844d-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45467c496e55391a079659de396bd042_3a27844d-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45467c496e55391a079659de396bd042_3a27844d.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45467c496e55391a079659de396bd042_3a27844d.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45467c496e55391a079659de396bd042_3a27844d.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45467c496e55391a079659de396bd042_3a27844d.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167998,"id":167998,"title":"3fa9753fa0468577707751706c953ae1_8dffb045.jpg","filename":"3fa9753fa0468577707751706c953ae1_8dffb045.jpg","filesize":298395,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3fa9753fa0468577707751706c953ae1_8dffb045.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-corallo\/3fa9753fa0468577707751706c953ae1_8dffb045-jpg\/","alt":"","author":"0","description":"","caption":"","name":"3fa9753fa0468577707751706c953ae1_8dffb045-jpg","status":"inherit","uploaded_to":167990,"date":"2025-04-18 09:02:33","modified":"2025-04-18 12:12:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3fa9753fa0468577707751706c953ae1_8dffb045-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3fa9753fa0468577707751706c953ae1_8dffb045-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3fa9753fa0468577707751706c953ae1_8dffb045-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3fa9753fa0468577707751706c953ae1_8dffb045-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3fa9753fa0468577707751706c953ae1_8dffb045-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3fa9753fa0468577707751706c953ae1_8dffb045.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3fa9753fa0468577707751706c953ae1_8dffb045.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3fa9753fa0468577707751706c953ae1_8dffb045.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3fa9753fa0468577707751706c953ae1_8dffb045.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":168005,"id":168005,"title":"9b5e9b0dbee681cef4274015438787d1_5bd403e2.jpg","filename":"9b5e9b0dbee681cef4274015438787d1_5bd403e2.jpg","filesize":38357,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9b5e9b0dbee681cef4274015438787d1_5bd403e2.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-corallo\/9b5e9b0dbee681cef4274015438787d1_5bd403e2-jpg\/","alt":"","author":"0","description":"","caption":"","name":"9b5e9b0dbee681cef4274015438787d1_5bd403e2-jpg","status":"inherit","uploaded_to":167990,"date":"2025-04-18 09:02:35","modified":"2025-04-18 12:12:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":360,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9b5e9b0dbee681cef4274015438787d1_5bd403e2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9b5e9b0dbee681cef4274015438787d1_5bd403e2-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9b5e9b0dbee681cef4274015438787d1_5bd403e2.jpg","medium_large-width":360,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9b5e9b0dbee681cef4274015438787d1_5bd403e2.jpg","large-width":360,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9b5e9b0dbee681cef4274015438787d1_5bd403e2.jpg","1536x1536-width":360,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9b5e9b0dbee681cef4274015438787d1_5bd403e2.jpg","2048x2048-width":360,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9b5e9b0dbee681cef4274015438787d1_5bd403e2.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9b5e9b0dbee681cef4274015438787d1_5bd403e2.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9b5e9b0dbee681cef4274015438787d1_5bd403e2.jpg","gform-image-choice-lg-width":360,"gform-image-choice-lg-height":480}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":168012,"id":168012,"title":"504482f260ab390e3f07b1bfcb4b2adf_b2293c62.jpg","filename":"504482f260ab390e3f07b1bfcb4b2adf_b2293c62.jpg","filesize":46502,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/504482f260ab390e3f07b1bfcb4b2adf_b2293c62.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-corallo\/504482f260ab390e3f07b1bfcb4b2adf_b2293c62-jpg\/","alt":"","author":"0","description":"","caption":"","name":"504482f260ab390e3f07b1bfcb4b2adf_b2293c62-jpg","status":"inherit","uploaded_to":167990,"date":"2025-04-18 09:02:36","modified":"2025-04-18 12:12:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":640,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/504482f260ab390e3f07b1bfcb4b2adf_b2293c62-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/504482f260ab390e3f07b1bfcb4b2adf_b2293c62-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/504482f260ab390e3f07b1bfcb4b2adf_b2293c62.jpg","medium_large-width":640,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/504482f260ab390e3f07b1bfcb4b2adf_b2293c62.jpg","large-width":640,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/504482f260ab390e3f07b1bfcb4b2adf_b2293c62.jpg","1536x1536-width":640,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/504482f260ab390e3f07b1bfcb4b2adf_b2293c62.jpg","2048x2048-width":640,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/504482f260ab390e3f07b1bfcb4b2adf_b2293c62.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/504482f260ab390e3f07b1bfcb4b2adf_b2293c62.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/504482f260ab390e3f07b1bfcb4b2adf_b2293c62.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":168019,"id":168019,"title":"590529fc433f78f390a58528eff90106_0db51db6.jpg","filename":"590529fc433f78f390a58528eff90106_0db51db6.jpg","filesize":52063,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/590529fc433f78f390a58528eff90106_0db51db6.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-corallo\/590529fc433f78f390a58528eff90106_0db51db6-jpg\/","alt":"","author":"0","description":"","caption":"","name":"590529fc433f78f390a58528eff90106_0db51db6-jpg","status":"inherit","uploaded_to":167990,"date":"2025-04-18 09:02:37","modified":"2025-04-18 12:12:54","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":360,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/590529fc433f78f390a58528eff90106_0db51db6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/590529fc433f78f390a58528eff90106_0db51db6-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/590529fc433f78f390a58528eff90106_0db51db6.jpg","medium_large-width":360,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/590529fc433f78f390a58528eff90106_0db51db6.jpg","large-width":360,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/590529fc433f78f390a58528eff90106_0db51db6.jpg","1536x1536-width":360,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/590529fc433f78f390a58528eff90106_0db51db6.jpg","2048x2048-width":360,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/590529fc433f78f390a58528eff90106_0db51db6.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/590529fc433f78f390a58528eff90106_0db51db6.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/590529fc433f78f390a58528eff90106_0db51db6.jpg","gform-image-choice-lg-width":360,"gform-image-choice-lg-height":480}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":168026,"id":168026,"title":"e99658b34989d64103c9b398001fa578_05ad60ed.jpg","filename":"e99658b34989d64103c9b398001fa578_05ad60ed.jpg","filesize":51095,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99658b34989d64103c9b398001fa578_05ad60ed.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-corallo\/e99658b34989d64103c9b398001fa578_05ad60ed-jpg\/","alt":"","author":"0","description":"","caption":"","name":"e99658b34989d64103c9b398001fa578_05ad60ed-jpg","status":"inherit","uploaded_to":167990,"date":"2025-04-18 09:02:38","modified":"2025-04-18 12:12:54","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":360,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99658b34989d64103c9b398001fa578_05ad60ed-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99658b34989d64103c9b398001fa578_05ad60ed-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99658b34989d64103c9b398001fa578_05ad60ed.jpg","medium_large-width":360,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99658b34989d64103c9b398001fa578_05ad60ed.jpg","large-width":360,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99658b34989d64103c9b398001fa578_05ad60ed.jpg","1536x1536-width":360,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99658b34989d64103c9b398001fa578_05ad60ed.jpg","2048x2048-width":360,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99658b34989d64103c9b398001fa578_05ad60ed.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99658b34989d64103c9b398001fa578_05ad60ed.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e99658b34989d64103c9b398001fa578_05ad60ed.jpg","gform-image-choice-lg-width":360,"gform-image-choice-lg-height":480}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":168033,"id":168033,"title":"47da94623ce85c35175be331c14f860e_f2b91dfb.jpg","filename":"47da94623ce85c35175be331c14f860e_f2b91dfb.jpg","filesize":32969,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47da94623ce85c35175be331c14f860e_f2b91dfb.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-corallo\/47da94623ce85c35175be331c14f860e_f2b91dfb-jpg\/","alt":"","author":"0","description":"","caption":"","name":"47da94623ce85c35175be331c14f860e_f2b91dfb-jpg","status":"inherit","uploaded_to":167990,"date":"2025-04-18 09:02:39","modified":"2025-04-18 12:12:54","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":360,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47da94623ce85c35175be331c14f860e_f2b91dfb-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47da94623ce85c35175be331c14f860e_f2b91dfb-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47da94623ce85c35175be331c14f860e_f2b91dfb.jpg","medium_large-width":360,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47da94623ce85c35175be331c14f860e_f2b91dfb.jpg","large-width":360,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47da94623ce85c35175be331c14f860e_f2b91dfb.jpg","1536x1536-width":360,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47da94623ce85c35175be331c14f860e_f2b91dfb.jpg","2048x2048-width":360,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47da94623ce85c35175be331c14f860e_f2b91dfb.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47da94623ce85c35175be331c14f860e_f2b91dfb.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/47da94623ce85c35175be331c14f860e_f2b91dfb.jpg","gform-image-choice-lg-width":360,"gform-image-choice-lg-height":480}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":168040,"id":168040,"title":"698e32996795f35f72d215c6f637e7fd_0448fc78.jpg","filename":"698e32996795f35f72d215c6f637e7fd_0448fc78.jpg","filesize":32287,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/698e32996795f35f72d215c6f637e7fd_0448fc78.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-corallo\/698e32996795f35f72d215c6f637e7fd_0448fc78-jpg\/","alt":"","author":"0","description":"","caption":"","name":"698e32996795f35f72d215c6f637e7fd_0448fc78-jpg","status":"inherit","uploaded_to":167990,"date":"2025-04-18 09:02:40","modified":"2025-04-18 12:12:54","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":360,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/698e32996795f35f72d215c6f637e7fd_0448fc78-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/698e32996795f35f72d215c6f637e7fd_0448fc78-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/698e32996795f35f72d215c6f637e7fd_0448fc78.jpg","medium_large-width":360,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/698e32996795f35f72d215c6f637e7fd_0448fc78.jpg","large-width":360,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/698e32996795f35f72d215c6f637e7fd_0448fc78.jpg","1536x1536-width":360,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/698e32996795f35f72d215c6f637e7fd_0448fc78.jpg","2048x2048-width":360,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/698e32996795f35f72d215c6f637e7fd_0448fc78.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/698e32996795f35f72d215c6f637e7fd_0448fc78.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/698e32996795f35f72d215c6f637e7fd_0448fc78.jpg","gform-image-choice-lg-width":360,"gform-image-choice-lg-height":480}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":168047,"id":168047,"title":"c297523f671b7a82f05655df244c7091_0b56298a.jpg","filename":"c297523f671b7a82f05655df244c7091_0b56298a.jpg","filesize":219508,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c297523f671b7a82f05655df244c7091_0b56298a.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-corallo\/c297523f671b7a82f05655df244c7091_0b56298a-jpg\/","alt":"","author":"0","description":"","caption":"","name":"c297523f671b7a82f05655df244c7091_0b56298a-jpg","status":"inherit","uploaded_to":167990,"date":"2025-04-18 09:02:41","modified":"2025-04-18 12:12:54","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c297523f671b7a82f05655df244c7091_0b56298a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c297523f671b7a82f05655df244c7091_0b56298a-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c297523f671b7a82f05655df244c7091_0b56298a-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c297523f671b7a82f05655df244c7091_0b56298a-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c297523f671b7a82f05655df244c7091_0b56298a-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c297523f671b7a82f05655df244c7091_0b56298a.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c297523f671b7a82f05655df244c7091_0b56298a.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c297523f671b7a82f05655df244c7091_0b56298a.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c297523f671b7a82f05655df244c7091_0b56298a.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>The apartment is located in a building dating back to 1866 in the historic centre of Lower Bergamo, a 5-minute walk from the famous shopping street. Well served by public transport, it is halfway between two bus lines. In the area, you can find nice restaurants and boutiques, but also supermarkets, such as Esselunga and Carrefour express, open until midnight.&#13;<br \/>\nThe entire house is available. It has been renovated recently and consists of three rooms: two bedrooms overlooking the historic street of Via San Bernardino, a large room with kitchen and a lovely terrace.&#13;<br \/>\nThe spaces are well organised and the room is bright. Ideal for families or groups of around 4 people.<\/p>\n","indepth":"","howtogetthere":"<p>Located near the La Taverna del Gallo restaurant and Libraccio book shop. It can be reached by taking bus numbers 5 or 9, stopping in Piazza Pontida.<\/p>\n","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"<p>The tourist tax is not included in the price of the apartment<\/p>\n","parking":"<p>Along Via San Bernardino you can find a series of paid car parks (Blue Line) which then become free in the evening. Otherwise in the university area, just 5\/10 minutes on foot you can find free parking (white line)<\/p>\n","restaurant":"<p>You can enjoy the excellent cuisine at Taverna del Gallo located just before our B&#038;B.<\/p>\n","breakfast":"","internet":"<p>Free WIFI<\/p>\n","children":"<p>Unfortunately, we are not equipped to accommodate very young children or babies but we will be happy to welcome your children if the services we offer are suitable for them.<\/p>\n","pets":"<p>Pets are not allowed<\/p>\n","latitude":"45.690539","longitude":"9.663259","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"Gabriella Cordani","registered_office":"","iu_addr_streetnumber":"Via S. Bernardino, 23","iu_addr_postalcode":"24122","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 3398933487","iu_cell":"3398933487","iu_website":"https:\/\/www.booking.com\/hotel\/it\/residenza-corallo.html?lang=xu","iu_email":"immobiliarecorallosas@gmail.com","iu_vat":"02249070166","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"2","iu_beds":"4","id_madeep":"","id_visit_manza":"8370","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"time":"<p>check-in entro le 22:30&#13;<br \/>\ncheck-out entro le 12<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"wifi","label":"Wi-Fi"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"balcony","label":"Balcone"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/167990","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/167990\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media\/167991"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media?parent=167990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/categories?post=167990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/tags?post=167990"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/aggr?post=167990"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/area?post=167990"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/kind?post=167990"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/zona?post=167990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}