{"id":169446,"date":"2025-04-18T13:31:46","date_gmt":"2025-04-18T11:31:46","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/life-hotel\/"},"modified":"2025-04-18T14:14:37","modified_gmt":"2025-04-18T12:14:37","slug":"life-hotel","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/","title":{"rendered":"Life Hotel"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":169447,"template":"","categories":[997],"tags":[],"aggr":[],"area":[],"kind":[18723],"zona":[],"class_list":["post-169446","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sleep","kind-strutturaricettiva-en"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Life Hotel","hero_text":"<p>Life Hotel welcomes you to enjoy an experience that envelops the senses<\/p>\n","slides":[{"image":{"ID":169447,"id":169447,"title":"e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a","filename":"e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a.jpg","filesize":477701,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a\/","alt":"","author":"0","description":"","caption":"","name":"e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:33","modified":"2025-04-18 12:14:39","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1281,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a.jpg","2048x2048-width":1920,"2048x2048-height":1281,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3b2f56a3c4348faff92a422af297b1e_1d3dcf7a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169454,"id":169454,"title":"2184c2ca60179164b41b72ea8269beaa_c62b3c75","filename":"2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","filesize":125032,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/2184c2ca60179164b41b72ea8269beaa_c62b3c75\/","alt":"","author":"0","description":"","caption":"","name":"2184c2ca60179164b41b72ea8269beaa_c62b3c75","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:35","modified":"2025-04-18 12:14:39","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1000,"height":667,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","large-width":1000,"large-height":667,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","1536x1536-width":1000,"1536x1536-height":667,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","2048x2048-width":1000,"2048x2048-height":667,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2184c2ca60179164b41b72ea8269beaa_c62b3c75.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169461,"id":169461,"title":"23dfbb15fc3990a40c0107c909aac0f5_241be0fd","filename":"23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","filesize":125696,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd\/","alt":"","author":"0","description":"","caption":"","name":"23dfbb15fc3990a40c0107c909aac0f5_241be0fd","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:36","modified":"2025-04-18 12:14:39","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1000,"height":667,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","large-width":1000,"large-height":667,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","1536x1536-width":1000,"1536x1536-height":667,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","2048x2048-width":1000,"2048x2048-height":667,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23dfbb15fc3990a40c0107c909aac0f5_241be0fd.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169468,"id":169468,"title":"f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310","filename":"f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","filesize":96617,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310\/","alt":"","author":"0","description":"","caption":"","name":"f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:37","modified":"2025-04-18 12:14:39","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1000,"height":667,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","large-width":1000,"large-height":667,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","1536x1536-width":1000,"1536x1536-height":667,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","2048x2048-width":1000,"2048x2048-height":667,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0ca1d5a84f6887a94f3a3630c9eeba8_271ea310.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169475,"id":169475,"title":"3084b00a752fc069f77371521a0b235f_2d1982c4","filename":"3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","filesize":97509,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/3084b00a752fc069f77371521a0b235f_2d1982c4\/","alt":"","author":"0","description":"","caption":"","name":"3084b00a752fc069f77371521a0b235f_2d1982c4","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:37","modified":"2025-04-18 12:14:39","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3084b00a752fc069f77371521a0b235f_2d1982c4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169482,"id":169482,"title":"dfe098cca3166e98967f2433428601d3_57554850","filename":"dfe098cca3166e98967f2433428601d3_57554850.jpg","filesize":100341,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/dfe098cca3166e98967f2433428601d3_57554850\/","alt":"","author":"0","description":"","caption":"","name":"dfe098cca3166e98967f2433428601d3_57554850","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:38","modified":"2025-04-18 12:14:39","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dfe098cca3166e98967f2433428601d3_57554850.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169489,"id":169489,"title":"6f3d4df145a440ae61beed14c5099ffe_32e41977","filename":"6f3d4df145a440ae61beed14c5099ffe_32e41977.jpg","filesize":370298,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/6f3d4df145a440ae61beed14c5099ffe_32e41977\/","alt":"","author":"0","description":"","caption":"","name":"6f3d4df145a440ae61beed14c5099ffe_32e41977","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:39","modified":"2025-04-18 12:14:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1281,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977.jpg","2048x2048-width":1920,"2048x2048-height":1281,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6f3d4df145a440ae61beed14c5099ffe_32e41977.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169496,"id":169496,"title":"00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2","filename":"00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","filesize":107234,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2\/","alt":"","author":"0","description":"","caption":"","name":"00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:40","modified":"2025-04-18 12:14:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/00a1cf17ea5fbe3367f24f96625fe88f_19e6ead2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169503,"id":169503,"title":"7e73c88faf58710af309bc4abb37524f_6a172f37","filename":"7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","filesize":99549,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/7e73c88faf58710af309bc4abb37524f_6a172f37\/","alt":"","author":"0","description":"","caption":"","name":"7e73c88faf58710af309bc4abb37524f_6a172f37","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:41","modified":"2025-04-18 12:14:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7e73c88faf58710af309bc4abb37524f_6a172f37.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169510,"id":169510,"title":"3be66e1e8b99e626c58453a1a3b14719_ebe8d495","filename":"3be66e1e8b99e626c58453a1a3b14719_ebe8d495.jpg","filesize":437229,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495\/","alt":"","author":"0","description":"","caption":"","name":"3be66e1e8b99e626c58453a1a3b14719_ebe8d495","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:42","modified":"2025-04-18 12:14:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2048,"height":1364,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495-1024x682.jpg","large-width":1024,"large-height":682,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495-1536x1023.jpg","1536x1536-width":1536,"1536x1536-height":1023,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495.jpg","2048x2048-width":2048,"2048x2048-height":1364,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3be66e1e8b99e626c58453a1a3b14719_ebe8d495.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169517,"id":169517,"title":"01da58f1f39bcac4398bd5bbd575134a_56333e0f","filename":"01da58f1f39bcac4398bd5bbd575134a_56333e0f.jpg","filesize":403219,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/01da58f1f39bcac4398bd5bbd575134a_56333e0f\/","alt":"","author":"0","description":"","caption":"","name":"01da58f1f39bcac4398bd5bbd575134a_56333e0f","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:43","modified":"2025-04-18 12:14:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1281,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f.jpg","2048x2048-width":1920,"2048x2048-height":1281,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/01da58f1f39bcac4398bd5bbd575134a_56333e0f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169524,"id":169524,"title":"56f120473cece6a6e2167b36819f3740_a96493be","filename":"56f120473cece6a6e2167b36819f3740_a96493be.jpg","filesize":491638,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/56f120473cece6a6e2167b36819f3740_a96493be\/","alt":"","author":"0","description":"","caption":"","name":"56f120473cece6a6e2167b36819f3740_a96493be","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:44","modified":"2025-04-18 12:14:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1620,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be.jpg","2048x2048-width":1620,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56f120473cece6a6e2167b36819f3740_a96493be.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169531,"id":169531,"title":"1d661b27034707f6e632fba680589e14_fb21ec4e","filename":"1d661b27034707f6e632fba680589e14_fb21ec4e.jpg","filesize":487474,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/1d661b27034707f6e632fba680589e14_fb21ec4e\/","alt":"","author":"0","description":"","caption":"","name":"1d661b27034707f6e632fba680589e14_fb21ec4e","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:46","modified":"2025-04-18 12:14:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1619,"height":1080,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e.jpg","2048x2048-width":1619,"2048x2048-height":1080,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1d661b27034707f6e632fba680589e14_fb21ec4e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169538,"id":169538,"title":"dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76","filename":"dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","filesize":150588,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76\/","alt":"","author":"0","description":"","caption":"","name":"dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:47","modified":"2025-04-18 12:14:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dd4e30805ee4efb4c85b66479c32bc0b_d8c3ab76.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":169545,"id":169545,"title":"f898aed797c695793de66299c05b9086_eeeb1d67","filename":"f898aed797c695793de66299c05b9086_eeeb1d67.jpg","filesize":98566,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/life-hotel\/f898aed797c695793de66299c05b9086_eeeb1d67\/","alt":"","author":"0","description":"","caption":"","name":"f898aed797c695793de66299c05b9086_eeeb1d67","status":"inherit","uploaded_to":169446,"date":"2025-04-18 09:08:47","modified":"2025-04-18 12:14:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":683,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67.jpg","1536x1536-width":1024,"1536x1536-height":683,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67.jpg","2048x2048-width":1024,"2048x2048-height":683,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f898aed797c695793de66299c05b9086_eeeb1d67.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>Located on the outskirts of Bergamo, Life Hotel welcomes its guests in a hospitable, elegant and low environmental impact structure, with Leed Gold certification. A place where nature becomes inspiration, in which to enjoy a long stay or a short stay in the name of well-being. An integral part of the Life Source hospitality centre, the comfort of the rooms and suites of the 4* hotel is integrated with the different experiences of the structure: from the Food Experience in its three different gastronomic formats to our Wellness area with spa and fitness area, here every moment is an opportunity for pleasure.&#13;<br \/>\nEach room and suite of Life Hotel is equipped with:&#13;<br \/>\n&#13;<br \/>\nDorelan high quality beds, for a pleasant and comfortable sleep during your stay;&#13;<br \/>\nTV with Chromecast system that allows the use of streaming content (on request for a fee);&#13;<br \/>\nsoundproofing of the room.&#13;<br \/>\n&#13;<br \/>\nThe rooms of Life Hotel have state-of-the-art equipment: from internal temperature control to advanced lighting management and more, easily accessible and adjustable by the guest according to their needs.&#13;<br \/>\nThe location is ideal for business meetings, thanks also to its own meeting rooms, with cutting-edge technological equipment and large windows that allow illumination by natural light.&#13;<br \/>\nThe palate is the protagonist during a stay at Life Hotel. In fact, guests will be able to enjoy the centre\u2019s three gastronomic proposals: Le Terre Restaurant, for high-level and surprising gourmet cuisine, Onda Bistrot, for &#8216;pop&#8217; cuisine, simple and delicious and Atmospheres Rooftop &#8211; the terrace with a panoramic view of Bergamo\u2019s hills \u2013 perfect to relax in the open air.<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.689193","longitude":"9.646426","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"LIFE SOURCE s.r.l.","registered_office":"","iu_addr_streetnumber":"Via Briantea, 5","iu_addr_postalcode":"24128","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 035 05 26 169","iu_cell":"","iu_website":"http:\/\/www.lifehotelbergamo.it","iu_email":"info@lifehotelbergamo.it","iu_vat":"03678420161","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"4","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"10174","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"parking","label":"Parcheggio gratuito"},{"value":"elevator","label":"Ascensore"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"pool","label":"Piscina"},{"value":"restaurant","label":"Ristorante"},{"value":"health_club","label":"Centro benessere"},{"value":"bar","label":"Bar"},{"value":"conference_hall","label":"Sala congressi"},{"value":"meeting_room","label":"Sala riunioni"},{"value":"tv_lounge","label":"Sala TV"},{"value":"wifi","label":"Wi-Fi"},{"value":"sauna","label":"Sauna"},{"value":"shower","label":"Bagni con doccia"},{"value":"safe_deposit_box","label":"Cassetta di sicurezza"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"room_service","label":"Servizio in camera"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"mini_bar","label":"Frigo bar"},{"value":"tv_room","label":"TV in camera"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/169446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/169446\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media\/169447"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media?parent=169446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/categories?post=169446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/tags?post=169446"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/aggr?post=169446"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/area?post=169446"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/kind?post=169446"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/zona?post=169446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}