{"id":173050,"date":"2025-04-18T13:36:19","date_gmt":"2025-04-18T11:36:19","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/la-casa-di-milvia\/"},"modified":"2025-04-18T14:20:06","modified_gmt":"2025-04-18T12:20:06","slug":"la-casa-di-milvia","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/la-casa-di-milvia\/","title":{"rendered":"La Casa di Milvia"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":185423,"template":"","categories":[997],"tags":[],"aggr":[],"area":[],"kind":[18723],"zona":[],"class_list":["post-173050","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sleep","kind-strutturaricettiva-en"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"La Casa di Milvia","hero_text":"<p>Milvia&#8217;s House, a nest of tranquility in the historic center of Citt\u00e0 Alta.<\/p>\n","buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>Milvia&#8217;s House is an apartment located within a residential complex in the historic center of Citt\u00e0 Alta.&#13;<br \/>\nThe house consists of 2 rooms, a bathroom, a living room with a large sofa, and a kitchen fully equipped with cookware. It has been recently renovated and features modern amenities.&#13;<br \/>\nThe rental includes the entire house; it is not shared with other guests.&#13;<br \/>\n\u00a0<\/p>\n","indepth":"","howtogetthere":"<p>The building is located in the historic center with an entrance from Via Colleoni 4.&#13;<br \/>\nThe entrance is about 30 meters from Piazza Vecchia and is situated between the BIPER bank and the KIKO store.<\/p>\n","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"","parking":"<p>The house is located within the limited traffic zone (ZTL).&#13;<br \/>\nWithin a 300-meter radius, there are two parking areas: one with access in a free traffic zone, and the other within the limited traffic zone.<\/p>\n","restaurant":"<p>The house features a beautiful kitchen with a refrigerator, stovetop, dishwasher, microwave, and cookware.&#13;<br \/>\nThere are many restaurants in the area within walking distance.<\/p>\n","breakfast":"","internet":"","children":"<p>The house is equipped with a beautiful kitchen featuring a refrigerator, stovetop, dishwasher, microwave, and cookware.&#13;<br \/>\nThere are many restaurants in the area that are within walking distance.<\/p>\n","pets":"","latitude":"45.704084","longitude":"9.664005","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"MARCO LORENZO MANZONI","registered_office":"Via San Lorenzo 6 Bergamo","iu_addr_streetnumber":"Via S. Lorenzo, 6","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"3280272580","iu_cell":"","iu_website":"","iu_email":"lacasadimilvia@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"2","iu_beds":"3","id_madeep":"","id_visit_manza":"10972","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"time":"<p>Il check-in \u00e8 previsto dalle ore 14.00 alle 19.00 mentre il check-out per le ore 11.&#13;<br \/>\nSe non ci sono ulteriori prenotazioni gli orari sono flessibili per circa 2 ore prima o dopo, oltre a quegli orari \u00e8 previsto in supplemento.<\/p>\n","service_icons":[],"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","slides":[{"image":{"ID":185423,"id":185423,"title":"bf83c05ee33f1052948f93470187374c_88d5d821.jpg","filename":"bf83c05ee33f1052948f93470187374c_88d5d821.jpg","filesize":291050,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf83c05ee33f1052948f93470187374c_88d5d821.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/la-casa-di-milvia\/bf83c05ee33f1052948f93470187374c_88d5d821-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"bf83c05ee33f1052948f93470187374c_88d5d821-jpg-2","status":"inherit","uploaded_to":173050,"date":"2025-04-28 21:50:59","modified":"2025-04-28 21:50:59","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf83c05ee33f1052948f93470187374c_88d5d821-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf83c05ee33f1052948f93470187374c_88d5d821-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf83c05ee33f1052948f93470187374c_88d5d821-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf83c05ee33f1052948f93470187374c_88d5d821-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf83c05ee33f1052948f93470187374c_88d5d821-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf83c05ee33f1052948f93470187374c_88d5d821.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf83c05ee33f1052948f93470187374c_88d5d821.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf83c05ee33f1052948f93470187374c_88d5d821.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf83c05ee33f1052948f93470187374c_88d5d821.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":185430,"id":185430,"title":"6618c07d64a57353e6ab47c7161a4646_40b282b4.jpg","filename":"6618c07d64a57353e6ab47c7161a4646_40b282b4.jpg","filesize":185479,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6618c07d64a57353e6ab47c7161a4646_40b282b4.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/la-casa-di-milvia\/6618c07d64a57353e6ab47c7161a4646_40b282b4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6618c07d64a57353e6ab47c7161a4646_40b282b4-jpg-2","status":"inherit","uploaded_to":173050,"date":"2025-04-28 21:51:00","modified":"2025-04-28 21:51:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":968,"height":1453,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6618c07d64a57353e6ab47c7161a4646_40b282b4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6618c07d64a57353e6ab47c7161a4646_40b282b4-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6618c07d64a57353e6ab47c7161a4646_40b282b4-768x1153.jpg","medium_large-width":768,"medium_large-height":1153,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6618c07d64a57353e6ab47c7161a4646_40b282b4-682x1024.jpg","large-width":682,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6618c07d64a57353e6ab47c7161a4646_40b282b4.jpg","1536x1536-width":968,"1536x1536-height":1453,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6618c07d64a57353e6ab47c7161a4646_40b282b4.jpg","2048x2048-width":968,"2048x2048-height":1453,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6618c07d64a57353e6ab47c7161a4646_40b282b4.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6618c07d64a57353e6ab47c7161a4646_40b282b4.jpg","gform-image-choice-md-width":266,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6618c07d64a57353e6ab47c7161a4646_40b282b4.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":185437,"id":185437,"title":"27c3109c9f0487ec36934d9895721a8a_76d1ba23.jpg","filename":"27c3109c9f0487ec36934d9895721a8a_76d1ba23.jpg","filesize":181028,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27c3109c9f0487ec36934d9895721a8a_76d1ba23.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/la-casa-di-milvia\/27c3109c9f0487ec36934d9895721a8a_76d1ba23-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"27c3109c9f0487ec36934d9895721a8a_76d1ba23-jpg-2","status":"inherit","uploaded_to":173050,"date":"2025-04-28 21:51:02","modified":"2025-04-28 21:51:02","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1288,"height":920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27c3109c9f0487ec36934d9895721a8a_76d1ba23-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27c3109c9f0487ec36934d9895721a8a_76d1ba23-300x214.jpg","medium-width":300,"medium-height":214,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27c3109c9f0487ec36934d9895721a8a_76d1ba23-768x549.jpg","medium_large-width":768,"medium_large-height":549,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27c3109c9f0487ec36934d9895721a8a_76d1ba23-1024x731.jpg","large-width":1024,"large-height":731,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27c3109c9f0487ec36934d9895721a8a_76d1ba23.jpg","1536x1536-width":1288,"1536x1536-height":920,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27c3109c9f0487ec36934d9895721a8a_76d1ba23.jpg","2048x2048-width":1288,"2048x2048-height":920,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27c3109c9f0487ec36934d9895721a8a_76d1ba23.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":214,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27c3109c9f0487ec36934d9895721a8a_76d1ba23.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":286,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27c3109c9f0487ec36934d9895721a8a_76d1ba23.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":429}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":185444,"id":185444,"title":"85943aaabe0176b10954e0aa494bee97_c26d2cb7.jpg","filename":"85943aaabe0176b10954e0aa494bee97_c26d2cb7.jpg","filesize":543847,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85943aaabe0176b10954e0aa494bee97_c26d2cb7.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/la-casa-di-milvia\/85943aaabe0176b10954e0aa494bee97_c26d2cb7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"85943aaabe0176b10954e0aa494bee97_c26d2cb7-jpg-2","status":"inherit","uploaded_to":173050,"date":"2025-04-28 21:51:03","modified":"2025-04-28 21:51:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2000,"height":1500,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85943aaabe0176b10954e0aa494bee97_c26d2cb7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85943aaabe0176b10954e0aa494bee97_c26d2cb7-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85943aaabe0176b10954e0aa494bee97_c26d2cb7-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85943aaabe0176b10954e0aa494bee97_c26d2cb7-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85943aaabe0176b10954e0aa494bee97_c26d2cb7-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85943aaabe0176b10954e0aa494bee97_c26d2cb7.jpg","2048x2048-width":2000,"2048x2048-height":1500,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85943aaabe0176b10954e0aa494bee97_c26d2cb7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85943aaabe0176b10954e0aa494bee97_c26d2cb7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/85943aaabe0176b10954e0aa494bee97_c26d2cb7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":185451,"id":185451,"title":"4b15411eb66916852e28900323abdb2e_ea40a79d.jpg","filename":"4b15411eb66916852e28900323abdb2e_ea40a79d.jpg","filesize":536063,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b15411eb66916852e28900323abdb2e_ea40a79d.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/la-casa-di-milvia\/4b15411eb66916852e28900323abdb2e_ea40a79d-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4b15411eb66916852e28900323abdb2e_ea40a79d-jpg-2","status":"inherit","uploaded_to":173050,"date":"2025-04-28 21:51:04","modified":"2025-04-28 21:51:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":2000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b15411eb66916852e28900323abdb2e_ea40a79d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b15411eb66916852e28900323abdb2e_ea40a79d-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b15411eb66916852e28900323abdb2e_ea40a79d-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b15411eb66916852e28900323abdb2e_ea40a79d-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b15411eb66916852e28900323abdb2e_ea40a79d-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b15411eb66916852e28900323abdb2e_ea40a79d.jpg","2048x2048-width":1500,"2048x2048-height":2000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b15411eb66916852e28900323abdb2e_ea40a79d.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b15411eb66916852e28900323abdb2e_ea40a79d.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4b15411eb66916852e28900323abdb2e_ea40a79d.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":185458,"id":185458,"title":"1f31e7ae73741c0ea7f9078f5049fee8_35000347.jpg","filename":"1f31e7ae73741c0ea7f9078f5049fee8_35000347.jpg","filesize":509572,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f31e7ae73741c0ea7f9078f5049fee8_35000347.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/la-casa-di-milvia\/1f31e7ae73741c0ea7f9078f5049fee8_35000347-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1f31e7ae73741c0ea7f9078f5049fee8_35000347-jpg-2","status":"inherit","uploaded_to":173050,"date":"2025-04-28 21:51:06","modified":"2025-04-28 21:51:06","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2048,"height":1580,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f31e7ae73741c0ea7f9078f5049fee8_35000347-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f31e7ae73741c0ea7f9078f5049fee8_35000347-300x231.jpg","medium-width":300,"medium-height":231,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f31e7ae73741c0ea7f9078f5049fee8_35000347-768x593.jpg","medium_large-width":768,"medium_large-height":593,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f31e7ae73741c0ea7f9078f5049fee8_35000347-1024x790.jpg","large-width":1024,"large-height":790,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f31e7ae73741c0ea7f9078f5049fee8_35000347-1536x1185.jpg","1536x1536-width":1536,"1536x1536-height":1185,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f31e7ae73741c0ea7f9078f5049fee8_35000347.jpg","2048x2048-width":2048,"2048x2048-height":1580,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f31e7ae73741c0ea7f9078f5049fee8_35000347.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":231,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f31e7ae73741c0ea7f9078f5049fee8_35000347.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":309,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1f31e7ae73741c0ea7f9078f5049fee8_35000347.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":463}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":185465,"id":185465,"title":"7480b52967378ef6b2ecbf68a1e7199d_f83b8c6f.jpg","filename":"7480b52967378ef6b2ecbf68a1e7199d_f83b8c6f.jpg","filesize":309079,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7480b52967378ef6b2ecbf68a1e7199d_f83b8c6f.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/la-casa-di-milvia\/7480b52967378ef6b2ecbf68a1e7199d_f83b8c6f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"7480b52967378ef6b2ecbf68a1e7199d_f83b8c6f-jpg-2","status":"inherit","uploaded_to":173050,"date":"2025-04-28 21:51:07","modified":"2025-04-28 21:51:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7480b52967378ef6b2ecbf68a1e7199d_f83b8c6f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7480b52967378ef6b2ecbf68a1e7199d_f83b8c6f-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7480b52967378ef6b2ecbf68a1e7199d_f83b8c6f-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7480b52967378ef6b2ecbf68a1e7199d_f83b8c6f-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7480b52967378ef6b2ecbf68a1e7199d_f83b8c6f-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7480b52967378ef6b2ecbf68a1e7199d_f83b8c6f.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7480b52967378ef6b2ecbf68a1e7199d_f83b8c6f.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7480b52967378ef6b2ecbf68a1e7199d_f83b8c6f.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7480b52967378ef6b2ecbf68a1e7199d_f83b8c6f.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":185472,"id":185472,"title":"a48a9d6477a09dc9e31907b4b9ade6e3_8938d6a4.jpg","filename":"a48a9d6477a09dc9e31907b4b9ade6e3_8938d6a4.jpg","filesize":248855,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a48a9d6477a09dc9e31907b4b9ade6e3_8938d6a4.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/la-casa-di-milvia\/a48a9d6477a09dc9e31907b4b9ade6e3_8938d6a4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a48a9d6477a09dc9e31907b4b9ade6e3_8938d6a4-jpg-2","status":"inherit","uploaded_to":173050,"date":"2025-04-28 21:51:09","modified":"2025-04-28 21:51:09","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a48a9d6477a09dc9e31907b4b9ade6e3_8938d6a4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a48a9d6477a09dc9e31907b4b9ade6e3_8938d6a4-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a48a9d6477a09dc9e31907b4b9ade6e3_8938d6a4-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a48a9d6477a09dc9e31907b4b9ade6e3_8938d6a4-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a48a9d6477a09dc9e31907b4b9ade6e3_8938d6a4-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a48a9d6477a09dc9e31907b4b9ade6e3_8938d6a4.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a48a9d6477a09dc9e31907b4b9ade6e3_8938d6a4.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a48a9d6477a09dc9e31907b4b9ade6e3_8938d6a4.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a48a9d6477a09dc9e31907b4b9ade6e3_8938d6a4.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":185479,"id":185479,"title":"e9f525e3363a8e4ab8d115faa86d1f67_42d240ec.jpg","filename":"e9f525e3363a8e4ab8d115faa86d1f67_42d240ec.jpg","filesize":308254,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e9f525e3363a8e4ab8d115faa86d1f67_42d240ec.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/la-casa-di-milvia\/e9f525e3363a8e4ab8d115faa86d1f67_42d240ec-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e9f525e3363a8e4ab8d115faa86d1f67_42d240ec-jpg-2","status":"inherit","uploaded_to":173050,"date":"2025-04-28 21:51:11","modified":"2025-04-28 21:51:11","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":2000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e9f525e3363a8e4ab8d115faa86d1f67_42d240ec-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e9f525e3363a8e4ab8d115faa86d1f67_42d240ec-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e9f525e3363a8e4ab8d115faa86d1f67_42d240ec-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e9f525e3363a8e4ab8d115faa86d1f67_42d240ec-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e9f525e3363a8e4ab8d115faa86d1f67_42d240ec-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e9f525e3363a8e4ab8d115faa86d1f67_42d240ec.jpg","2048x2048-width":1500,"2048x2048-height":2000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e9f525e3363a8e4ab8d115faa86d1f67_42d240ec.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e9f525e3363a8e4ab8d115faa86d1f67_42d240ec.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e9f525e3363a8e4ab8d115faa86d1f67_42d240ec.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":185486,"id":185486,"title":"7c9d1b862616e2504c62c285527b8a79_1de5598c.jpg","filename":"7c9d1b862616e2504c62c285527b8a79_1de5598c.jpg","filesize":256685,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7c9d1b862616e2504c62c285527b8a79_1de5598c.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/la-casa-di-milvia\/7c9d1b862616e2504c62c285527b8a79_1de5598c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"7c9d1b862616e2504c62c285527b8a79_1de5598c-jpg-2","status":"inherit","uploaded_to":173050,"date":"2025-04-28 21:51:13","modified":"2025-04-28 21:51:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1478,"height":1126,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7c9d1b862616e2504c62c285527b8a79_1de5598c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7c9d1b862616e2504c62c285527b8a79_1de5598c-300x229.jpg","medium-width":300,"medium-height":229,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7c9d1b862616e2504c62c285527b8a79_1de5598c-768x585.jpg","medium_large-width":768,"medium_large-height":585,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7c9d1b862616e2504c62c285527b8a79_1de5598c-1024x780.jpg","large-width":1024,"large-height":780,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7c9d1b862616e2504c62c285527b8a79_1de5598c.jpg","1536x1536-width":1478,"1536x1536-height":1126,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7c9d1b862616e2504c62c285527b8a79_1de5598c.jpg","2048x2048-width":1478,"2048x2048-height":1126,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7c9d1b862616e2504c62c285527b8a79_1de5598c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":229,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7c9d1b862616e2504c62c285527b8a79_1de5598c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":305,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7c9d1b862616e2504c62c285527b8a79_1de5598c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":457}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/173050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/173050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media\/185423"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media?parent=173050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/categories?post=173050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/tags?post=173050"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/aggr?post=173050"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/area?post=173050"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/kind?post=173050"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/zona?post=173050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}