{"id":176228,"date":"2025-04-18T13:39:41","date_gmt":"2025-04-18T11:39:41","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/il-vicoletto\/"},"modified":"2025-04-18T14:24:54","modified_gmt":"2025-04-18T12:24:54","slug":"il-vicoletto","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/","title":{"rendered":"IL VICOLETTO"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":176229,"template":"","categories":[997],"tags":[],"aggr":[],"area":[],"kind":[18723],"zona":[],"class_list":["post-176228","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sleep","kind-strutturaricettiva-en"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"IL VICOLETTO","hero_text":"<p>Bright and spacious studio apartment in the heart of the city, full of restaurants, bars and shops.<\/p>\n","slides":[{"image":{"ID":176229,"id":176229,"title":"e94aba27d22e2a72f788b63dfe0921a1_2e599f41.jpg","filename":"e94aba27d22e2a72f788b63dfe0921a1_2e599f41.jpg","filesize":68600,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e94aba27d22e2a72f788b63dfe0921a1_2e599f41.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/e94aba27d22e2a72f788b63dfe0921a1_2e599f41-jpg\/","alt":"","author":"0","description":"","caption":"","name":"e94aba27d22e2a72f788b63dfe0921a1_2e599f41-jpg","status":"inherit","uploaded_to":176228,"date":"2025-04-18 09:39:13","modified":"2025-04-18 12:24:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e94aba27d22e2a72f788b63dfe0921a1_2e599f41-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e94aba27d22e2a72f788b63dfe0921a1_2e599f41-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e94aba27d22e2a72f788b63dfe0921a1_2e599f41.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e94aba27d22e2a72f788b63dfe0921a1_2e599f41.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e94aba27d22e2a72f788b63dfe0921a1_2e599f41.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e94aba27d22e2a72f788b63dfe0921a1_2e599f41.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e94aba27d22e2a72f788b63dfe0921a1_2e599f41.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e94aba27d22e2a72f788b63dfe0921a1_2e599f41.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e94aba27d22e2a72f788b63dfe0921a1_2e599f41.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176236,"id":176236,"title":"808562fd3d0bae4d826954ffbb5ffc58_77450b9a.jpg","filename":"808562fd3d0bae4d826954ffbb5ffc58_77450b9a.jpg","filesize":60167,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/808562fd3d0bae4d826954ffbb5ffc58_77450b9a.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/808562fd3d0bae4d826954ffbb5ffc58_77450b9a-jpg\/","alt":"","author":"0","description":"","caption":"","name":"808562fd3d0bae4d826954ffbb5ffc58_77450b9a-jpg","status":"inherit","uploaded_to":176228,"date":"2025-04-18 09:39:14","modified":"2025-04-18 12:24:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/808562fd3d0bae4d826954ffbb5ffc58_77450b9a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/808562fd3d0bae4d826954ffbb5ffc58_77450b9a-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/808562fd3d0bae4d826954ffbb5ffc58_77450b9a.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/808562fd3d0bae4d826954ffbb5ffc58_77450b9a.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/808562fd3d0bae4d826954ffbb5ffc58_77450b9a.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/808562fd3d0bae4d826954ffbb5ffc58_77450b9a.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/808562fd3d0bae4d826954ffbb5ffc58_77450b9a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/808562fd3d0bae4d826954ffbb5ffc58_77450b9a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/808562fd3d0bae4d826954ffbb5ffc58_77450b9a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176243,"id":176243,"title":"e8c268a12830124d5687aeaa23f6534f_0a8843dc.jpg","filename":"e8c268a12830124d5687aeaa23f6534f_0a8843dc.jpg","filesize":76089,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8c268a12830124d5687aeaa23f6534f_0a8843dc.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/e8c268a12830124d5687aeaa23f6534f_0a8843dc-jpg\/","alt":"","author":"0","description":"","caption":"","name":"e8c268a12830124d5687aeaa23f6534f_0a8843dc-jpg","status":"inherit","uploaded_to":176228,"date":"2025-04-18 09:39:15","modified":"2025-04-18 12:24:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8c268a12830124d5687aeaa23f6534f_0a8843dc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8c268a12830124d5687aeaa23f6534f_0a8843dc-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8c268a12830124d5687aeaa23f6534f_0a8843dc.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8c268a12830124d5687aeaa23f6534f_0a8843dc.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8c268a12830124d5687aeaa23f6534f_0a8843dc.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8c268a12830124d5687aeaa23f6534f_0a8843dc.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8c268a12830124d5687aeaa23f6534f_0a8843dc.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8c268a12830124d5687aeaa23f6534f_0a8843dc.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e8c268a12830124d5687aeaa23f6534f_0a8843dc.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176250,"id":176250,"title":"17c35e1ece7d6bb032fe65b246186524_8d97fc53.jpg","filename":"17c35e1ece7d6bb032fe65b246186524_8d97fc53.jpg","filesize":61936,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/17c35e1ece7d6bb032fe65b246186524_8d97fc53.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/17c35e1ece7d6bb032fe65b246186524_8d97fc53-jpg\/","alt":"","author":"0","description":"","caption":"","name":"17c35e1ece7d6bb032fe65b246186524_8d97fc53-jpg","status":"inherit","uploaded_to":176228,"date":"2025-04-18 09:39:16","modified":"2025-04-18 12:24:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/17c35e1ece7d6bb032fe65b246186524_8d97fc53-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/17c35e1ece7d6bb032fe65b246186524_8d97fc53-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/17c35e1ece7d6bb032fe65b246186524_8d97fc53.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/17c35e1ece7d6bb032fe65b246186524_8d97fc53.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/17c35e1ece7d6bb032fe65b246186524_8d97fc53.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/17c35e1ece7d6bb032fe65b246186524_8d97fc53.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/17c35e1ece7d6bb032fe65b246186524_8d97fc53.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/17c35e1ece7d6bb032fe65b246186524_8d97fc53.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/17c35e1ece7d6bb032fe65b246186524_8d97fc53.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176257,"id":176257,"title":"c5bea66ac21442e1f31610c609f72555_45978530.jpg","filename":"c5bea66ac21442e1f31610c609f72555_45978530.jpg","filesize":129449,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5bea66ac21442e1f31610c609f72555_45978530.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/c5bea66ac21442e1f31610c609f72555_45978530-jpg\/","alt":"","author":"0","description":"","caption":"","name":"c5bea66ac21442e1f31610c609f72555_45978530-jpg","status":"inherit","uploaded_to":176228,"date":"2025-04-18 09:39:17","modified":"2025-04-18 12:24:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5bea66ac21442e1f31610c609f72555_45978530-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5bea66ac21442e1f31610c609f72555_45978530-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5bea66ac21442e1f31610c609f72555_45978530.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5bea66ac21442e1f31610c609f72555_45978530.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5bea66ac21442e1f31610c609f72555_45978530.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5bea66ac21442e1f31610c609f72555_45978530.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5bea66ac21442e1f31610c609f72555_45978530.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5bea66ac21442e1f31610c609f72555_45978530.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5bea66ac21442e1f31610c609f72555_45978530.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176264,"id":176264,"title":"e2114deafe7f2004b41396d04019857b_72ee59d8.jpg","filename":"e2114deafe7f2004b41396d04019857b_72ee59d8.jpg","filesize":34026,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2114deafe7f2004b41396d04019857b_72ee59d8.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/e2114deafe7f2004b41396d04019857b_72ee59d8-jpg\/","alt":"","author":"0","description":"","caption":"","name":"e2114deafe7f2004b41396d04019857b_72ee59d8-jpg","status":"inherit","uploaded_to":176228,"date":"2025-04-18 09:39:18","modified":"2025-04-18 12:24:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":337,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2114deafe7f2004b41396d04019857b_72ee59d8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2114deafe7f2004b41396d04019857b_72ee59d8-211x300.jpg","medium-width":211,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2114deafe7f2004b41396d04019857b_72ee59d8.jpg","medium_large-width":337,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2114deafe7f2004b41396d04019857b_72ee59d8.jpg","large-width":337,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2114deafe7f2004b41396d04019857b_72ee59d8.jpg","1536x1536-width":337,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2114deafe7f2004b41396d04019857b_72ee59d8.jpg","2048x2048-width":337,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2114deafe7f2004b41396d04019857b_72ee59d8.jpg","gform-image-choice-sm-width":211,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2114deafe7f2004b41396d04019857b_72ee59d8.jpg","gform-image-choice-md-width":281,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e2114deafe7f2004b41396d04019857b_72ee59d8.jpg","gform-image-choice-lg-width":337,"gform-image-choice-lg-height":480}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176271,"id":176271,"title":"42e78ef869f4710576f8435bd1f48e71_69d981a6.jpg","filename":"42e78ef869f4710576f8435bd1f48e71_69d981a6.jpg","filesize":58372,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42e78ef869f4710576f8435bd1f48e71_69d981a6.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/42e78ef869f4710576f8435bd1f48e71_69d981a6-jpg\/","alt":"","author":"0","description":"","caption":"","name":"42e78ef869f4710576f8435bd1f48e71_69d981a6-jpg","status":"inherit","uploaded_to":176228,"date":"2025-04-18 09:39:19","modified":"2025-04-18 12:24:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42e78ef869f4710576f8435bd1f48e71_69d981a6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42e78ef869f4710576f8435bd1f48e71_69d981a6-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42e78ef869f4710576f8435bd1f48e71_69d981a6.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42e78ef869f4710576f8435bd1f48e71_69d981a6.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42e78ef869f4710576f8435bd1f48e71_69d981a6.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42e78ef869f4710576f8435bd1f48e71_69d981a6.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42e78ef869f4710576f8435bd1f48e71_69d981a6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42e78ef869f4710576f8435bd1f48e71_69d981a6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42e78ef869f4710576f8435bd1f48e71_69d981a6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176278,"id":176278,"title":"5d180985f86250f16c376895c3e443c1_939ad811.jpg","filename":"5d180985f86250f16c376895c3e443c1_939ad811.jpg","filesize":54277,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d180985f86250f16c376895c3e443c1_939ad811.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/5d180985f86250f16c376895c3e443c1_939ad811-jpg\/","alt":"","author":"0","description":"","caption":"","name":"5d180985f86250f16c376895c3e443c1_939ad811-jpg","status":"inherit","uploaded_to":176228,"date":"2025-04-18 09:39:20","modified":"2025-04-18 12:24:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d180985f86250f16c376895c3e443c1_939ad811-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d180985f86250f16c376895c3e443c1_939ad811-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d180985f86250f16c376895c3e443c1_939ad811.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d180985f86250f16c376895c3e443c1_939ad811.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d180985f86250f16c376895c3e443c1_939ad811.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d180985f86250f16c376895c3e443c1_939ad811.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d180985f86250f16c376895c3e443c1_939ad811.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d180985f86250f16c376895c3e443c1_939ad811.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5d180985f86250f16c376895c3e443c1_939ad811.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176285,"id":176285,"title":"b54150c1c1ddb05560cae90760d38772_10fdd8e1.jpg","filename":"b54150c1c1ddb05560cae90760d38772_10fdd8e1.jpg","filesize":73590,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b54150c1c1ddb05560cae90760d38772_10fdd8e1.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/b54150c1c1ddb05560cae90760d38772_10fdd8e1-jpg\/","alt":"","author":"0","description":"","caption":"","name":"b54150c1c1ddb05560cae90760d38772_10fdd8e1-jpg","status":"inherit","uploaded_to":176228,"date":"2025-04-18 09:39:21","modified":"2025-04-18 12:24:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b54150c1c1ddb05560cae90760d38772_10fdd8e1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b54150c1c1ddb05560cae90760d38772_10fdd8e1-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b54150c1c1ddb05560cae90760d38772_10fdd8e1.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b54150c1c1ddb05560cae90760d38772_10fdd8e1.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b54150c1c1ddb05560cae90760d38772_10fdd8e1.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b54150c1c1ddb05560cae90760d38772_10fdd8e1.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b54150c1c1ddb05560cae90760d38772_10fdd8e1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b54150c1c1ddb05560cae90760d38772_10fdd8e1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b54150c1c1ddb05560cae90760d38772_10fdd8e1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176292,"id":176292,"title":"dccf522e68e46b72e0942980ec56125c_c27536e4.jpg","filename":"dccf522e68e46b72e0942980ec56125c_c27536e4.jpg","filesize":56784,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dccf522e68e46b72e0942980ec56125c_c27536e4.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/dccf522e68e46b72e0942980ec56125c_c27536e4-jpg\/","alt":"","author":"0","description":"","caption":"","name":"dccf522e68e46b72e0942980ec56125c_c27536e4-jpg","status":"inherit","uploaded_to":176228,"date":"2025-04-18 09:39:22","modified":"2025-04-18 12:24:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dccf522e68e46b72e0942980ec56125c_c27536e4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dccf522e68e46b72e0942980ec56125c_c27536e4-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dccf522e68e46b72e0942980ec56125c_c27536e4.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dccf522e68e46b72e0942980ec56125c_c27536e4.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dccf522e68e46b72e0942980ec56125c_c27536e4.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dccf522e68e46b72e0942980ec56125c_c27536e4.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dccf522e68e46b72e0942980ec56125c_c27536e4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dccf522e68e46b72e0942980ec56125c_c27536e4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dccf522e68e46b72e0942980ec56125c_c27536e4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176299,"id":176299,"title":"a608aba8c4cf7c11b069cd7dd0a36a67_27d9b230.jpg","filename":"a608aba8c4cf7c11b069cd7dd0a36a67_27d9b230.jpg","filesize":77078,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a608aba8c4cf7c11b069cd7dd0a36a67_27d9b230.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/a608aba8c4cf7c11b069cd7dd0a36a67_27d9b230-jpg\/","alt":"","author":"0","description":"","caption":"","name":"a608aba8c4cf7c11b069cd7dd0a36a67_27d9b230-jpg","status":"inherit","uploaded_to":176228,"date":"2025-04-18 09:39:23","modified":"2025-04-18 12:24:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a608aba8c4cf7c11b069cd7dd0a36a67_27d9b230-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a608aba8c4cf7c11b069cd7dd0a36a67_27d9b230-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a608aba8c4cf7c11b069cd7dd0a36a67_27d9b230.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a608aba8c4cf7c11b069cd7dd0a36a67_27d9b230.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a608aba8c4cf7c11b069cd7dd0a36a67_27d9b230.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a608aba8c4cf7c11b069cd7dd0a36a67_27d9b230.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a608aba8c4cf7c11b069cd7dd0a36a67_27d9b230.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a608aba8c4cf7c11b069cd7dd0a36a67_27d9b230.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a608aba8c4cf7c11b069cd7dd0a36a67_27d9b230.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176306,"id":176306,"title":"9fc598ad00dd38657ecabae5ac432ce7_71cc3ea0.jpg","filename":"9fc598ad00dd38657ecabae5ac432ce7_71cc3ea0.jpg","filesize":75750,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9fc598ad00dd38657ecabae5ac432ce7_71cc3ea0.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/9fc598ad00dd38657ecabae5ac432ce7_71cc3ea0-jpg\/","alt":"","author":"0","description":"","caption":"","name":"9fc598ad00dd38657ecabae5ac432ce7_71cc3ea0-jpg","status":"inherit","uploaded_to":176228,"date":"2025-04-18 09:39:24","modified":"2025-04-18 12:24:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9fc598ad00dd38657ecabae5ac432ce7_71cc3ea0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9fc598ad00dd38657ecabae5ac432ce7_71cc3ea0-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9fc598ad00dd38657ecabae5ac432ce7_71cc3ea0.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9fc598ad00dd38657ecabae5ac432ce7_71cc3ea0.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9fc598ad00dd38657ecabae5ac432ce7_71cc3ea0.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9fc598ad00dd38657ecabae5ac432ce7_71cc3ea0.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9fc598ad00dd38657ecabae5ac432ce7_71cc3ea0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9fc598ad00dd38657ecabae5ac432ce7_71cc3ea0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9fc598ad00dd38657ecabae5ac432ce7_71cc3ea0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176313,"id":176313,"title":"9affd952ce6f0b0b1c880801af4ee76e_03a760a3.jpg","filename":"9affd952ce6f0b0b1c880801af4ee76e_03a760a3.jpg","filesize":77344,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9affd952ce6f0b0b1c880801af4ee76e_03a760a3.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/9affd952ce6f0b0b1c880801af4ee76e_03a760a3-jpg\/","alt":"","author":"0","description":"","caption":"","name":"9affd952ce6f0b0b1c880801af4ee76e_03a760a3-jpg","status":"inherit","uploaded_to":176228,"date":"2025-04-18 09:39:25","modified":"2025-04-18 12:24:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9affd952ce6f0b0b1c880801af4ee76e_03a760a3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9affd952ce6f0b0b1c880801af4ee76e_03a760a3-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9affd952ce6f0b0b1c880801af4ee76e_03a760a3.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9affd952ce6f0b0b1c880801af4ee76e_03a760a3.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9affd952ce6f0b0b1c880801af4ee76e_03a760a3.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9affd952ce6f0b0b1c880801af4ee76e_03a760a3.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9affd952ce6f0b0b1c880801af4ee76e_03a760a3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9affd952ce6f0b0b1c880801af4ee76e_03a760a3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9affd952ce6f0b0b1c880801af4ee76e_03a760a3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176320,"id":176320,"title":"078fa068817d0cdc0470c1353a2b6cd0_b902edc6.jpg","filename":"078fa068817d0cdc0470c1353a2b6cd0_b902edc6.jpg","filesize":52254,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/078fa068817d0cdc0470c1353a2b6cd0_b902edc6.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/il-vicoletto\/078fa068817d0cdc0470c1353a2b6cd0_b902edc6-jpg\/","alt":"","author":"0","description":"","caption":"","name":"078fa068817d0cdc0470c1353a2b6cd0_b902edc6-jpg","status":"inherit","uploaded_to":176228,"date":"2025-04-18 09:39:26","modified":"2025-04-18 12:24:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":720,"height":480,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/078fa068817d0cdc0470c1353a2b6cd0_b902edc6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/078fa068817d0cdc0470c1353a2b6cd0_b902edc6-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/078fa068817d0cdc0470c1353a2b6cd0_b902edc6.jpg","medium_large-width":720,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/078fa068817d0cdc0470c1353a2b6cd0_b902edc6.jpg","large-width":720,"large-height":480,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/078fa068817d0cdc0470c1353a2b6cd0_b902edc6.jpg","1536x1536-width":720,"1536x1536-height":480,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/078fa068817d0cdc0470c1353a2b6cd0_b902edc6.jpg","2048x2048-width":720,"2048x2048-height":480,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/078fa068817d0cdc0470c1353a2b6cd0_b902edc6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/078fa068817d0cdc0470c1353a2b6cd0_b902edc6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/078fa068817d0cdc0470c1353a2b6cd0_b902edc6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>On the third floor of a renovated historic building with a lift.&#13;<br \/>\nLarge living area with a queen size bed, equipped kitchen, bathroom with double shower and washing machine.&#13;<br \/>\nBed linen, sponges, WIFI and breakfast included.&#13;<br \/>\nI added a sofa bed for younger guests and teenagers up to 16 years old.&#13;<br \/>\nIl Vicoletto is a Hospitality partner of the Accademia Carrara, City Museum &#8211; lacarrara.it -&#13;<br \/>\nDiscounted price for guests: vouchers inside the property.<\/p>\n","indepth":"<p>Welcome!&#13;<br \/>\nI have a passion for furniture and with this new work endeavour I want my guests to feel at ease, in a welcoming, comfortable and familiar space, just like at home! I played around with some matching accessories &#8211; placemats for breakfast, cushions, plaids, bedspreads and towels &#8211; which make the atmosphere a little bit more special and harmonious.&#13;<br \/>\nFor years, I have enjoyed collecting ceramics, fabric, painted objects and dishes. I wanted to share my hobby with my guests, inserting a touch of my personality here and there.&#13;<br \/>\nThis is what makes my Vicoletto unique.<\/p>\n","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"<p>Il Vicoletto is located in a really convenient position also for heading out of town.&#13;<br \/>\nIt is 1km from the A4 Turin \/ Venice highway; Bergamo is in the centre between Milan &#8211; 55km &#8211; and Brescia &#8211; 52km.&#13;<br \/>\nIl Vicoletto is only 5.9km from Orio al Serio Airport, easily reachable by bus or taxi.&#13;<br \/>\nFor more information on the location of Il Vicoletto you can contact the property.&#13;<br \/>\nIl Vicoletto is located in a limited traffic zone.&#13;<br \/>\nI love to respect the privacy of my guests, but whenever they need it, I am available for any information that can help make their stay in my city more pleasant.&#13;<br \/>\nThere is a &#8216;guest book&#8217; where you can leave a comment or a greeting at the end of your stay. It would be highly appreciated and useful for me.&#13;<br \/>\nAs soon as you enter the apartment, on the right, above the console there is a booklet containing the house rules, such as the separate waste collection and other information that may be useful.&#13;<br \/>\nI have provided maps and information brochures at the apartment so you can visit Bergamo and its surroundings.&#13;<br \/>\nIl Vicoletto is now also a Hospitality Partner of the Accademia Carrara, the City Museum &#8211; lacarrara.it &#8211; this means that the customers who stay there are entitled to access the museum at a discounted price.&#13;<br \/>\nYou will find vouchers at the property.&#13;<br \/>\nAnyone wishing to relax with a good book can choose from some books and novels, in Italian and English that I have made available.&#13;<br \/>\nFinally, just above the bookshelf, there are some business cards of restaurants in the city. By presenting them you can take advantage of a small discount when paying the bill.<\/p>\n","parking":"<p>There are a number of paid parking spaces with blue lines. The fee is \u20ac2.00 \/ hour from 9.00am to 7.00pm and free from 7.00pm to 9.00am.&#13;<br \/>\nAlternatively, there is a car park, open 24 hours, a few minutes on foot: &#8216;Il Triangolo Parking&#8217;&#13;<br \/>\nThere is also the bus stop and a bicycle rental service nearby.&#13;<br \/>\nWalking remains the best and recommended way to discover and appreciate the hidden corners of this wonderful city.<\/p>\n","restaurant":"<p>The property is located in the city centre, full of restaurants and bars that can be easily reached on foot.<\/p>\n","breakfast":"<p>The property offers a welcome breakfast with coffee, tea, herbal tea, fruit juice, jam, nutella, rusks and snacks.<\/p>\n","internet":"<p>The property is equipped with WIFI, the access password will be provided by the property<\/p>\n","children":"<p>I added a sofa bed for younger guests and teenagers up to 16 years old.<\/p>\n","pets":"<p>Small pets are welcome<\/p>\n","latitude":"45.692480","longitude":"9.663134","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"Nicoletta Ferrara","registered_office":"","iu_addr_streetnumber":"Via S. Lazzaro, 1","iu_addr_postalcode":"24122","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"","iu_cell":"+39 334 7315955","iu_website":"","iu_email":"ferrara.nicoletta@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"1","iu_beds":"3","id_madeep":"","id_visit_manza":"5362","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"time":"<p>Il check-in \u00e8 presvisto per le ore 16:00 e il check-out \u00e8 previsto per le ore 11:00.&#13;<br \/>\nEventuali anticipazioni e dilazioni sono da concordare preventivamente con il gestore della struttura.<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"elevator","label":"Ascensore"},{"value":"laundry","label":"Lavanderia"},{"value":"wifi","label":"Wi-Fi"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"mini_bar","label":"Frigo bar"},{"value":"tv_room","label":"TV in camera"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"},{"value":"amex","label":"American Express"},{"value":"diners","label":"Diners Club"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/176228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/176228\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media\/176229"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media?parent=176228"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/categories?post=176228"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/tags?post=176228"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/aggr?post=176228"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/area?post=176228"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/kind?post=176228"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/zona?post=176228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}