{"id":176827,"date":"2025-04-18T13:40:17","date_gmt":"2025-04-18T11:40:17","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/bb-hotel-bergamo\/"},"modified":"2025-04-18T14:26:02","modified_gmt":"2025-04-18T12:26:02","slug":"bb-hotel-bergamo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-hotel-bergamo\/","title":{"rendered":"B&#038;B Hotel Bergamo"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":176828,"template":"","categories":[997],"tags":[],"aggr":[],"area":[],"kind":[18723],"zona":[],"class_list":["post-176827","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sleep","kind-strutturaricettiva-en"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"B&B Hotel Bergamo","hero_text":"<p>The B&#038;B Hotel is in an ideal position thanks to the fact that it is near the strategic points of the city: \u00a0railway station, highway and airport.<\/p>\n","slides":[{"image":{"ID":176828,"id":176828,"title":"fd5423449a554a0757456fe4b1f74fb6_af9eb779.jpg","filename":"fd5423449a554a0757456fe4b1f74fb6_af9eb779.jpg","filesize":292708,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fd5423449a554a0757456fe4b1f74fb6_af9eb779.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-hotel-bergamo\/fd5423449a554a0757456fe4b1f74fb6_af9eb779-jpg\/","alt":"","author":"0","description":"","caption":"","name":"fd5423449a554a0757456fe4b1f74fb6_af9eb779-jpg","status":"inherit","uploaded_to":176827,"date":"2025-04-18 09:41:27","modified":"2025-04-18 12:26:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fd5423449a554a0757456fe4b1f74fb6_af9eb779-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fd5423449a554a0757456fe4b1f74fb6_af9eb779-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fd5423449a554a0757456fe4b1f74fb6_af9eb779-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fd5423449a554a0757456fe4b1f74fb6_af9eb779-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fd5423449a554a0757456fe4b1f74fb6_af9eb779-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fd5423449a554a0757456fe4b1f74fb6_af9eb779.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fd5423449a554a0757456fe4b1f74fb6_af9eb779.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fd5423449a554a0757456fe4b1f74fb6_af9eb779.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fd5423449a554a0757456fe4b1f74fb6_af9eb779.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176835,"id":176835,"title":"5ade41e6aff6244dff82efea5984afeb_6fbe3279.jpg","filename":"5ade41e6aff6244dff82efea5984afeb_6fbe3279.jpg","filesize":376443,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ade41e6aff6244dff82efea5984afeb_6fbe3279.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-hotel-bergamo\/5ade41e6aff6244dff82efea5984afeb_6fbe3279-jpg\/","alt":"","author":"0","description":"","caption":"","name":"5ade41e6aff6244dff82efea5984afeb_6fbe3279-jpg","status":"inherit","uploaded_to":176827,"date":"2025-04-18 09:41:28","modified":"2025-04-18 12:26:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ade41e6aff6244dff82efea5984afeb_6fbe3279-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ade41e6aff6244dff82efea5984afeb_6fbe3279-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ade41e6aff6244dff82efea5984afeb_6fbe3279-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ade41e6aff6244dff82efea5984afeb_6fbe3279-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ade41e6aff6244dff82efea5984afeb_6fbe3279-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ade41e6aff6244dff82efea5984afeb_6fbe3279.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ade41e6aff6244dff82efea5984afeb_6fbe3279.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ade41e6aff6244dff82efea5984afeb_6fbe3279.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5ade41e6aff6244dff82efea5984afeb_6fbe3279.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176842,"id":176842,"title":"7710e2b24ca3f861a8fecefc1f426340_ac2cce8a.jpg","filename":"7710e2b24ca3f861a8fecefc1f426340_ac2cce8a.jpg","filesize":168242,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7710e2b24ca3f861a8fecefc1f426340_ac2cce8a.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-hotel-bergamo\/7710e2b24ca3f861a8fecefc1f426340_ac2cce8a-jpg\/","alt":"","author":"0","description":"","caption":"","name":"7710e2b24ca3f861a8fecefc1f426340_ac2cce8a-jpg","status":"inherit","uploaded_to":176827,"date":"2025-04-18 09:41:29","modified":"2025-04-18 12:26:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7710e2b24ca3f861a8fecefc1f426340_ac2cce8a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7710e2b24ca3f861a8fecefc1f426340_ac2cce8a-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7710e2b24ca3f861a8fecefc1f426340_ac2cce8a-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7710e2b24ca3f861a8fecefc1f426340_ac2cce8a-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7710e2b24ca3f861a8fecefc1f426340_ac2cce8a-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7710e2b24ca3f861a8fecefc1f426340_ac2cce8a.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7710e2b24ca3f861a8fecefc1f426340_ac2cce8a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7710e2b24ca3f861a8fecefc1f426340_ac2cce8a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/7710e2b24ca3f861a8fecefc1f426340_ac2cce8a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176849,"id":176849,"title":"6fc201072c6f064ffc7a821cefd9c64e_b7af76e2.jpg","filename":"6fc201072c6f064ffc7a821cefd9c64e_b7af76e2.jpg","filesize":298659,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fc201072c6f064ffc7a821cefd9c64e_b7af76e2.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-hotel-bergamo\/6fc201072c6f064ffc7a821cefd9c64e_b7af76e2-jpg\/","alt":"","author":"0","description":"","caption":"","name":"6fc201072c6f064ffc7a821cefd9c64e_b7af76e2-jpg","status":"inherit","uploaded_to":176827,"date":"2025-04-18 09:41:30","modified":"2025-04-18 12:26:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fc201072c6f064ffc7a821cefd9c64e_b7af76e2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fc201072c6f064ffc7a821cefd9c64e_b7af76e2-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fc201072c6f064ffc7a821cefd9c64e_b7af76e2-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fc201072c6f064ffc7a821cefd9c64e_b7af76e2-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fc201072c6f064ffc7a821cefd9c64e_b7af76e2-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fc201072c6f064ffc7a821cefd9c64e_b7af76e2.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fc201072c6f064ffc7a821cefd9c64e_b7af76e2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fc201072c6f064ffc7a821cefd9c64e_b7af76e2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6fc201072c6f064ffc7a821cefd9c64e_b7af76e2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":176856,"id":176856,"title":"4845763bd9677a5403513aa8acf87ca7_43286156.jpg","filename":"4845763bd9677a5403513aa8acf87ca7_43286156.jpg","filesize":261822,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4845763bd9677a5403513aa8acf87ca7_43286156.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/bb-hotel-bergamo\/4845763bd9677a5403513aa8acf87ca7_43286156-jpg\/","alt":"","author":"0","description":"","caption":"","name":"4845763bd9677a5403513aa8acf87ca7_43286156-jpg","status":"inherit","uploaded_to":176827,"date":"2025-04-18 09:41:31","modified":"2025-04-18 12:26:04","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4845763bd9677a5403513aa8acf87ca7_43286156-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4845763bd9677a5403513aa8acf87ca7_43286156-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4845763bd9677a5403513aa8acf87ca7_43286156-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4845763bd9677a5403513aa8acf87ca7_43286156-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4845763bd9677a5403513aa8acf87ca7_43286156-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4845763bd9677a5403513aa8acf87ca7_43286156.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4845763bd9677a5403513aa8acf87ca7_43286156.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4845763bd9677a5403513aa8acf87ca7_43286156.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4845763bd9677a5403513aa8acf87ca7_43286156.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>Near the center of Bergamo Bassa, the B&#038;B Hotel Bergamo is the ideal solution for visiting the city or if you\u2019re on business in the area around Bergamo and Milan, thanks to its nearness to the railway station. Since it is near the A4 Highway, it is perfect also for those headed to the Bergamo Orio al Serio Airport. The B&#038;B Hotel Bergamo offers superfast Wi in all rooms, a rich buffet breakfast and convenient parking. The hotel also features MIA \u2013 the personal automatic receptionist \u2013 allowing guests to check-in by themselves, even at night.<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","services":"<p>SERVIZIO SHUTTLE: for reservations with external companies www.citymoving.it or contact the staff at: bergamo@hotelbb.com<\/p>\n","parking":"<p>The B&#038;B Hotel Bergamo features a large covered parking lot \u2013 with limited parking spaces \u2013 and an open area nearby.  Numerous public parking areas are also present in the area.<\/p>\n","restaurant":"","breakfast":"<p>Reserve your buffet breakfast on-line for only 7,20\u20ac (3,80\u20ac for children under 10 years of age). Breakfast includes a vast assortment of savory and sweet, including croissants and home-made bread, cakes, muffins, cereal, yogurt, spreadable cheese, scrambled eggs and hot dogs, all of the best brands (Nutella, Kellogg&#8217;s, Lavazza, etc.). &#13;<br \/>\nOur buffet is available from 7:00 am to 10:00 am!<\/p>\n","internet":"<p>Internet WIFI 100 Mega superfast is free in all rooms.<\/p>\n","children":"<p>Contact the hotel for additional beds.<\/p>\n","pets":"<p>The B&#038;B Hotel Bergamo accepts pets.  With a supplement of 5,00\u20ac  per night per animal, you are welcome along with your four-legged friends.<\/p>\n","latitude":"45.686925","longitude":"9.667427","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"JEAN CLAUDE GHIOTTI","registered_office":"VIA DOMENICHINO 19 20149 MILANO","iu_addr_streetnumber":"Via Autostrada, 2","iu_addr_postalcode":"24126","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 035330171","iu_cell":"","iu_website":"http:\/\/www.hotel-bb.com","iu_email":"bergamo@hotelbb.com","iu_vat":"06291950969","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"3","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"6649","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"filotto_layout":"","filotto_fill":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","only_ambassadors":false,"service_icons":[],"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/176827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/176827\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media\/176828"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media?parent=176827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/categories?post=176827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/tags?post=176827"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/aggr?post=176827"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/area?post=176827"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/kind?post=176827"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/zona?post=176827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}