{"id":181896,"date":"2025-04-18T13:33:36","date_gmt":"2025-04-18T11:33:36","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/rezydencja-borgo\/"},"modified":"2025-04-18T13:33:36","modified_gmt":"2025-04-18T11:33:36","slug":"rezydencja-borgo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/rezydencja-borgo\/","title":{"rendered":"Rezydencja Borgo"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":171088,"template":"","categories":[991],"tags":[],"aggr":[],"area":[],"kind":[987],"zona":[],"class_list":["post-181896","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-dormire","kind-strutturaricettiva"],"acf":{"slides":[{"image":{"ID":171084,"id":171084,"title":"65855d06cb8aa69ea00ab2a8b26115d0_0f25a3a6.jpg","filename":"65855d06cb8aa69ea00ab2a8b26115d0_0f25a3a6.jpg","filesize":631393,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65855d06cb8aa69ea00ab2a8b26115d0_0f25a3a6.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/65855d06cb8aa69ea00ab2a8b26115d0_0f25a3a6-jpg\/","alt":"","author":"0","description":"","caption":"","name":"65855d06cb8aa69ea00ab2a8b26115d0_0f25a3a6-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:14:54","modified":"2025-04-18 12:16:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65855d06cb8aa69ea00ab2a8b26115d0_0f25a3a6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65855d06cb8aa69ea00ab2a8b26115d0_0f25a3a6-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65855d06cb8aa69ea00ab2a8b26115d0_0f25a3a6-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65855d06cb8aa69ea00ab2a8b26115d0_0f25a3a6-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65855d06cb8aa69ea00ab2a8b26115d0_0f25a3a6-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65855d06cb8aa69ea00ab2a8b26115d0_0f25a3a6.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65855d06cb8aa69ea00ab2a8b26115d0_0f25a3a6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65855d06cb8aa69ea00ab2a8b26115d0_0f25a3a6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65855d06cb8aa69ea00ab2a8b26115d0_0f25a3a6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171091,"id":171091,"title":"cc858e0551059b67cd04e62389d0b966_3bc10d52.jpg","filename":"cc858e0551059b67cd04e62389d0b966_3bc10d52.jpg","filesize":357675,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cc858e0551059b67cd04e62389d0b966_3bc10d52.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/cc858e0551059b67cd04e62389d0b966_3bc10d52-jpg\/","alt":"","author":"0","description":"","caption":"","name":"cc858e0551059b67cd04e62389d0b966_3bc10d52-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:14:55","modified":"2025-04-18 12:16:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cc858e0551059b67cd04e62389d0b966_3bc10d52-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cc858e0551059b67cd04e62389d0b966_3bc10d52-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cc858e0551059b67cd04e62389d0b966_3bc10d52-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cc858e0551059b67cd04e62389d0b966_3bc10d52-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cc858e0551059b67cd04e62389d0b966_3bc10d52-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cc858e0551059b67cd04e62389d0b966_3bc10d52.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cc858e0551059b67cd04e62389d0b966_3bc10d52.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cc858e0551059b67cd04e62389d0b966_3bc10d52.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cc858e0551059b67cd04e62389d0b966_3bc10d52.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171098,"id":171098,"title":"928b29715733c529a5aad8ab8f682e49_d9f8d06d.jpg","filename":"928b29715733c529a5aad8ab8f682e49_d9f8d06d.jpg","filesize":450335,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/928b29715733c529a5aad8ab8f682e49_d9f8d06d.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/928b29715733c529a5aad8ab8f682e49_d9f8d06d-jpg\/","alt":"","author":"0","description":"","caption":"","name":"928b29715733c529a5aad8ab8f682e49_d9f8d06d-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:14:56","modified":"2025-04-18 12:16:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/928b29715733c529a5aad8ab8f682e49_d9f8d06d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/928b29715733c529a5aad8ab8f682e49_d9f8d06d-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/928b29715733c529a5aad8ab8f682e49_d9f8d06d-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/928b29715733c529a5aad8ab8f682e49_d9f8d06d-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/928b29715733c529a5aad8ab8f682e49_d9f8d06d-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/928b29715733c529a5aad8ab8f682e49_d9f8d06d.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/928b29715733c529a5aad8ab8f682e49_d9f8d06d.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/928b29715733c529a5aad8ab8f682e49_d9f8d06d.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/928b29715733c529a5aad8ab8f682e49_d9f8d06d.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171105,"id":171105,"title":"e0b01987097fb367c4e95e82d03d3595_6478888e.jpg","filename":"e0b01987097fb367c4e95e82d03d3595_6478888e.jpg","filesize":566877,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0b01987097fb367c4e95e82d03d3595_6478888e.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/e0b01987097fb367c4e95e82d03d3595_6478888e-jpg\/","alt":"","author":"0","description":"","caption":"","name":"e0b01987097fb367c4e95e82d03d3595_6478888e-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:14:58","modified":"2025-04-18 12:16:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1247,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0b01987097fb367c4e95e82d03d3595_6478888e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0b01987097fb367c4e95e82d03d3595_6478888e-300x234.jpg","medium-width":300,"medium-height":234,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0b01987097fb367c4e95e82d03d3595_6478888e-768x599.jpg","medium_large-width":768,"medium_large-height":599,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0b01987097fb367c4e95e82d03d3595_6478888e-1024x798.jpg","large-width":1024,"large-height":798,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0b01987097fb367c4e95e82d03d3595_6478888e-1536x1197.jpg","1536x1536-width":1536,"1536x1536-height":1197,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0b01987097fb367c4e95e82d03d3595_6478888e.jpg","2048x2048-width":1600,"2048x2048-height":1247,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0b01987097fb367c4e95e82d03d3595_6478888e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":234,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0b01987097fb367c4e95e82d03d3595_6478888e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":312,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e0b01987097fb367c4e95e82d03d3595_6478888e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":468}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171112,"id":171112,"title":"1a5a2da02373a0f6726ce0071de4d598_59d986f2.jpg","filename":"1a5a2da02373a0f6726ce0071de4d598_59d986f2.jpg","filesize":440083,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a5a2da02373a0f6726ce0071de4d598_59d986f2.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/1a5a2da02373a0f6726ce0071de4d598_59d986f2-jpg\/","alt":"","author":"0","description":"","caption":"","name":"1a5a2da02373a0f6726ce0071de4d598_59d986f2-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:14:59","modified":"2025-04-18 12:16:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a5a2da02373a0f6726ce0071de4d598_59d986f2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a5a2da02373a0f6726ce0071de4d598_59d986f2-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a5a2da02373a0f6726ce0071de4d598_59d986f2-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a5a2da02373a0f6726ce0071de4d598_59d986f2-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a5a2da02373a0f6726ce0071de4d598_59d986f2-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a5a2da02373a0f6726ce0071de4d598_59d986f2.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a5a2da02373a0f6726ce0071de4d598_59d986f2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a5a2da02373a0f6726ce0071de4d598_59d986f2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1a5a2da02373a0f6726ce0071de4d598_59d986f2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171119,"id":171119,"title":"8c79c3231f831180787f7ea35ae2c5af_2b7d63a6.jpg","filename":"8c79c3231f831180787f7ea35ae2c5af_2b7d63a6.jpg","filesize":497541,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c79c3231f831180787f7ea35ae2c5af_2b7d63a6.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/8c79c3231f831180787f7ea35ae2c5af_2b7d63a6-jpg\/","alt":"","author":"0","description":"","caption":"","name":"8c79c3231f831180787f7ea35ae2c5af_2b7d63a6-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:15:00","modified":"2025-04-18 12:16:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1275,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c79c3231f831180787f7ea35ae2c5af_2b7d63a6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c79c3231f831180787f7ea35ae2c5af_2b7d63a6-300x239.jpg","medium-width":300,"medium-height":239,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c79c3231f831180787f7ea35ae2c5af_2b7d63a6-768x612.jpg","medium_large-width":768,"medium_large-height":612,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c79c3231f831180787f7ea35ae2c5af_2b7d63a6-1024x816.jpg","large-width":1024,"large-height":816,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c79c3231f831180787f7ea35ae2c5af_2b7d63a6-1536x1224.jpg","1536x1536-width":1536,"1536x1536-height":1224,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c79c3231f831180787f7ea35ae2c5af_2b7d63a6.jpg","2048x2048-width":1600,"2048x2048-height":1275,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c79c3231f831180787f7ea35ae2c5af_2b7d63a6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":239,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c79c3231f831180787f7ea35ae2c5af_2b7d63a6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":319,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c79c3231f831180787f7ea35ae2c5af_2b7d63a6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":478}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171126,"id":171126,"title":"b3c67548dedf0a2f73ecfec3b96ef6be_73ec195f.jpg","filename":"b3c67548dedf0a2f73ecfec3b96ef6be_73ec195f.jpg","filesize":538167,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3c67548dedf0a2f73ecfec3b96ef6be_73ec195f.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/b3c67548dedf0a2f73ecfec3b96ef6be_73ec195f-jpg\/","alt":"","author":"0","description":"","caption":"","name":"b3c67548dedf0a2f73ecfec3b96ef6be_73ec195f-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:15:01","modified":"2025-04-18 12:16:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3c67548dedf0a2f73ecfec3b96ef6be_73ec195f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3c67548dedf0a2f73ecfec3b96ef6be_73ec195f-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3c67548dedf0a2f73ecfec3b96ef6be_73ec195f-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3c67548dedf0a2f73ecfec3b96ef6be_73ec195f-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3c67548dedf0a2f73ecfec3b96ef6be_73ec195f-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3c67548dedf0a2f73ecfec3b96ef6be_73ec195f.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3c67548dedf0a2f73ecfec3b96ef6be_73ec195f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3c67548dedf0a2f73ecfec3b96ef6be_73ec195f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b3c67548dedf0a2f73ecfec3b96ef6be_73ec195f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171133,"id":171133,"title":"a1084ddcc29e7f8992cada1d1a66e89c_f3f6c60b.jpg","filename":"a1084ddcc29e7f8992cada1d1a66e89c_f3f6c60b.jpg","filesize":423458,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1084ddcc29e7f8992cada1d1a66e89c_f3f6c60b.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/a1084ddcc29e7f8992cada1d1a66e89c_f3f6c60b-jpg\/","alt":"","author":"0","description":"","caption":"","name":"a1084ddcc29e7f8992cada1d1a66e89c_f3f6c60b-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:15:03","modified":"2025-04-18 12:16:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1148,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1084ddcc29e7f8992cada1d1a66e89c_f3f6c60b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1084ddcc29e7f8992cada1d1a66e89c_f3f6c60b-215x300.jpg","medium-width":215,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1084ddcc29e7f8992cada1d1a66e89c_f3f6c60b-768x1070.jpg","medium_large-width":768,"medium_large-height":1070,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1084ddcc29e7f8992cada1d1a66e89c_f3f6c60b-735x1024.jpg","large-width":735,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1084ddcc29e7f8992cada1d1a66e89c_f3f6c60b-1102x1536.jpg","1536x1536-width":1102,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1084ddcc29e7f8992cada1d1a66e89c_f3f6c60b.jpg","2048x2048-width":1148,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1084ddcc29e7f8992cada1d1a66e89c_f3f6c60b.jpg","gform-image-choice-sm-width":215,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1084ddcc29e7f8992cada1d1a66e89c_f3f6c60b.jpg","gform-image-choice-md-width":287,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a1084ddcc29e7f8992cada1d1a66e89c_f3f6c60b.jpg","gform-image-choice-lg-width":431,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171140,"id":171140,"title":"2b41822387e8207547ce34b7ca2e19ea_4117d16f.jpg","filename":"2b41822387e8207547ce34b7ca2e19ea_4117d16f.jpg","filesize":380394,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b41822387e8207547ce34b7ca2e19ea_4117d16f.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/2b41822387e8207547ce34b7ca2e19ea_4117d16f-jpg\/","alt":"","author":"0","description":"","caption":"","name":"2b41822387e8207547ce34b7ca2e19ea_4117d16f-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:15:04","modified":"2025-04-18 12:16:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1058,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b41822387e8207547ce34b7ca2e19ea_4117d16f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b41822387e8207547ce34b7ca2e19ea_4117d16f-300x198.jpg","medium-width":300,"medium-height":198,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b41822387e8207547ce34b7ca2e19ea_4117d16f-768x508.jpg","medium_large-width":768,"medium_large-height":508,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b41822387e8207547ce34b7ca2e19ea_4117d16f-1024x677.jpg","large-width":1024,"large-height":677,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b41822387e8207547ce34b7ca2e19ea_4117d16f-1536x1016.jpg","1536x1536-width":1536,"1536x1536-height":1016,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b41822387e8207547ce34b7ca2e19ea_4117d16f.jpg","2048x2048-width":1600,"2048x2048-height":1058,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b41822387e8207547ce34b7ca2e19ea_4117d16f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":198,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b41822387e8207547ce34b7ca2e19ea_4117d16f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":265,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b41822387e8207547ce34b7ca2e19ea_4117d16f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":397}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171147,"id":171147,"title":"90a5d88c8b8a78e89084dc0162d63301_82ecb9e0.jpg","filename":"90a5d88c8b8a78e89084dc0162d63301_82ecb9e0.jpg","filesize":335314,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/90a5d88c8b8a78e89084dc0162d63301_82ecb9e0.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/90a5d88c8b8a78e89084dc0162d63301_82ecb9e0-jpg\/","alt":"","author":"0","description":"","caption":"","name":"90a5d88c8b8a78e89084dc0162d63301_82ecb9e0-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:15:05","modified":"2025-04-18 12:16:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1067,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/90a5d88c8b8a78e89084dc0162d63301_82ecb9e0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/90a5d88c8b8a78e89084dc0162d63301_82ecb9e0-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/90a5d88c8b8a78e89084dc0162d63301_82ecb9e0-768x1152.jpg","medium_large-width":768,"medium_large-height":1152,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/90a5d88c8b8a78e89084dc0162d63301_82ecb9e0-683x1024.jpg","large-width":683,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/90a5d88c8b8a78e89084dc0162d63301_82ecb9e0-1024x1536.jpg","1536x1536-width":1024,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/90a5d88c8b8a78e89084dc0162d63301_82ecb9e0.jpg","2048x2048-width":1067,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/90a5d88c8b8a78e89084dc0162d63301_82ecb9e0.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/90a5d88c8b8a78e89084dc0162d63301_82ecb9e0.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/90a5d88c8b8a78e89084dc0162d63301_82ecb9e0.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171154,"id":171154,"title":"6cb2dd065575998311ef48c691f58ea6_ee27ed27.jpg","filename":"6cb2dd065575998311ef48c691f58ea6_ee27ed27.jpg","filesize":445905,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cb2dd065575998311ef48c691f58ea6_ee27ed27.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/6cb2dd065575998311ef48c691f58ea6_ee27ed27-jpg\/","alt":"","author":"0","description":"","caption":"","name":"6cb2dd065575998311ef48c691f58ea6_ee27ed27-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:15:07","modified":"2025-04-18 12:16:54","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cb2dd065575998311ef48c691f58ea6_ee27ed27-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cb2dd065575998311ef48c691f58ea6_ee27ed27-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cb2dd065575998311ef48c691f58ea6_ee27ed27-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cb2dd065575998311ef48c691f58ea6_ee27ed27-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cb2dd065575998311ef48c691f58ea6_ee27ed27-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cb2dd065575998311ef48c691f58ea6_ee27ed27.jpg","2048x2048-width":1200,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cb2dd065575998311ef48c691f58ea6_ee27ed27.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cb2dd065575998311ef48c691f58ea6_ee27ed27.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6cb2dd065575998311ef48c691f58ea6_ee27ed27.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171161,"id":171161,"title":"fe539a0a003920b5d8119e929a1756e1_8a5b9985.jpg","filename":"fe539a0a003920b5d8119e929a1756e1_8a5b9985.jpg","filesize":435365,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fe539a0a003920b5d8119e929a1756e1_8a5b9985.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/fe539a0a003920b5d8119e929a1756e1_8a5b9985-jpg\/","alt":"","author":"0","description":"","caption":"","name":"fe539a0a003920b5d8119e929a1756e1_8a5b9985-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:15:08","modified":"2025-04-18 12:16:54","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fe539a0a003920b5d8119e929a1756e1_8a5b9985-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fe539a0a003920b5d8119e929a1756e1_8a5b9985-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fe539a0a003920b5d8119e929a1756e1_8a5b9985-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fe539a0a003920b5d8119e929a1756e1_8a5b9985-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fe539a0a003920b5d8119e929a1756e1_8a5b9985-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fe539a0a003920b5d8119e929a1756e1_8a5b9985.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fe539a0a003920b5d8119e929a1756e1_8a5b9985.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fe539a0a003920b5d8119e929a1756e1_8a5b9985.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fe539a0a003920b5d8119e929a1756e1_8a5b9985.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171168,"id":171168,"title":"66e3a771b31ded57cec968bcf695c9a8_5330af4d.jpg","filename":"66e3a771b31ded57cec968bcf695c9a8_5330af4d.jpg","filesize":600089,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/66e3a771b31ded57cec968bcf695c9a8_5330af4d.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/66e3a771b31ded57cec968bcf695c9a8_5330af4d-jpg\/","alt":"","author":"0","description":"","caption":"","name":"66e3a771b31ded57cec968bcf695c9a8_5330af4d-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:15:09","modified":"2025-04-18 12:16:54","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1163,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/66e3a771b31ded57cec968bcf695c9a8_5330af4d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/66e3a771b31ded57cec968bcf695c9a8_5330af4d-218x300.jpg","medium-width":218,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/66e3a771b31ded57cec968bcf695c9a8_5330af4d-768x1057.jpg","medium_large-width":768,"medium_large-height":1057,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/66e3a771b31ded57cec968bcf695c9a8_5330af4d-744x1024.jpg","large-width":744,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/66e3a771b31ded57cec968bcf695c9a8_5330af4d-1116x1536.jpg","1536x1536-width":1116,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/66e3a771b31ded57cec968bcf695c9a8_5330af4d.jpg","2048x2048-width":1163,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/66e3a771b31ded57cec968bcf695c9a8_5330af4d.jpg","gform-image-choice-sm-width":218,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/66e3a771b31ded57cec968bcf695c9a8_5330af4d.jpg","gform-image-choice-md-width":291,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/66e3a771b31ded57cec968bcf695c9a8_5330af4d.jpg","gform-image-choice-lg-width":436,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171175,"id":171175,"title":"ce5bd46ef60816468ab100e0d04b405a_213d467f.jpg","filename":"ce5bd46ef60816468ab100e0d04b405a_213d467f.jpg","filesize":388189,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ce5bd46ef60816468ab100e0d04b405a_213d467f.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/ce5bd46ef60816468ab100e0d04b405a_213d467f-jpg\/","alt":"","author":"0","description":"","caption":"","name":"ce5bd46ef60816468ab100e0d04b405a_213d467f-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:15:10","modified":"2025-04-18 12:16:54","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ce5bd46ef60816468ab100e0d04b405a_213d467f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ce5bd46ef60816468ab100e0d04b405a_213d467f-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ce5bd46ef60816468ab100e0d04b405a_213d467f-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ce5bd46ef60816468ab100e0d04b405a_213d467f-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ce5bd46ef60816468ab100e0d04b405a_213d467f-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ce5bd46ef60816468ab100e0d04b405a_213d467f.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ce5bd46ef60816468ab100e0d04b405a_213d467f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ce5bd46ef60816468ab100e0d04b405a_213d467f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ce5bd46ef60816468ab100e0d04b405a_213d467f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171182,"id":171182,"title":"58710f9c989a7c73393a1df26f027c6b_1a64d5af.jpg","filename":"58710f9c989a7c73393a1df26f027c6b_1a64d5af.jpg","filesize":404629,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58710f9c989a7c73393a1df26f027c6b_1a64d5af.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/58710f9c989a7c73393a1df26f027c6b_1a64d5af-jpg\/","alt":"","author":"0","description":"","caption":"","name":"58710f9c989a7c73393a1df26f027c6b_1a64d5af-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:15:12","modified":"2025-04-18 12:16:54","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58710f9c989a7c73393a1df26f027c6b_1a64d5af-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58710f9c989a7c73393a1df26f027c6b_1a64d5af-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58710f9c989a7c73393a1df26f027c6b_1a64d5af-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58710f9c989a7c73393a1df26f027c6b_1a64d5af-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58710f9c989a7c73393a1df26f027c6b_1a64d5af-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58710f9c989a7c73393a1df26f027c6b_1a64d5af.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58710f9c989a7c73393a1df26f027c6b_1a64d5af.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58710f9c989a7c73393a1df26f027c6b_1a64d5af.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/58710f9c989a7c73393a1df26f027c6b_1a64d5af.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":171189,"id":171189,"title":"c223fd0d1d5e719956cdd7ca7a63c850_b054e419.jpg","filename":"c223fd0d1d5e719956cdd7ca7a63c850_b054e419.jpg","filesize":445584,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c223fd0d1d5e719956cdd7ca7a63c850_b054e419.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/residenza-del-borgo\/c223fd0d1d5e719956cdd7ca7a63c850_b054e419-jpg\/","alt":"","author":"0","description":"","caption":"","name":"c223fd0d1d5e719956cdd7ca7a63c850_b054e419-jpg","status":"inherit","uploaded_to":171083,"date":"2025-04-18 09:15:13","modified":"2025-04-18 12:16:54","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1067,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c223fd0d1d5e719956cdd7ca7a63c850_b054e419-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c223fd0d1d5e719956cdd7ca7a63c850_b054e419-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c223fd0d1d5e719956cdd7ca7a63c850_b054e419-768x1152.jpg","medium_large-width":768,"medium_large-height":1152,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c223fd0d1d5e719956cdd7ca7a63c850_b054e419-683x1024.jpg","large-width":683,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c223fd0d1d5e719956cdd7ca7a63c850_b054e419-1024x1536.jpg","1536x1536-width":1024,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c223fd0d1d5e719956cdd7ca7a63c850_b054e419.jpg","2048x2048-width":1067,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c223fd0d1d5e719956cdd7ca7a63c850_b054e419.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c223fd0d1d5e719956cdd7ca7a63c850_b054e419.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c223fd0d1d5e719956cdd7ca7a63c850_b054e419.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"filotto_layout":"","filotto_fill":"","button_icon":"none","tcm_content":false,"style":"primary","icon":{"button_icon":"none"},"target":"_self","hero_type":"images","hero_buttons":false,"function":"link","target_modal":"","latitude":"45.705408","longitude":"9.682486","accessibilitycontent":{"tcm_content":false},"startingprice":"","gpxmap":"","id_madeep":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_kids":true,"iu_shortprice":"","iu_addr_postalcode":"24124","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 035 3097909","iu_cell":"","iu_email":"info@residenzadelborgo.eu","iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_gpxtrack":"","size":"full","id_visit_manza":"8139","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","id_east":"","id_ristora":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"validfrom":"","validto":"","only_ambassadors":false,"id_eppen":"","hours":"","accessibilityicons":[],"description":"<p>Jasne kolory witryn sklepowych, aromaty delikates\u00f3w, staro\u017cytne pa\u0142ace i stare sklepy, kt\u00f3re nadal charakteryzuj\u0105 wiosk\u0119, w kt\u00f3rej znajduje si\u0119 nasz hotel, wprowadzaj\u0105 odwiedzaj\u0105cych w wyj\u0105tkow\u0105 atmosfer\u0119; t\u0119 sam\u0105 atmosfer\u0119, kt\u00f3ra charakteryzuje ka\u017cdy z 18 mini-apartament\u00f3w, w kt\u00f3rych znajduje si\u0119 &#8220;Residenza&#8221;.<br \/>\nKa\u017cdy z pokoi (o powierzchni od 27 m2 w pokojach standardowych do 80 m2 w apartamentach) jest dostosowany &#8220;ad hoc&#8221;, ze starannie dobranymi ro\u015blinami ozdobnymi, aby zapewni\u0107 ci\u0105g\u0142\u0105 regeneracj\u0119 powietrza, jasnymi i przyjaznymi kolorami, kt\u00f3re odr\u00f3\u017cniaj\u0105 je od siebie, oraz najnowocze\u015bniejsz\u0105 technologi\u0105, tak\u0105 jak telewizory SMART HOTEL z dost\u0119pem do Internetu i r\u00f3\u017cnych us\u0142ug sieciowych. Wszystkie wyposa\u017cone s\u0105 w: aneks kuchenny, minibar, piekarnik i ekspres do kawy, prywatn\u0105 \u0142azienk\u0119, klimatyzacj\u0119, sejf, uprzejm\u0105 lini\u0119, r\u0119czniki, fotele, sofy i tarasy (w zale\u017cno\u015bci od wybranego rodzaju pokoju), odkryte i\/lub zadaszone miejsce parkingowe. <\/p>\n","hero_title":"Rezydencja Borgo","hero_text":"<p>W po\u0142\u0105czeniu staro\u017cytno\u015bci i nowoczesno\u015bci, kultury i historii, hotel<strong>&#8220;Residenza del Borgo<\/strong>&#8221; jest gotowy powita\u0107 i zaoferowa\u0107 swoim go\u015bciom niezapomniany pobyt.<\/p>\n","indepth":"<p>Hotel &#8220;Residenza del Borgo&#8221; mie\u015bci si\u0119 w jednym z najstarszych pa\u0142ac\u00f3w w mie\u015bcie i nowo odrestaurowanym dawnym klasztorze, dzi\u0119ki czemu znajduje si\u0119 we wspania\u0142ym historycznym kontek\u015bcie, kt\u00f3ry \u0142\u0105czy histori\u0119 i nowoczesno\u015b\u0107.<\/p>\n","howtogetthere":"<p>Hotel &#8220;Residenza del Borgo&#8221; po\u0142o\u017cony jest przy via Borgo Santa Caterina 41, jednej ze staro\u017cytnych wiosek w centrum miasta, kt\u00f3ra najlepiej oddaje ducha Bergamo. Znajduje si\u0119 on 10 minut spacerem od &#8220;Citt\u00e0 Alta&#8221; i g\u0142\u00f3wnego dworca kolejowego oraz 15 minut jazdy od lotniska. Jest on r\u00f3wnie\u017c \u0142atwo dost\u0119pny \u015brodkami transportu miejskiego. Zaledwie 2 kroki od Accademia Carrara i, dla mi\u0142o\u015bnik\u00f3w sportu, 5 minut od stadionu Atleti Azzurri D&#8217;Italia, nasz hotel jest r\u00f3wnie\u017c zanurzony w wyj\u0105tkowej atmosferze.   <\/p>\n","time":"<p>Hotel czynny jest codziennie od 07:00 do 00:00.<\/p>\n","iu_addr_streetnumber":"Via Borgo Santa Caterina, 41","iu_website":"http:\/\/www.residenzadelborgo.eu","url":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/181896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/181896\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media\/171088"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media?parent=181896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/categories?post=181896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/tags?post=181896"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/aggr?post=181896"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/area?post=181896"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/kind?post=181896"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/zona?post=181896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}