{"id":231741,"date":"2026-01-19T14:56:08","date_gmt":"2026-01-19T13:56:08","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/ciaspolando-con-gusto-2\/"},"modified":"2026-01-22T10:48:33","modified_gmt":"2026-01-22T09:48:33","slug":"ciaspolando-con-gusto-2","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/ciaspolando-con-gusto-2\/","title":{"rendered":"Ciaspolando con gusto"},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":219223,"template":"","categories":[2131],"tags":[17224],"aggr":[],"area":[1014,955],"kind":[2109],"zona":[1282,1268],"class_list":["post-231741","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-events","tag-outdoor-en","area-cusio","area-montagna","kind-evento","zona-cusio","zona-val-brembana"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Ciaspolando con gusto","hero_text":"","hero_random_sort":false,"slides":[{"image":{"ID":219208,"id":219208,"title":"ciaspolando-con_2025_01_09T16_42_04_740857_original.jpg","filename":"ciaspolando-con_2025_01_09T16_42_04_740857_original.jpg","filesize":395501,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2026\/01\/ciaspolando-con_2025_01_09T16_42_04_740857_original.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/ciaspolando-con-gusto\/ciaspolando-con_2025_01_09t16_42_04_740857_original-jpg-2\/","alt":"","author":"3","description":"","caption":"","name":"ciaspolando-con_2025_01_09t16_42_04_740857_original-jpg-2","status":"inherit","uploaded_to":231728,"date":"2026-01-19 13:56:01","modified":"2026-01-19 13:56:01","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2026\/01\/ciaspolando-con_2025_01_09T16_42_04_740857_original-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2026\/01\/ciaspolando-con_2025_01_09T16_42_04_740857_original-300x188.jpg","medium-width":300,"medium-height":188,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2026\/01\/ciaspolando-con_2025_01_09T16_42_04_740857_original-768x480.jpg","medium_large-width":768,"medium_large-height":480,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2026\/01\/ciaspolando-con_2025_01_09T16_42_04_740857_original-1024x640.jpg","large-width":1024,"large-height":640,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2026\/01\/ciaspolando-con_2025_01_09T16_42_04_740857_original-1536x960.jpg","1536x1536-width":1536,"1536x1536-height":960,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2026\/01\/ciaspolando-con_2025_01_09T16_42_04_740857_original-2048x1280.jpg","2048x2048-width":2048,"2048x2048-height":1280,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2026\/01\/ciaspolando-con_2025_01_09T16_42_04_740857_original.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":188,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2026\/01\/ciaspolando-con_2025_01_09T16_42_04_740857_original.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":250,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2026\/01\/ciaspolando-con_2025_01_09T16_42_04_740857_original.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":375}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto_no_overlay":false,"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""},"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""}},"description":"<p>Ciaspolata gastronomica tra le baite d&#8217;alpeggio dei Piani dell&#8217;Avaro che si svolge su un percorso semplice e adatto a tutti, anche ai bambini e a chi non ha mai messo le ciaspole.<\/p>\n","indepth":"<p>Ciaspolando con Gusto \u00e8 una ciaspolata gastronomica tra le baite d&#8217;alpeggio dei Piani dell&#8217;Avaro che si svolge su un percorso semplice e adatto a tutti, anche ai bambini e a chi non ha mai messo le ciaspole, \u00e8 di circa 4 km tra le distese dei Piani dell&#8217;Avaro, essendo ben segnalato e senza pericoli verr\u00e0 svolto in autonomia.<\/p>\n<p>Durante la ciaspolata si incontreranno diverse tappe in cui i produttori locali faranno assaggiare le loro specialit\u00e0.<br \/>Le degustazioni prevedono tutti i prodotti del territorio, come salumi nostrani, formaggi locali, polenta e dolci artigianali e tanto altro.<\/p>\n<p>Sar\u00e0 quindi l&#8217;occasione per fare un pranzo speciale, itinerante sulla neve, immersi nello splendido paesaggio dei piani dell&#8217;Avaro.<br \/>Tutti gli assaggi saranno inclusi nel pass che si acquister\u00e0 all&#8217;inizio del percorso, presso il nostro Infopoint, da l\u00ec poi inizier\u00e0 il giro ad anello di Ciaspolando con Gusto.<\/p>\n<p>Adulti 30 \u20ac;<br \/>Ragazzi (6-15 anni) 25 \u20ac;<br \/>Bambini (fino a 5 anni) Gratis.<br \/>Noleggio Ciaspole 10 \u20ac, per i bambini fino a 5 anni l&#8217;utilizzo delle ciaspole \u00e8 sconsigliato anche se il percorso \u00e8 praticabile.<\/p>\n<p>La prenotazione \u00e8 obbligatoria, le iscrizioni chiuderanno una volta raggiunto il numero massimo di partecipanti.<br \/>Il pagamento verr\u00e0 effettuato al momento della partenza presso il nostro Infopoint ai Piani dell&#8217;Avaro il giorno della Ciaspolata.<\/p>\n<p>La partenza \u00e8 possibile dalle 9.30 alle 13, essendo il percorso segnalato, ognuno pu\u00f2 percorrerlo in autonomia al proprio passo.<br \/>Per agevolare le iscrizioni e per evitare assembramenti, sono state stabilite sette fasce orarie, a partire dalle 9.30 sino alle 13 con intervalli di mezz&#8217;ora.<\/p>\n","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"<p>Adulti 30 \u20ac; Ragazzi (6-15 anni) 25 \u20ac; Bambini (fino a 5 anni) Gratis.<\/p>\n","time":"<p>09:30 &#8211; 16:00<\/p>\n","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.990793","longitude":"9.603297","startingprice":"","gpxmap":"","iu_motor_accessibility":"0","iu_visual_accessibility":"0","iu_auditory_accessibility":"0","iu_cognitive_accessibility":"0","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"","iu_addr_postalcode":"24010","iu_addr_city":"Cusio","iu_addr_province":"BG","iu_phone":"","iu_cell":"3332858655","iu_website":"https:\/\/www.kairosemotion.it","iu_email":"kairos.emotion@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_startingdate":"15\/03\/2026","iu_closingdate":"15\/03\/2026","iu_manager":"Kairos Brembo Emotion","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"253616","style":"primary","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"15\/03\/2026","validto":"15\/03\/2026","hours":"09:30 - 16:00","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","related":false,"iu_timetable":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/231741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":1,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/231741\/revisions"}],"predecessor-version":[{"id":231747,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/231741\/revisions\/231747"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media\/219223"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media?parent=231741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/categories?post=231741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/tags?post=231741"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/aggr?post=231741"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/area?post=231741"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/kind?post=231741"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/zona?post=231741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}