{"id":85398,"date":"2025-05-12T20:24:06","date_gmt":"2025-05-12T18:24:06","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/salami-salam-of-the-bergamasque-region\/"},"modified":"2024-10-08T15:02:36","modified_gmt":"2024-10-08T13:02:36","slug":"salami-salam-of-the-bergamasque-region","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/salami-salam-of-the-bergamasque-region\/","title":{"rendered":"Salami (Salam) of the Bergamasque region"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":66850,"template":"","categories":[829],"tags":[],"aggr":[],"area":[],"kind":[18707],"zona":[],"class_list":["post-85398","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-eating-en","kind-prodotto-tipico-en"],"acf":{"iu_shortprice":"","button_icon":"none","function":"link","latitude":"","longitude":"","startingprice":"","gpxmap":"","iu_addr_postalcode":"","iu_addr_city":"","iu_phone":"","iu_cell":"","iu_email":"","id_visit_manza":"","iu_motor_accessibility":"","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","id_east":"5201794","id_ristora":"","description":"<p>It falls on December 8, Immaculate Conception Day, the traditional date when in the past Bergamo families &#8220;killed the pig.&#8221; This ritual marked the main event of the winter: all the members, from children to the elderly, were involved, under the guidance of the norcino, the one who directed the operations and gave the magic touch by adding spices (strictly secret) and salt (from which the salami takes its name). Climate, humidity, ventilation and production techniques handed down through the centuries, plus the special manual skill and &#8220;know-how&#8221; of Bergamo&#8217;s norcini, make this product inimitable outside its territory. You won&#8217;t be able to resist it! Compact, doughy and soft at the same time, fragrant and succulent, magically soluble; red bell pepper and garlic scent, with delicate hints of fresh meat. Expertly spiced with pepper, nutmeg, cloves, mace, cinnamon, coriander and other &#8220;secret&#8221; ingredients that the art of the apothecaries has handed down with cookbooks dating as far back as the 16th century to the pork butchers of Bergamo, the true directors of the finished product. Salami in the Bergamo area was and is the noble product of pork butchering. The pieces of meat are chosen by the pork butcher who masterfully minces the lean parts (thigh, shoulder, coppa) combining them with about 20 percent fat parts (chinstrap or pancettone). Then he cuts the lard with a knife so that it does not get hot. Finally he takes the bag of his spices, salt, garlic soaked in red wine, and pepper and kneads everything on the table. He inserts the mixture into the casing and proceeds to tying. This is followed by curing in a cellar or in rooms with controlled temperature and humidity. The end result is a balance of flavors, smells and aromas and a perfect slice that does not crumble and comes off the skin easily. A work of art all to be enjoyed! The Associazione norcini bergamaschi organizes courses that attract students from all over the world.<br \/>\nAssociazione Norcini bergamaschi, via Dante Alighieri, 27. Calcinate (BG). Tel. 00393384645479 <\/p>\n","style":"primary","target":"_self","hero_type":"images","hero_title":"Salami (Salam) of the Bergamasque region","size":"full","curiosities":"<p>The norcino, copasun\u00ec or masant was an esteemed person who arrived at the farmsteads on a suitable day, that is, cold and dry, in the months from December to February, to kill the pig.<br \/>\nHe would bring the wooden box, panar\u00f6la , panar\u00f6l or cas\u00e9ta of fixed size, necessary to mix in the salami paste and then the cotechini paste.<br \/>\nAt dawn the copasun\u00ec carried the sack full of tools: ropes, knives, pulleys, meat grinders and funnels for bagging.<br \/>\nEach pork butcher had his own secret spices, different for each type of sausage.<br \/>\nCurrently, sheep salami, goat salami, wild boar, chamois, horse, donkey and also salami processed with Branzi, such as drop salami, are produced in the Bergamo area. <\/p>\n","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"target_modal":"","id_madeep":"","iu_addr_province":"","iu_manager":"","validfrom":"","validto":"","icon":{"button_icon":"none"},"cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_startingdate":"","iu_closingdate":"","iu_gpxtrack":"","url":"","iu_bookingurl":"","id_eppen":"","text":"","url_youtube":"","hero_buttons":false,"iu_kids":false,"iu_timetable":false,"iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"buttons":false,"hero_text":"","hours":"","service_icons":[],"iu_company_name":"","iu_vat":"","iu_stars":"","iu_rooms":"","iu_beds":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","time":"","registered_office":"","slides":[{"image":{"ID":66850,"id":66850,"title":"1624000130-salamebergamascodsc9911.jpg","filename":"1624000130-salamebergamascodsc9911.jpg","filesize":182261,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1624000130-salamebergamascodsc9911.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/salame-della-bergamasca-bergamo-salami\/1624000130-salamebergamascodsc9911-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1624000130-salamebergamascodsc9911-jpg-2","status":"inherit","uploaded_to":70758,"date":"2024-06-25 10:31:58","modified":"2025-05-12 18:25:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1624000130-salamebergamascodsc9911-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1624000130-salamebergamascodsc9911-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1624000130-salamebergamascodsc9911-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1624000130-salamebergamascodsc9911-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1624000130-salamebergamascodsc9911.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1624000130-salamebergamascodsc9911.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1624000130-salamebergamascodsc9911.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1624000130-salamebergamascodsc9911.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/1624000130-salamebergamascodsc9911.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70231,"id":70231,"title":"1624000142-salamebergamascodsc9892.jpg","filename":"1624000142-salamebergamascodsc9892.jpg","filesize":185945,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000142-salamebergamascodsc9892.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/salame-della-bergamasca-bergamo-salami\/1624000142-salamebergamascodsc9892-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1624000142-salamebergamascodsc9892-jpg-2","status":"inherit","uploaded_to":70758,"date":"2024-07-08 17:04:33","modified":"2025-05-12 18:25:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000142-salamebergamascodsc9892-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000142-salamebergamascodsc9892-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000142-salamebergamascodsc9892-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000142-salamebergamascodsc9892-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000142-salamebergamascodsc9892.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000142-salamebergamascodsc9892.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000142-salamebergamascodsc9892.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000142-salamebergamascodsc9892.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000142-salamebergamascodsc9892.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70237,"id":70237,"title":"1624000147-salamebergamascodsc9898.jpg","filename":"1624000147-salamebergamascodsc9898.jpg","filesize":168052,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000147-salamebergamascodsc9898.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/salame-della-bergamasca-bergamo-salami\/1624000147-salamebergamascodsc9898-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1624000147-salamebergamascodsc9898-jpg-2","status":"inherit","uploaded_to":70758,"date":"2024-07-08 17:04:35","modified":"2025-05-12 18:25:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000147-salamebergamascodsc9898-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000147-salamebergamascodsc9898-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000147-salamebergamascodsc9898-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000147-salamebergamascodsc9898-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000147-salamebergamascodsc9898.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000147-salamebergamascodsc9898.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000147-salamebergamascodsc9898.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000147-salamebergamascodsc9898.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000147-salamebergamascodsc9898.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70243,"id":70243,"title":"1624000150-salamebergamascodsc9901.jpg","filename":"1624000150-salamebergamascodsc9901.jpg","filesize":186281,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000150-salamebergamascodsc9901.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/salame-della-bergamasca-bergamo-salami\/1624000150-salamebergamascodsc9901-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1624000150-salamebergamascodsc9901-jpg-2","status":"inherit","uploaded_to":70758,"date":"2024-07-08 17:04:37","modified":"2025-05-12 18:25:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000150-salamebergamascodsc9901-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000150-salamebergamascodsc9901-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000150-salamebergamascodsc9901-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000150-salamebergamascodsc9901-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000150-salamebergamascodsc9901.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000150-salamebergamascodsc9901.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000150-salamebergamascodsc9901.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000150-salamebergamascodsc9901.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000150-salamebergamascodsc9901.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70249,"id":70249,"title":"1624000162-salamebergamascodsc9904.jpg","filename":"1624000162-salamebergamascodsc9904.jpg","filesize":171123,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000162-salamebergamascodsc9904.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/salame-della-bergamasca-bergamo-salami\/1624000162-salamebergamascodsc9904-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1624000162-salamebergamascodsc9904-jpg-2","status":"inherit","uploaded_to":70758,"date":"2024-07-08 17:04:38","modified":"2025-05-12 18:25:30","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000162-salamebergamascodsc9904-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000162-salamebergamascodsc9904-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000162-salamebergamascodsc9904-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000162-salamebergamascodsc9904-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000162-salamebergamascodsc9904.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000162-salamebergamascodsc9904.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000162-salamebergamascodsc9904.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000162-salamebergamascodsc9904.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000162-salamebergamascodsc9904.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70255,"id":70255,"title":"1624000166-salamebergamascodsc9907.jpg","filename":"1624000166-salamebergamascodsc9907.jpg","filesize":215964,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000166-salamebergamascodsc9907.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/salame-della-bergamasca-bergamo-salami\/1624000166-salamebergamascodsc9907-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1624000166-salamebergamascodsc9907-jpg-2","status":"inherit","uploaded_to":70758,"date":"2024-07-08 17:04:40","modified":"2025-05-12 18:25:30","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000166-salamebergamascodsc9907-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000166-salamebergamascodsc9907-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000166-salamebergamascodsc9907-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000166-salamebergamascodsc9907-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000166-salamebergamascodsc9907.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000166-salamebergamascodsc9907.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000166-salamebergamascodsc9907.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000166-salamebergamascodsc9907.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000166-salamebergamascodsc9907.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70261,"id":70261,"title":"1624000169-salamebergamascodsc9910.jpg","filename":"1624000169-salamebergamascodsc9910.jpg","filesize":294753,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000169-salamebergamascodsc9910.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/salame-della-bergamasca-bergamo-salami\/1624000169-salamebergamascodsc9910-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1624000169-salamebergamascodsc9910-jpg-2","status":"inherit","uploaded_to":70758,"date":"2024-07-08 17:04:42","modified":"2025-05-12 18:25:30","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000169-salamebergamascodsc9910-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000169-salamebergamascodsc9910-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000169-salamebergamascodsc9910-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000169-salamebergamascodsc9910-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000169-salamebergamascodsc9910.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000169-salamebergamascodsc9910.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000169-salamebergamascodsc9910.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000169-salamebergamascodsc9910.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000169-salamebergamascodsc9910.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":70267,"id":70267,"title":"1624000172-salamebergamascodsc9913.jpg","filename":"1624000172-salamebergamascodsc9913.jpg","filesize":283308,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000172-salamebergamascodsc9913.jpg","link":"https:\/\/visit.valueservice.cloud\/en\/oggetto\/salame-della-bergamasca-bergamo-salami\/1624000172-salamebergamascodsc9913-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1624000172-salamebergamascodsc9913-jpg-2","status":"inherit","uploaded_to":70758,"date":"2024-07-08 17:04:44","modified":"2025-05-12 18:25:30","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1400,"height":1400,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000172-salamebergamascodsc9913-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000172-salamebergamascodsc9913-300x300.jpg","medium-width":300,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000172-salamebergamascodsc9913-768x768.jpg","medium_large-width":768,"medium_large-height":768,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000172-salamebergamascodsc9913-1024x1024.jpg","large-width":1024,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000172-salamebergamascodsc9913.jpg","1536x1536-width":1400,"1536x1536-height":1400,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000172-salamebergamascodsc9913.jpg","2048x2048-width":1400,"2048x2048-height":1400,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000172-salamebergamascodsc9913.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000172-salamebergamascodsc9913.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/07\/1624000172-salamebergamascodsc9913.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/85398","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/oggetto\/85398\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media\/66850"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/media?parent=85398"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/categories?post=85398"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/tags?post=85398"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/aggr?post=85398"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/area?post=85398"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/kind?post=85398"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/en\/wp-json\/wp\/v2\/zona?post=85398"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}