{"id":114229,"date":"2025-06-08T14:58:08","date_gmt":"2025-06-08T12:58:08","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/114229\/"},"modified":"2025-05-12T19:58:48","modified_gmt":"2025-05-12T17:58:48","slug":"parque-espeleologico-de-dossena-en-el-valle-brembana-y-almuerzo-tipico","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/parque-espeleologico-de-dossena-en-el-valle-brembana-y-almuerzo-tipico\/","title":{"rendered":"Parque Espeleol\u00f3gico de Dossena en el Valle Brembana y almuerzo t\u00edpico."},"excerpt":{"rendered":"<p>Degusta un almuerzo t\u00edpico bergamasco y luego descubre el \u00fanico parque espeleol\u00f3gico en Europa, har\u00e1s una mezcla entre v\u00eda ferrata f\u00e1cil y parque de aventuras&#8230; pero en el coraz\u00f3n de la Tierra!<\/p>\n","protected":false},"author":0,"featured_media":184335,"template":"","categories":[521,525],"tags":[17228],"aggr":[],"area":[],"kind":[18702],"zona":[],"class_list":["post-114229","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-esperienze","category-experiencias","tag-exterior-es","kind-esperienza-es"],"acf":{"buttons":[{"style":"primary","text":"Comprar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contactar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Parque Espeleol\u00f3gico de Dossena en el Valle Brembana y almuerzo t\u00edpico.","hero_text":"<p>Degusta un almuerzo t\u00edpico bergamasco y luego descubre el \u00fanico parque espeleol\u00f3gico en Europa, har\u00e1s una mezcla entre v\u00eda ferrata f\u00e1cil y parque de aventuras&#8230; pero en el coraz\u00f3n de la Tierra!<\/p>\n","slides":[{"image":{"ID":184335,"id":184335,"title":"ec_service_4140_4","filename":"ec_service_4140_4.jpg","filesize":112755,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_4.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/parque-espeleologico-de-dossena-en-el-valle-brembana-y-almuerzo-tipico\/ec_service_4140_4-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4140_4-2","status":"inherit","uploaded_to":114229,"date":"2025-04-22 17:49:51","modified":"2025-05-12 17:58:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":517,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_4-300x129.jpg","medium-width":300,"medium-height":129,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_4-768x331.jpg","medium_large-width":768,"medium_large-height":331,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_4-1024x441.jpg","large-width":1024,"large-height":441,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_4.jpg","1536x1536-width":1200,"1536x1536-height":517,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_4.jpg","2048x2048-width":1200,"2048x2048-height":517,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":129,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":172,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":259}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":114247,"id":114247,"title":"ec_service_4140_4_2.jpg","filename":"ec_service_4140_4_2.jpg","filesize":140471,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_2.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/parque-espeleologico-de-dossena-en-el-valle-brembana-y-almuerzo-tipico\/ec_service_4140_4_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4140_4_2-jpg-2","status":"inherit","uploaded_to":114229,"date":"2025-01-20 15:00:46","modified":"2025-05-12 17:58:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":524,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_2-300x131.jpg","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_2-768x335.jpg","medium_large-width":768,"medium_large-height":335,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_2-1024x447.jpg","large-width":1024,"large-height":447,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_2.jpg","1536x1536-width":1200,"1536x1536-height":524,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_2.jpg","2048x2048-width":1200,"2048x2048-height":524,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_2-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_2-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_2-600x524.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":524}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":114248,"id":114248,"title":"ec_service_4140_4_3.jpg","filename":"ec_service_4140_4_3.jpg","filesize":86486,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_3.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/parque-espeleologico-de-dossena-en-el-valle-brembana-y-almuerzo-tipico\/ec_service_4140_4_3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4140_4_3-jpg-2","status":"inherit","uploaded_to":114229,"date":"2025-01-20 15:00:47","modified":"2025-05-12 17:58:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":431,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_3-300x108.jpg","medium-width":300,"medium-height":108,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_3-768x276.jpg","medium_large-width":768,"medium_large-height":276,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_3-1024x368.jpg","large-width":1024,"large-height":368,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_3.jpg","1536x1536-width":1200,"1536x1536-height":431,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_3.jpg","2048x2048-width":1200,"2048x2048-height":431,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_3-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_3-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_4_3-600x431.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":431}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":[{"style":"primary","text":"Comprar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contactar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>En Dossena, en el Valle Brembana, puedes encontrar el \u00fanico parque espeleol\u00f3gico de Europa!<br \/>\nSe trata de un recorrido guiado por una mina, entre pasajes suspendidos, cuevas naturales y chimeneas artificiales, para explorar las antiguas galer\u00edas de las minas de Dossena a trav\u00e9s de telesillas, puentes y pasajes suspendidos.<br \/>\nUna inmersi\u00f3n de un kil\u00f3metro a una temperatura constante de 12C que te permitir\u00e1 vivir una experiencia l\u00fadico-cultural totalmente inesperada.  <\/p>\n<p>PROGRAMA:<br \/>\n&#8211; A partir de las 12:00, almuerzo en la Trattoria Alpina de Dossena, Via Don Pietro Rigoli, 30 en Dossena.<br \/>\n&#8211; Traslado aut\u00f3nomo al parque espeleol\u00f3gico.<br \/>\n&#8211; Encuentro en la localidad de Paglio-Pignolino, 15 minutos antes de la hora elegida.<br \/>\n&#8211; Comienza tu aventura, llena de diversi\u00f3n! El recorrido en el parque espeleol\u00f3gico dura 1 hora y 15 minutos.  <\/p>\n<p>Se recomienda, a continuaci\u00f3n, visitar el Becco di Dossena, una terraza panor\u00e1mica de acceso libre y gratuito, con un precipicio de unos 250 metros y unas vistas impresionantes del Valle Parina.  <\/p>\n<p>Para finalizar mejor el d\u00eda, es posible reservar un aperitivo del territorio en el Hotel Moderno de Serina, no incluido en el precio del paquete, por 15 euros por persona.<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Todo el a\u00f1o.<br \/>\nLUN: A LAS 14:00;<br \/>\nVIE: A LAS 14:00;<br \/>\nS\u00c1B: A LAS 15:00, 16:30;<br \/>\nDOM: A LAS 15:00, 16:30.<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>3. MODIFICACI\u00d3N\/CANCELACI\u00d3N DEL SERVICIO<br \/>\n3.1 ASD se reserva el derecho de comunicar (mediante SMS, tel\u00e9fono y\/o correo electr\u00f3nico a los datos de contacto proporcionados al momento de la reserva) al Consumidor la imposibilidad de prestar el Servicio para la fecha y hora acordada o la necesidad de modificar el Servicio acordado hasta dieciocho (18) horas antes de la prestaci\u00f3n del Servicio, incluso en ausencia de causas de fuerza mayor. En este caso, el Consumidor tendr\u00e1 derecho a un vale por un monto determinado por ASD correspondiente a la parte del Servicio no prestado, o podr\u00e1 reprogramar la fecha y hora del Servicio y el contenido del mismo seg\u00fan la disponibilidad del momento; el Consumidor deber\u00e1 comunicar su elecci\u00f3n dentro de las cuarenta y ocho (48) horas siguientes a la comunicaci\u00f3n de ASD de no poder prestar el Servicio en las condiciones inicialmente acordadas. En cualquier caso, ASD no estar\u00e1 obligada a reembolsar cualquier gasto de viaje, transporte, alojamiento, etc., que el Consumidor haya incurrido en relaci\u00f3n con la prestaci\u00f3n del Servicio sujeto a cancelaci\u00f3n o modificaci\u00f3n.<br \/>\n3.2 ASD se reserva el derecho, a su exclusivo juicio, de modificar los horarios y las condiciones de prestaci\u00f3n del Servicio, si debido a causas de fuerza mayor, como por ejemplo malas condiciones meteorol\u00f3gicas (lluvia o viento fuerte) y\/o situaciones ambientales y\/o condiciones de los equipos y las instalaciones que no permitan la realizaci\u00f3n del Servicio de manera segura, incluso durante per\u00edodos limitados durante el d\u00eda. En este caso, el Consumidor tendr\u00e1 derecho a un vale por un monto determinado por ASD correspondiente a la parte del Servicio no prestado, o podr\u00e1 reprogramar la fecha y hora del Servicio y el contenido del mismo seg\u00fan la disponibilidad del momento. En cualquier caso, ASD no estar\u00e1 obligada a reembolsar cualquier gasto de viaje, transporte, alojamiento, etc., que el Consumidor haya incurrido en relaci\u00f3n con la prestaci\u00f3n del Servicio sujeto a cancelaci\u00f3n o modificaci\u00f3n.<br \/>\n3.3 Si despu\u00e9s de la prestaci\u00f3n de parte del Servicio acordado, la parte restante del Servicio no pudiera ser prestada, incluso en ausencia de causas de fuerza mayor, ASD dispondr\u00e1, cuando sea posible, soluciones alternativas, de acuerdo con las necesidades t\u00e9cnicas y de seguridad, sin cargos adicionales para el Consumidor.<br \/>\n3.4 Si el Consumidor desea modificar la fecha y\/o la hora del Servicio previamente adquirido, ser\u00e1 posible realizar dicha modificaci\u00f3n, seg\u00fan las condiciones previstas en el sitio web www.visitdossena.it y seg\u00fan la disponibilidad de los siguientes seis (6) meses, \u00fanicamente dentro de los 2 (dos) d\u00edas naturales antes de la fecha inicialmente adquirida, bajo las siguientes condiciones: con el pago de un costo adicional de gesti\u00f3n de 5,00 euros si la modificaci\u00f3n se realiza entre los 2 (dos) y 5 (cinco) d\u00edas naturales antes de la fecha inicialmente adquirida, de forma gratuita si la modificaci\u00f3n se realiza m\u00e1s de 5 (cinco) d\u00edas naturales antes de la fecha inicialmente adquirida. Adem\u00e1s, si la modificaci\u00f3n implica un precio del Servicio mayor que el originalmente adquirido, el Consumidor deber\u00e1 abonar la diferencia a ASD al momento de la solicitud de modificaci\u00f3n.<br \/>\n3.5 En caso de que el Consumidor no se presente en el check-in en Piazzale degli Alpini n.1 (Infopoint) o en el punto de recepci\u00f3n en las minas dentro del horario establecido, ASD podr\u00e1 no admitirlo al Servicio, y el billete correspondiente se considerar\u00e1 utilizado a todos los efectos, por lo que no podr\u00e1 ser reembolsado en ning\u00fan caso.<\/p>\n","moredetails":"<p>La experiencia incluye el almuerzo en la Trattoria Alpina de Dossena, tu experiencia comienza desde el paladar a las 12:00!<br \/>\nLa hora de la reserva corresponde a la hora de llegada a las Minas de Dossena; en caso de retraso, se perder\u00e1 el ticket y no habr\u00e1 reembolso en dinero\/voucher. Organiza bien el viaje para no perder tu experiencia, te recomendamos llegar con 15 minutos de antelaci\u00f3n a las minas para la fase de preparaci\u00f3n. Edad m\u00ednima 12 a\u00f1os y altura m\u00ednima de 140 cm.  <\/p>\n<p>Utiliza \u00daNICAMENTE GOOGLE MAPS para llegar al compartimento minero y no otros sistemas de navegaci\u00f3n. No pueden realizar el recorrido personas con problemas card\u00edacos, de movilidad o que sufran de v\u00e9rtigo o claustrofobia; los hu\u00e9spedes no deben haber consumido alcohol, sustancias psicoactivas o medicamentos que limiten la lucidez.  <\/p>\n<p>Recuerda, si tienes el cabello largo, recogerlo adecuadamente para evitar que se enrede durante el recorrido. Recuerda llevar los guantes, son obligatorios!  <\/p>\n<p>Vivir\u00e1s una aventura inolvidable, descubriendo la historia y la belleza de las minas, una experiencia que se puede realizar incluso en caso de mal tiempo! Recuerda llevar ropa deportiva y abrigada, con calzado adecuado.<br \/>\nUna vez estacionado el autom\u00f3vil en la localidad de Paglio-Pignolino, llegar\u00e1s al compartimento minero. Con la ayuda del personal calificado, completar\u00e1s el &#8220;registro de visitas&#8221; y te pondr\u00e1s el casco, los guantes y el arn\u00e9s.<br \/>\nTras una breve charla informativa, ser\u00e1s acompa\u00f1ado por un gu\u00eda experto a descubrir el mundo subterr\u00e1neo.<\/p>\n","whatsincluded":"<p>&#8211; Almuerzo t\u00edpico con casoncelli a la bergamasca, tabla de embutidos y quesos locales, quesos curados en la mina, postre de la casa, 1\/2 litro de agua, caf\u00e9 y cubiertos;<br \/>\n&#8211; Alquiler de arn\u00e9s y casco;<br \/>\n&#8211; Asistencia con personal cualificado.<br \/>\n&#8211; Seguro de accidentes.<\/p>\n","whatsnotincluded":"<p>&#8211; Transfer desde\/hacia el lugar de la experiencia<br \/>\n&#8211; Otras atracciones de VisitDossena<br \/>\n&#8211; Herramientas para servicios fotogr\u00e1ficos<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.87902360","longitude":"9.69944420","startingprice":"62.00","gpxmap":"","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Don Pietro Rigoli, 30","iu_addr_postalcode":"24010","iu_addr_city":"Dossena","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"VIsit Dossena, Via Chiesa, 6, Dossena","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=esp&no_qr=si&styleid=3073&ecomid=4140&serviceid=4","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"Tarde","iu_languages":"Ingl\u00e9s - italiano","iu_minpeople":"M\u00ednimo 1 persona","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_4140_4","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"20\/01\/2025","validto":"20\/01\/2026","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","iu_cognitive_accessibility":"no","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","experience_data":{"description":"<p>En Dossena, en el Valle Brembana, puedes encontrar el \u00fanico parque espeleol\u00f3gico de Europa!<br \/>\nSe trata de un recorrido guiado por una mina, entre pasajes suspendidos, cuevas naturales y chimeneas artificiales, para explorar las antiguas galer\u00edas de las minas de Dossena a trav\u00e9s de telesillas, puentes y pasajes suspendidos.<br \/>\nUna inmersi\u00f3n de un kil\u00f3metro a una temperatura constante de 12C que te permitir\u00e1 vivir una experiencia l\u00fadico-cultural totalmente inesperada.  <\/p>\n<p>PROGRAMA:<br \/>\n&#8211; A partir de las 12:00, almuerzo en la Trattoria Alpina de Dossena, Via Don Pietro Rigoli, 30 en Dossena.<br \/>\n&#8211; Traslado aut\u00f3nomo al parque espeleol\u00f3gico.<br \/>\n&#8211; Encuentro en la localidad de Paglio-Pignolino, 15 minutos antes de la hora elegida.<br \/>\n&#8211; Comienza tu aventura, llena de diversi\u00f3n! El recorrido en el parque espeleol\u00f3gico dura 1 hora y 15 minutos.  <\/p>\n<p>Se recomienda, a continuaci\u00f3n, visitar el Becco di Dossena, una terraza panor\u00e1mica de acceso libre y gratuito, con un precipicio de unos 250 metros y unas vistas impresionantes del Valle Parina.  <\/p>\n<p>Para finalizar mejor el d\u00eda, es posible reservar un aperitivo del territorio en el Hotel Moderno de Serina, no incluido en el precio del paquete, por 15 euros por persona.<\/p>\n","indepth":"","latitude":"45.87902360","longitude":"9.69944420","iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","iu_cognitive_accessibility":"no","iu_addr_streetnumber":"Via Don Pietro Rigoli, 30","iu_addr_postalcode":"24010","iu_addr_city":"Dossena","iu_addr_province":"Bergamo","timerange":"<p>Todo el a\u00f1o.<br \/>\nLUN: A LAS 14:00;<br \/>\nVIE: A LAS 14:00;<br \/>\nS\u00c1B: A LAS 15:00, 16:30;<br \/>\nDOM: A LAS 15:00, 16:30.<\/p>\n","cancellationpolicy":"<p>3. MODIFICACI\u00d3N\/CANCELACI\u00d3N DEL SERVICIO<br \/>\n3.1 ASD se reserva el derecho de comunicar (mediante SMS, tel\u00e9fono y\/o correo electr\u00f3nico a los datos de contacto proporcionados al momento de la reserva) al Consumidor la imposibilidad de prestar el Servicio para la fecha y hora acordada o la necesidad de modificar el Servicio acordado hasta dieciocho (18) horas antes de la prestaci\u00f3n del Servicio, incluso en ausencia de causas de fuerza mayor. En este caso, el Consumidor tendr\u00e1 derecho a un vale por un monto determinado por ASD correspondiente a la parte del Servicio no prestado, o podr\u00e1 reprogramar la fecha y hora del Servicio y el contenido del mismo seg\u00fan la disponibilidad del momento; el Consumidor deber\u00e1 comunicar su elecci\u00f3n dentro de las cuarenta y ocho (48) horas siguientes a la comunicaci\u00f3n de ASD de no poder prestar el Servicio en las condiciones inicialmente acordadas. En cualquier caso, ASD no estar\u00e1 obligada a reembolsar cualquier gasto de viaje, transporte, alojamiento, etc., que el Consumidor haya incurrido en relaci\u00f3n con la prestaci\u00f3n del Servicio sujeto a cancelaci\u00f3n o modificaci\u00f3n.<br \/>\n3.2 ASD se reserva el derecho, a su exclusivo juicio, de modificar los horarios y las condiciones de prestaci\u00f3n del Servicio, si debido a causas de fuerza mayor, como por ejemplo malas condiciones meteorol\u00f3gicas (lluvia o viento fuerte) y\/o situaciones ambientales y\/o condiciones de los equipos y las instalaciones que no permitan la realizaci\u00f3n del Servicio de manera segura, incluso durante per\u00edodos limitados durante el d\u00eda. En este caso, el Consumidor tendr\u00e1 derecho a un vale por un monto determinado por ASD correspondiente a la parte del Servicio no prestado, o podr\u00e1 reprogramar la fecha y hora del Servicio y el contenido del mismo seg\u00fan la disponibilidad del momento. En cualquier caso, ASD no estar\u00e1 obligada a reembolsar cualquier gasto de viaje, transporte, alojamiento, etc., que el Consumidor haya incurrido en relaci\u00f3n con la prestaci\u00f3n del Servicio sujeto a cancelaci\u00f3n o modificaci\u00f3n.<br \/>\n3.3 Si despu\u00e9s de la prestaci\u00f3n de parte del Servicio acordado, la parte restante del Servicio no pudiera ser prestada, incluso en ausencia de causas de fuerza mayor, ASD dispondr\u00e1, cuando sea posible, soluciones alternativas, de acuerdo con las necesidades t\u00e9cnicas y de seguridad, sin cargos adicionales para el Consumidor.<br \/>\n3.4 Si el Consumidor desea modificar la fecha y\/o la hora del Servicio previamente adquirido, ser\u00e1 posible realizar dicha modificaci\u00f3n, seg\u00fan las condiciones previstas en el sitio web www.visitdossena.it y seg\u00fan la disponibilidad de los siguientes seis (6) meses, \u00fanicamente dentro de los 2 (dos) d\u00edas naturales antes de la fecha inicialmente adquirida, bajo las siguientes condiciones: con el pago de un costo adicional de gesti\u00f3n de 5,00 euros si la modificaci\u00f3n se realiza entre los 2 (dos) y 5 (cinco) d\u00edas naturales antes de la fecha inicialmente adquirida, de forma gratuita si la modificaci\u00f3n se realiza m\u00e1s de 5 (cinco) d\u00edas naturales antes de la fecha inicialmente adquirida. Adem\u00e1s, si la modificaci\u00f3n implica un precio del Servicio mayor que el originalmente adquirido, el Consumidor deber\u00e1 abonar la diferencia a ASD al momento de la solicitud de modificaci\u00f3n.<br \/>\n3.5 En caso de que el Consumidor no se presente en el check-in en Piazzale degli Alpini n.1 (Infopoint) o en el punto de recepci\u00f3n en las minas dentro del horario establecido, ASD podr\u00e1 no admitirlo al Servicio, y el billete correspondiente se considerar\u00e1 utilizado a todos los efectos, por lo que no podr\u00e1 ser reembolsado en ning\u00fan caso.<\/p>\n","moredetails":"<p>La experiencia incluye el almuerzo en la Trattoria Alpina de Dossena, tu experiencia comienza desde el paladar a las 12:00!<br \/>\nLa hora de la reserva corresponde a la hora de llegada a las Minas de Dossena; en caso de retraso, se perder\u00e1 el ticket y no habr\u00e1 reembolso en dinero\/voucher. Organiza bien el viaje para no perder tu experiencia, te recomendamos llegar con 15 minutos de antelaci\u00f3n a las minas para la fase de preparaci\u00f3n. Edad m\u00ednima 12 a\u00f1os y altura m\u00ednima de 140 cm.  <\/p>\n<p>Utiliza \u00daNICAMENTE GOOGLE MAPS para llegar al compartimento minero y no otros sistemas de navegaci\u00f3n. No pueden realizar el recorrido personas con problemas card\u00edacos, de movilidad o que sufran de v\u00e9rtigo o claustrofobia; los hu\u00e9spedes no deben haber consumido alcohol, sustancias psicoactivas o medicamentos que limiten la lucidez.  <\/p>\n<p>Recuerda, si tienes el cabello largo, recogerlo adecuadamente para evitar que se enrede durante el recorrido. Recuerda llevar los guantes, son obligatorios!  <\/p>\n<p>Vivir\u00e1s una aventura inolvidable, descubriendo la historia y la belleza de las minas, una experiencia que se puede realizar incluso en caso de mal tiempo! Recuerda llevar ropa deportiva y abrigada, con calzado adecuado.<br \/>\nUna vez estacionado el autom\u00f3vil en la localidad de Paglio-Pignolino, llegar\u00e1s al compartimento minero. Con la ayuda del personal calificado, completar\u00e1s el &#8220;registro de visitas&#8221; y te pondr\u00e1s el casco, los guantes y el arn\u00e9s.<br \/>\nTras una breve charla informativa, ser\u00e1s acompa\u00f1ado por un gu\u00eda experto a descubrir el mundo subterr\u00e1neo.<\/p>\n","whatsincluded":"<p>&#8211; Almuerzo t\u00edpico con casoncelli a la bergamasca, tabla de embutidos y quesos locales, quesos curados en la mina, postre de la casa, 1\/2 litro de agua, caf\u00e9 y cubiertos;<br \/>\n&#8211; Alquiler de arn\u00e9s y casco;<br \/>\n&#8211; Asistencia con personal cualificado.<br \/>\n&#8211; Seguro de accidentes.<\/p>\n","whatsnotincluded":"<p>&#8211; Transfer desde\/hacia el lugar de la experiencia<br \/>\n&#8211; Otras atracciones de VisitDossena<br \/>\n&#8211; Herramientas para servicios fotogr\u00e1ficos<\/p>\n","startingprice":"62.00","id_madeep":"652_4140_4","iu_minpeople":"M\u00ednimo 1 persona","iu_maxpeople":"","iu_languages":"Ingl\u00e9s - italiano","iu_duration":"Tarde","iu_difficulty":"","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=esp&no_qr=si&styleid=3073&ecomid=4140&serviceid=4","iu_manager":"VIsit Dossena, Via Chiesa, 6, Dossena","review":false,"validfrom":"20\/01\/2025","validto":"20\/01\/2026"},"featured_video":false,"is_an_ambassador":false,"only_ambassadors":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/114229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/114229\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/184335"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=114229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=114229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=114229"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=114229"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=114229"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=114229"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=114229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}