{"id":114501,"date":"2025-06-08T14:58:13","date_gmt":"2025-06-08T12:58:13","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/114501\/"},"modified":"2025-05-12T19:58:56","modified_gmt":"2025-05-12T17:58:56","slug":"una-noche-de-camping-con-visita-a-la-finca-y-cena-tipica","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/una-noche-de-camping-con-visita-a-la-finca-y-cena-tipica\/","title":{"rendered":"Una noche de camping con visita a la finca y cena t\u00edpica"},"excerpt":{"rendered":"<p>Pasa dos d\u00edas inmerso en el bosque del eco-camping Placat en la meseta de Bossico. Duerme bajo las estrellas, disfruta de una cena t\u00edpica bergamasca y visita una finca.<\/p>\n","protected":false},"author":0,"featured_media":184349,"template":"","categories":[521,525],"tags":[],"aggr":[],"area":[],"kind":[18702],"zona":[],"class_list":["post-114501","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-esperienze","category-experiencias","kind-esperienza-es"],"acf":{"buttons":[{"style":"primary","text":"Comprar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contactar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Una noche de camping con visita a la finca y cena t\u00edpica","hero_text":"<p>Pasa dos d\u00edas inmerso en el bosque del eco-camping Placat en la meseta de Bossico. Duerme bajo las estrellas, disfruta de una cena t\u00edpica bergamasca y visita una finca.<\/p>\n","hero_buttons_group":{"buttons":[{"style":"primary","text":"Comprar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contactar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>Pasa un d\u00eda completo rodeado de naturaleza y bienestar en la meseta de Bossico, en las tierras altas del Lago de Iseo.<br \/>\nEl eco-camping Placat te espera para acogerte con una c\u00f3moda tienda ya montada, con colch\u00f3n, saco de dormir y funda de almohada.<br \/>\nA tu llegada, el personal del camping te mostrar\u00e1 los servicios del camping y te proporcionar\u00e1 un mapa detallado, con el que podr\u00e1s orientarte y recorrer en unos 30 minutos los senderos hasta una finca. All\u00ed visitar\u00e1s la granja con las cabras y podr\u00e1s observar el proceso de orde\u00f1o. El regreso al camping ser\u00e1 a pie, a tiempo para una deliciosa cena t\u00edpica en la Osteria di Montagna del camping.<br \/>\nDuerme acunado por la brisa del bosque y, al d\u00eda siguiente, revitalizado, disfruta de un delicioso desayuno antes de despedirte del camping, la meseta y el parque. Sabemos que volver\u00e1s a visitarnos!<\/p>\n<p>PROGRAMA:<br \/>\nD\u00cdA 1<br \/>\nCheck-in en el eco-camping Placat a las 14:00<br \/>\nRecepci\u00f3n en el camping, acomodaci\u00f3n en la tienda y recogida del mapa para una breve excursi\u00f3n a pie por cuenta propia.<br \/>\n15:45 Trekking de 30 minutos hasta la finca Filisetti<br \/>\n16:30 Inicio de la visita guiada en la finca &#8211; visita a la granja y proceso de orde\u00f1o.<br \/>\n17:30 Aproximadamente, trekking de 30 minutos para regresar al camping.<br \/>\nA partir de las 19:00: Cena t\u00edpica en la Osteria di Montagna.<br \/>\nAlojamiento en tienda ya montada con colch\u00f3n, saco de dormir y funda de almohada.<\/p>\n<p>D\u00cdA 2<br \/>\nDesayuno delicioso con productos horneados caseros.<br \/>\n10:00 Check-out<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Abril, Mayo, Septiembre, Octubre de mi\u00e9rcoles a domingo;<br \/>\nde Junio a Agosto, todos los d\u00edas.<br \/>\nLas tiendas est\u00e1n disponibles de abril a octubre.<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>No hay reembolso por no presentaci\u00f3n.<br \/>\nReembolso total si la cancelaci\u00f3n se realiza 15 d\u00edas antes de la fecha reservada.<\/p>\n","moredetails":"<p>PRECIOS:<br \/>\nAdultos: 91 euros<br \/>\nNi\u00f1os de 2 a 11 a\u00f1os: 69 euros<br \/>\nNi\u00f1os de 0 a 2 a\u00f1os: gratuito<br \/>\nSe admiten perros con una limpieza final de 10 euros, a pagar en el lugar.<\/p>\n<p>C\u00d3MO LLEGAR AL CAMPING<br \/>\nLlegar a un lugar escondido en el bosque requiere indicaciones precisas. Por lo tanto, sigue las breves pero espec\u00edficas instrucciones que te detallamos aqu\u00ed. Recomendamos subir a pie o en bicicleta, los aparcamientos est\u00e1n a solo 10 minutos.<br \/>\nNO SIGAS el navegador: te llevar\u00e1 por caminos equivocados!<\/p>\n<p>A pie<br \/>\nDesde la Piazza San Pietro o desde el aparcamiento del Campo Sportivo en Viale Vittorio Emanuele, el camping se encuentra a 20 minutos a pie, mientras que desde el aparcamiento en Localit\u00e0 Pila se encuentra a 10 minutos.<\/p>\n<p>En coche<br \/>\nEs necesario tener el permiso regional para transitar por la carretera agro-silvo-pastoral. El pase diario se puede comprar tanto en el camping como en la Piazza San Pietro en el Ayuntamiento de Bossico. El costo del pase diario es de 10 euros.<br \/>\nPara los clientes del camping, el permiso es v\u00e1lido por 24 horas. Es posible solicitar el servicio de transporte o subir de forma gratuita solo para cargar y descargar el equipaje.<\/p>\n","whatsincluded":"<p>&#8211; Alojamiento en tienda ya montada con colch\u00f3n, saco de dormir y funda de almohada. Tienda para un m\u00e1ximo de 4 personas.<br \/>\n&#8211; Indicaciones para una caminata f\u00e1cil<br \/>\n&#8211; Visita a la finca<br \/>\n&#8211; Cena en el camping<br \/>\n&#8211; Desayuno en el camping  <\/p>\n<p>La cena para adultos incluye tabla de embutidos del agricultor + primer plato a elegir + postre + caf\u00e9 + 1 bebida o copa de vino + agua y cubierto.<br \/>\nLa cena para ni\u00f1os incluye primer plato a elegir + postre + bebida + agua y cubierto.<\/p>\n","whatsnotincluded":"<p>&#8211; Transfer al \/ desde el camping<br \/>\n&#8211; Todo lo que no est\u00e9 indicado en  &#8220;Que incluye&#8221;<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.82756030","longitude":"10.04485120","startingprice":"91.00","gpxmap":"","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Piazza San Pietro","iu_addr_postalcode":"24060","iu_addr_city":"Bossico","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"Ecocampeggio Placat , Parco di Gavazzano Localit\u00e0 St\u00e0,, Bossico","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=esp&no_qr=si&styleid=3073&ecomid=4143&serviceid=2","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"todo el dia","iu_languages":"Ingl\u00e9s - italiano","iu_minpeople":"M\u00ednimo 2 personas","iu_maxpeople":"M\u00e1ximo 8 personas","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_4143_2","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"22\/01\/2025","validto":"22\/01\/2026","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_visual_accessibility":"yes","iu_auditory_accessibility":"yes","iu_cognitive_accessibility":"yes","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","experience_data":{"description":"<p>Pasa un d\u00eda completo rodeado de naturaleza y bienestar en la meseta de Bossico, en las tierras altas del Lago de Iseo.<br \/>\nEl eco-camping Placat te espera para acogerte con una c\u00f3moda tienda ya montada, con colch\u00f3n, saco de dormir y funda de almohada.<br \/>\nA tu llegada, el personal del camping te mostrar\u00e1 los servicios del camping y te proporcionar\u00e1 un mapa detallado, con el que podr\u00e1s orientarte y recorrer en unos 30 minutos los senderos hasta una finca. All\u00ed visitar\u00e1s la granja con las cabras y podr\u00e1s observar el proceso de orde\u00f1o. El regreso al camping ser\u00e1 a pie, a tiempo para una deliciosa cena t\u00edpica en la Osteria di Montagna del camping.<br \/>\nDuerme acunado por la brisa del bosque y, al d\u00eda siguiente, revitalizado, disfruta de un delicioso desayuno antes de despedirte del camping, la meseta y el parque. Sabemos que volver\u00e1s a visitarnos!<\/p>\n<p>PROGRAMA:<br \/>\nD\u00cdA 1<br \/>\nCheck-in en el eco-camping Placat a las 14:00<br \/>\nRecepci\u00f3n en el camping, acomodaci\u00f3n en la tienda y recogida del mapa para una breve excursi\u00f3n a pie por cuenta propia.<br \/>\n15:45 Trekking de 30 minutos hasta la finca Filisetti<br \/>\n16:30 Inicio de la visita guiada en la finca &#8211; visita a la granja y proceso de orde\u00f1o.<br \/>\n17:30 Aproximadamente, trekking de 30 minutos para regresar al camping.<br \/>\nA partir de las 19:00: Cena t\u00edpica en la Osteria di Montagna.<br \/>\nAlojamiento en tienda ya montada con colch\u00f3n, saco de dormir y funda de almohada.<\/p>\n<p>D\u00cdA 2<br \/>\nDesayuno delicioso con productos horneados caseros.<br \/>\n10:00 Check-out<\/p>\n","indepth":"","latitude":"45.82756030","longitude":"10.04485120","iu_motor_accessibility":"no","iu_visual_accessibility":"yes","iu_auditory_accessibility":"yes","iu_cognitive_accessibility":"yes","iu_addr_streetnumber":"Piazza San Pietro","iu_addr_postalcode":"24060","iu_addr_city":"Bossico","iu_addr_province":"Bergamo","timerange":"<p>Abril, Mayo, Septiembre, Octubre de mi\u00e9rcoles a domingo;<br \/>\nde Junio a Agosto, todos los d\u00edas.<br \/>\nLas tiendas est\u00e1n disponibles de abril a octubre.<\/p>\n","cancellationpolicy":"<p>No hay reembolso por no presentaci\u00f3n.<br \/>\nReembolso total si la cancelaci\u00f3n se realiza 15 d\u00edas antes de la fecha reservada.<\/p>\n","moredetails":"<p>PRECIOS:<br \/>\nAdultos: 91 euros<br \/>\nNi\u00f1os de 2 a 11 a\u00f1os: 69 euros<br \/>\nNi\u00f1os de 0 a 2 a\u00f1os: gratuito<br \/>\nSe admiten perros con una limpieza final de 10 euros, a pagar en el lugar.<\/p>\n<p>C\u00d3MO LLEGAR AL CAMPING<br \/>\nLlegar a un lugar escondido en el bosque requiere indicaciones precisas. Por lo tanto, sigue las breves pero espec\u00edficas instrucciones que te detallamos aqu\u00ed. Recomendamos subir a pie o en bicicleta, los aparcamientos est\u00e1n a solo 10 minutos.<br \/>\nNO SIGAS el navegador: te llevar\u00e1 por caminos equivocados!<\/p>\n<p>A pie<br \/>\nDesde la Piazza San Pietro o desde el aparcamiento del Campo Sportivo en Viale Vittorio Emanuele, el camping se encuentra a 20 minutos a pie, mientras que desde el aparcamiento en Localit\u00e0 Pila se encuentra a 10 minutos.<\/p>\n<p>En coche<br \/>\nEs necesario tener el permiso regional para transitar por la carretera agro-silvo-pastoral. El pase diario se puede comprar tanto en el camping como en la Piazza San Pietro en el Ayuntamiento de Bossico. El costo del pase diario es de 10 euros.<br \/>\nPara los clientes del camping, el permiso es v\u00e1lido por 24 horas. Es posible solicitar el servicio de transporte o subir de forma gratuita solo para cargar y descargar el equipaje.<\/p>\n","whatsincluded":"<p>&#8211; Alojamiento en tienda ya montada con colch\u00f3n, saco de dormir y funda de almohada. Tienda para un m\u00e1ximo de 4 personas.<br \/>\n&#8211; Indicaciones para una caminata f\u00e1cil<br \/>\n&#8211; Visita a la finca<br \/>\n&#8211; Cena en el camping<br \/>\n&#8211; Desayuno en el camping  <\/p>\n<p>La cena para adultos incluye tabla de embutidos del agricultor + primer plato a elegir + postre + caf\u00e9 + 1 bebida o copa de vino + agua y cubierto.<br \/>\nLa cena para ni\u00f1os incluye primer plato a elegir + postre + bebida + agua y cubierto.<\/p>\n","whatsnotincluded":"<p>&#8211; Transfer al \/ desde el camping<br \/>\n&#8211; Todo lo que no est\u00e9 indicado en  &#8220;Que incluye&#8221;<\/p>\n","startingprice":"91.00","id_madeep":"652_4143_2","iu_minpeople":"M\u00ednimo 2 personas","iu_maxpeople":"M\u00e1ximo 8 personas","iu_languages":"Ingl\u00e9s - italiano","iu_duration":"todo el dia","iu_difficulty":"","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=esp&no_qr=si&styleid=3073&ecomid=4143&serviceid=2","iu_manager":"Ecocampeggio Placat , Parco di Gavazzano Localit\u00e0 St\u00e0,, Bossico","review":false,"validfrom":"22\/01\/2025","validto":"22\/01\/2026"},"featured_video":false,"is_an_ambassador":false,"only_ambassadors":false,"slides":[{"image":{"ID":184349,"id":184349,"title":"ec_service_4143_2","filename":"ec_service_4143_2.jpg","filesize":155139,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4143_2.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/una-noche-de-camping-con-visita-a-la-finca-y-cena-tipica\/ec_service_4143_2-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4143_2-2","status":"inherit","uploaded_to":114501,"date":"2025-04-22 17:49:55","modified":"2025-05-12 17:58:57","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":486,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4143_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4143_2-300x122.jpg","medium-width":300,"medium-height":122,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4143_2-768x311.jpg","medium_large-width":768,"medium_large-height":311,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4143_2-1024x415.jpg","large-width":1024,"large-height":415,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4143_2.jpg","1536x1536-width":1200,"1536x1536-height":486,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4143_2.jpg","2048x2048-width":1200,"2048x2048-height":486,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4143_2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":122,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4143_2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":162,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4143_2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":243}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":114503,"id":114503,"title":"ec_service_4143_2_2.jpg","filename":"ec_service_4143_2_2.jpg","filesize":124009,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4143_2_2.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/una-noche-de-camping-con-visita-a-la-finca-y-cena-tipica\/ec_service_4143_2_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4143_2_2-jpg-2","status":"inherit","uploaded_to":114501,"date":"2025-01-22 12:00:50","modified":"2025-05-12 17:58:58","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":483,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4143_2_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4143_2_2-300x121.jpg","medium-width":300,"medium-height":121,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4143_2_2-768x309.jpg","medium_large-width":768,"medium_large-height":309,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4143_2_2-1024x412.jpg","large-width":1024,"large-height":412,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4143_2_2.jpg","1536x1536-width":1200,"1536x1536-height":483,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4143_2_2.jpg","2048x2048-width":1200,"2048x2048-height":483,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4143_2_2-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4143_2_2-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4143_2_2-600x483.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":483}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/114501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/114501\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/184349"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=114501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=114501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=114501"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=114501"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=114501"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=114501"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=114501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}