{"id":126412,"date":"2025-05-12T20:24:47","date_gmt":"2025-05-12T18:24:47","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/valcalepio-doc\/"},"modified":"2025-03-11T13:25:01","modified_gmt":"2025-03-11T12:25:01","slug":"valcalepio-doc","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/valcalepio-doc\/","title":{"rendered":"Valcalepio DOC"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":126441,"template":"","categories":[857],"tags":[],"aggr":[],"area":[],"kind":[18710],"zona":[],"class_list":["post-126412","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-comer","kind-prodotto-tipico-es"],"acf":{"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"button_icon":"none","style":"primary","icon":{"button_icon":"none"},"target":"_self","hero_type":"images","hero_buttons":false,"function":"link","target_modal":"","latitude":"","longitude":"","startingprice":"","gpxmap":"","id_madeep":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"iu_kids":false,"iu_shortprice":"","iu_addr_postalcode":"","iu_addr_city":"","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_email":"","iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_gpxtrack":"","size":"full","id_visit_manza":"","iu_motor_accessibility":"","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","id_east":"6605155","id_ristora":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"validfrom":"","validto":"","id_eppen":"","description":"<p>Alabo a los excelentes bergamascos que plantan vi\u00f1as en suelos poderosos&#8221;: as\u00ed elogiaba el agr\u00f3nomo bresciano Agostino Gallo la viticultura bergamasca ya a mediados del siglo XVI.<br \/>\nEn las estribaciones entre el r\u00edo Adda al oeste y el lago de Iseo al este, puedes ver las vi\u00f1as de Valcalepio cultivadas en una superficie de unas 900 hect\u00e1reas: una enorme extensi\u00f3n verde dise\u00f1ada por hileras regulares.<\/p>\n<p>\u00bfSabes cu\u00e1ntos tipos de ValCalepio hay?<br \/>\nCuatro: blanco, tinto, tinto riserva y moscato passito.<\/p>\n<p>Valcalepio D.O.C. BLANCO de uvas Pinot Bianco, Pinot Grigio y Chardonnay prensadas suavemente y fermentadas a temperatura controlada; periodo de envejecimiento de tres meses, normalmente en barricas de acero. A continuaci\u00f3n se embotella. Tiene un color amarillo pajizo claro y un bouquet con notas afrutadas y florales. Ideal como aperitivo y para acompa\u00f1ar platos de pescado.   <\/p>\n<p>Valcalepio D.O.C. TINTO de uvas Cabernet Sauvignon y Merlot; es la llamada &#8220;mezcla bordelesa&#8221;. Se afina en grandes barricas de roble durante al menos seis meses y otros tres meses en botella. Excelente maridado con platos t\u00edpicos bergamascos, primeros platos, polenta, carnes, embutidos y quesos.  <\/p>\n<p>Valcalepio D.O.C. ROSSO RISERVA. Es la evoluci\u00f3n del Valcalepio Rosso y se elabora en a\u00f1adas que han dado un producto adecuado para envejecer en barricas de roble durante tres a\u00f1os, seguido de otro a\u00f1o de afinamiento en botella. Con cuerpo pero equilibrado, combina bien con quesos curados, platos de carne, asados y caza.  <\/p>\n<p>Valcalepio D.O.C. MOSCATO PASSITO. Se produce a partir de la variedad aut\u00f3ctona de uva tinta arom\u00e1tica Moscato di Scanzo, en terrenos situados fuera del municipio de Scanzorosciate.<br \/>\nLas uvas cuidadosamente seleccionadas en el vi\u00f1edo se secan durante un periodo m\u00ednimo de tres semanas. A continuaci\u00f3n se procede a la vinificaci\u00f3n en tinto con maceraci\u00f3n pelicular. La fermentaci\u00f3n lenta se interrumpe cuando la graduaci\u00f3n alcoh\u00f3lica alcanza los 15 grados. El Valcalepio D.O.C. Moscato Passito puede comercializarse a partir de mayo del segundo a\u00f1o siguiente a la vendimia.   <\/p>\n<p>Tiene un aroma intenso y persistente y un sabor moderadamente dulce. Es excelente con quesos azules o curados y reposter\u00eda seca. <\/p>\n","hero_title":"Valcalepio DOC","curiosities":"<p>Bartolomeo Colleoni fue un famoso condottiero italiano (Solza, 1395; Malpaga, 1475) que siempre estuvo muy vinculado a la zona de B\u00e9rgamo. Estuvo al servicio de Venecia y Mil\u00e1n.<br \/>\nSu familia pose\u00eda una inmensa finca entre los r\u00edos Adda y Oglio. Hizo construir la capilla Colleoni en Citt\u00e0 Alta, la iglesia parroquial de Sant&#8217;Agata in Martinengo, y su compromiso c\u00edvico fue considerable. En este sentido, fund\u00f3 el Luogo Pio della Piet\u00e0 Istituto Bartolomeo Colleoni, que a\u00fan existe.  <\/p>\n","text":"","url":"","buttons":false,"hero_text":"","hours":"","service_icons":[],"iu_company_name":"","iu_vat":"","iu_stars":"","iu_rooms":"","iu_beds":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","time":"","registered_office":"","slides":[{"image":{"ID":126441,"id":126441,"title":"1599761740-dabd89706941d2e8608ac571bbd4b554be7f4702.jpg","filename":"1599761740-dabd89706941d2e8608ac571bbd4b554be7f4702.jpg","filesize":331498,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/1599761740-dabd89706941d2e8608ac571bbd4b554be7f4702.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/valcalepio-doc\/1599761740-dabd89706941d2e8608ac571bbd4b554be7f4702-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1599761740-dabd89706941d2e8608ac571bbd4b554be7f4702-jpg-2","status":"inherit","uploaded_to":126412,"date":"2024-11-10 17:24:07","modified":"2024-11-10 17:24:07","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":762,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/1599761740-dabd89706941d2e8608ac571bbd4b554be7f4702-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/1599761740-dabd89706941d2e8608ac571bbd4b554be7f4702-300x145.jpg","medium-width":300,"medium-height":145,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/1599761740-dabd89706941d2e8608ac571bbd4b554be7f4702-768x370.jpg","medium_large-width":768,"medium_large-height":370,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/1599761740-dabd89706941d2e8608ac571bbd4b554be7f4702-1024x494.jpg","large-width":1024,"large-height":494,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/1599761740-dabd89706941d2e8608ac571bbd4b554be7f4702-1536x741.jpg","1536x1536-width":1536,"1536x1536-height":741,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/1599761740-dabd89706941d2e8608ac571bbd4b554be7f4702.jpg","2048x2048-width":1580,"2048x2048-height":762,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/1599761740-dabd89706941d2e8608ac571bbd4b554be7f4702.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":145,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/1599761740-dabd89706941d2e8608ac571bbd4b554be7f4702.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":193,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/11\/1599761740-dabd89706941d2e8608ac571bbd4b554be7f4702.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":289}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/126412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/126412\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/126441"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=126412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=126412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=126412"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=126412"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=126412"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=126412"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=126412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}