{"id":147095,"date":"2025-06-08T14:58:42","date_gmt":"2025-06-08T12:58:42","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/horse-experience-a-caballo-en-la-val-seriana\/"},"modified":"2025-05-12T19:59:43","modified_gmt":"2025-05-12T17:59:43","slug":"horse-experience-a-caballo-en-la-val-seriana","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/horse-experience-a-caballo-en-la-val-seriana\/","title":{"rendered":"Horse Experience, a caballo en la Val Seriana"},"excerpt":{"rendered":"<p>Vive una aventura a caballo por los bosques y los impresionantes paisajes del Valle de Seriana<\/p>\n","protected":false},"author":0,"featured_media":184440,"template":"","categories":[521,525],"tags":[17270],"aggr":[],"area":[],"kind":[18702],"zona":[],"class_list":["post-147095","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-esperienze","category-experiencias","tag-orobie-inteligente-es","kind-esperienza-es"],"acf":{"buttons":[{"style":"primary","text":"Comprar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contactar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Horse Experience, a caballo en la Val Seriana","hero_text":"<p>Vive una aventura a caballo por los bosques y los impresionantes paisajes del Valle de Seriana<\/p>\n","hero_buttons_group":{"buttons":[{"style":"primary","text":"Comprar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contactar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"description":"<p>La Fattoria della Felicit\u00e0 te ofrece la posibilidad de vivir una aventura a caballo en el coraz\u00f3n de las monta\u00f1as Orobie de B\u00e9rgamo, a la sombra del macizo de Presolana.<\/p>\n<p>QU\u00c9 TE ESPERA<br \/>\nLos primeros 30 minutos estar\u00e1n dedicados a aprender informaci\u00f3n \u00fatil sobre el mundo de la equitaci\u00f3n, los caballos y sus costumbres. En particular, descubrir\u00e1s c\u00f3mo manejar tu caballo durante el paseo. Al final de la lecci\u00f3n, te parecer\u00e1 facil\u00edsimo mantener el equilibrio en la silla y dar simples \u00f3rdenes a tu caballo!<\/p>\n<p>Finalmente listos, seguir\u00e1s a nuestro gu\u00eda ecuestre en una fascinante excursi\u00f3n de una hora por la naturaleza. Ir\u00e1s por caminos de tierra y gravilla, prados y algunos senderos de monta\u00f1a. Montado en tu valiente corcel, pasear\u00e1s por el Valle de Seriana en un ambiente de total despreocupaci\u00f3n y te quedar\u00e1s encantado con la vista del macizo monta\u00f1oso de la Presolana.<\/p>\n<p>Luego tendr\u00e1s la oportunidad de degustar un almuerzo en la granja, con un costo de 20 euros por un plato o de 32 euros por una comida completa (entrantes, primer plato, segundo plato), agua, postre y caf\u00e9 siempre incluidos.<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Todos los d\u00edas<\/p>\n<p>La experiencia no se llevar\u00e1 a cabo en caso de mal tiempo; se recomienda contactar con la instalaci\u00f3n unas horas antes para verificar las condiciones meteorol\u00f3gicas.<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>&#8211; No hay reembolso por no presentaci\u00f3n.<br \/>\n&#8211; Reembolso total por cancelaciones hasta 72 horas antes de la experiencia.<\/p>\n","moredetails":"<p>PRECIOS<br \/>\nAdulto: 45,00 euros<br \/>\nLa experiencia est\u00e1 destinada solo a adultos mayores de 14 a\u00f1os.<\/p>\n<p>ROPA<br \/>\nSe recomienda llevar zapatillas deportivas o botas de senderismo, pantalones largos y c\u00f3modos.<\/p>\n<p>NOTA<br \/>\n&#8211; La experiencia no se llevar\u00e1 a cabo en caso de mal tiempo; se recomienda contactar con la instalaci\u00f3n unas horas antes para verificar las condiciones meteorol\u00f3gicas.<\/p>\n<p>EXTRA<br \/>\nExiste la posibilidad de a\u00f1adir un almuerzo, aperitivo o cata en la granja. Podr\u00e1s elegir entre el men\u00fa de 20 euros que incluye un plato, agua, postre y caf\u00e9, o el men\u00fa de 32 euros que incluye entrantes, primer plato, segundo plato, agua, postre y caf\u00e9.<\/p>\n","whatsincluded":"<p>&#8211; Lecci\u00f3n a caballo de 30 minutos de duraci\u00f3n.<br \/>\n&#8211; Excursi\u00f3n guiada de 1 hora de duraci\u00f3n.<\/p>\n","whatsnotincluded":"<p>&#8211; Transporte de ida y vuelta a la finca.<br \/>\n&#8211; Todo lo que no est\u00e9 expl\u00edcitamente indicado en &#8220;qu\u00e9 incluye&#8221;.<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.89417930","longitude":"10.02484800","startingprice":"45.00","gpxmap":"","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Loc. Zanecla","iu_addr_postalcode":"24020","iu_addr_city":"Zanecla","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"Fattoria della Felicit\u00e0, Localit\u00e0 Zanecla, Onore","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=esp&no_qr=si&styleid=3073&ecomid=4165&serviceid=7","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"1h 30 min","iu_languages":"italiano - Ingl\u00e9s","iu_minpeople":"M\u00ednimo 2 personas","iu_maxpeople":"M\u00e1ximo 4 personas","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_4165_7","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"28\/01\/2025","validto":"30\/12\/2025","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"yes","iu_cognitive_accessibility":"no","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"max_elements":"","show_total":false,"see_all":false,"order_by":"","order_way":"","experience_data":{"description":"<p>La Fattoria della Felicit\u00e0 te ofrece la posibilidad de vivir una aventura a caballo en el coraz\u00f3n de las monta\u00f1as Orobie de B\u00e9rgamo, a la sombra del macizo de Presolana.<\/p>\n<p>QU\u00c9 TE ESPERA<br \/>\nLos primeros 30 minutos estar\u00e1n dedicados a aprender informaci\u00f3n \u00fatil sobre el mundo de la equitaci\u00f3n, los caballos y sus costumbres. En particular, descubrir\u00e1s c\u00f3mo manejar tu caballo durante el paseo. Al final de la lecci\u00f3n, te parecer\u00e1 facil\u00edsimo mantener el equilibrio en la silla y dar simples \u00f3rdenes a tu caballo!<\/p>\n<p>Finalmente listos, seguir\u00e1s a nuestro gu\u00eda ecuestre en una fascinante excursi\u00f3n de una hora por la naturaleza. Ir\u00e1s por caminos de tierra y gravilla, prados y algunos senderos de monta\u00f1a. Montado en tu valiente corcel, pasear\u00e1s por el Valle de Seriana en un ambiente de total despreocupaci\u00f3n y te quedar\u00e1s encantado con la vista del macizo monta\u00f1oso de la Presolana.<\/p>\n<p>Luego tendr\u00e1s la oportunidad de degustar un almuerzo en la granja, con un costo de 20 euros por un plato o de 32 euros por una comida completa (entrantes, primer plato, segundo plato), agua, postre y caf\u00e9 siempre incluidos.<\/p>\n","indepth":"","latitude":"45.89417930","longitude":"10.02484800","iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"yes","iu_cognitive_accessibility":"no","iu_addr_streetnumber":"Loc. Zanecla","iu_addr_postalcode":"24020","iu_addr_city":"Zanecla","iu_addr_province":"Bergamo","timerange":"<p>Todos los d\u00edas<\/p>\n<p>La experiencia no se llevar\u00e1 a cabo en caso de mal tiempo; se recomienda contactar con la instalaci\u00f3n unas horas antes para verificar las condiciones meteorol\u00f3gicas.<\/p>\n","cancellationpolicy":"<p>&#8211; No hay reembolso por no presentaci\u00f3n.<br \/>\n&#8211; Reembolso total por cancelaciones hasta 72 horas antes de la experiencia.<\/p>\n","moredetails":"<p>PRECIOS<br \/>\nAdulto: 45,00 euros<br \/>\nLa experiencia est\u00e1 destinada solo a adultos mayores de 14 a\u00f1os.<\/p>\n<p>ROPA<br \/>\nSe recomienda llevar zapatillas deportivas o botas de senderismo, pantalones largos y c\u00f3modos.<\/p>\n<p>NOTA<br \/>\n&#8211; La experiencia no se llevar\u00e1 a cabo en caso de mal tiempo; se recomienda contactar con la instalaci\u00f3n unas horas antes para verificar las condiciones meteorol\u00f3gicas.<\/p>\n<p>EXTRA<br \/>\nExiste la posibilidad de a\u00f1adir un almuerzo, aperitivo o cata en la granja. Podr\u00e1s elegir entre el men\u00fa de 20 euros que incluye un plato, agua, postre y caf\u00e9, o el men\u00fa de 32 euros que incluye entrantes, primer plato, segundo plato, agua, postre y caf\u00e9.<\/p>\n","whatsincluded":"<p>&#8211; Lecci\u00f3n a caballo de 30 minutos de duraci\u00f3n.<br \/>\n&#8211; Excursi\u00f3n guiada de 1 hora de duraci\u00f3n.<\/p>\n","whatsnotincluded":"<p>&#8211; Transporte de ida y vuelta a la finca.<br \/>\n&#8211; Todo lo que no est\u00e9 expl\u00edcitamente indicado en &#8220;qu\u00e9 incluye&#8221;.<\/p>\n","startingprice":"45.00","id_madeep":"652_4165_7","iu_minpeople":"M\u00ednimo 2 personas","iu_maxpeople":"M\u00e1ximo 4 personas","iu_languages":"italiano - Ingl\u00e9s","iu_duration":"1h 30 min","iu_difficulty":"","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=esp&no_qr=si&styleid=3073&ecomid=4165&serviceid=7","iu_manager":"Fattoria della Felicit\u00e0, Localit\u00e0 Zanecla, Onore","review":false,"validfrom":"28\/01\/2025","validto":"30\/12\/2025"},"featured_video":false,"is_an_ambassador":false,"only_ambassadors":false,"slides":[{"image":{"ID":184440,"id":184440,"title":"ec_service_4165_7","filename":"ec_service_4165_7-1.jpg","filesize":145240,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7-1.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/horse-experience-a-caballo-en-la-val-seriana\/ec_service_4165_7-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4165_7-2","status":"inherit","uploaded_to":147095,"date":"2025-04-22 17:50:29","modified":"2025-05-12 17:59:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":470,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7-1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7-1-300x118.jpg","medium-width":300,"medium-height":118,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7-1-768x301.jpg","medium_large-width":768,"medium_large-height":301,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7-1-1024x401.jpg","large-width":1024,"large-height":401,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7-1.jpg","1536x1536-width":1200,"1536x1536-height":470,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7-1.jpg","2048x2048-width":1200,"2048x2048-height":470,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7-1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":118,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7-1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":157,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7-1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":235}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":147069,"id":147069,"title":"ec_service_4165_7_2.jpg","filename":"ec_service_4165_7_2.jpg","filesize":112550,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_2.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/horse-experience-a-caballo-en-la-val-seriana\/ec_service_4165_7_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4165_7_2-jpg-2","status":"inherit","uploaded_to":147095,"date":"2025-04-15 22:03:11","modified":"2025-05-12 17:59:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":567,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_2-300x142.jpg","medium-width":300,"medium-height":142,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_2-768x363.jpg","medium_large-width":768,"medium_large-height":363,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_2-1024x484.jpg","large-width":1024,"large-height":484,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_2.jpg","1536x1536-width":1200,"1536x1536-height":567,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_2.jpg","2048x2048-width":1200,"2048x2048-height":567,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":142,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":189,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":284}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":147076,"id":147076,"title":"ec_service_4165_7_3.jpg","filename":"ec_service_4165_7_3.jpg","filesize":215475,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_3.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/horse-experience-a-caballo-en-la-val-seriana\/ec_service_4165_7_3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4165_7_3-jpg-2","status":"inherit","uploaded_to":147095,"date":"2025-04-15 22:03:12","modified":"2025-05-12 17:59:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1181,"height":422,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_3-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_3-768x274.jpg","medium_large-width":768,"medium_large-height":274,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_3-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_3.jpg","1536x1536-width":1181,"1536x1536-height":422,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_3.jpg","2048x2048-width":1181,"2048x2048-height":422,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":214}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":147083,"id":147083,"title":"ec_service_4165_7_4.jpg","filename":"ec_service_4165_7_4.jpg","filesize":128127,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_4.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/horse-experience-a-caballo-en-la-val-seriana\/ec_service_4165_7_4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4165_7_4-jpg-2","status":"inherit","uploaded_to":147095,"date":"2025-04-15 22:03:13","modified":"2025-05-12 17:59:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":524,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_4-300x131.jpg","medium-width":300,"medium-height":131,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_4-768x335.jpg","medium_large-width":768,"medium_large-height":335,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_4-1024x447.jpg","large-width":1024,"large-height":447,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_4.jpg","1536x1536-width":1200,"1536x1536-height":524,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_4.jpg","2048x2048-width":1200,"2048x2048-height":524,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":131,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":175,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4165_7_4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":262}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/147095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/147095\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/184440"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=147095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=147095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=147095"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=147095"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=147095"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=147095"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=147095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}