{"id":181249,"date":"2025-04-18T13:26:53","date_gmt":"2025-04-18T11:26:53","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/appartamento-madonna-delle-nevi\/"},"modified":"2025-04-18T16:25:41","modified_gmt":"2025-04-18T14:25:41","slug":"appartamento-madonna-delle-nevi","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/","title":{"rendered":"Appartamento Madonna delle Nevi"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":164436,"template":"","categories":[1009],"tags":[],"aggr":[],"area":[],"kind":[18726],"zona":[],"class_list":["post-181249","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-dormir","kind-strutturaricettiva-es"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Appartamento Madonna delle Nevi","hero_text":"<p>Al entrar, te sorprender\u00e1n los amplios espacios disponibles que caracterizan el ambiente.<\/p>\n<p>&#13;<\/p>\n<p>La residencia cuenta con una cocina amplia y luminosa, con una gran terraza con una vista impresionante de las Prealpes Orobie, equipada con sillas, una mesa y tumbonas donde podr\u00e1s relajarte al fresco durante las noches de verano.<\/p>\n<p>&#13;<\/p>\n<p>La cocina est\u00e1 completamente equipada y dispone de electrodom\u00e9sticos de alta calidad, lo que te permitir\u00e1 cocinar c\u00f3modamente. Hay un refrigerador grande y un televisor en el lugar. Los armarios y estantes ofrecen mucho espacio para los utensilios de cocina y los productos alimenticios. A tu disposici\u00f3n, una m\u00e1quina de caf\u00e9 Lavazza con c\u00e1psulas y una selecci\u00f3n de t\u00e9s proporcionados por la casa.<\/p>\n<p>&#13;<\/p>\n<p>Si prefieres disfrutar de la cocina local, en la planta baja y en las inmediaciones de la residencia encontrar\u00e1s un bar con servicio de comida r\u00e1pida abierto los 7 d\u00edas de la semana, donde podr\u00e1s degustar deliciosos men\u00fas, as\u00ed como una pizzer\u00eda para llevar.<\/p>\n<p>&#13;<\/p>\n<p>El sal\u00f3n es grande y c\u00f3modo, con dos sillones reclinables y un sof\u00e1, un guardarropa y una librer\u00eda a tu disposici\u00f3n con interesantes libros en italiano para acompa\u00f1arte en las noches de tranquilidad. Tambi\u00e9n hay una Smart TV de 32 pulgadas con acceso a Internet para YouTube y Rai Play.<\/p>\n<p>&#13;<\/p>\n<p>Tambi\u00e9n tendr\u00e1s acceso a un peque\u00f1o balc\u00f3n especialmente reservado para fumadores.<\/p>\n<p>&#13;<\/p>\n<p>Un pasillo te llevar\u00e1 a la zona de noche, donde hay un ba\u00f1o\/lavander\u00eda con ducha, lavabo, lavadora y WC.<\/p>\n<p>&#13;<\/p>\n<p>Una habitaci\u00f3n luminosa, de estilo moderno, con una cama individual y la posibilidad de agregar otra cama, y un gran armario con cajonera y perchas, donde podr\u00e1s guardar de todo. Tambi\u00e9n cuenta con una Smart TV exclusiva de 24 pulgadas con Internet y acceso al balc\u00f3n reservado para fumadores.<\/p>\n<p>&#13;<\/p>\n<p>Una habitaci\u00f3n matrimonial luminosa, finamente decorada con una cama matrimonial de cuero blanco y un c\u00f3modo colch\u00f3n de espuma con memoria, mesitas de noche espaciosas, un gran armario, cajonera y armario alto donde encontrar\u00e1s espacio realmente para todo. Tambi\u00e9n hay una Smart TV exclusiva de 24 pulgadas con Internet. Ventana y acceso directo al bonito balc\u00f3n reservado para fumadores.<\/p>\n<p>&#13;<\/p>\n<p>Bajo petici\u00f3n, es posible agregar una cuna para ni\u00f1os en la habitaci\u00f3n (a convenir antes de la reserva).<\/p>\n<p>&#13;<\/p>\n<p>Un ba\u00f1o principal con ba\u00f1era, mueble de almacenamiento con cajones y dos lavabos, un gran espejo iluminado, bid\u00e9 y WC.<\/p>\n<p>&#13;<\/p>\n<p>No te faltar\u00e1 espacio en la residencia &#8216;Madonna delle Nevi&#8217;; te sentir\u00e1s como en casa. Ponemos a tu disposici\u00f3n todas las comodidades necesarias para una estancia agradable. Podr\u00e1s disfrutar de una conexi\u00f3n a Internet Wi-Fi muy r\u00e1pida, de tres Smart TV y de una TV.<\/p>\n<p>&#13;<\/p>\n<p>Una en cada habitaci\u00f3n, para que todos los hu\u00e9spedes puedan disfrutar de sus programas favoritos.<\/p>\n<p>&#13;<\/p>\n<p>Los dos ba\u00f1os cuentan con ducha o ba\u00f1era, garantiz\u00e1ndote la relajaci\u00f3n que mereces.<\/p>\n<p>&#13;<\/p>\n<p>La lavadora disponible te ofrecer\u00e1 la posibilidad de hacer la colada durante tu viaje.<\/p>\n<p>&#13;<\/p>\n<p>Proporcionamos secadores de pelo, batas, ropa de cama y kits de cortes\u00eda.<\/p>\n<p>&#13;<\/p>\n<p>Cuidamos de tu estancia para hacerla agradable y perfecta.<\/p>\n","slides":[{"image":{"ID":164436,"id":164436,"title":"63b042feeadc1ceef410ceb2a33302ab_4de39578.jpg","filename":"63b042feeadc1ceef410ceb2a33302ab_4de39578.jpg","filesize":295032,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63b042feeadc1ceef410ceb2a33302ab_4de39578.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/63b042feeadc1ceef410ceb2a33302ab_4de39578-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"63b042feeadc1ceef410ceb2a33302ab_4de39578-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:47:49","modified":"2025-04-18 14:25:43","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63b042feeadc1ceef410ceb2a33302ab_4de39578-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63b042feeadc1ceef410ceb2a33302ab_4de39578-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63b042feeadc1ceef410ceb2a33302ab_4de39578-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63b042feeadc1ceef410ceb2a33302ab_4de39578-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63b042feeadc1ceef410ceb2a33302ab_4de39578-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63b042feeadc1ceef410ceb2a33302ab_4de39578.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63b042feeadc1ceef410ceb2a33302ab_4de39578.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63b042feeadc1ceef410ceb2a33302ab_4de39578.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/63b042feeadc1ceef410ceb2a33302ab_4de39578.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164443,"id":164443,"title":"10e599b2d465bea57c63c31aad6c6b3b_ba354c70.jpg","filename":"10e599b2d465bea57c63c31aad6c6b3b_ba354c70.jpg","filesize":274688,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/10e599b2d465bea57c63c31aad6c6b3b_ba354c70.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/10e599b2d465bea57c63c31aad6c6b3b_ba354c70-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"10e599b2d465bea57c63c31aad6c6b3b_ba354c70-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:47:50","modified":"2025-04-18 14:25:43","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/10e599b2d465bea57c63c31aad6c6b3b_ba354c70-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/10e599b2d465bea57c63c31aad6c6b3b_ba354c70-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/10e599b2d465bea57c63c31aad6c6b3b_ba354c70-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/10e599b2d465bea57c63c31aad6c6b3b_ba354c70-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/10e599b2d465bea57c63c31aad6c6b3b_ba354c70-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/10e599b2d465bea57c63c31aad6c6b3b_ba354c70.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/10e599b2d465bea57c63c31aad6c6b3b_ba354c70.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/10e599b2d465bea57c63c31aad6c6b3b_ba354c70.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/10e599b2d465bea57c63c31aad6c6b3b_ba354c70.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164450,"id":164450,"title":"5dd8d4804e304830aead4649569d7665_ec26559a.jpg","filename":"5dd8d4804e304830aead4649569d7665_ec26559a.jpg","filesize":264503,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dd8d4804e304830aead4649569d7665_ec26559a.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/5dd8d4804e304830aead4649569d7665_ec26559a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"5dd8d4804e304830aead4649569d7665_ec26559a-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:47:51","modified":"2025-04-18 14:25:43","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dd8d4804e304830aead4649569d7665_ec26559a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dd8d4804e304830aead4649569d7665_ec26559a-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dd8d4804e304830aead4649569d7665_ec26559a-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dd8d4804e304830aead4649569d7665_ec26559a-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dd8d4804e304830aead4649569d7665_ec26559a-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dd8d4804e304830aead4649569d7665_ec26559a.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dd8d4804e304830aead4649569d7665_ec26559a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dd8d4804e304830aead4649569d7665_ec26559a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5dd8d4804e304830aead4649569d7665_ec26559a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164457,"id":164457,"title":"6439e36e912a24c07172d55a0304483e_9d689765.jpg","filename":"6439e36e912a24c07172d55a0304483e_9d689765.jpg","filesize":319268,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6439e36e912a24c07172d55a0304483e_9d689765.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/6439e36e912a24c07172d55a0304483e_9d689765-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6439e36e912a24c07172d55a0304483e_9d689765-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:47:52","modified":"2025-04-18 14:25:43","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6439e36e912a24c07172d55a0304483e_9d689765-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6439e36e912a24c07172d55a0304483e_9d689765-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6439e36e912a24c07172d55a0304483e_9d689765-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6439e36e912a24c07172d55a0304483e_9d689765-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6439e36e912a24c07172d55a0304483e_9d689765-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6439e36e912a24c07172d55a0304483e_9d689765.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6439e36e912a24c07172d55a0304483e_9d689765.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6439e36e912a24c07172d55a0304483e_9d689765.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6439e36e912a24c07172d55a0304483e_9d689765.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164464,"id":164464,"title":"664037944713453990c4101f9a404561_9987847f.jpg","filename":"664037944713453990c4101f9a404561_9987847f.jpg","filesize":333078,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/664037944713453990c4101f9a404561_9987847f.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/664037944713453990c4101f9a404561_9987847f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"664037944713453990c4101f9a404561_9987847f-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:47:53","modified":"2025-04-18 14:25:43","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/664037944713453990c4101f9a404561_9987847f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/664037944713453990c4101f9a404561_9987847f-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/664037944713453990c4101f9a404561_9987847f-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/664037944713453990c4101f9a404561_9987847f-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/664037944713453990c4101f9a404561_9987847f-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/664037944713453990c4101f9a404561_9987847f.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/664037944713453990c4101f9a404561_9987847f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/664037944713453990c4101f9a404561_9987847f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/664037944713453990c4101f9a404561_9987847f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164471,"id":164471,"title":"98b0d8a74dfda23763b20c86bead9df7_28bb2a53.jpg","filename":"98b0d8a74dfda23763b20c86bead9df7_28bb2a53.jpg","filesize":469345,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98b0d8a74dfda23763b20c86bead9df7_28bb2a53.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/98b0d8a74dfda23763b20c86bead9df7_28bb2a53-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"98b0d8a74dfda23763b20c86bead9df7_28bb2a53-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:47:54","modified":"2025-04-18 14:25:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98b0d8a74dfda23763b20c86bead9df7_28bb2a53-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98b0d8a74dfda23763b20c86bead9df7_28bb2a53-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98b0d8a74dfda23763b20c86bead9df7_28bb2a53-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98b0d8a74dfda23763b20c86bead9df7_28bb2a53-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98b0d8a74dfda23763b20c86bead9df7_28bb2a53-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98b0d8a74dfda23763b20c86bead9df7_28bb2a53.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98b0d8a74dfda23763b20c86bead9df7_28bb2a53.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98b0d8a74dfda23763b20c86bead9df7_28bb2a53.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/98b0d8a74dfda23763b20c86bead9df7_28bb2a53.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164478,"id":164478,"title":"d9337ddd6aa663678ee63a1eba1c62f6_a76ff84b.jpg","filename":"d9337ddd6aa663678ee63a1eba1c62f6_a76ff84b.jpg","filesize":280590,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d9337ddd6aa663678ee63a1eba1c62f6_a76ff84b.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/d9337ddd6aa663678ee63a1eba1c62f6_a76ff84b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d9337ddd6aa663678ee63a1eba1c62f6_a76ff84b-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:47:55","modified":"2025-04-18 14:25:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d9337ddd6aa663678ee63a1eba1c62f6_a76ff84b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d9337ddd6aa663678ee63a1eba1c62f6_a76ff84b-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d9337ddd6aa663678ee63a1eba1c62f6_a76ff84b-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d9337ddd6aa663678ee63a1eba1c62f6_a76ff84b-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d9337ddd6aa663678ee63a1eba1c62f6_a76ff84b-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d9337ddd6aa663678ee63a1eba1c62f6_a76ff84b.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d9337ddd6aa663678ee63a1eba1c62f6_a76ff84b.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d9337ddd6aa663678ee63a1eba1c62f6_a76ff84b.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d9337ddd6aa663678ee63a1eba1c62f6_a76ff84b.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164485,"id":164485,"title":"f671b515893beac8667b317d54474352_f795662a.jpg","filename":"f671b515893beac8667b317d54474352_f795662a.jpg","filesize":217643,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f671b515893beac8667b317d54474352_f795662a.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/f671b515893beac8667b317d54474352_f795662a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"f671b515893beac8667b317d54474352_f795662a-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:47:56","modified":"2025-04-18 14:25:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f671b515893beac8667b317d54474352_f795662a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f671b515893beac8667b317d54474352_f795662a-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f671b515893beac8667b317d54474352_f795662a-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f671b515893beac8667b317d54474352_f795662a-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f671b515893beac8667b317d54474352_f795662a-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f671b515893beac8667b317d54474352_f795662a.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f671b515893beac8667b317d54474352_f795662a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f671b515893beac8667b317d54474352_f795662a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f671b515893beac8667b317d54474352_f795662a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164493,"id":164493,"title":"eede2094f1ba647f282a842e31f7921b_db0c134c.jpg","filename":"eede2094f1ba647f282a842e31f7921b_db0c134c.jpg","filesize":276927,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eede2094f1ba647f282a842e31f7921b_db0c134c.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/eede2094f1ba647f282a842e31f7921b_db0c134c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"eede2094f1ba647f282a842e31f7921b_db0c134c-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:47:58","modified":"2025-04-18 14:25:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eede2094f1ba647f282a842e31f7921b_db0c134c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eede2094f1ba647f282a842e31f7921b_db0c134c-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eede2094f1ba647f282a842e31f7921b_db0c134c-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eede2094f1ba647f282a842e31f7921b_db0c134c-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eede2094f1ba647f282a842e31f7921b_db0c134c-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eede2094f1ba647f282a842e31f7921b_db0c134c.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eede2094f1ba647f282a842e31f7921b_db0c134c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eede2094f1ba647f282a842e31f7921b_db0c134c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eede2094f1ba647f282a842e31f7921b_db0c134c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164500,"id":164500,"title":"a6c2c53ec61d0ef1f1faa74d5360944f_0e65fdc1.jpg","filename":"a6c2c53ec61d0ef1f1faa74d5360944f_0e65fdc1.jpg","filesize":242653,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6c2c53ec61d0ef1f1faa74d5360944f_0e65fdc1.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/a6c2c53ec61d0ef1f1faa74d5360944f_0e65fdc1-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a6c2c53ec61d0ef1f1faa74d5360944f_0e65fdc1-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:47:59","modified":"2025-04-18 14:25:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6c2c53ec61d0ef1f1faa74d5360944f_0e65fdc1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6c2c53ec61d0ef1f1faa74d5360944f_0e65fdc1-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6c2c53ec61d0ef1f1faa74d5360944f_0e65fdc1-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6c2c53ec61d0ef1f1faa74d5360944f_0e65fdc1-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6c2c53ec61d0ef1f1faa74d5360944f_0e65fdc1-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6c2c53ec61d0ef1f1faa74d5360944f_0e65fdc1.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6c2c53ec61d0ef1f1faa74d5360944f_0e65fdc1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6c2c53ec61d0ef1f1faa74d5360944f_0e65fdc1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6c2c53ec61d0ef1f1faa74d5360944f_0e65fdc1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164507,"id":164507,"title":"e399efcadea381a653e9bfafb91419c8_74077161.jpg","filename":"e399efcadea381a653e9bfafb91419c8_74077161.jpg","filesize":324130,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e399efcadea381a653e9bfafb91419c8_74077161.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/e399efcadea381a653e9bfafb91419c8_74077161-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e399efcadea381a653e9bfafb91419c8_74077161-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:48:00","modified":"2025-04-18 14:25:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e399efcadea381a653e9bfafb91419c8_74077161-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e399efcadea381a653e9bfafb91419c8_74077161-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e399efcadea381a653e9bfafb91419c8_74077161-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e399efcadea381a653e9bfafb91419c8_74077161-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e399efcadea381a653e9bfafb91419c8_74077161-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e399efcadea381a653e9bfafb91419c8_74077161.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e399efcadea381a653e9bfafb91419c8_74077161.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e399efcadea381a653e9bfafb91419c8_74077161.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e399efcadea381a653e9bfafb91419c8_74077161.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164514,"id":164514,"title":"a6d338d489715fc36e84ddf751b4b1a7_1414953b.jpg","filename":"a6d338d489715fc36e84ddf751b4b1a7_1414953b.jpg","filesize":219772,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6d338d489715fc36e84ddf751b4b1a7_1414953b.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/a6d338d489715fc36e84ddf751b4b1a7_1414953b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a6d338d489715fc36e84ddf751b4b1a7_1414953b-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:48:01","modified":"2025-04-18 14:25:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6d338d489715fc36e84ddf751b4b1a7_1414953b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6d338d489715fc36e84ddf751b4b1a7_1414953b-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6d338d489715fc36e84ddf751b4b1a7_1414953b-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6d338d489715fc36e84ddf751b4b1a7_1414953b-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6d338d489715fc36e84ddf751b4b1a7_1414953b-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6d338d489715fc36e84ddf751b4b1a7_1414953b.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6d338d489715fc36e84ddf751b4b1a7_1414953b.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6d338d489715fc36e84ddf751b4b1a7_1414953b.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a6d338d489715fc36e84ddf751b4b1a7_1414953b.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164521,"id":164521,"title":"c560a3acfef27533d05c433b88ad3c01_699daf0d.jpg","filename":"c560a3acfef27533d05c433b88ad3c01_699daf0d.jpg","filesize":237916,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c560a3acfef27533d05c433b88ad3c01_699daf0d.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/c560a3acfef27533d05c433b88ad3c01_699daf0d-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c560a3acfef27533d05c433b88ad3c01_699daf0d-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:48:02","modified":"2025-04-18 14:25:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c560a3acfef27533d05c433b88ad3c01_699daf0d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c560a3acfef27533d05c433b88ad3c01_699daf0d-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c560a3acfef27533d05c433b88ad3c01_699daf0d-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c560a3acfef27533d05c433b88ad3c01_699daf0d-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c560a3acfef27533d05c433b88ad3c01_699daf0d-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c560a3acfef27533d05c433b88ad3c01_699daf0d.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c560a3acfef27533d05c433b88ad3c01_699daf0d.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c560a3acfef27533d05c433b88ad3c01_699daf0d.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c560a3acfef27533d05c433b88ad3c01_699daf0d.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164528,"id":164528,"title":"d3a9e3f5d26eb511a64e4299c6cac0e9_f2d4f5c2.jpg","filename":"d3a9e3f5d26eb511a64e4299c6cac0e9_f2d4f5c2.jpg","filesize":153994,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3a9e3f5d26eb511a64e4299c6cac0e9_f2d4f5c2.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/d3a9e3f5d26eb511a64e4299c6cac0e9_f2d4f5c2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d3a9e3f5d26eb511a64e4299c6cac0e9_f2d4f5c2-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:48:03","modified":"2025-04-18 14:25:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3a9e3f5d26eb511a64e4299c6cac0e9_f2d4f5c2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3a9e3f5d26eb511a64e4299c6cac0e9_f2d4f5c2-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3a9e3f5d26eb511a64e4299c6cac0e9_f2d4f5c2-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3a9e3f5d26eb511a64e4299c6cac0e9_f2d4f5c2-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3a9e3f5d26eb511a64e4299c6cac0e9_f2d4f5c2-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3a9e3f5d26eb511a64e4299c6cac0e9_f2d4f5c2.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3a9e3f5d26eb511a64e4299c6cac0e9_f2d4f5c2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3a9e3f5d26eb511a64e4299c6cac0e9_f2d4f5c2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d3a9e3f5d26eb511a64e4299c6cac0e9_f2d4f5c2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164535,"id":164535,"title":"45aa7a110975cf88278455cf28e7eea8_22d08fb0.jpg","filename":"45aa7a110975cf88278455cf28e7eea8_22d08fb0.jpg","filesize":215327,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45aa7a110975cf88278455cf28e7eea8_22d08fb0.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/45aa7a110975cf88278455cf28e7eea8_22d08fb0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"45aa7a110975cf88278455cf28e7eea8_22d08fb0-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:48:04","modified":"2025-04-18 14:25:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45aa7a110975cf88278455cf28e7eea8_22d08fb0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45aa7a110975cf88278455cf28e7eea8_22d08fb0-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45aa7a110975cf88278455cf28e7eea8_22d08fb0-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45aa7a110975cf88278455cf28e7eea8_22d08fb0-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45aa7a110975cf88278455cf28e7eea8_22d08fb0-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45aa7a110975cf88278455cf28e7eea8_22d08fb0.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45aa7a110975cf88278455cf28e7eea8_22d08fb0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45aa7a110975cf88278455cf28e7eea8_22d08fb0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45aa7a110975cf88278455cf28e7eea8_22d08fb0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164542,"id":164542,"title":"cac737ff581ad5ee2ab8beb4f86d8b2e_ba3596e9.jpg","filename":"cac737ff581ad5ee2ab8beb4f86d8b2e_ba3596e9.jpg","filesize":203873,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cac737ff581ad5ee2ab8beb4f86d8b2e_ba3596e9.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/cac737ff581ad5ee2ab8beb4f86d8b2e_ba3596e9-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"cac737ff581ad5ee2ab8beb4f86d8b2e_ba3596e9-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:48:06","modified":"2025-04-18 14:25:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cac737ff581ad5ee2ab8beb4f86d8b2e_ba3596e9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cac737ff581ad5ee2ab8beb4f86d8b2e_ba3596e9-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cac737ff581ad5ee2ab8beb4f86d8b2e_ba3596e9-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cac737ff581ad5ee2ab8beb4f86d8b2e_ba3596e9-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cac737ff581ad5ee2ab8beb4f86d8b2e_ba3596e9-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cac737ff581ad5ee2ab8beb4f86d8b2e_ba3596e9.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cac737ff581ad5ee2ab8beb4f86d8b2e_ba3596e9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cac737ff581ad5ee2ab8beb4f86d8b2e_ba3596e9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cac737ff581ad5ee2ab8beb4f86d8b2e_ba3596e9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164549,"id":164549,"title":"bbc2c0427b958d521669e516de05e589_800a165c.jpg","filename":"bbc2c0427b958d521669e516de05e589_800a165c.jpg","filesize":207444,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bbc2c0427b958d521669e516de05e589_800a165c.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/bbc2c0427b958d521669e516de05e589_800a165c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"bbc2c0427b958d521669e516de05e589_800a165c-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:48:07","modified":"2025-04-18 14:25:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bbc2c0427b958d521669e516de05e589_800a165c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bbc2c0427b958d521669e516de05e589_800a165c-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bbc2c0427b958d521669e516de05e589_800a165c-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bbc2c0427b958d521669e516de05e589_800a165c-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bbc2c0427b958d521669e516de05e589_800a165c-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bbc2c0427b958d521669e516de05e589_800a165c.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bbc2c0427b958d521669e516de05e589_800a165c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bbc2c0427b958d521669e516de05e589_800a165c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bbc2c0427b958d521669e516de05e589_800a165c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":164556,"id":164556,"title":"f031290bfccc4d3d5271c333f1436b7b_960483b7.jpg","filename":"f031290bfccc4d3d5271c333f1436b7b_960483b7.jpg","filesize":224772,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f031290bfccc4d3d5271c333f1436b7b_960483b7.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/appartamento-madonna-delle-nevi\/f031290bfccc4d3d5271c333f1436b7b_960483b7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"f031290bfccc4d3d5271c333f1436b7b_960483b7-jpg-2","status":"inherit","uploaded_to":181249,"date":"2025-04-18 08:48:08","modified":"2025-04-18 14:25:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f031290bfccc4d3d5271c333f1436b7b_960483b7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f031290bfccc4d3d5271c333f1436b7b_960483b7-300x107.jpg","medium-width":300,"medium-height":107,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f031290bfccc4d3d5271c333f1436b7b_960483b7-768x275.jpg","medium_large-width":768,"medium_large-height":275,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f031290bfccc4d3d5271c333f1436b7b_960483b7-1024x366.jpg","large-width":1024,"large-height":366,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f031290bfccc4d3d5271c333f1436b7b_960483b7-1536x549.jpg","1536x1536-width":1536,"1536x1536-height":549,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f031290bfccc4d3d5271c333f1436b7b_960483b7.jpg","2048x2048-width":1580,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f031290bfccc4d3d5271c333f1436b7b_960483b7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":107,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f031290bfccc4d3d5271c333f1436b7b_960483b7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":143,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f031290bfccc4d3d5271c333f1436b7b_960483b7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":215}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""},"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""}},"description":"","indepth":"<p>Seriate es un municipio italiano de la provincia de B\u00e9rgamo en Lombard\u00eda, atravesado de norte a sur por el r\u00edo Serio. Se encuentra a unos 4 kil\u00f3metros al este de la capital or\u00f3bica B\u00e9rgamo y forma parte del \u00e1rea metropolitana de B\u00e9rgamo. El n\u00facleo urbano de Seriate se extiende sobre un \u00e1rea de 12,41 kil\u00f3metros cuadrados, predominantemente plana, situada a ambos lados del Serio, que lo atraviesa en direcci\u00f3n norte-sur.&#13;<br \/>\nLa atracci\u00f3n ejercida hist\u00f3ricamente por el \u00e1rea de Seriate, especialmente hacia otros municipios de la provincia de B\u00e9rgamo, se puede documentar f\u00e1cilmente a trav\u00e9s de la descomposici\u00f3n de los residentes: por un lado, aquellos que residen desde su nacimiento, y por otro, los inmigrantes; de este an\u00e1lisis se desprende que m\u00e1s del 60% de la poblaci\u00f3n proviene de fuera del \u00e1rea.&#13;<br \/>\nLa Seriate actual surgi\u00f3 a principios de los a\u00f1os sesenta, los a\u00f1os de la reconstrucci\u00f3n y el auge econ\u00f3mico. Tradicionalmente agr\u00edcola, a finales del siglo pasado vio nacer muchos complejos industriales: una f\u00e1brica de cerveza, plantas de tejido, industrias qu\u00edmicas y mec\u00e1nicas. Las perspectivas de bienestar aumentaron el fen\u00f3meno de la inmigraci\u00f3n y el \u00e1rea comenz\u00f3 a expandirse inicialmente a lo largo de las v\u00edas y luego como una mancha de aceite.&#13;<br \/>\nDespu\u00e9s de los a\u00f1os 60, con el cierre progresivo de las grandes f\u00e1bricas, el car\u00e1cter residencial de Seriate se consolid\u00f3 a\u00fan m\u00e1s. En esos a\u00f1os surgieron barrios completos desde cero, y con el incremento poblacional tambi\u00e9n surgi\u00f3 la necesidad de tener servicios de apoyo para la vida en el territorio. Esta necesidad ha acompa\u00f1ado a Seriate en las d\u00e9cadas siguientes, en las que se ha tratado de hacer del municipio una ciudad muy cercana a B\u00e9rgamo, pero que no es su periferia dormitorio.&#13;<br \/>\nSeriate es hoy un municipio con alta industrializaci\u00f3n, especialmente en el sector manufacturero y de la construcci\u00f3n, caracterizado por empresas de peque\u00f1o tama\u00f1o. Tambi\u00e9n es importante el sector terciario, relacionado tanto con la presencia de servicios sanitarios (la estructura hospitalaria) como de servicios p\u00fablicos (ayuntamiento, escuelas, correos), as\u00ed como con un sector comercial proporcional al peso demogr\u00e1fico del municipio.&#13;<br \/>\nMediante recursos propios y en colaboraci\u00f3n con los del propio territorio, el municipio garantiza servicios y promueve actividades e iniciativas para todas las franjas de edad. Servicios importantes no solo para la ciudad, sino tambi\u00e9n para los municipios cercanos, respecto a los cuales Seriate es un punto de referencia.&#13;<br \/>\nLa zona es muy apreciada por los ciclistas debido a la cercan\u00eda de las subidas m\u00e1s famosas, que a menudo son protagonistas en las famosas competiciones del Giro de Italia y el Giro de Lombard\u00eda para profesionales, as\u00ed como en numerosas competiciones amateur.&#13;<br \/>\nA 3 kil\u00f3metros del apartamento se encuentran las famosas colinas de Scanzorosciate, donde se produce el prestigioso Moscato de Scanzo. Durante el a\u00f1o se organizan rutas gastron\u00f3micas y festivales tem\u00e1ticos.&#13;<br \/>\nLa ubicaci\u00f3n estrat\u00e9gica del apartamento le permitir\u00e1 explorar f\u00e1cilmente el territorio de B\u00e9rgamo y sus alrededores. En las cercan\u00edas encontrar\u00e1:&#13;<br \/>\n&#8211; B\u00e9rgamo Citt\u00e0 Alta (11 km)- Feria de B\u00e9rgamo (3,5 km)- Centro de congresos Papa Giovanni XXIII (5,7 km)- Aeropuerto Caravaggio de Orio al Serio (10 km)- Hospital Bolognini de Seriate (1,8 km)- Hospital Papa Giovanni XXIII (11 km)- Academia Carrara (7,8 km)- Leolandia (27 km)- Estadio Gewiss (7,4 km)- Parque Faun\u00edstico Le Cornelle (17 km)- Observatorio astron\u00f3mico La Torre del Sole (18,5 km)<\/p>\n","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.691203","longitude":"9.724294","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"Rizzi Omar","registered_office":"Via Leonardo Da Vinci 10 , 24040 Osio Sopra (BG)","iu_addr_streetnumber":"Piazza Madonna delle Nevi, 23","iu_addr_postalcode":"24068","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+393201446025","iu_cell":"+393201446025","iu_website":"https:\/\/omar7379.wixsite.com\/madseriate","iu_email":"madseriate@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"2","iu_beds":"5","id_madeep":"","id_visit_manza":"10647","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"time":"<p>&#13;<br \/>\nCheck-in dopo le ore 15:00&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\nCheck-out entro le ore 10:00&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n\u00a0&#13;<br \/>\nMassimo 5 ospiti&#13;<br \/>\n&#13;<br \/>\n\u00a0&#13;<br \/>\nSiamo dotati di &#8216;Self Check-in&#8217; per agevolarti nell&#8217;orario di arrivo. &#13;<br \/>\nAppena fuori dall&#8217;appartamento \u00e8 presente una security box con combinazione dove troverai le chiavi di accesso. La combinazione verr\u00e0 fornita alla prenotazione.&#13;<br \/>\n&#13;<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"elevator","label":"Ascensore"},{"value":"laundry","label":"Lavanderia"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"wifi","label":"Wi-Fi"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"balcony","label":"Balcone"},{"value":"tv_room","label":"TV in camera"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"},{"value":"amex","label":"American Express"},{"value":"diners","label":"Diners Club"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/181249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/181249\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/164436"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=181249"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=181249"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=181249"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=181249"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=181249"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=181249"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=181249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}