{"id":181299,"date":"2025-04-18T13:27:53","date_gmt":"2025-04-18T11:27:53","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/centrale\/"},"modified":"2025-04-18T16:26:54","modified_gmt":"2025-04-18T14:26:54","slug":"centrale-2","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/","title":{"rendered":"CENTRALE"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":165439,"template":"","categories":[1009],"tags":[],"aggr":[],"area":[],"kind":[18726],"zona":[],"class_list":["post-181299","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-dormir","kind-strutturaricettiva-es"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"CENTRALE","hero_text":"<p><span id='docs-internal-guid-84e2fb45-7fff-7a02-a497-49ddd50614d0'><span>En Orio al Serio, 1,1 km lejos del aeropuerto, CENTRALE proporciona alojamientos muy bien equipados con conexi\u00f3n a internet gratis. <\/span><\/span><\/p>\n","slides":[{"image":{"ID":165439,"id":165439,"title":"8c51384e7d998a6239db8b8309256ec2_94ffff34.jpg","filename":"8c51384e7d998a6239db8b8309256ec2_94ffff34.jpg","filesize":658023,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c51384e7d998a6239db8b8309256ec2_94ffff34.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/8c51384e7d998a6239db8b8309256ec2_94ffff34-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"8c51384e7d998a6239db8b8309256ec2_94ffff34-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:44","modified":"2025-04-18 14:27:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c51384e7d998a6239db8b8309256ec2_94ffff34-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c51384e7d998a6239db8b8309256ec2_94ffff34-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c51384e7d998a6239db8b8309256ec2_94ffff34-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c51384e7d998a6239db8b8309256ec2_94ffff34-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c51384e7d998a6239db8b8309256ec2_94ffff34.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c51384e7d998a6239db8b8309256ec2_94ffff34.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c51384e7d998a6239db8b8309256ec2_94ffff34.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c51384e7d998a6239db8b8309256ec2_94ffff34.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8c51384e7d998a6239db8b8309256ec2_94ffff34.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165446,"id":165446,"title":"39674c2152321a2bdb26d1b075a12d2e_4ce4cce0.jpg","filename":"39674c2152321a2bdb26d1b075a12d2e_4ce4cce0.jpg","filesize":958044,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/39674c2152321a2bdb26d1b075a12d2e_4ce4cce0.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/39674c2152321a2bdb26d1b075a12d2e_4ce4cce0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"39674c2152321a2bdb26d1b075a12d2e_4ce4cce0-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:45","modified":"2025-04-18 14:27:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/39674c2152321a2bdb26d1b075a12d2e_4ce4cce0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/39674c2152321a2bdb26d1b075a12d2e_4ce4cce0-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/39674c2152321a2bdb26d1b075a12d2e_4ce4cce0-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/39674c2152321a2bdb26d1b075a12d2e_4ce4cce0-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/39674c2152321a2bdb26d1b075a12d2e_4ce4cce0.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/39674c2152321a2bdb26d1b075a12d2e_4ce4cce0.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/39674c2152321a2bdb26d1b075a12d2e_4ce4cce0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/39674c2152321a2bdb26d1b075a12d2e_4ce4cce0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/39674c2152321a2bdb26d1b075a12d2e_4ce4cce0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165453,"id":165453,"title":"2490f090998007529d07822a64de7afc_9331a126.jpg","filename":"2490f090998007529d07822a64de7afc_9331a126.jpg","filesize":624616,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2490f090998007529d07822a64de7afc_9331a126.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/2490f090998007529d07822a64de7afc_9331a126-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"2490f090998007529d07822a64de7afc_9331a126-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:46","modified":"2025-04-18 14:27:19","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2490f090998007529d07822a64de7afc_9331a126-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2490f090998007529d07822a64de7afc_9331a126-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2490f090998007529d07822a64de7afc_9331a126-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2490f090998007529d07822a64de7afc_9331a126-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2490f090998007529d07822a64de7afc_9331a126.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2490f090998007529d07822a64de7afc_9331a126.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2490f090998007529d07822a64de7afc_9331a126.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2490f090998007529d07822a64de7afc_9331a126.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2490f090998007529d07822a64de7afc_9331a126.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165460,"id":165460,"title":"adbc2f3b1c5ecd550303adf4f12b18a5_266e0f63.jpg","filename":"adbc2f3b1c5ecd550303adf4f12b18a5_266e0f63.jpg","filesize":585206,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/adbc2f3b1c5ecd550303adf4f12b18a5_266e0f63.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/adbc2f3b1c5ecd550303adf4f12b18a5_266e0f63-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"adbc2f3b1c5ecd550303adf4f12b18a5_266e0f63-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:48","modified":"2025-04-18 14:27:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/adbc2f3b1c5ecd550303adf4f12b18a5_266e0f63-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/adbc2f3b1c5ecd550303adf4f12b18a5_266e0f63-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/adbc2f3b1c5ecd550303adf4f12b18a5_266e0f63-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/adbc2f3b1c5ecd550303adf4f12b18a5_266e0f63-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/adbc2f3b1c5ecd550303adf4f12b18a5_266e0f63.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/adbc2f3b1c5ecd550303adf4f12b18a5_266e0f63.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/adbc2f3b1c5ecd550303adf4f12b18a5_266e0f63.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/adbc2f3b1c5ecd550303adf4f12b18a5_266e0f63.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/adbc2f3b1c5ecd550303adf4f12b18a5_266e0f63.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165467,"id":165467,"title":"f3a49e4c7efed436ba930b61464a4a18_bd00a1f1.jpg","filename":"f3a49e4c7efed436ba930b61464a4a18_bd00a1f1.jpg","filesize":810313,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3a49e4c7efed436ba930b61464a4a18_bd00a1f1.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/f3a49e4c7efed436ba930b61464a4a18_bd00a1f1-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"f3a49e4c7efed436ba930b61464a4a18_bd00a1f1-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:49","modified":"2025-04-18 14:27:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1000,"height":1500,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3a49e4c7efed436ba930b61464a4a18_bd00a1f1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3a49e4c7efed436ba930b61464a4a18_bd00a1f1-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3a49e4c7efed436ba930b61464a4a18_bd00a1f1-768x1152.jpg","medium_large-width":768,"medium_large-height":1152,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3a49e4c7efed436ba930b61464a4a18_bd00a1f1-683x1024.jpg","large-width":683,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3a49e4c7efed436ba930b61464a4a18_bd00a1f1.jpg","1536x1536-width":1000,"1536x1536-height":1500,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3a49e4c7efed436ba930b61464a4a18_bd00a1f1.jpg","2048x2048-width":1000,"2048x2048-height":1500,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3a49e4c7efed436ba930b61464a4a18_bd00a1f1.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3a49e4c7efed436ba930b61464a4a18_bd00a1f1.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3a49e4c7efed436ba930b61464a4a18_bd00a1f1.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165474,"id":165474,"title":"f3dca16a7451a05a0764e07e4f84d868_0c66f607.jpg","filename":"f3dca16a7451a05a0764e07e4f84d868_0c66f607.jpg","filesize":562626,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3dca16a7451a05a0764e07e4f84d868_0c66f607.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/f3dca16a7451a05a0764e07e4f84d868_0c66f607-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"f3dca16a7451a05a0764e07e4f84d868_0c66f607-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:50","modified":"2025-04-18 14:27:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3dca16a7451a05a0764e07e4f84d868_0c66f607-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3dca16a7451a05a0764e07e4f84d868_0c66f607-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3dca16a7451a05a0764e07e4f84d868_0c66f607-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3dca16a7451a05a0764e07e4f84d868_0c66f607-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3dca16a7451a05a0764e07e4f84d868_0c66f607.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3dca16a7451a05a0764e07e4f84d868_0c66f607.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3dca16a7451a05a0764e07e4f84d868_0c66f607.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3dca16a7451a05a0764e07e4f84d868_0c66f607.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f3dca16a7451a05a0764e07e4f84d868_0c66f607.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165481,"id":165481,"title":"fa2b2f0b6eb2561364525de83c3994c3_b2a9fdd8.jpg","filename":"fa2b2f0b6eb2561364525de83c3994c3_b2a9fdd8.jpg","filesize":653217,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa2b2f0b6eb2561364525de83c3994c3_b2a9fdd8.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/fa2b2f0b6eb2561364525de83c3994c3_b2a9fdd8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"fa2b2f0b6eb2561364525de83c3994c3_b2a9fdd8-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:51","modified":"2025-04-18 14:27:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa2b2f0b6eb2561364525de83c3994c3_b2a9fdd8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa2b2f0b6eb2561364525de83c3994c3_b2a9fdd8-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa2b2f0b6eb2561364525de83c3994c3_b2a9fdd8-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa2b2f0b6eb2561364525de83c3994c3_b2a9fdd8-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa2b2f0b6eb2561364525de83c3994c3_b2a9fdd8.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa2b2f0b6eb2561364525de83c3994c3_b2a9fdd8.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa2b2f0b6eb2561364525de83c3994c3_b2a9fdd8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa2b2f0b6eb2561364525de83c3994c3_b2a9fdd8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fa2b2f0b6eb2561364525de83c3994c3_b2a9fdd8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165488,"id":165488,"title":"c541d9e3361efa6c702f85f2c371c122_40abede0.jpg","filename":"c541d9e3361efa6c702f85f2c371c122_40abede0.jpg","filesize":603430,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c541d9e3361efa6c702f85f2c371c122_40abede0.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/c541d9e3361efa6c702f85f2c371c122_40abede0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c541d9e3361efa6c702f85f2c371c122_40abede0-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:52","modified":"2025-04-18 14:27:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1461,"height":972,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c541d9e3361efa6c702f85f2c371c122_40abede0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c541d9e3361efa6c702f85f2c371c122_40abede0-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c541d9e3361efa6c702f85f2c371c122_40abede0-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c541d9e3361efa6c702f85f2c371c122_40abede0-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c541d9e3361efa6c702f85f2c371c122_40abede0.jpg","1536x1536-width":1461,"1536x1536-height":972,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c541d9e3361efa6c702f85f2c371c122_40abede0.jpg","2048x2048-width":1461,"2048x2048-height":972,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c541d9e3361efa6c702f85f2c371c122_40abede0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c541d9e3361efa6c702f85f2c371c122_40abede0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c541d9e3361efa6c702f85f2c371c122_40abede0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165495,"id":165495,"title":"67f9dca461c25d173d4a1b295bf0aef2_6f34b1a3.jpg","filename":"67f9dca461c25d173d4a1b295bf0aef2_6f34b1a3.jpg","filesize":593331,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67f9dca461c25d173d4a1b295bf0aef2_6f34b1a3.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/67f9dca461c25d173d4a1b295bf0aef2_6f34b1a3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"67f9dca461c25d173d4a1b295bf0aef2_6f34b1a3-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:53","modified":"2025-04-18 14:27:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67f9dca461c25d173d4a1b295bf0aef2_6f34b1a3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67f9dca461c25d173d4a1b295bf0aef2_6f34b1a3-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67f9dca461c25d173d4a1b295bf0aef2_6f34b1a3-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67f9dca461c25d173d4a1b295bf0aef2_6f34b1a3-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67f9dca461c25d173d4a1b295bf0aef2_6f34b1a3.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67f9dca461c25d173d4a1b295bf0aef2_6f34b1a3.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67f9dca461c25d173d4a1b295bf0aef2_6f34b1a3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67f9dca461c25d173d4a1b295bf0aef2_6f34b1a3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/67f9dca461c25d173d4a1b295bf0aef2_6f34b1a3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165502,"id":165502,"title":"3c62c2fd7ecad728eec2390b0a348864_740bf820.jpg","filename":"3c62c2fd7ecad728eec2390b0a348864_740bf820.jpg","filesize":553962,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c62c2fd7ecad728eec2390b0a348864_740bf820.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/3c62c2fd7ecad728eec2390b0a348864_740bf820-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3c62c2fd7ecad728eec2390b0a348864_740bf820-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:54","modified":"2025-04-18 14:27:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c62c2fd7ecad728eec2390b0a348864_740bf820-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c62c2fd7ecad728eec2390b0a348864_740bf820-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c62c2fd7ecad728eec2390b0a348864_740bf820-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c62c2fd7ecad728eec2390b0a348864_740bf820-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c62c2fd7ecad728eec2390b0a348864_740bf820.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c62c2fd7ecad728eec2390b0a348864_740bf820.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c62c2fd7ecad728eec2390b0a348864_740bf820.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c62c2fd7ecad728eec2390b0a348864_740bf820.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c62c2fd7ecad728eec2390b0a348864_740bf820.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165509,"id":165509,"title":"4f536715b82c4b0a5ecde34d853b0a4b_e0fc4536.jpg","filename":"4f536715b82c4b0a5ecde34d853b0a4b_e0fc4536.jpg","filesize":428442,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f536715b82c4b0a5ecde34d853b0a4b_e0fc4536.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/4f536715b82c4b0a5ecde34d853b0a4b_e0fc4536-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4f536715b82c4b0a5ecde34d853b0a4b_e0fc4536-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:55","modified":"2025-04-18 14:27:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1340,"height":892,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f536715b82c4b0a5ecde34d853b0a4b_e0fc4536-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f536715b82c4b0a5ecde34d853b0a4b_e0fc4536-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f536715b82c4b0a5ecde34d853b0a4b_e0fc4536-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f536715b82c4b0a5ecde34d853b0a4b_e0fc4536-1024x682.jpg","large-width":1024,"large-height":682,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f536715b82c4b0a5ecde34d853b0a4b_e0fc4536.jpg","1536x1536-width":1340,"1536x1536-height":892,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f536715b82c4b0a5ecde34d853b0a4b_e0fc4536.jpg","2048x2048-width":1340,"2048x2048-height":892,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f536715b82c4b0a5ecde34d853b0a4b_e0fc4536.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f536715b82c4b0a5ecde34d853b0a4b_e0fc4536.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4f536715b82c4b0a5ecde34d853b0a4b_e0fc4536.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165516,"id":165516,"title":"5fe793fdc101608400dd2667a8ba1437_3b397968.jpg","filename":"5fe793fdc101608400dd2667a8ba1437_3b397968.jpg","filesize":522739,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5fe793fdc101608400dd2667a8ba1437_3b397968.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/5fe793fdc101608400dd2667a8ba1437_3b397968-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"5fe793fdc101608400dd2667a8ba1437_3b397968-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:56","modified":"2025-04-18 14:27:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1000,"height":1500,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5fe793fdc101608400dd2667a8ba1437_3b397968-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5fe793fdc101608400dd2667a8ba1437_3b397968-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5fe793fdc101608400dd2667a8ba1437_3b397968-768x1152.jpg","medium_large-width":768,"medium_large-height":1152,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5fe793fdc101608400dd2667a8ba1437_3b397968-683x1024.jpg","large-width":683,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5fe793fdc101608400dd2667a8ba1437_3b397968.jpg","1536x1536-width":1000,"1536x1536-height":1500,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5fe793fdc101608400dd2667a8ba1437_3b397968.jpg","2048x2048-width":1000,"2048x2048-height":1500,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5fe793fdc101608400dd2667a8ba1437_3b397968.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5fe793fdc101608400dd2667a8ba1437_3b397968.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5fe793fdc101608400dd2667a8ba1437_3b397968.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165523,"id":165523,"title":"bb2b72611bfaf21a6c31db8780b4b5ed_4a0a25cc.jpg","filename":"bb2b72611bfaf21a6c31db8780b4b5ed_4a0a25cc.jpg","filesize":445828,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bb2b72611bfaf21a6c31db8780b4b5ed_4a0a25cc.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/bb2b72611bfaf21a6c31db8780b4b5ed_4a0a25cc-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"bb2b72611bfaf21a6c31db8780b4b5ed_4a0a25cc-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:57","modified":"2025-04-18 14:27:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bb2b72611bfaf21a6c31db8780b4b5ed_4a0a25cc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bb2b72611bfaf21a6c31db8780b4b5ed_4a0a25cc-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bb2b72611bfaf21a6c31db8780b4b5ed_4a0a25cc-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bb2b72611bfaf21a6c31db8780b4b5ed_4a0a25cc-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bb2b72611bfaf21a6c31db8780b4b5ed_4a0a25cc.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bb2b72611bfaf21a6c31db8780b4b5ed_4a0a25cc.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bb2b72611bfaf21a6c31db8780b4b5ed_4a0a25cc.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bb2b72611bfaf21a6c31db8780b4b5ed_4a0a25cc.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bb2b72611bfaf21a6c31db8780b4b5ed_4a0a25cc.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165530,"id":165530,"title":"b7f86c879f9e9f5117dbd4371d11142d_b2d97a9b.jpg","filename":"b7f86c879f9e9f5117dbd4371d11142d_b2d97a9b.jpg","filesize":526277,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7f86c879f9e9f5117dbd4371d11142d_b2d97a9b.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/b7f86c879f9e9f5117dbd4371d11142d_b2d97a9b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"b7f86c879f9e9f5117dbd4371d11142d_b2d97a9b-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:58","modified":"2025-04-18 14:27:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7f86c879f9e9f5117dbd4371d11142d_b2d97a9b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7f86c879f9e9f5117dbd4371d11142d_b2d97a9b-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7f86c879f9e9f5117dbd4371d11142d_b2d97a9b-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7f86c879f9e9f5117dbd4371d11142d_b2d97a9b-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7f86c879f9e9f5117dbd4371d11142d_b2d97a9b.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7f86c879f9e9f5117dbd4371d11142d_b2d97a9b.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7f86c879f9e9f5117dbd4371d11142d_b2d97a9b.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7f86c879f9e9f5117dbd4371d11142d_b2d97a9b.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b7f86c879f9e9f5117dbd4371d11142d_b2d97a9b.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165537,"id":165537,"title":"49fa5f38b592c2178a54d59e2f4e6f34_afb5a0ce.jpg","filename":"49fa5f38b592c2178a54d59e2f4e6f34_afb5a0ce.jpg","filesize":473687,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/49fa5f38b592c2178a54d59e2f4e6f34_afb5a0ce.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/49fa5f38b592c2178a54d59e2f4e6f34_afb5a0ce-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"49fa5f38b592c2178a54d59e2f4e6f34_afb5a0ce-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:51:59","modified":"2025-04-18 14:27:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/49fa5f38b592c2178a54d59e2f4e6f34_afb5a0ce-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/49fa5f38b592c2178a54d59e2f4e6f34_afb5a0ce-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/49fa5f38b592c2178a54d59e2f4e6f34_afb5a0ce-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/49fa5f38b592c2178a54d59e2f4e6f34_afb5a0ce-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/49fa5f38b592c2178a54d59e2f4e6f34_afb5a0ce.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/49fa5f38b592c2178a54d59e2f4e6f34_afb5a0ce.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/49fa5f38b592c2178a54d59e2f4e6f34_afb5a0ce.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/49fa5f38b592c2178a54d59e2f4e6f34_afb5a0ce.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/49fa5f38b592c2178a54d59e2f4e6f34_afb5a0ce.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165544,"id":165544,"title":"5a6b43f702ecf9c8aa2092834db8acf0_0ae24a00.jpg","filename":"5a6b43f702ecf9c8aa2092834db8acf0_0ae24a00.jpg","filesize":555573,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a6b43f702ecf9c8aa2092834db8acf0_0ae24a00.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/5a6b43f702ecf9c8aa2092834db8acf0_0ae24a00-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"5a6b43f702ecf9c8aa2092834db8acf0_0ae24a00-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:52:00","modified":"2025-04-18 14:27:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1000,"height":1500,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a6b43f702ecf9c8aa2092834db8acf0_0ae24a00-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a6b43f702ecf9c8aa2092834db8acf0_0ae24a00-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a6b43f702ecf9c8aa2092834db8acf0_0ae24a00-768x1152.jpg","medium_large-width":768,"medium_large-height":1152,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a6b43f702ecf9c8aa2092834db8acf0_0ae24a00-683x1024.jpg","large-width":683,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a6b43f702ecf9c8aa2092834db8acf0_0ae24a00.jpg","1536x1536-width":1000,"1536x1536-height":1500,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a6b43f702ecf9c8aa2092834db8acf0_0ae24a00.jpg","2048x2048-width":1000,"2048x2048-height":1500,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a6b43f702ecf9c8aa2092834db8acf0_0ae24a00.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a6b43f702ecf9c8aa2092834db8acf0_0ae24a00.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a6b43f702ecf9c8aa2092834db8acf0_0ae24a00.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165551,"id":165551,"title":"56fbc597126885205520887eb41781a3_9149b56d.jpg","filename":"56fbc597126885205520887eb41781a3_9149b56d.jpg","filesize":460150,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56fbc597126885205520887eb41781a3_9149b56d.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/56fbc597126885205520887eb41781a3_9149b56d-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"56fbc597126885205520887eb41781a3_9149b56d-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:52:02","modified":"2025-04-18 14:27:20","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1472,"height":980,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56fbc597126885205520887eb41781a3_9149b56d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56fbc597126885205520887eb41781a3_9149b56d-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56fbc597126885205520887eb41781a3_9149b56d-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56fbc597126885205520887eb41781a3_9149b56d-1024x682.jpg","large-width":1024,"large-height":682,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56fbc597126885205520887eb41781a3_9149b56d.jpg","1536x1536-width":1472,"1536x1536-height":980,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56fbc597126885205520887eb41781a3_9149b56d.jpg","2048x2048-width":1472,"2048x2048-height":980,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56fbc597126885205520887eb41781a3_9149b56d.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56fbc597126885205520887eb41781a3_9149b56d.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/56fbc597126885205520887eb41781a3_9149b56d.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165558,"id":165558,"title":"80ffed11680d08b8a1f59bd6770c46be_52170a20.jpg","filename":"80ffed11680d08b8a1f59bd6770c46be_52170a20.jpg","filesize":699318,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80ffed11680d08b8a1f59bd6770c46be_52170a20.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/80ffed11680d08b8a1f59bd6770c46be_52170a20-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"80ffed11680d08b8a1f59bd6770c46be_52170a20-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:52:03","modified":"2025-04-18 14:27:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80ffed11680d08b8a1f59bd6770c46be_52170a20-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80ffed11680d08b8a1f59bd6770c46be_52170a20-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80ffed11680d08b8a1f59bd6770c46be_52170a20-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80ffed11680d08b8a1f59bd6770c46be_52170a20-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80ffed11680d08b8a1f59bd6770c46be_52170a20.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80ffed11680d08b8a1f59bd6770c46be_52170a20.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80ffed11680d08b8a1f59bd6770c46be_52170a20.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80ffed11680d08b8a1f59bd6770c46be_52170a20.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/80ffed11680d08b8a1f59bd6770c46be_52170a20.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165565,"id":165565,"title":"1578267f478131298ce82d71bf9b31d9_75b10145.jpg","filename":"1578267f478131298ce82d71bf9b31d9_75b10145.jpg","filesize":617269,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1578267f478131298ce82d71bf9b31d9_75b10145.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/1578267f478131298ce82d71bf9b31d9_75b10145-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1578267f478131298ce82d71bf9b31d9_75b10145-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:52:04","modified":"2025-04-18 14:27:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1578267f478131298ce82d71bf9b31d9_75b10145-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1578267f478131298ce82d71bf9b31d9_75b10145-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1578267f478131298ce82d71bf9b31d9_75b10145-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1578267f478131298ce82d71bf9b31d9_75b10145-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1578267f478131298ce82d71bf9b31d9_75b10145.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1578267f478131298ce82d71bf9b31d9_75b10145.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1578267f478131298ce82d71bf9b31d9_75b10145.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1578267f478131298ce82d71bf9b31d9_75b10145.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1578267f478131298ce82d71bf9b31d9_75b10145.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165572,"id":165572,"title":"b6bc5c00cf2e0abd7e6f6f1e2647e0cc_426ce47d.jpg","filename":"b6bc5c00cf2e0abd7e6f6f1e2647e0cc_426ce47d.jpg","filesize":679022,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b6bc5c00cf2e0abd7e6f6f1e2647e0cc_426ce47d.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/b6bc5c00cf2e0abd7e6f6f1e2647e0cc_426ce47d-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"b6bc5c00cf2e0abd7e6f6f1e2647e0cc_426ce47d-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:52:05","modified":"2025-04-18 14:27:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b6bc5c00cf2e0abd7e6f6f1e2647e0cc_426ce47d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b6bc5c00cf2e0abd7e6f6f1e2647e0cc_426ce47d-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b6bc5c00cf2e0abd7e6f6f1e2647e0cc_426ce47d-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b6bc5c00cf2e0abd7e6f6f1e2647e0cc_426ce47d-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b6bc5c00cf2e0abd7e6f6f1e2647e0cc_426ce47d.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b6bc5c00cf2e0abd7e6f6f1e2647e0cc_426ce47d.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b6bc5c00cf2e0abd7e6f6f1e2647e0cc_426ce47d.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b6bc5c00cf2e0abd7e6f6f1e2647e0cc_426ce47d.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b6bc5c00cf2e0abd7e6f6f1e2647e0cc_426ce47d.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165579,"id":165579,"title":"d84e1d30f78d4b6d550b8359f969a3dd_b4a9acf2.jpg","filename":"d84e1d30f78d4b6d550b8359f969a3dd_b4a9acf2.jpg","filesize":495490,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d84e1d30f78d4b6d550b8359f969a3dd_b4a9acf2.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/d84e1d30f78d4b6d550b8359f969a3dd_b4a9acf2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d84e1d30f78d4b6d550b8359f969a3dd_b4a9acf2-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:52:06","modified":"2025-04-18 14:27:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1328,"height":884,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d84e1d30f78d4b6d550b8359f969a3dd_b4a9acf2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d84e1d30f78d4b6d550b8359f969a3dd_b4a9acf2-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d84e1d30f78d4b6d550b8359f969a3dd_b4a9acf2-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d84e1d30f78d4b6d550b8359f969a3dd_b4a9acf2-1024x682.jpg","large-width":1024,"large-height":682,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d84e1d30f78d4b6d550b8359f969a3dd_b4a9acf2.jpg","1536x1536-width":1328,"1536x1536-height":884,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d84e1d30f78d4b6d550b8359f969a3dd_b4a9acf2.jpg","2048x2048-width":1328,"2048x2048-height":884,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d84e1d30f78d4b6d550b8359f969a3dd_b4a9acf2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d84e1d30f78d4b6d550b8359f969a3dd_b4a9acf2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d84e1d30f78d4b6d550b8359f969a3dd_b4a9acf2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165586,"id":165586,"title":"6eee21c4a40a0a7848f1450d944c0c96_4fc16e9b.jpg","filename":"6eee21c4a40a0a7848f1450d944c0c96_4fc16e9b.jpg","filesize":508750,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eee21c4a40a0a7848f1450d944c0c96_4fc16e9b.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/6eee21c4a40a0a7848f1450d944c0c96_4fc16e9b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6eee21c4a40a0a7848f1450d944c0c96_4fc16e9b-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:52:07","modified":"2025-04-18 14:27:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eee21c4a40a0a7848f1450d944c0c96_4fc16e9b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eee21c4a40a0a7848f1450d944c0c96_4fc16e9b-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eee21c4a40a0a7848f1450d944c0c96_4fc16e9b-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eee21c4a40a0a7848f1450d944c0c96_4fc16e9b-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eee21c4a40a0a7848f1450d944c0c96_4fc16e9b.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eee21c4a40a0a7848f1450d944c0c96_4fc16e9b.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eee21c4a40a0a7848f1450d944c0c96_4fc16e9b.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eee21c4a40a0a7848f1450d944c0c96_4fc16e9b.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6eee21c4a40a0a7848f1450d944c0c96_4fc16e9b.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165593,"id":165593,"title":"0c96f46a27276b53d5fc2a0a7b3183cb_3d229824.jpg","filename":"0c96f46a27276b53d5fc2a0a7b3183cb_3d229824.jpg","filesize":579384,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0c96f46a27276b53d5fc2a0a7b3183cb_3d229824.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/0c96f46a27276b53d5fc2a0a7b3183cb_3d229824-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"0c96f46a27276b53d5fc2a0a7b3183cb_3d229824-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:52:09","modified":"2025-04-18 14:27:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0c96f46a27276b53d5fc2a0a7b3183cb_3d229824-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0c96f46a27276b53d5fc2a0a7b3183cb_3d229824-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0c96f46a27276b53d5fc2a0a7b3183cb_3d229824-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0c96f46a27276b53d5fc2a0a7b3183cb_3d229824-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0c96f46a27276b53d5fc2a0a7b3183cb_3d229824.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0c96f46a27276b53d5fc2a0a7b3183cb_3d229824.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0c96f46a27276b53d5fc2a0a7b3183cb_3d229824.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0c96f46a27276b53d5fc2a0a7b3183cb_3d229824.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0c96f46a27276b53d5fc2a0a7b3183cb_3d229824.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165600,"id":165600,"title":"e97ecd52fa98283063bba7c50d936dc4_2f75e414.jpg","filename":"e97ecd52fa98283063bba7c50d936dc4_2f75e414.jpg","filesize":488390,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e97ecd52fa98283063bba7c50d936dc4_2f75e414.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/e97ecd52fa98283063bba7c50d936dc4_2f75e414-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e97ecd52fa98283063bba7c50d936dc4_2f75e414-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:52:10","modified":"2025-04-18 14:27:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e97ecd52fa98283063bba7c50d936dc4_2f75e414-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e97ecd52fa98283063bba7c50d936dc4_2f75e414-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e97ecd52fa98283063bba7c50d936dc4_2f75e414-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e97ecd52fa98283063bba7c50d936dc4_2f75e414-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e97ecd52fa98283063bba7c50d936dc4_2f75e414.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e97ecd52fa98283063bba7c50d936dc4_2f75e414.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e97ecd52fa98283063bba7c50d936dc4_2f75e414.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e97ecd52fa98283063bba7c50d936dc4_2f75e414.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e97ecd52fa98283063bba7c50d936dc4_2f75e414.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165607,"id":165607,"title":"3840f9019b23fa873265cf7835a27921_5e4fac0a.jpg","filename":"3840f9019b23fa873265cf7835a27921_5e4fac0a.jpg","filesize":462512,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3840f9019b23fa873265cf7835a27921_5e4fac0a.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/3840f9019b23fa873265cf7835a27921_5e4fac0a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3840f9019b23fa873265cf7835a27921_5e4fac0a-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:52:11","modified":"2025-04-18 14:27:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1000,"height":1500,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3840f9019b23fa873265cf7835a27921_5e4fac0a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3840f9019b23fa873265cf7835a27921_5e4fac0a-200x300.jpg","medium-width":200,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3840f9019b23fa873265cf7835a27921_5e4fac0a-768x1152.jpg","medium_large-width":768,"medium_large-height":1152,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3840f9019b23fa873265cf7835a27921_5e4fac0a-683x1024.jpg","large-width":683,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3840f9019b23fa873265cf7835a27921_5e4fac0a.jpg","1536x1536-width":1000,"1536x1536-height":1500,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3840f9019b23fa873265cf7835a27921_5e4fac0a.jpg","2048x2048-width":1000,"2048x2048-height":1500,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3840f9019b23fa873265cf7835a27921_5e4fac0a.jpg","gform-image-choice-sm-width":200,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3840f9019b23fa873265cf7835a27921_5e4fac0a.jpg","gform-image-choice-md-width":267,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3840f9019b23fa873265cf7835a27921_5e4fac0a.jpg","gform-image-choice-lg-width":400,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165614,"id":165614,"title":"57e6e13b7d7e57dd66080db79c3d4aa3_3fb78ffd.jpg","filename":"57e6e13b7d7e57dd66080db79c3d4aa3_3fb78ffd.jpg","filesize":897195,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57e6e13b7d7e57dd66080db79c3d4aa3_3fb78ffd.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/57e6e13b7d7e57dd66080db79c3d4aa3_3fb78ffd-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"57e6e13b7d7e57dd66080db79c3d4aa3_3fb78ffd-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:52:12","modified":"2025-04-18 14:27:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57e6e13b7d7e57dd66080db79c3d4aa3_3fb78ffd-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57e6e13b7d7e57dd66080db79c3d4aa3_3fb78ffd-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57e6e13b7d7e57dd66080db79c3d4aa3_3fb78ffd-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57e6e13b7d7e57dd66080db79c3d4aa3_3fb78ffd-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57e6e13b7d7e57dd66080db79c3d4aa3_3fb78ffd.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57e6e13b7d7e57dd66080db79c3d4aa3_3fb78ffd.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57e6e13b7d7e57dd66080db79c3d4aa3_3fb78ffd.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57e6e13b7d7e57dd66080db79c3d4aa3_3fb78ffd.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/57e6e13b7d7e57dd66080db79c3d4aa3_3fb78ffd.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165621,"id":165621,"title":"3de5f19da55e8338a9899ea36c251395_bbc22b35.jpg","filename":"3de5f19da55e8338a9899ea36c251395_bbc22b35.jpg","filesize":819753,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3de5f19da55e8338a9899ea36c251395_bbc22b35.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/3de5f19da55e8338a9899ea36c251395_bbc22b35-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3de5f19da55e8338a9899ea36c251395_bbc22b35-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:52:13","modified":"2025-04-18 14:27:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3de5f19da55e8338a9899ea36c251395_bbc22b35-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3de5f19da55e8338a9899ea36c251395_bbc22b35-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3de5f19da55e8338a9899ea36c251395_bbc22b35-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3de5f19da55e8338a9899ea36c251395_bbc22b35-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3de5f19da55e8338a9899ea36c251395_bbc22b35.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3de5f19da55e8338a9899ea36c251395_bbc22b35.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3de5f19da55e8338a9899ea36c251395_bbc22b35.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3de5f19da55e8338a9899ea36c251395_bbc22b35.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3de5f19da55e8338a9899ea36c251395_bbc22b35.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165628,"id":165628,"title":"bf31598db18786c8a74118619b5015b9_4b7630c1.jpg","filename":"bf31598db18786c8a74118619b5015b9_4b7630c1.jpg","filesize":532001,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf31598db18786c8a74118619b5015b9_4b7630c1.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/bf31598db18786c8a74118619b5015b9_4b7630c1-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"bf31598db18786c8a74118619b5015b9_4b7630c1-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:52:14","modified":"2025-04-18 14:27:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf31598db18786c8a74118619b5015b9_4b7630c1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf31598db18786c8a74118619b5015b9_4b7630c1-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf31598db18786c8a74118619b5015b9_4b7630c1-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf31598db18786c8a74118619b5015b9_4b7630c1-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf31598db18786c8a74118619b5015b9_4b7630c1.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf31598db18786c8a74118619b5015b9_4b7630c1.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf31598db18786c8a74118619b5015b9_4b7630c1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf31598db18786c8a74118619b5015b9_4b7630c1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/bf31598db18786c8a74118619b5015b9_4b7630c1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":165635,"id":165635,"title":"07b53524244836f3f3f964828ad658cb_185a7712.jpg","filename":"07b53524244836f3f3f964828ad658cb_185a7712.jpg","filesize":649625,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/07b53524244836f3f3f964828ad658cb_185a7712.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/centrale-2\/07b53524244836f3f3f964828ad658cb_185a7712-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"07b53524244836f3f3f964828ad658cb_185a7712-jpg-2","status":"inherit","uploaded_to":181299,"date":"2025-04-18 08:52:15","modified":"2025-04-18 14:27:21","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1500,"height":1000,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/07b53524244836f3f3f964828ad658cb_185a7712-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/07b53524244836f3f3f964828ad658cb_185a7712-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/07b53524244836f3f3f964828ad658cb_185a7712-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/07b53524244836f3f3f964828ad658cb_185a7712-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/07b53524244836f3f3f964828ad658cb_185a7712.jpg","1536x1536-width":1500,"1536x1536-height":1000,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/07b53524244836f3f3f964828ad658cb_185a7712.jpg","2048x2048-width":1500,"2048x2048-height":1000,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/07b53524244836f3f3f964828ad658cb_185a7712.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/07b53524244836f3f3f964828ad658cb_185a7712.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/07b53524244836f3f3f964828ad658cb_185a7712.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""},"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""}},"description":"<p>El B&#038;B ofrece distintos tipos de habitaciones, todas con aire acondicionado, TV de pantalla plana, ba\u00f1o privado con art\u00edculos de tocador y secador de pelo. Las habitaciones cuentan tambi\u00e9n con un set para preparar t\u00e8 o caf\u00e9. Por la ma\u00f1ana, con solicitud, os espera el desayuno continental.\u00a0&#13;<br \/>\nSituado en posici\u00f3n estrat\u00e9gica, a 5 minutos de distancia del aeropuerto de Mil\u00e1n &#8211; B\u00e9rgamo y del centro comercial Oriocenter, que se pueden alcanzar andando a trav\u00e9s de una c\u00f3moda ruta peatonal, con un paseo de 20 minutos.\u00a0\u00a0&#13;<br \/>\n\u00a0<\/p>\n","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"<p>Habitaci\u00f3n individual: \u20ac 50&#13;<br \/>\n\u00a0&#13;<br \/>\nHabitaci\u00f3n doble: \u20ac 60&#13;<br \/>\n\u00a0&#13;<br \/>\nHabitaci\u00f3n individual: \u20ac 80&#13;<br \/>\n\u00a0<\/p>\n","services":"","parking":"<p>Aparcamiento p\u00fablico gratuito disponible alrededor del alojamiento. &#13;<br \/>\nParking privado de pago Orio.20 Parking (recomendado para estancias de m\u00e1s de 3 d\u00edas).<\/p>\n","restaurant":"<p>Restaurante Pizzeria Lo Scalo dei Sapori, con precios especiales.&#13;<br \/>\nRestaurante Pizzeria Il Giardinetto, con precios especiales.<\/p>\n","breakfast":"<p>El desayuno continental se sirve con solicitud previa, desde las 7 hasta las 10.<\/p>\n","internet":"<p>Conexi\u00f3n WIFI gratuita.<\/p>\n","children":"","pets":"","latitude":"45.674593","longitude":"9.690404","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"MAPELLI MARILENA","registered_office":"Via Roma,5 Orio al Serio","iu_addr_streetnumber":"Via IV Novembre, 11","iu_addr_postalcode":"24050","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 3391745005","iu_cell":"+39 3391745005","iu_website":"http:\/\/www.bbcentraleorio.com","iu_email":"bbcentrale.orio@libero.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"4","iu_beds":"11","id_madeep":"","id_visit_manza":"9375","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"time":"<p>Check-in: dalle15:00 alle 00:00&#13;<br \/>\nCheck-out: dalle 02:00 alle 11:00<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"bar","label":"Bar"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"balcony","label":"Balcone"},{"value":"mini_bar","label":"Frigo bar"},{"value":"satellite_tv","label":"TV satellitare"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/181299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/181299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/165439"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=181299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=181299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=181299"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=181299"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=181299"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=181299"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=181299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}