{"id":181415,"date":"2025-04-18T13:29:43","date_gmt":"2025-04-18T11:29:43","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/solemahouse\/"},"modified":"2025-04-18T16:29:06","modified_gmt":"2025-04-18T14:29:06","slug":"solemahouse","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/solemahouse\/","title":{"rendered":"Solemahouse"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":167612,"template":"","categories":[1009],"tags":[],"aggr":[],"area":[],"kind":[18726],"zona":[],"class_list":["post-181415","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-dormir","kind-strutturaricettiva-es"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Solemahouse","hero_text":"","slides":[{"image":{"ID":167612,"id":167612,"title":"45d8d2c09350bf4664f54fca31751a51_5e2eacab.jpg","filename":"45d8d2c09350bf4664f54fca31751a51_5e2eacab.jpg","filesize":456774,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45d8d2c09350bf4664f54fca31751a51_5e2eacab.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/solemahouse\/45d8d2c09350bf4664f54fca31751a51_5e2eacab-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"45d8d2c09350bf4664f54fca31751a51_5e2eacab-jpg-2","status":"inherit","uploaded_to":181415,"date":"2025-04-18 09:00:42","modified":"2025-04-18 14:30:13","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2048,"height":1092,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45d8d2c09350bf4664f54fca31751a51_5e2eacab-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45d8d2c09350bf4664f54fca31751a51_5e2eacab-300x160.jpg","medium-width":300,"medium-height":160,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45d8d2c09350bf4664f54fca31751a51_5e2eacab-768x410.jpg","medium_large-width":768,"medium_large-height":410,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45d8d2c09350bf4664f54fca31751a51_5e2eacab-1024x546.jpg","large-width":1024,"large-height":546,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45d8d2c09350bf4664f54fca31751a51_5e2eacab-1536x819.jpg","1536x1536-width":1536,"1536x1536-height":819,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45d8d2c09350bf4664f54fca31751a51_5e2eacab.jpg","2048x2048-width":2048,"2048x2048-height":1092,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45d8d2c09350bf4664f54fca31751a51_5e2eacab.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":160,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45d8d2c09350bf4664f54fca31751a51_5e2eacab.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":213,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/45d8d2c09350bf4664f54fca31751a51_5e2eacab.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":320}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167619,"id":167619,"title":"ffd5cbf33248b7cac38ab190d2e3e6af_3d5835b8.jpg","filename":"ffd5cbf33248b7cac38ab190d2e3e6af_3d5835b8.jpg","filesize":99055,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ffd5cbf33248b7cac38ab190d2e3e6af_3d5835b8.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/solemahouse\/ffd5cbf33248b7cac38ab190d2e3e6af_3d5835b8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ffd5cbf33248b7cac38ab190d2e3e6af_3d5835b8-jpg-2","status":"inherit","uploaded_to":181415,"date":"2025-04-18 09:00:43","modified":"2025-04-18 14:30:14","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":505,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ffd5cbf33248b7cac38ab190d2e3e6af_3d5835b8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ffd5cbf33248b7cac38ab190d2e3e6af_3d5835b8-300x148.jpg","medium-width":300,"medium-height":148,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ffd5cbf33248b7cac38ab190d2e3e6af_3d5835b8-768x379.jpg","medium_large-width":768,"medium_large-height":379,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ffd5cbf33248b7cac38ab190d2e3e6af_3d5835b8.jpg","large-width":1024,"large-height":505,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ffd5cbf33248b7cac38ab190d2e3e6af_3d5835b8.jpg","1536x1536-width":1024,"1536x1536-height":505,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ffd5cbf33248b7cac38ab190d2e3e6af_3d5835b8.jpg","2048x2048-width":1024,"2048x2048-height":505,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ffd5cbf33248b7cac38ab190d2e3e6af_3d5835b8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":148,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ffd5cbf33248b7cac38ab190d2e3e6af_3d5835b8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":197,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ffd5cbf33248b7cac38ab190d2e3e6af_3d5835b8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":296}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167626,"id":167626,"title":"8bc2c252250061b99b14913c518f2fb0_eb1c24df.jpg","filename":"8bc2c252250061b99b14913c518f2fb0_eb1c24df.jpg","filesize":300076,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8bc2c252250061b99b14913c518f2fb0_eb1c24df.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/solemahouse\/8bc2c252250061b99b14913c518f2fb0_eb1c24df-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"8bc2c252250061b99b14913c518f2fb0_eb1c24df-jpg-2","status":"inherit","uploaded_to":181415,"date":"2025-04-18 09:00:44","modified":"2025-04-18 14:30:14","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1536,"height":2048,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8bc2c252250061b99b14913c518f2fb0_eb1c24df-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8bc2c252250061b99b14913c518f2fb0_eb1c24df-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8bc2c252250061b99b14913c518f2fb0_eb1c24df-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8bc2c252250061b99b14913c518f2fb0_eb1c24df-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8bc2c252250061b99b14913c518f2fb0_eb1c24df-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8bc2c252250061b99b14913c518f2fb0_eb1c24df.jpg","2048x2048-width":1536,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8bc2c252250061b99b14913c518f2fb0_eb1c24df.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8bc2c252250061b99b14913c518f2fb0_eb1c24df.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8bc2c252250061b99b14913c518f2fb0_eb1c24df.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167633,"id":167633,"title":"6e4bc891c6f41d2e4877e0a6b2179c50_245696da.jpg","filename":"6e4bc891c6f41d2e4877e0a6b2179c50_245696da.jpg","filesize":171267,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e4bc891c6f41d2e4877e0a6b2179c50_245696da.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/solemahouse\/6e4bc891c6f41d2e4877e0a6b2179c50_245696da-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6e4bc891c6f41d2e4877e0a6b2179c50_245696da-jpg-2","status":"inherit","uploaded_to":181415,"date":"2025-04-18 09:00:46","modified":"2025-04-18 14:30:14","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e4bc891c6f41d2e4877e0a6b2179c50_245696da-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e4bc891c6f41d2e4877e0a6b2179c50_245696da-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e4bc891c6f41d2e4877e0a6b2179c50_245696da-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e4bc891c6f41d2e4877e0a6b2179c50_245696da.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e4bc891c6f41d2e4877e0a6b2179c50_245696da.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e4bc891c6f41d2e4877e0a6b2179c50_245696da.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e4bc891c6f41d2e4877e0a6b2179c50_245696da.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e4bc891c6f41d2e4877e0a6b2179c50_245696da.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6e4bc891c6f41d2e4877e0a6b2179c50_245696da.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167640,"id":167640,"title":"0d7b54ff1b483dfa5c0778eb6090c19b_25deef36.jpg","filename":"0d7b54ff1b483dfa5c0778eb6090c19b_25deef36.jpg","filesize":254228,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0d7b54ff1b483dfa5c0778eb6090c19b_25deef36.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/solemahouse\/0d7b54ff1b483dfa5c0778eb6090c19b_25deef36-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"0d7b54ff1b483dfa5c0778eb6090c19b_25deef36-jpg-2","status":"inherit","uploaded_to":181415,"date":"2025-04-18 09:00:47","modified":"2025-04-18 14:30:14","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2048,"height":1126,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0d7b54ff1b483dfa5c0778eb6090c19b_25deef36-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0d7b54ff1b483dfa5c0778eb6090c19b_25deef36-300x165.jpg","medium-width":300,"medium-height":165,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0d7b54ff1b483dfa5c0778eb6090c19b_25deef36-768x422.jpg","medium_large-width":768,"medium_large-height":422,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0d7b54ff1b483dfa5c0778eb6090c19b_25deef36-1024x563.jpg","large-width":1024,"large-height":563,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0d7b54ff1b483dfa5c0778eb6090c19b_25deef36-1536x845.jpg","1536x1536-width":1536,"1536x1536-height":845,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0d7b54ff1b483dfa5c0778eb6090c19b_25deef36.jpg","2048x2048-width":2048,"2048x2048-height":1126,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0d7b54ff1b483dfa5c0778eb6090c19b_25deef36.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":165,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0d7b54ff1b483dfa5c0778eb6090c19b_25deef36.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":220,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0d7b54ff1b483dfa5c0778eb6090c19b_25deef36.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":330}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167647,"id":167647,"title":"916a0716dd1c13fb073c5d63c79efc05_0c504403.jpg","filename":"916a0716dd1c13fb073c5d63c79efc05_0c504403.jpg","filesize":213392,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/916a0716dd1c13fb073c5d63c79efc05_0c504403.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/solemahouse\/916a0716dd1c13fb073c5d63c79efc05_0c504403-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"916a0716dd1c13fb073c5d63c79efc05_0c504403-jpg-2","status":"inherit","uploaded_to":181415,"date":"2025-04-18 09:00:48","modified":"2025-04-18 14:30:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":718,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/916a0716dd1c13fb073c5d63c79efc05_0c504403-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/916a0716dd1c13fb073c5d63c79efc05_0c504403-300x210.jpg","medium-width":300,"medium-height":210,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/916a0716dd1c13fb073c5d63c79efc05_0c504403-768x539.jpg","medium_large-width":768,"medium_large-height":539,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/916a0716dd1c13fb073c5d63c79efc05_0c504403.jpg","large-width":1024,"large-height":718,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/916a0716dd1c13fb073c5d63c79efc05_0c504403.jpg","1536x1536-width":1024,"1536x1536-height":718,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/916a0716dd1c13fb073c5d63c79efc05_0c504403.jpg","2048x2048-width":1024,"2048x2048-height":718,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/916a0716dd1c13fb073c5d63c79efc05_0c504403.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":210,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/916a0716dd1c13fb073c5d63c79efc05_0c504403.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":280,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/916a0716dd1c13fb073c5d63c79efc05_0c504403.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":421}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167654,"id":167654,"title":"302589c12652b0afa1efd33cf17fba2a_246176a3.jpg","filename":"302589c12652b0afa1efd33cf17fba2a_246176a3.jpg","filesize":356856,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/302589c12652b0afa1efd33cf17fba2a_246176a3.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/solemahouse\/302589c12652b0afa1efd33cf17fba2a_246176a3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"302589c12652b0afa1efd33cf17fba2a_246176a3-jpg-2","status":"inherit","uploaded_to":181415,"date":"2025-04-18 09:00:49","modified":"2025-04-18 14:30:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":1200,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/302589c12652b0afa1efd33cf17fba2a_246176a3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/302589c12652b0afa1efd33cf17fba2a_246176a3-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/302589c12652b0afa1efd33cf17fba2a_246176a3-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/302589c12652b0afa1efd33cf17fba2a_246176a3-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/302589c12652b0afa1efd33cf17fba2a_246176a3-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/302589c12652b0afa1efd33cf17fba2a_246176a3.jpg","2048x2048-width":1600,"2048x2048-height":1200,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/302589c12652b0afa1efd33cf17fba2a_246176a3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/302589c12652b0afa1efd33cf17fba2a_246176a3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/302589c12652b0afa1efd33cf17fba2a_246176a3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167661,"id":167661,"title":"aed35bdc557649ef72a0c54a5a5672af_8f747bd4.jpg","filename":"aed35bdc557649ef72a0c54a5a5672af_8f747bd4.jpg","filesize":700688,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/aed35bdc557649ef72a0c54a5a5672af_8f747bd4.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/solemahouse\/aed35bdc557649ef72a0c54a5a5672af_8f747bd4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"aed35bdc557649ef72a0c54a5a5672af_8f747bd4-jpg-2","status":"inherit","uploaded_to":181415,"date":"2025-04-18 09:00:50","modified":"2025-04-18 14:30:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1536,"height":2048,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/aed35bdc557649ef72a0c54a5a5672af_8f747bd4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/aed35bdc557649ef72a0c54a5a5672af_8f747bd4-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/aed35bdc557649ef72a0c54a5a5672af_8f747bd4-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/aed35bdc557649ef72a0c54a5a5672af_8f747bd4-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/aed35bdc557649ef72a0c54a5a5672af_8f747bd4-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/aed35bdc557649ef72a0c54a5a5672af_8f747bd4.jpg","2048x2048-width":1536,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/aed35bdc557649ef72a0c54a5a5672af_8f747bd4.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/aed35bdc557649ef72a0c54a5a5672af_8f747bd4.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/aed35bdc557649ef72a0c54a5a5672af_8f747bd4.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167668,"id":167668,"title":"492065748d9bd83c9858fc0c4fed830e_031b09d9.jpg","filename":"492065748d9bd83c9858fc0c4fed830e_031b09d9.jpg","filesize":380420,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/492065748d9bd83c9858fc0c4fed830e_031b09d9.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/solemahouse\/492065748d9bd83c9858fc0c4fed830e_031b09d9-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"492065748d9bd83c9858fc0c4fed830e_031b09d9-jpg-2","status":"inherit","uploaded_to":181415,"date":"2025-04-18 09:00:52","modified":"2025-04-18 14:30:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1536,"height":2048,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/492065748d9bd83c9858fc0c4fed830e_031b09d9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/492065748d9bd83c9858fc0c4fed830e_031b09d9-225x300.jpg","medium-width":225,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/492065748d9bd83c9858fc0c4fed830e_031b09d9-768x1024.jpg","medium_large-width":768,"medium_large-height":1024,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/492065748d9bd83c9858fc0c4fed830e_031b09d9-768x1024.jpg","large-width":768,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/492065748d9bd83c9858fc0c4fed830e_031b09d9-1152x1536.jpg","1536x1536-width":1152,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/492065748d9bd83c9858fc0c4fed830e_031b09d9.jpg","2048x2048-width":1536,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/492065748d9bd83c9858fc0c4fed830e_031b09d9.jpg","gform-image-choice-sm-width":225,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/492065748d9bd83c9858fc0c4fed830e_031b09d9.jpg","gform-image-choice-md-width":300,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/492065748d9bd83c9858fc0c4fed830e_031b09d9.jpg","gform-image-choice-lg-width":450,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167675,"id":167675,"title":"ca0f342830848f0d1b59ef7235dba387_f940ebd1.jpg","filename":"ca0f342830848f0d1b59ef7235dba387_f940ebd1.jpg","filesize":181223,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca0f342830848f0d1b59ef7235dba387_f940ebd1.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/solemahouse\/ca0f342830848f0d1b59ef7235dba387_f940ebd1-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ca0f342830848f0d1b59ef7235dba387_f940ebd1-jpg-2","status":"inherit","uploaded_to":181415,"date":"2025-04-18 09:00:53","modified":"2025-04-18 14:30:16","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1600,"height":805,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca0f342830848f0d1b59ef7235dba387_f940ebd1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca0f342830848f0d1b59ef7235dba387_f940ebd1-300x151.jpg","medium-width":300,"medium-height":151,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca0f342830848f0d1b59ef7235dba387_f940ebd1-768x386.jpg","medium_large-width":768,"medium_large-height":386,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca0f342830848f0d1b59ef7235dba387_f940ebd1-1024x515.jpg","large-width":1024,"large-height":515,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca0f342830848f0d1b59ef7235dba387_f940ebd1-1536x773.jpg","1536x1536-width":1536,"1536x1536-height":773,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca0f342830848f0d1b59ef7235dba387_f940ebd1.jpg","2048x2048-width":1600,"2048x2048-height":805,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca0f342830848f0d1b59ef7235dba387_f940ebd1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":151,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca0f342830848f0d1b59ef7235dba387_f940ebd1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":201,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca0f342830848f0d1b59ef7235dba387_f940ebd1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":302}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":167682,"id":167682,"title":"3d42b170c07f554c7207cdab9bbcba43_ee2b3272.jpg","filename":"3d42b170c07f554c7207cdab9bbcba43_ee2b3272.jpg","filesize":260366,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3d42b170c07f554c7207cdab9bbcba43_ee2b3272.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/solemahouse\/3d42b170c07f554c7207cdab9bbcba43_ee2b3272-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3d42b170c07f554c7207cdab9bbcba43_ee2b3272-jpg-2","status":"inherit","uploaded_to":181415,"date":"2025-04-18 09:00:54","modified":"2025-04-18 14:30:17","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2048,"height":1536,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3d42b170c07f554c7207cdab9bbcba43_ee2b3272-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3d42b170c07f554c7207cdab9bbcba43_ee2b3272-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3d42b170c07f554c7207cdab9bbcba43_ee2b3272-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3d42b170c07f554c7207cdab9bbcba43_ee2b3272-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3d42b170c07f554c7207cdab9bbcba43_ee2b3272-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3d42b170c07f554c7207cdab9bbcba43_ee2b3272.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3d42b170c07f554c7207cdab9bbcba43_ee2b3272.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3d42b170c07f554c7207cdab9bbcba43_ee2b3272.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3d42b170c07f554c7207cdab9bbcba43_ee2b3272.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""},"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"","filotto_fill":"","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":"","order_by":"","order_way":""}},"description":"","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.688740","longitude":"9.668521","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"Samanta Ligato","registered_office":"Bergamo Via San Giorgio 6","iu_addr_streetnumber":"Via S. Giorgio, 6","iu_addr_postalcode":"24122","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"","iu_cell":"00393495186487","iu_website":"","iu_email":"solemahouse@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"1","iu_beds":"4","id_madeep":"","id_visit_manza":"10158","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"time":"<p>Check-in h. 2 pm&#13;<br \/>\nCheck-out h. 11 am&#13;<br \/>\nChiedere per eventuale disponibilita&#8217; di cambio orario.&#13;<br \/>\nAl momento la consegna\/ritiro delle chiavi avviene personalmente.\u00a0<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"disabled_access","label":"Accessibile disabili"},{"value":"elevator","label":"Ascensore"},{"value":"audiovisual_equipment","label":"Impianti audiovisivi"},{"value":"laundry","label":"Lavanderia"},{"value":"tv_lounge","label":"Sala TV"},{"value":"solarium","label":"Solarium"},{"value":"wifi","label":"Wi-Fi"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"balcony","label":"Balcone"},{"value":"tv_room","label":"TV in camera"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/181415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/181415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/167612"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=181415"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=181415"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=181415"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=181415"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=181415"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=181415"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=181415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}