{"id":19379,"date":"2024-05-08T11:03:22","date_gmt":"2024-05-08T09:03:22","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/museo-delle-storie-di-bergamo-mauro-gelfi-lottocento\/"},"modified":"2025-02-16T09:56:38","modified_gmt":"2025-02-16T08:56:38","slug":"museo-delle-storie-di-bergamo-mauro-gelfi-lottocento","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/museo-delle-storie-di-bergamo-mauro-gelfi-lottocento\/","title":{"rendered":"Museo de Historia de B\u00e9rgamo &#8220;Mauro Gelfi&#8221;.\nEl siglo XIX"},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":2730,"template":"","categories":[164],"tags":[],"aggr":[],"area":[867],"kind":[18679],"zona":[18759],"class_list":["post-19379","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-donde-ir","area-bergamo","kind-poi-es","zona-bergamo-es"],"acf":{"hero_text":"<p>\u00a1Descubre este hermoso punto panor\u00e1mico de B\u00e9rgamo! Disfruta con una espl\u00e9ndida vista de la llanura, los Alpes Orobie y Mil\u00e1n al horizonte.<\/p>\n","filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","latitude":"45.703588","longitude":"9.666298","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_phone":"+39 035247116","iu_cell":"","iu_email":"info@museodellestorie.bergamo.it","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"19","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"https:\/\/www.museodellestorie.bergamo.it\/storia-della-rocca\/","target":"","url_youtube":"","target_modal":""},"iu_shortprice":"\u20ac5 - \u20ac3","iu_timetable":[{"day":{"value":"monday","label":"Luned\u00ec"},"open":false,"time":false},{"day":{"value":"tuesday","label":"Marted\u00ec"},"open":true,"time":[{"opening":"11:00 am","closing":"6:00 pm"}]},{"day":{"value":"wednesday","label":"Mercoled\u00ec"},"open":true,"time":[{"opening":"11:00 am","closing":"6:00 pm"}]},{"day":{"value":"thursday","label":"Gioved\u00ec"},"open":true,"time":[{"opening":"11:00 am","closing":"6:00 pm"}]},{"day":{"value":"friday","label":"Venerd\u00ec"},"open":true,"time":[{"opening":"11:00 am","closing":"6:00 pm"}]},{"day":{"value":"saturday","label":"Sabato"},"open":true,"time":[{"opening":"11:00 am","closing":"6:00 pm"}]},{"day":{"value":"sunday","label":"Domenica"},"open":true,"time":[{"opening":"11:00 am","closing":"6:18 pm"}]}],"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Ficha t\u00e9cnica"},{"acf_fc_layout":"text","text":""}],"description":"<p class=\"LO-normal\">Al entrar en la <strong>Rocca<\/strong>, una antigua ciudadela que data de 1331, te encontrar\u00e1s recorriendo la historia de B\u00e9rgamo.<\/p>\n<p class=\"LO-normal\">La ruta es, ante todo, la visita <em>guiada<\/em> a <strong>la secci\u00f3n del siglo XIX del Museo delle Storie di Bergamo (Museo de Historia de B\u00e9rgamo<\/strong> ), que se encuentra aqu\u00ed, pero tambi\u00e9n es el recorrido por los jardines, galer\u00edas, torres y reliquias de guerra que encontrar\u00e1s al explorar esta fortificaci\u00f3n.<\/p>\n<p class=\"LO-normal\">Precisamente siguiendo el recorrido de la <strong>galer\u00eda<\/strong>, el que hac\u00edan hace siglos los soldados de guardia, puedes vivir una experiencia realmente m\u00e1gica: un recorrido panor\u00e1mico de 360\u00b0 por el per\u00edmetro del edificio.<\/p>\n<p class=\"LO-normal\">Podr\u00e1s disfrutar de un vistazo de la Ciudad Alta, las Monta\u00f1as Orobie y toda la llanura de abajo.<br \/>\nEl paseo por la historia tambi\u00e9n contin\u00faa en el jard\u00edn: \u00a1descubre las numerosas reliquias de las dos guerras mundiales!   <\/p>\n","buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"https:\/\/www.museodellestorie.bergamo.it\/storia-della-rocca\/","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","filotto_fill":"manual","url":"https:\/\/www.museodellestorie.bergamo.it\/storia-della-rocca\/","hero_title":"Museo de Historia de B\u00e9rgamo \"Mauro Gelfi\".\nEl siglo XIX ","indepth":"<p class=\"LO-normal\">La construcci\u00f3n del complejo comenz\u00f3 en 1331, pero con el tiempo se fue mejorando, sobre todo en su funci\u00f3n defensiva.<\/p>\n<p class=\"LO-normal\">Uno de los elementos m\u00e1s llamativos es sin duda la <strong>torre del homenaje<\/strong> circular, la torre principal de la fortaleza desde la que -al ser el punto m\u00e1s alto de todo el edificio- la vista panor\u00e1mica no tiene precio: si tienes suerte, desde aqu\u00ed, en un d\u00eda despejado, \u00a1podr\u00e1s incluso vislumbrar a lo lejos el perfil de Mil\u00e1n!<\/p>\n<p class=\"LO-normal\">Mientras caminas por las murallas de la fortaleza, podr\u00e1s vislumbrar el <strong>Parco delle Rimembranze (Parque del Recuerdo<\/strong>) que hay debajo; los m\u00e1s peque\u00f1os apreciar\u00e1n sin duda los ca\u00f1ones y el tanque que se guardan aqu\u00ed.<\/p>\n<p class=\"LO-normal\">Para las almas m\u00e1s tranquilas, en cambio, los senderos sombreados por cipreses ofrecer\u00e1n un lugar lleno de recuerdos y encanto para pasear.  <\/p>\n","price":"<p>ntero 5\u20ac *Reducido 3<\/p>\n<p><span>GRATIFICACIONES Y REDUCCIONES<\/span><\/p>\n<p><span>Entrada gratuita<\/span>: estudiantes menores de 18 a\u00f1os, discapacitados, miembros del ICOM, periodistas, gu\u00edas cualificados, Abbonamento Musei Lombardia<\/p>\n<p><span>*Entrada<\/span> reducida: amigos del Museo de Historia de B\u00e9rgamo, estudiantes universitarios de hasta 26 a\u00f1os, miembros del Touring Club Italiano, grupos de al menos 15 ps<\/p>\n","time":"<p>Mar-Dom: 11h-18h<\/p>\n<p><span>Cerrado los lunes 25 de diciembre y 1 de enero<\/span><\/p>\n","iu_addr_streetnumber":"Via Alla Rocca","iu_website":"https:\/\/www.museodellestorie.bergamo.it\/storia-della-rocca\/","hero_type":"images","iu_addr_province":"Bergamo","filotto_items":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Ficha t\u00e9cnica"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"poi_data":{"description":"<p class=\"LO-normal\">Al entrar en la <strong>Rocca<\/strong>, una antigua ciudadela que data de 1331, te encontrar\u00e1s recorriendo la historia de B\u00e9rgamo.<\/p>\n<p class=\"LO-normal\">La ruta es, ante todo, la visita <em>guiada<\/em> a <strong>la secci\u00f3n del siglo XIX del Museo delle Storie di Bergamo (Museo de Historia de B\u00e9rgamo<\/strong> ), que se encuentra aqu\u00ed, pero tambi\u00e9n es el recorrido por los jardines, galer\u00edas, torres y reliquias de guerra que encontrar\u00e1s al explorar esta fortificaci\u00f3n.<\/p>\n<p class=\"LO-normal\">Precisamente siguiendo el recorrido de la <strong>galer\u00eda<\/strong>, el que hac\u00edan hace siglos los soldados de guardia, puedes vivir una experiencia realmente m\u00e1gica: un recorrido panor\u00e1mico de 360\u00b0 por el per\u00edmetro del edificio.<\/p>\n<p class=\"LO-normal\">Podr\u00e1s disfrutar de un vistazo de la Ciudad Alta, las Monta\u00f1as Orobie y toda la llanura de abajo.<br \/>\nEl paseo por la historia tambi\u00e9n contin\u00faa en el jard\u00edn: \u00a1descubre las numerosas reliquias de las dos guerras mundiales!   <\/p>\n","indepth":"<p class=\"LO-normal\">La construcci\u00f3n del complejo comenz\u00f3 en 1331, pero con el tiempo se fue mejorando, sobre todo en su funci\u00f3n defensiva.<\/p>\n<p class=\"LO-normal\">Uno de los elementos m\u00e1s llamativos es sin duda la <strong>torre del homenaje<\/strong> circular, la torre principal de la fortaleza desde la que -al ser el punto m\u00e1s alto de todo el edificio- la vista panor\u00e1mica no tiene precio: si tienes suerte, desde aqu\u00ed, en un d\u00eda despejado, \u00a1podr\u00e1s incluso vislumbrar a lo lejos el perfil de Mil\u00e1n!<\/p>\n<p class=\"LO-normal\">Mientras caminas por las murallas de la fortaleza, podr\u00e1s vislumbrar el <strong>Parco delle Rimembranze (Parque del Recuerdo<\/strong>) que hay debajo; los m\u00e1s peque\u00f1os apreciar\u00e1n sin duda los ca\u00f1ones y el tanque que se guardan aqu\u00ed.<\/p>\n<p class=\"LO-normal\">Para las almas m\u00e1s tranquilas, en cambio, los senderos sombreados por cipreses ofrecer\u00e1n un lugar lleno de recuerdos y encanto para pasear.  <\/p>\n","howtogetthere":"","price":"<p>ntero 5\u20ac *Reducido 3<\/p>\n<p><span>GRATIFICACIONES Y REDUCCIONES<\/span><\/p>\n<p><span>Entrada gratuita<\/span>: estudiantes menores de 18 a\u00f1os, discapacitados, miembros del ICOM, periodistas, gu\u00edas cualificados, Abbonamento Musei Lombardia<\/p>\n<p><span>*Entrada<\/span> reducida: amigos del Museo de Historia de B\u00e9rgamo, estudiantes universitarios de hasta 26 a\u00f1os, miembros del Touring Club Italiano, grupos de al menos 15 ps<\/p>\n","time":"<p>Mar-Dom: 11h-18h<\/p>\n<p><span>Cerrado los lunes 25 de diciembre y 1 de enero<\/span><\/p>\n","latitude":"45.703588","longitude":"9.666298","id_visit_manza":"19","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"\u20ac5 - \u20ac3","iu_addr_streetnumber":"Via Alla Rocca","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"Bergamo","iu_phone":"+39 035247116","iu_cell":"","iu_website":"https:\/\/www.museodellestorie.bergamo.it\/storia-della-rocca\/","iu_email":"info@museodellestorie.bergamo.it","iu_document_label":"","iu_document":false,"iu_timetable":[{"day":{"value":"monday","label":"Luned\u00ec"},"open":false,"time":false},{"day":{"value":"tuesday","label":"Marted\u00ec"},"open":true,"time":[{"opening":"11:00 am","closing":"6:00 pm"}]},{"day":{"value":"wednesday","label":"Mercoled\u00ec"},"open":true,"time":[{"opening":"11:00 am","closing":"6:00 pm"}]},{"day":{"value":"thursday","label":"Gioved\u00ec"},"open":true,"time":[{"opening":"11:00 am","closing":"6:00 pm"}]},{"day":{"value":"friday","label":"Venerd\u00ec"},"open":true,"time":[{"opening":"11:00 am","closing":"6:00 pm"}]},{"day":{"value":"saturday","label":"Sabato"},"open":true,"time":[{"opening":"11:00 am","closing":"6:00 pm"}]},{"day":{"value":"sunday","label":"Domenica"},"open":true,"time":[{"opening":"11:00 am","closing":"6:18 pm"}]}]},"size":"full","hero_buttons_group":{"buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"https:\/\/www.museodellestorie.bergamo.it\/storia-della-rocca\/","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}]},"slides":[{"image":false,"video":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/POI_Museo-800.mp4","video_mobile":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/POI_Museo-800_VETR.mp4","video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"modules":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":"","hero_buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"https:\/\/www.museodellestorie.bergamo.it\/storia-della-rocca\/","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"iu_kids":false,"featured_video":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/POI_Museo-800_SH.mp4","is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/19379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/19379\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/2730"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=19379"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=19379"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=19379"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=19379"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=19379"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=19379"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=19379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}