{"id":19439,"date":"2024-05-08T11:03:43","date_gmt":"2024-05-08T09:03:43","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/castillo-de-malpaga\/"},"modified":"2025-02-16T09:57:30","modified_gmt":"2025-02-16T08:57:30","slug":"malpaga","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/malpaga\/","title":{"rendered":"Malpaga"},"excerpt":{"rendered":"<p>Feudo del valeroso caudillo Bartolomeo Colleoni, el castillo de Malpaga encierra el encanto de una belleza intemporal.<\/p>\n","protected":false},"author":3,"featured_media":3976,"template":"","categories":[],"tags":[],"aggr":[],"area":[939],"kind":[18679],"zona":[19035],"class_list":["post-19439","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","area-cavernago","kind-poi-es","zona-cavernago-es"],"acf":{"hero_buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.castellomalpaga.it","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","latitude":"45.616458","longitude":"9.760183","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_addr_postalcode":"24050","iu_addr_city":"Cavernago","iu_addr_province":"","iu_phone":"+39 035840003","iu_cell":"","iu_email":"prenotazioni@castellomalpaga.it","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"56","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"http:\/\/www.castellomalpaga.it","target":"","url_youtube":"","target_modal":""},"iu_shortprice":"\u20ac7 - \u20ac15","iu_timetable":false,"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Ficha t\u00e9cnica"},{"acf_fc_layout":"text","text":""}],"description":"<p>Descubre <strong>el Castillo de Malpaga<\/strong> (Cavernago), antigua residencia de <strong>Bartolomeo Colleoni<\/strong>. D\u00e9jate hechizar por los frescos hist\u00f3ricos, revive la historia con eventos y recreaciones \u00fanicas, y saborea la atm\u00f3sfera medieval de este emblema arquitect\u00f3nico lombardo del siglo XIV. <\/p>\n<h3>Historia<\/h3>\n<p><strong>El castillo de Malpaga<\/strong> fue construido por un gibelino seguramente antes del descubrimiento de la p\u00f3lvora. Gracias al profundo foso que lo protege, el Maniero permaneci\u00f3 inexpugnable durante mucho tiempo y s\u00f3lo volvi\u00f3 a la vida en 1456, cuando el famoso Capit\u00e1n General de la Rep\u00fablica de Venecia, <strong>Bartolomeo Colleoni<\/strong>, decidi\u00f3 comprar el <strong>Borgo di Malpaga<\/strong> por 100 ducados de oro, con la intenci\u00f3n de convertirlo en su residencia privada y en el centro de sus dominios. El Castillo se convirti\u00f3 en el cuartel general del Condottiero y fue testigo de gloriosos acontecimientos hist\u00f3ricos, acogiendo a personajes ilustres como Borso d&#8217;Este, los hijos de Francesco Sforza, Carlos II duque de Borgo\u00f1a y Cristi\u00e1n I rey de Dinamarca, que de vez en cuando ven\u00edan a rendir homenaje al gran Capit\u00e1n. <\/p>\n","buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.castellomalpaga.it","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","filotto_fill":"manual","url":"http:\/\/www.castellomalpaga.it","hero_title":"Malpaga","hero_text":"<p>Feudo del valeroso caudillo Bartolomeo Colleoni, <strong>el castillo de Malpaga<\/strong> encierra el encanto de una belleza intemporal.<\/p>\n","indepth":"<h3 dir=\"ltr\">Arquitectura y medio ambiente<\/h3>\n<p dir=\"ltr\"><strong>El Castillo de Malpaga<\/strong> es uno de los edificios lombardos m\u00e1s importantes del siglo XIV.<br \/>\nDomina una extensi\u00f3n de 330 hect\u00e1reas de campos agr\u00edcolas dentro del Parque Fluvial del Serio, formando un conjunto natural\u00edstico y arquitect\u00f3nico de gran valor, protagonista del proyecto de reordenaci\u00f3n territorial <strong>PER MALPAGA<\/strong>. <\/p>\n<h3 dir=\"ltr\">Eventos y visitas<\/h3>\n<p dir=\"ltr\"><strong>El Castillo de Malpaga <\/strong>es un lugar vivo abierto al p\u00fablico con un rico calendario de eventos.<br \/>\nEn un recorrido por el castillo podr\u00e1s admirar los hermosos frescos de las antiguas salas, obra de famosos artistas que vivieron entre los siglos XV y XVII, y experimentar el encanto del pasado, cruzando el umbral de los interiores amueblados con reconstrucciones de muebles de \u00e9poca. <\/p>\n<p dir=\"ltr\">Numerosos eventos, manifestaciones y recreaciones hist\u00f3ricas animan el Borgo y dan vida al castillo a lo largo del a\u00f1o.<\/p>\n","price":"<p>Adulto con visita guiada: 15\u20ac Adulto con audiogu\u00eda: 12\u20ac Ni\u00f1os con visita guiada (de 6 a 12 a\u00f1os): 10\u20ac Ni\u00f1os con audiogu\u00eda (de 6 a 12 a\u00f1os): 7\u20ac Gratis hasta 5 a\u00f1os<\/p>\n","time":"<p>Abierto de febrero a diciembre. Los horarios se pueden consultar en el siguiente enlace:<\/p>\n<p>E <a href=\"https:\/\/shop.castellomalpaga.it\/eventi\/\" target=\"_blank\" rel=\"noopener\">ventos &#8211; Tienda del Castillo de Malpaga (castellomalpaga.it)<\/a> Es necesario reservar.<\/p>\n","iu_addr_streetnumber":"Via Marconi","iu_website":"http:\/\/www.castellomalpaga.it","filotto_items":false,"hero_type":"images","accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Ficha t\u00e9cnica"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"poi_data":{"description":"<p>Descubre <strong>el Castillo de Malpaga<\/strong> (Cavernago), antigua residencia de <strong>Bartolomeo Colleoni<\/strong>. D\u00e9jate hechizar por los frescos hist\u00f3ricos, revive la historia con eventos y recreaciones \u00fanicas, y saborea la atm\u00f3sfera medieval de este emblema arquitect\u00f3nico lombardo del siglo XIV. <\/p>\n<h3>Historia<\/h3>\n<p><strong>El castillo de Malpaga<\/strong> fue construido por un gibelino seguramente antes del descubrimiento de la p\u00f3lvora. Gracias al profundo foso que lo protege, el Maniero permaneci\u00f3 inexpugnable durante mucho tiempo y s\u00f3lo volvi\u00f3 a la vida en 1456, cuando el famoso Capit\u00e1n General de la Rep\u00fablica de Venecia, <strong>Bartolomeo Colleoni<\/strong>, decidi\u00f3 comprar el <strong>Borgo di Malpaga<\/strong> por 100 ducados de oro, con la intenci\u00f3n de convertirlo en su residencia privada y en el centro de sus dominios. El Castillo se convirti\u00f3 en el cuartel general del Condottiero y fue testigo de gloriosos acontecimientos hist\u00f3ricos, acogiendo a personajes ilustres como Borso d&#8217;Este, los hijos de Francesco Sforza, Carlos II duque de Borgo\u00f1a y Cristi\u00e1n I rey de Dinamarca, que de vez en cuando ven\u00edan a rendir homenaje al gran Capit\u00e1n. <\/p>\n","indepth":"<h3 dir=\"ltr\">Arquitectura y medio ambiente<\/h3>\n<p dir=\"ltr\"><strong>El Castillo de Malpaga<\/strong> es uno de los edificios lombardos m\u00e1s importantes del siglo XIV.<br \/>\nDomina una extensi\u00f3n de 330 hect\u00e1reas de campos agr\u00edcolas dentro del Parque Fluvial del Serio, formando un conjunto natural\u00edstico y arquitect\u00f3nico de gran valor, protagonista del proyecto de reordenaci\u00f3n territorial <strong>PER MALPAGA<\/strong>. <\/p>\n<h3 dir=\"ltr\">Eventos y visitas<\/h3>\n<p dir=\"ltr\"><strong>El Castillo de Malpaga <\/strong>es un lugar vivo abierto al p\u00fablico con un rico calendario de eventos.<br \/>\nEn un recorrido por el castillo podr\u00e1s admirar los hermosos frescos de las antiguas salas, obra de famosos artistas que vivieron entre los siglos XV y XVII, y experimentar el encanto del pasado, cruzando el umbral de los interiores amueblados con reconstrucciones de muebles de \u00e9poca. <\/p>\n<p dir=\"ltr\">Numerosos eventos, manifestaciones y recreaciones hist\u00f3ricas animan el Borgo y dan vida al castillo a lo largo del a\u00f1o.<\/p>\n","howtogetthere":"","price":"<p>Adulto con visita guiada: 15\u20ac Adulto con audiogu\u00eda: 12\u20ac Ni\u00f1os con visita guiada (de 6 a 12 a\u00f1os): 10\u20ac Ni\u00f1os con audiogu\u00eda (de 6 a 12 a\u00f1os): 7\u20ac Gratis hasta 5 a\u00f1os<\/p>\n","time":"<p>Abierto de febrero a diciembre. Los horarios se pueden consultar en el siguiente enlace:<\/p>\n<p>E <a href=\"https:\/\/shop.castellomalpaga.it\/eventi\/\" target=\"_blank\" rel=\"noopener\">ventos &#8211; Tienda del Castillo de Malpaga (castellomalpaga.it)<\/a> Es necesario reservar.<\/p>\n","latitude":"45.616458","longitude":"9.760183","id_visit_manza":"56","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"\u20ac7 - \u20ac15","iu_addr_streetnumber":"Via Marconi","iu_addr_postalcode":"24050","iu_addr_city":"Cavernago","iu_addr_province":"","iu_phone":"+39 035840003","iu_cell":"","iu_website":"http:\/\/www.castellomalpaga.it","iu_email":"prenotazioni@castellomalpaga.it","iu_document_label":"","iu_document":false,"iu_timetable":false},"size":"full","hero_buttons_group":{"buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.castellomalpaga.it","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}]},"slides":[{"image":false,"video":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/POI-Malpaga.mp4","video_mobile":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/POI-Malpaga-V.mp4","video_with_audio":false,"duration_ms":"","title":"malpaga 3","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"modules":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":"","iu_kids":false,"featured_video":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/POI-Malpaga_SH.mp4","is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/19439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/19439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/3976"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=19439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=19439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=19439"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=19439"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=19439"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=19439"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=19439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}