{"id":19449,"date":"2024-05-08T11:03:46","date_gmt":"2024-05-08T09:03:46","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/san-pellegrino-entre-las-termas-y-el-refinado-stile-liberty\/"},"modified":"2025-04-13T17:19:00","modified_gmt":"2025-04-13T15:19:00","slug":"san-pellegrino-entre-las-termas-y-el-refinado-stile-liberty","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/san-pellegrino-entre-las-termas-y-el-refinado-stile-liberty\/","title":{"rendered":"QC Termas de San Pellegrino"},"excerpt":{"rendered":"<p>Ir a QC Terme San Pellegrino no es s\u00f3lo sumergirse en sus aguas, sino tambi\u00e9n en el ambiente de la belle \u00e9poque que a\u00fan impregna toda la ciudad.  <\/p>\n","protected":false},"author":616,"featured_media":4084,"template":"","categories":[],"tags":[],"aggr":[],"area":[1030],"kind":[18679],"zona":[19292],"class_list":["post-19449","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","area-san-pellegrino-terme","kind-poi-es","zona-san-pellegrino-terme-es"],"acf":{"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","latitude":"45.840030","longitude":"9.661090","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_postalcode":"24016","iu_addr_city":"San Pellegrino Terme","iu_phone":"+39034520102","iu_cell":"","iu_email":"info@qctermesanpellegrino.it","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"65","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"http:\/\/www.qctermesanpellegrino.it\/","target":"","url_youtube":"","target_modal":""},"iu_timetable":[{"day":{"value":"monday","label":"Luned\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"10:00 pm"}]},{"day":{"value":"tuesday","label":"Marted\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"10:00 pm"}]},{"day":{"value":"wednesday","label":"Mercoled\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"10:00 pm"}]},{"day":{"value":"thursday","label":"Gioved\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"10:00 pm"}]},{"day":{"value":"friday","label":"Venerd\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"10:00 pm"}]},{"day":{"value":"saturday","label":"Sabato"},"open":true,"time":[{"opening":"10:00 am","closing":"10:00 pm"}]},{"day":{"value":"sunday","label":"Domenica"},"open":true,"time":[{"opening":"10:00 am","closing":"10:00 pm"}]}],"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Ficha t\u00e9cnica"},{"acf_fc_layout":"text","text":""}],"description":"<p>Las antiguas curas termales dan paso ahora a una nueva forma de bienestar, abrazada por maravillas del pasado, donde frescos, columnatas y techos de principios del siglo XX se mezclan inesperadamente con arquitectura e instalaciones de dise\u00f1o moderno.<\/p>\n<p>\u00a0<\/p>\n<p>A s\u00f3lo veinticinco kil\u00f3metros de B\u00e9rgamo, en medio del paisaje monta\u00f1oso de la Val Brembana,<strong> San Pellegrino<\/strong> se hab\u00eda convertido en un balneario de moda y popular en plena temporada de la irrepetible Belle Epoque.<\/p>\n<p>\u00a0<\/p>\n<p>Ya a principios del siglo XX, San Pellegrino Terme se hab\u00eda dotado de instalaciones y servicios que asombraron a los visitantes y contribuyeron a difundir su fama. El complejo del Casino data de 1904, con una entrada espectacular, una escalera monumental y hermosas salas, entre ellas el Salone delle Feste; al lado, las <strong>Termas<\/strong> inmersas en el verdor, con salones y p\u00f3rticos donde la ostentaci\u00f3n del m\u00e1rmol, los mosaicos y las espl\u00e9ndidas vidrieras se acompa\u00f1aba de instalaciones sanitarias y servicios de \u00faltima generaci\u00f3n; m\u00e1s abajo, alineado a lo largo del r\u00edo Brembo, dominado por una fachada de 128 metros, est\u00e1 el colosal Grand Hotel, construido en 1905. El estilo Art Nouveau se asoci\u00f3 con el gusto y el estilo de vida de una sociedad cosmopolita.<\/p>\n","slides":[{"image":false,"video":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/POI-QC-Terme.mp4","video_mobile":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/POI-QC-Terme-V.mp4","video_with_audio":false,"duration_ms":"","title":"Qc spa","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.qctermesanpellegrino.it\/","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","filotto_fill":"manual","url":"http:\/\/www.qctermesanpellegrino.it\/","hero_title":"QC Termas de San Pellegrino","hero_text":"<p>Ir a QC Terme San Pellegrino no es s\u00f3lo sumergirse en sus aguas, sino tambi\u00e9n en el ambiente de la belle \u00e9poque que a\u00fan impregna toda la ciudad.<\/p>\n","indepth":"<p><strong>Sus aguas<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>Excelentes para combatir los c\u00e1lculos y las enfermedades hep\u00e1ticas y digestivas, los manantiales de San Pellegrino eran conocidos desde la Edad Media, pero hasta el siglo XVIII no empezaron a explotarse sus propiedades terap\u00e9uticas. A finales del mismo siglo y principios del XX, la localidad se convirti\u00f3 en un centro balneario de primer orden. <\/p>\n<p>\u00a0<\/p>\n<p>La Gran Guerra marc\u00f3 el declive de los ba\u00f1os termales, mientras crec\u00eda la explotaci\u00f3n de los excelentes manantiales. El agua mineral S.Pellegrino est\u00e1 en las mesas de todo el mundo. <\/p>\n<p><strong>El Camino del Bienestar<\/strong><\/p>\n<p>M\u00e1s de treinta y cinco pr\u00e1cticas, alojadas en dos edificios ricos en historia y encanto, que incluyen, ba\u00f1os panor\u00e1micos, ba\u00f1eras de hidromasaje, hidromasajes, ba\u00f1os sensoriales, cascadas, sendero Kneipp, duchas Vichy, saunas, salas de relajaci\u00f3n y solarium natural. Reg\u00e1late un ba\u00f1o termal en uno de los lugares m\u00e1s famosos de la historia del termalismo. <\/p>\n","price":"<p>Consulta las tarifas actualizadas en: https:\/\/www.qcterme.com\/it\/san-pellegrino\/qc-terme-san-pellegrino\/orari-e-prezzi<\/p>\n","time":"<p>Consulta los horarios de apertura y cierre actualizados en: https:\/\/www.qcterme.com\/it\/san-pellegrino\/qc-terme-san-pellegrino\/orari-e-prezzi<\/p>\n","iu_addr_streetnumber":"Viale della Vittoria, 53","iu_website":"http:\/\/www.qctermesanpellegrino.it\/","size":"full","filotto_items":false,"hero_type":"images","accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Ficha t\u00e9cnica"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"iu_addr_province":"Bergamo","poi_data":{"description":"<p>Las antiguas curas termales dan paso ahora a una nueva forma de bienestar, abrazada por maravillas del pasado, donde frescos, columnatas y techos de principios del siglo XX se mezclan inesperadamente con arquitectura e instalaciones de dise\u00f1o moderno.<\/p>\n<p>\u00a0<\/p>\n<p>A s\u00f3lo veinticinco kil\u00f3metros de B\u00e9rgamo, en medio del paisaje monta\u00f1oso de la Val Brembana,<strong> San Pellegrino<\/strong> se hab\u00eda convertido en un balneario de moda y popular en plena temporada de la irrepetible Belle Epoque.<\/p>\n<p>\u00a0<\/p>\n<p>Ya a principios del siglo XX, San Pellegrino Terme se hab\u00eda dotado de instalaciones y servicios que asombraron a los visitantes y contribuyeron a difundir su fama. El complejo del Casino data de 1904, con una entrada espectacular, una escalera monumental y hermosas salas, entre ellas el Salone delle Feste; al lado, las <strong>Termas<\/strong> inmersas en el verdor, con salones y p\u00f3rticos donde la ostentaci\u00f3n del m\u00e1rmol, los mosaicos y las espl\u00e9ndidas vidrieras se acompa\u00f1aba de instalaciones sanitarias y servicios de \u00faltima generaci\u00f3n; m\u00e1s abajo, alineado a lo largo del r\u00edo Brembo, dominado por una fachada de 128 metros, est\u00e1 el colosal Grand Hotel, construido en 1905. El estilo Art Nouveau se asoci\u00f3 con el gusto y el estilo de vida de una sociedad cosmopolita.<\/p>\n","indepth":"<p><strong>Sus aguas<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>Excelentes para combatir los c\u00e1lculos y las enfermedades hep\u00e1ticas y digestivas, los manantiales de San Pellegrino eran conocidos desde la Edad Media, pero hasta el siglo XVIII no empezaron a explotarse sus propiedades terap\u00e9uticas. A finales del mismo siglo y principios del XX, la localidad se convirti\u00f3 en un centro balneario de primer orden. <\/p>\n<p>\u00a0<\/p>\n<p>La Gran Guerra marc\u00f3 el declive de los ba\u00f1os termales, mientras crec\u00eda la explotaci\u00f3n de los excelentes manantiales. El agua mineral S.Pellegrino est\u00e1 en las mesas de todo el mundo. <\/p>\n<p><strong>El Camino del Bienestar<\/strong><\/p>\n<p>M\u00e1s de treinta y cinco pr\u00e1cticas, alojadas en dos edificios ricos en historia y encanto, que incluyen, ba\u00f1os panor\u00e1micos, ba\u00f1eras de hidromasaje, hidromasajes, ba\u00f1os sensoriales, cascadas, sendero Kneipp, duchas Vichy, saunas, salas de relajaci\u00f3n y solarium natural. Reg\u00e1late un ba\u00f1o termal en uno de los lugares m\u00e1s famosos de la historia del termalismo. <\/p>\n","howtogetthere":"","price":"<p>Consulta las tarifas actualizadas en: https:\/\/www.qcterme.com\/it\/san-pellegrino\/qc-terme-san-pellegrino\/orari-e-prezzi<\/p>\n","time":"<p>Consulta los horarios de apertura y cierre actualizados en: https:\/\/www.qcterme.com\/it\/san-pellegrino\/qc-terme-san-pellegrino\/orari-e-prezzi<\/p>\n","latitude":"45.840030","longitude":"9.661090","id_visit_manza":"65","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"Viale della Vittoria, 53","iu_addr_postalcode":"24016","iu_addr_city":"San Pellegrino Terme","iu_addr_province":"Bergamo","iu_phone":"+39034520102","iu_cell":"","iu_website":"http:\/\/www.qctermesanpellegrino.it\/","iu_email":"info@qctermesanpellegrino.it","iu_document_label":"","iu_document":false,"iu_timetable":[{"day":{"value":"monday","label":"Luned\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"10:00 pm"}]},{"day":{"value":"tuesday","label":"Marted\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"10:00 pm"}]},{"day":{"value":"wednesday","label":"Mercoled\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"10:00 pm"}]},{"day":{"value":"thursday","label":"Gioved\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"10:00 pm"}]},{"day":{"value":"friday","label":"Venerd\u00ec"},"open":true,"time":[{"opening":"10:00 am","closing":"10:00 pm"}]},{"day":{"value":"saturday","label":"Sabato"},"open":true,"time":[{"opening":"10:00 am","closing":"10:00 pm"}]},{"day":{"value":"sunday","label":"Domenica"},"open":true,"time":[{"opening":"10:00 am","closing":"10:00 pm"}]}]},"hero_buttons_group":{"buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.qctermesanpellegrino.it\/","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}]},"modules":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":"","hero_buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.qctermesanpellegrino.it\/","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"iu_kids":false,"featured_video":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/POI-QC-Terme_SH.mp4","is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/19449","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/users\/616"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/19449\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/4084"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=19449"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=19449"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=19449"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=19449"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=19449"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=19449"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=19449"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}