{"id":19503,"date":"2024-05-08T11:04:05","date_gmt":"2024-05-08T09:04:05","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/infopoint-basso-sebino\/"},"modified":"2025-04-13T17:09:48","modified_gmt":"2025-04-13T15:09:48","slug":"infopoint-basso-sebino","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/infopoint-basso-sebino\/","title":{"rendered":"INFOPUNTO LAGO BAJO ISEO Y VALCALEPIO"},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":5002,"template":"","categories":[],"tags":[],"aggr":[17651],"area":[928],"kind":[18679],"zona":[18999],"class_list":["post-19503","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","aggr-noflussi-es","area-sarnico","kind-poi-es","zona-sarnico-es"],"acf":{"hero_text":"<p>..<\/p>\n","filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"indepth":"","howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","latitude":"45.666706","longitude":"9.956991","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_postalcode":"24067","iu_addr_city":"Sarnico","iu_phone":"+39 035 910900","iu_cell":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"6494","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"http:\/\/www.prolocosarnico.it","target":"","url_youtube":"","target_modal":""},"iu_timetable":[{"day":{"value":"monday","label":"Luned\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"12:30 pm"},{"opening":"2:30 pm","closing":"6:00 pm"}]},{"day":{"value":"tuesday","label":"Marted\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"12:30 pm"},{"opening":"2:30 pm","closing":"6:00 pm"}]},{"day":{"value":"wednesday","label":"Mercoled\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"12:30 pm"},{"opening":"2:30 pm","closing":"6:00 pm"}]},{"day":{"value":"thursday","label":"Gioved\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"12:30 pm"},{"opening":"2:30 pm","closing":"6:00 pm"}]},{"day":{"value":"friday","label":"Venerd\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"12:30 pm"},{"opening":"2:30 pm","closing":"6:00 pm"}]},{"day":{"value":"saturday","label":"Sabato"},"open":true,"time":[{"opening":"9:00 am","closing":"12:30 pm"},{"opening":"2:30 pm","closing":"6:00 pm"}]},{"day":{"value":"sunday","label":"Domenica"},"open":false,"time":[{"opening":"9:30 am","closing":"12:00 pm"}]},{"day":{"value":"monday","label":"Luned\u00ec"},"open":false,"time":false}],"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Ficha t\u00e9cnica"},{"acf_fc_layout":"text","text":""}],"description":"<p>El Infopunto de Basso Lago d&#8217;Iseo y Valcalepio se encuentra en Sarnico, en Via Tresanda 1, en pleno centro hist\u00f3rico, y est\u00e1 gestionado por la asociaci\u00f3n Pro-Loco Sarnico. El personal cualificado est\u00e1 a tu disposici\u00f3n para cualquier informaci\u00f3n relativa a la zona de Basso Sebino y a la provincia en general. Nuestra tarea es proporcionar a turistas y ciudadanos toda la informaci\u00f3n que necesiten para vivir plenamente la zona en la que operamos.<\/p>\n<p><strong>Los principales servicios que se ofrecen a los visitantes son<\/strong><\/p>\n<p>&#8211; recepci\u00f3n tur\u00edstica; &#8211; informaci\u00f3n tur\u00edstica sobre las principales atracciones tur\u00edsticas del lago de Iseo y, en general, de toda la provincia; &#8211; informaci\u00f3n sobre los alojamientos de la zona; &#8211; informaci\u00f3n sobre eventos y espect\u00e1culos; &#8211; publicaci\u00f3n y distribuci\u00f3n de material tur\u00edstico, folletos y mapas, horarios de transporte, calendarios de eventos organizados en la zona del Bajo Sebino.<\/p>\n<p>Tambi\u00e9n somos: &#8211; Taquilla de Navigazione Lago Iseo, tanto para embarcaciones de l\u00ednea ordinaria como para cruceros nocturnos y diurnos; &#8211; Ventanilla p\u00fablica y Oficina de Registro N\u00e1utico de la Autoridad de Cuenca de los lagos Iseo, Endine y Moro.<\/p>\n<p>El territorio del Bajo Sebino se encuentra en la zona bisagra entre la f\u00e9rtil llanura del Po y las primeras ondulaciones de esa parte de la cadena alpina que los ge\u00f3logos llaman Alpes Meridionales.<\/p>\n<p>Geogr\u00e1ficamente bien delimitada, comprende<span> la parte meridional de la orilla bergamasca del lago de Iseo y el interior inmediato<\/span>, casi todo ocupado por colinas y monta\u00f1as escarpadas, que se elevan desde una altitud de 197 m s.n.m. en Sarnico a 753 m s.n.m. en Parzanica hasta la cumbre del Monte Bronzone, de 1.334 m s.n.m.<br \/>\nde Parzanica a la cumbre del Monte Bronzone, 1.334 m s.n.m.<br \/>\nLos pueblos incluidos son: Adrara San Martino, Adrara San Rocco, Castelli Calepio, Chiuduno, Credaro, Foresto Sparso, Gandosso, Grumello del Monte, Parzanica, Predore, Sarnico, Tavernola B.sca, Viadanica, Vigolo, para un territorio total de unos 123 km2 y un total de unos 53.000 habitantes.  <\/p>\n<p>Los peque\u00f1os asentamientos, vinculados por acontecimientos hist\u00f3ricos comunes, est\u00e1n unidos por una identidad medioambiental precisa: el lago de Iseo (o Sebino).<br \/>\nLa <span>belleza de la zona<\/span>, felizmente definida como &#8220;entre las monta\u00f1as y el lago&#8221;, se refleja tambi\u00e9n en los pueblos hist\u00f3ricos con elementos de estructuras de fortaleza, santuarios y extraordinarios tesoros art\u00edsticos.<br \/>\nLas comunidades situadas frente al lago combinan elementos arquitect\u00f3nicos de la antigua nobleza, vestigios de arqueolog\u00eda industrial e instalaciones tur\u00edsticas modernas, mientras que el interior permite el feliz descubrimiento de una civilizaci\u00f3n rural y monta\u00f1esa que sigue intacta en muchos aspectos.  <\/p>\n<p>Tambi\u00e9n<span> merece la pena descubrir<\/span> el Bajo Sebino<span> por su gastronom\u00eda, sus productos t\u00edpicos<\/span> (queso, salchich\u00f3n, miel, vino, aceite de oliva&#8230;),<span> el senderismo por los senderos de las colinas, los deportes acu\u00e1ticos y las manifestaciones culturales y folcl\u00f3ricas.<\/span><\/p>\n","slides":[{"image":{"ID":5002,"id":5002,"title":"dfd95a8569206be5e61909b25a5e5a5b_7f54ed0e.jpg","filename":"dfd95a8569206be5e61909b25a5e5a5b_7f54ed0e.jpg","filesize":811180,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/dfd95a8569206be5e61909b25a5e5a5b_7f54ed0e.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/infopoint-basso-sebino\/dfd95a8569206be5e61909b25a5e5a5b_7f54ed0e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"dfd95a8569206be5e61909b25a5e5a5b_7f54ed0e-jpg-2","status":"inherit","uploaded_to":19503,"date":"2024-05-08 08:38:55","modified":"2024-05-08 12:21:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":942,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/dfd95a8569206be5e61909b25a5e5a5b_7f54ed0e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/dfd95a8569206be5e61909b25a5e5a5b_7f54ed0e-300x179.jpg","medium-width":300,"medium-height":179,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/dfd95a8569206be5e61909b25a5e5a5b_7f54ed0e-768x458.jpg","medium_large-width":768,"medium_large-height":458,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/dfd95a8569206be5e61909b25a5e5a5b_7f54ed0e-1024x611.jpg","large-width":1024,"large-height":611,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/dfd95a8569206be5e61909b25a5e5a5b_7f54ed0e-1536x916.jpg","1536x1536-width":1536,"1536x1536-height":916,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/dfd95a8569206be5e61909b25a5e5a5b_7f54ed0e.jpg","2048x2048-width":1580,"2048x2048-height":942,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/dfd95a8569206be5e61909b25a5e5a5b_7f54ed0e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":179,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/dfd95a8569206be5e61909b25a5e5a5b_7f54ed0e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":238,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/dfd95a8569206be5e61909b25a5e5a5b_7f54ed0e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":358}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"infopunto iseo lago bajo","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":5008,"id":5008,"title":"89ee03ef821616264056d02caaf6ab1b_fbbe3add.jpg","filename":"89ee03ef821616264056d02caaf6ab1b_fbbe3add.jpg","filesize":656458,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89ee03ef821616264056d02caaf6ab1b_fbbe3add.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/infopoint-basso-sebino\/89ee03ef821616264056d02caaf6ab1b_fbbe3add-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"89ee03ef821616264056d02caaf6ab1b_fbbe3add-jpg-2","status":"inherit","uploaded_to":19503,"date":"2024-05-08 08:38:56","modified":"2024-05-08 12:21:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":961,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89ee03ef821616264056d02caaf6ab1b_fbbe3add-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89ee03ef821616264056d02caaf6ab1b_fbbe3add-300x182.jpg","medium-width":300,"medium-height":182,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89ee03ef821616264056d02caaf6ab1b_fbbe3add-768x467.jpg","medium_large-width":768,"medium_large-height":467,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89ee03ef821616264056d02caaf6ab1b_fbbe3add-1024x623.jpg","large-width":1024,"large-height":623,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89ee03ef821616264056d02caaf6ab1b_fbbe3add-1536x934.jpg","1536x1536-width":1536,"1536x1536-height":934,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89ee03ef821616264056d02caaf6ab1b_fbbe3add.jpg","2048x2048-width":1580,"2048x2048-height":961,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89ee03ef821616264056d02caaf6ab1b_fbbe3add.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":182,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89ee03ef821616264056d02caaf6ab1b_fbbe3add.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":243,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/89ee03ef821616264056d02caaf6ab1b_fbbe3add.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":365}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"infopunto iseo lago bajo","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":5014,"id":5014,"title":"2d7ef0eae3cceedd1dd54dbe025e3b55_7bfd6038.jpg","filename":"2d7ef0eae3cceedd1dd54dbe025e3b55_7bfd6038.jpg","filesize":550696,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2d7ef0eae3cceedd1dd54dbe025e3b55_7bfd6038.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/infopoint-basso-sebino\/2d7ef0eae3cceedd1dd54dbe025e3b55_7bfd6038-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"2d7ef0eae3cceedd1dd54dbe025e3b55_7bfd6038-jpg-2","status":"inherit","uploaded_to":19503,"date":"2024-05-08 08:38:56","modified":"2024-05-08 12:21:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":907,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2d7ef0eae3cceedd1dd54dbe025e3b55_7bfd6038-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2d7ef0eae3cceedd1dd54dbe025e3b55_7bfd6038-300x172.jpg","medium-width":300,"medium-height":172,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2d7ef0eae3cceedd1dd54dbe025e3b55_7bfd6038-768x441.jpg","medium_large-width":768,"medium_large-height":441,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2d7ef0eae3cceedd1dd54dbe025e3b55_7bfd6038-1024x588.jpg","large-width":1024,"large-height":588,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2d7ef0eae3cceedd1dd54dbe025e3b55_7bfd6038-1536x882.jpg","1536x1536-width":1536,"1536x1536-height":882,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2d7ef0eae3cceedd1dd54dbe025e3b55_7bfd6038.jpg","2048x2048-width":1580,"2048x2048-height":907,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2d7ef0eae3cceedd1dd54dbe025e3b55_7bfd6038.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":172,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2d7ef0eae3cceedd1dd54dbe025e3b55_7bfd6038.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":230,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/2d7ef0eae3cceedd1dd54dbe025e3b55_7bfd6038.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":344}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"infopunto iseo lago bajo","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.prolocosarnico.it","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","filotto_fill":"manual","url":"http:\/\/www.prolocosarnico.it","hero_title":"INFOPUNTO LAGO BAJO ISEO Y VALCALEPIO","time":"<p>De octubre a marzo:<\/p>\n<p>De lunes a s\u00e1bado de 9.00 a 12.30 h. y de 14.30 a 18.00 h. Domingos y festivos CERRADO<\/p>\n<p>De abril a septiembre:<\/p>\n<p>De lunes a s\u00e1bado de 9.00 a 12.30 h. y de 14.30 a 18.00 h. Domingos y festivos de 9.30 a 12.30 h.<\/p>\n","iu_addr_streetnumber":"Via Tresanda, 1","iu_website":"http:\/\/www.prolocosarnico.it","featured_video":false,"filotto_items":false,"hero_type":"images","iu_addr_province":"Bergamo","size":"full","filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","modules":false,"hero_buttons":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Ficha t\u00e9cnica"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"iu_kids":false,"iu_email":"info@prolocosarnico.it","poi_data":{"description":"<p>El Infopunto de Basso Lago d&#8217;Iseo y Valcalepio se encuentra en Sarnico, en Via Tresanda 1, en pleno centro hist\u00f3rico, y est\u00e1 gestionado por la asociaci\u00f3n Pro-Loco Sarnico. El personal cualificado est\u00e1 a tu disposici\u00f3n para cualquier informaci\u00f3n relativa a la zona de Basso Sebino y a la provincia en general. Nuestra tarea es proporcionar a turistas y ciudadanos toda la informaci\u00f3n que necesiten para vivir plenamente la zona en la que operamos.<\/p>\n<p><strong>Los principales servicios que se ofrecen a los visitantes son<\/strong><\/p>\n<p>&#8211; recepci\u00f3n tur\u00edstica; &#8211; informaci\u00f3n tur\u00edstica sobre las principales atracciones tur\u00edsticas del lago de Iseo y, en general, de toda la provincia; &#8211; informaci\u00f3n sobre los alojamientos de la zona; &#8211; informaci\u00f3n sobre eventos y espect\u00e1culos; &#8211; publicaci\u00f3n y distribuci\u00f3n de material tur\u00edstico, folletos y mapas, horarios de transporte, calendarios de eventos organizados en la zona del Bajo Sebino.<\/p>\n<p>Tambi\u00e9n somos: &#8211; Taquilla de Navigazione Lago Iseo, tanto para embarcaciones de l\u00ednea ordinaria como para cruceros nocturnos y diurnos; &#8211; Ventanilla p\u00fablica y Oficina de Registro N\u00e1utico de la Autoridad de Cuenca de los lagos Iseo, Endine y Moro.<\/p>\n<p>El territorio del Bajo Sebino se encuentra en la zona bisagra entre la f\u00e9rtil llanura del Po y las primeras ondulaciones de esa parte de la cadena alpina que los ge\u00f3logos llaman Alpes Meridionales.<\/p>\n<p>Geogr\u00e1ficamente bien delimitada, comprende<span> la parte meridional de la orilla bergamasca del lago de Iseo y el interior inmediato<\/span>, casi todo ocupado por colinas y monta\u00f1as escarpadas, que se elevan desde una altitud de 197 m s.n.m. en Sarnico a 753 m s.n.m. en Parzanica hasta la cumbre del Monte Bronzone, de 1.334 m s.n.m.<br \/>\nde Parzanica a la cumbre del Monte Bronzone, 1.334 m s.n.m.<br \/>\nLos pueblos incluidos son: Adrara San Martino, Adrara San Rocco, Castelli Calepio, Chiuduno, Credaro, Foresto Sparso, Gandosso, Grumello del Monte, Parzanica, Predore, Sarnico, Tavernola B.sca, Viadanica, Vigolo, para un territorio total de unos 123 km2 y un total de unos 53.000 habitantes.  <\/p>\n<p>Los peque\u00f1os asentamientos, vinculados por acontecimientos hist\u00f3ricos comunes, est\u00e1n unidos por una identidad medioambiental precisa: el lago de Iseo (o Sebino).<br \/>\nLa <span>belleza de la zona<\/span>, felizmente definida como &#8220;entre las monta\u00f1as y el lago&#8221;, se refleja tambi\u00e9n en los pueblos hist\u00f3ricos con elementos de estructuras de fortaleza, santuarios y extraordinarios tesoros art\u00edsticos.<br \/>\nLas comunidades situadas frente al lago combinan elementos arquitect\u00f3nicos de la antigua nobleza, vestigios de arqueolog\u00eda industrial e instalaciones tur\u00edsticas modernas, mientras que el interior permite el feliz descubrimiento de una civilizaci\u00f3n rural y monta\u00f1esa que sigue intacta en muchos aspectos.  <\/p>\n<p>Tambi\u00e9n<span> merece la pena descubrir<\/span> el Bajo Sebino<span> por su gastronom\u00eda, sus productos t\u00edpicos<\/span> (queso, salchich\u00f3n, miel, vino, aceite de oliva&#8230;),<span> el senderismo por los senderos de las colinas, los deportes acu\u00e1ticos y las manifestaciones culturales y folcl\u00f3ricas.<\/span><\/p>\n","indepth":"","howtogetthere":"","price":"","time":"<p>De octubre a marzo:<\/p>\n<p>De lunes a s\u00e1bado de 9.00 a 12.30 h. y de 14.30 a 18.00 h. Domingos y festivos CERRADO<\/p>\n<p>De abril a septiembre:<\/p>\n<p>De lunes a s\u00e1bado de 9.00 a 12.30 h. y de 14.30 a 18.00 h. Domingos y festivos de 9.30 a 12.30 h.<\/p>\n","latitude":"45.666706","longitude":"9.956991","id_visit_manza":"6494","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"Via Tresanda, 1","iu_addr_postalcode":"24067","iu_addr_city":"Sarnico","iu_addr_province":"Bergamo","iu_phone":"+39 035 910900","iu_cell":"","iu_website":"http:\/\/www.prolocosarnico.it","iu_email":"info@prolocosarnico.it","iu_document_label":"","iu_document":false,"iu_timetable":[{"day":{"value":"monday","label":"Luned\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"12:30 pm"},{"opening":"2:30 pm","closing":"6:00 pm"}]},{"day":{"value":"tuesday","label":"Marted\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"12:30 pm"},{"opening":"2:30 pm","closing":"6:00 pm"}]},{"day":{"value":"wednesday","label":"Mercoled\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"12:30 pm"},{"opening":"2:30 pm","closing":"6:00 pm"}]},{"day":{"value":"thursday","label":"Gioved\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"12:30 pm"},{"opening":"2:30 pm","closing":"6:00 pm"}]},{"day":{"value":"friday","label":"Venerd\u00ec"},"open":true,"time":[{"opening":"9:00 am","closing":"12:30 pm"},{"opening":"2:30 pm","closing":"6:00 pm"}]},{"day":{"value":"saturday","label":"Sabato"},"open":true,"time":[{"opening":"9:00 am","closing":"12:30 pm"},{"opening":"2:30 pm","closing":"6:00 pm"}]},{"day":{"value":"sunday","label":"Domenica"},"open":false,"time":[{"opening":"9:30 am","closing":"12:00 pm"}]},{"day":{"value":"monday","label":"Luned\u00ec"},"open":false,"time":false}]},"is_an_ambassador":false,"accessibilityicons":[]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/19503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/19503\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/5002"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=19503"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=19503"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=19503"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=19503"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=19503"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=19503"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=19503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}