{"id":19594,"date":"2024-05-08T11:04:38","date_gmt":"2024-05-08T09:04:38","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/puerta-san-giacomo\/"},"modified":"2025-02-16T09:59:49","modified_gmt":"2025-02-16T08:59:49","slug":"puerta-san-giacomo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/puerta-san-giacomo\/","title":{"rendered":"Puerta de Santiago"},"excerpt":{"rendered":"<p>La \u00fanica brecha en las Murallas visible desde la Baja B\u00e9rgamo, la \u00fanica de m\u00e1rmol blanco pulido, la \u00fanica precedida por un viaducto de piedra que domina la llanura.  <\/p>\n","protected":false},"author":3,"featured_media":6622,"template":"","categories":[],"tags":[],"aggr":[],"area":[867],"kind":[18679],"zona":[18759],"class_list":["post-19594","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","area-bergamo","kind-poi-es","zona-bergamo-es"],"acf":{"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","latitude":"45.701325","longitude":"9.662940","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"6560","url":"","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"","target":"","url_youtube":"","target_modal":""},"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Ficha t\u00e9cnica"},{"acf_fc_layout":"text","text":""}],"description":"<p>En el pasado, la Puerta de San Giacomo era la entrada a Citt\u00e0 Alta para quienes llegaban desde Mil\u00e1n.<br \/>\nEs el \u00fanico acceso a las Murallas perfectamente visible desde Viale Vittorio Emanuele, el eje que atraviesa la parte baja de B\u00e9rgamo de sur a norte, tanto por su posici\u00f3n como por su color.<br \/>\nEl m\u00e1rmol blanco con el que est\u00e1 construido, extra\u00eddo de las canteras de Zandobbio, en la cercana Val Cavallina, hace que destaque sobre la piedra gris de las murallas defensivas.<br \/>\nPor estas caracter\u00edsticas, adem\u00e1s de ser uno de los lugares m\u00e1s fotografiados de B\u00e9rgamo, es un tel\u00f3n de fondo perfecto para proyectar luces de colores durante acontecimientos especiales (por ejemplo, la tricolor de la bandera italiana durante celebraciones relacionadas con aniversarios nacionales).<br \/>\nApoyado en la balaustrada disfrutar\u00e1s, por un lado, de una hermosa vista de las fortificaciones venecianas y, por otro, de una espl\u00e9ndida panor\u00e1mica de la Ciudad Baja y de la llanura hasta los Apeninos.    <\/p>\n","slides":[{"image":{"ID":6622,"id":6622,"title":"c987f17a0c75c3e6aa776d824750c376_fc5b6281.jpg","filename":"c987f17a0c75c3e6aa776d824750c376_fc5b6281.jpg","filesize":667602,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/puerta-san-giacomo\/c987f17a0c75c3e6aa776d824750c376_fc5b6281-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c987f17a0c75c3e6aa776d824750c376_fc5b6281-jpg-2","status":"inherit","uploaded_to":19594,"date":"2024-05-08 08:42:41","modified":"2024-05-08 12:22:24","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1285,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281-768x514.jpg","medium_large-width":768,"medium_large-height":514,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281-1024x685.jpg","large-width":1024,"large-height":685,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281-1536x1028.jpg","1536x1536-width":1536,"1536x1536-height":1028,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281.jpg","2048x2048-width":1920,"2048x2048-height":1285,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":402}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"porta san giacomo 1","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":6628,"id":6628,"title":"0487d66663ce51306fa12250ffedcc07_3638c838.jpg","filename":"0487d66663ce51306fa12250ffedcc07_3638c838.jpg","filesize":766538,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/puerta-san-giacomo\/0487d66663ce51306fa12250ffedcc07_3638c838-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"0487d66663ce51306fa12250ffedcc07_3638c838-jpg-2","status":"inherit","uploaded_to":19594,"date":"2024-05-08 08:42:42","modified":"2024-05-08 12:22:24","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1277,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838-1536x1022.jpg","1536x1536-width":1536,"1536x1536-height":1022,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838.jpg","2048x2048-width":1920,"2048x2048-height":1277,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"porta san giacomo detalle","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":6634,"id":6634,"title":"17d7eb37fd6a5fce963059c933588665_e9f539eb.jpg","filename":"17d7eb37fd6a5fce963059c933588665_e9f539eb.jpg","filesize":463730,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/puerta-san-giacomo\/17d7eb37fd6a5fce963059c933588665_e9f539eb-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"17d7eb37fd6a5fce963059c933588665_e9f539eb-jpg-2","status":"inherit","uploaded_to":19594,"date":"2024-05-08 08:42:42","modified":"2024-05-08 12:22:24","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":743,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb-1536x594.jpg","1536x1536-width":1536,"1536x1536-height":594,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb.jpg","2048x2048-width":1920,"2048x2048-height":743,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"porta san giacomo retro","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","filotto_fill":"manual","hero_title":"Puerta de Santiago","hero_text":"<p><span id=\"docs-internal-guid-83cf3d0d-7d5b-d56e-4e7d-c7895f4875e7\"><span>La \u00fanica brecha en las Murallas visible desde la Baja B\u00e9rgamo, la \u00fanica de m\u00e1rmol blanco pulido, la \u00fanica precedida por un viaducto de piedra que domina la llanura.<\/span><span><br class=\"kix-line-break\"><\/span><\/span><\/p>\n","indepth":"<p>Esta puerta est\u00e1 formada por un front\u00f3n triangular sostenido por semicolumnas de estilo cl\u00e1sico; al igual que las dem\u00e1s entradas a la ciudad, \u00e9sta est\u00e1 dominada por el Le\u00f3n de San Marcos esculpido, s\u00edmbolo del dominio veneciano.<br \/>\nEl aspecto de la Puerta de San Giacomo no siempre fue el que ves hoy: el antiguo puente levadizo de madera, que cerraba la entrada en caso de peligro, fue derribado a finales del siglo XVIII por orden del gobernador veneciano Alvise Contarini.<br \/>\nEn su lugar se construy\u00f3 el camino de mamposter\u00eda que a\u00fan hoy puede recorrerse.<br \/>\nLa belleza de la Puerta de San Giacomo deriva del rom\u00e1ntico viaducto de acceso, pero tambi\u00e9n del brillo del m\u00e1rmol con el que se construy\u00f3: este mineral se extra\u00eda desde la antig\u00fcedad en Zandobbio, en la provincia de B\u00e9rgamo.<br \/>\nLos bergamascos tambi\u00e9n lo utilizaron en la construcci\u00f3n de otros importantes edificios de la ciudad, como el Palazzo Nuovo (actual Biblioteca Angelo Mai) y la Fuente Contarini de la Piazza Vecchia.    <\/p>\n<h3>Curiosidad:<\/h3>\n<p>Al igual que las dem\u00e1s puertas de las Murallas, a las 22 h. de cada noche se cerraba Porta San Giacomo para garantizar la seguridad de la ciudad.<\/p>\n","hero_type":"images","filotto_items":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Ficha t\u00e9cnica"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"iu_kids":false,"iu_timetable":false,"poi_data":{"description":"<p>En el pasado, la Puerta de San Giacomo era la entrada a Citt\u00e0 Alta para quienes llegaban desde Mil\u00e1n.<br \/>\nEs el \u00fanico acceso a las Murallas perfectamente visible desde Viale Vittorio Emanuele, el eje que atraviesa la parte baja de B\u00e9rgamo de sur a norte, tanto por su posici\u00f3n como por su color.<br \/>\nEl m\u00e1rmol blanco con el que est\u00e1 construido, extra\u00eddo de las canteras de Zandobbio, en la cercana Val Cavallina, hace que destaque sobre la piedra gris de las murallas defensivas.<br \/>\nPor estas caracter\u00edsticas, adem\u00e1s de ser uno de los lugares m\u00e1s fotografiados de B\u00e9rgamo, es un tel\u00f3n de fondo perfecto para proyectar luces de colores durante acontecimientos especiales (por ejemplo, la tricolor de la bandera italiana durante celebraciones relacionadas con aniversarios nacionales).<br \/>\nApoyado en la balaustrada disfrutar\u00e1s, por un lado, de una hermosa vista de las fortificaciones venecianas y, por otro, de una espl\u00e9ndida panor\u00e1mica de la Ciudad Baja y de la llanura hasta los Apeninos.    <\/p>\n","indepth":"<p>Esta puerta est\u00e1 formada por un front\u00f3n triangular sostenido por semicolumnas de estilo cl\u00e1sico; al igual que las dem\u00e1s entradas a la ciudad, \u00e9sta est\u00e1 dominada por el Le\u00f3n de San Marcos esculpido, s\u00edmbolo del dominio veneciano.<br \/>\nEl aspecto de la Puerta de San Giacomo no siempre fue el que ves hoy: el antiguo puente levadizo de madera, que cerraba la entrada en caso de peligro, fue derribado a finales del siglo XVIII por orden del gobernador veneciano Alvise Contarini.<br \/>\nEn su lugar se construy\u00f3 el camino de mamposter\u00eda que a\u00fan hoy puede recorrerse.<br \/>\nLa belleza de la Puerta de San Giacomo deriva del rom\u00e1ntico viaducto de acceso, pero tambi\u00e9n del brillo del m\u00e1rmol con el que se construy\u00f3: este mineral se extra\u00eda desde la antig\u00fcedad en Zandobbio, en la provincia de B\u00e9rgamo.<br \/>\nLos bergamascos tambi\u00e9n lo utilizaron en la construcci\u00f3n de otros importantes edificios de la ciudad, como el Palazzo Nuovo (actual Biblioteca Angelo Mai) y la Fuente Contarini de la Piazza Vecchia.    <\/p>\n<h3>Curiosidad:<\/h3>\n<p>Al igual que las dem\u00e1s puertas de las Murallas, a las 22 h. de cada noche se cerraba Porta San Giacomo para garantizar la seguridad de la ciudad.<\/p>\n","howtogetthere":"","price":"","time":"","latitude":"45.701325","longitude":"9.662940","id_visit_manza":"6560","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":false},"size":"full","featured_video":false,"is_an_ambassador":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/19594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/19594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/6622"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=19594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=19594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=19594"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=19594"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=19594"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=19594"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=19594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}