{"id":19620,"date":"2024-05-08T11:04:49","date_gmt":"2024-05-08T09:04:49","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/academia-de-bellas-artes-tadini\/"},"modified":"2025-02-16T10:00:15","modified_gmt":"2025-02-16T09:00:15","slug":"academia-de-bellas-artes-tadini","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/academia-de-bellas-artes-tadini\/","title":{"rendered":"Academia de Bellas Artes Tadini"},"excerpt":{"rendered":"<p>Luigi Tadini (nacido en Verona en 1745 y fallecido en Lovere en 1829) encarna la figura del &#8220;noble aficionado&#8221;, amante del progreso, el arte y la ciencia y comprometido personalmente con el bienestar de la comunidad en los \u00e1mbitos pol\u00edtico, social y cultural.<\/p>\n","protected":false},"author":3,"featured_media":7144,"template":"","categories":[],"tags":[],"aggr":[],"area":[],"kind":[18679],"zona":[],"class_list":["post-19620","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","kind-poi-es"],"acf":{"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"indepth":"","howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","latitude":"45.815399","longitude":"10.073900","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"","iu_addr_city":"","iu_addr_province":"","iu_phone":"+39035962780","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"6062","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"http:\/\/www.accademiatadini.it","target":"","url_youtube":"","target_modal":""},"iu_timetable":false,"featured_video":false,"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Ficha t\u00e9cnica"},{"acf_fc_layout":"text","text":""}],"description":"<p>El proyecto cultural del conde se inscrib\u00eda en el animado debate sobre la funci\u00f3n educativa del museo, apoyado por instancias de tipo ilustrado y un fuerte sentido del deber c\u00edvico, que vio nacer, entre los siglos XVIII y XIX, &#8220;establecimientos&#8221; o &#8220;institutos&#8221; privados de bellas artes: la Accademia Carrara de B\u00e9rgamo (1795), la Pinacoteca di Paolo Tosio de Brescia (1832), el Stabilimento di belle arti Malaspina de Pav\u00eda (1833), el Istituto Ala Ponzone de Cremona (1842), que est\u00e1n en el origen del actual sistema muse\u00edstico de Lombard\u00eda.<br \/>\nDe todos ellos, la Accademia es el \u00fanico que ha conservado sus colecciones, biblioteca y archivos hist\u00f3ricos en su emplazamiento original, lo que, unido a su ubicaci\u00f3n panor\u00e1mica a orillas del lago, le confiere un encanto \u00fanico. <\/p>\n<p>\u00a0<\/p>\n<p>El conde Tadini frecuentaba Lovere con su familia como lugar de vacaciones.<br \/>\nTras la tr\u00e1gica muerte de su hijo Faustino, arrastrado por el derrumbe de un edificio en 1799, estuvo ausente de la ciudad durante mucho tiempo, a la que regres\u00f3 en 1818 con la intenci\u00f3n de construir un palacio para albergar sus ricas colecciones de arte.<br \/>\nEl encargo fue confiado a Sebastiano Salimbeni, arquitecto aficionado, que dise\u00f1\u00f3 un palacio en torno a la capilla consagrada a la memoria de Faustino Tadini (celebrada por una Estela esculpida por Antonio Canova) que servir\u00eda tanto de exposici\u00f3n de las colecciones como de sede de la escuela de dibujo y m\u00fasica, importante punto de referencia para la zona Sebino-Camuno.  <\/p>\n<p>\u00a0<\/p>\n<p>El nuevo edificio, construido entre 1821 y 1824, ya pod\u00eda albergar las colecciones de arte, que hasta entonces se expon\u00edan en las diez salas de la residencia privada del conde en Crema.<br \/>\nLa Academia de Bellas Artes Tadini, creada formalmente en 1829 a la muerte de su fundador, es uno de los museos m\u00e1s antiguos de Lombard\u00eda, fiel testigo del gusto de la \u00e9poca neocl\u00e1sica.<br \/>\nTodav\u00eda hoy est\u00e1 activa la Escuela de M\u00fasica, con un curso escolar regular y cursos de especializaci\u00f3n en verano para violinistas, violonchelistas y cantantes de \u00f3pera.<br \/>\nLa Sala de Conciertos acoge cada a\u00f1o, desde 1927, en abril y mayo, una prestigiosa temporada de conciertos de m\u00fasica de c\u00e1mara con int\u00e9rpretes de renombre internacional.   <\/p>\n<p>\u00a0<\/p>\n<h2>Criterios de exposici\u00f3n &#8211; Itinerario de visita<\/h2>\n<p>\u00a0<\/p>\n<p>El solemne palacio con vistas al lago ha conservado el encanto del antiguo museo.<br \/>\nLa colecci\u00f3n reunida por el conde Luigi Tadini refleja la variedad de intereses de un arist\u00f3crata que creci\u00f3 en el clima de la Ilustraci\u00f3n lombarda y que coleccion\u00f3 en su biblioteca obras de literatura, filosof\u00eda, historia y ciencia.<br \/>\nDe hecho, sus intereses se dirig\u00edan hacia las m\u00e1s variadas expresiones del arte, la t\u00e9cnica y la naturaleza: junto a pinturas, esculturas, dibujos y grabados, coleccionaba porcelana, y despu\u00e9s minerales, f\u00f3siles y animales.<br \/>\nUn resumen de su pensamiento parece expresarse en el sencillo ep\u00edgrafe dedicatorio que dict\u00f3, colocado en la escalera de entrada: A. MDCCCXXVI \/ LITTERIS ARTIBUS NATURAE \/ DICATUM.   <\/p>\n<p>\u00a0<\/p>\n<p>El coraz\u00f3n de la colecci\u00f3n son las obras de Antonio Canova, que mantuvo constantes relaciones amistosas con la familia: la Religi\u00f3n, un raro boceto en terracota para el monumento a Clemente XIII, y la Estela Tadini, consagrada a la memoria de Faustino, el hijo del conde, en el silencio de la capilla, que figura entre las \u00faltimas obras maestras del gran escultor.<br \/>\nLa Galer\u00eda, a la que se accede por una amplia escalera de tres tramos, est\u00e1 dispuesta a lo largo de 23 salas interconectadas que reproponen la antigua distribuci\u00f3n: el Gabinete Arqueol\u00f3gico es uno de los pocos de Lombard\u00eda que conserva su mobiliario del siglo XIX, y todas las salas lucen techos pintados por el trevigliese Luigi Dell&#8217;Era (1826). <\/p>\n<p>\u00a0<\/p>\n<p>La exposici\u00f3n incluye una fina selecci\u00f3n de objetos de arte de gusto neocl\u00e1sico, entre ellos una importante colecci\u00f3n de porcelana de las m\u00e1s importantes manufacturas italianas y europeas: Meissen, Sevres, la Real F\u00e1brica de N\u00e1poles.<br \/>\nEntre las obras maestras que no debes perderte se encuentran una Virgen con el Ni\u00f1o de Jacopo Bellini, un San Antonio de Padua de Antonio y Bartolomeo Vivarini, un hermoso retablo de Paris Bordon, un Retrato de hombre como posadero de Giacomo Ceruti conocido como il Pitocchetto, tres importantes cuadros de Francesco Hayez (Ecce Homo, Autorretrato, Virgen) una secci\u00f3n destinada a exponer, en rotaci\u00f3n, ejemplos significativos de arte moderno y contempor\u00e1neo adquiridos a lo largo del tiempo. <\/p>\n<p>\u00a0<\/p>\n<p>Las adquisiciones posteriores, tras las exposiciones en el Atelier Tadini, fueron constituyendo la colecci\u00f3n de la secci\u00f3n de arte moderno y contempor\u00e1neo.<br \/>\nEspecialmente importante a este respecto fue la exposici\u00f3n Europars, por el alto nivel de los artistas presentados.<br \/>\nVarios frescos del siglo XVI, desprendidos en distintas \u00e9pocas de los exteriores de casas de Lovere, y recogidos en el Aula Magna, documentan el compromiso de la Academia con la protecci\u00f3n y valorizaci\u00f3n de la zona.  <\/p>\n<p>\u00a0<\/p>\n<p>Tasa de entrada.<br \/>\nReducciones previstas. <\/p>\n<p>\u00a0<\/p>\n<p>Informaci\u00f3n sobre visitas &#8211; Se pueden organizar visitas guiadas para grupos y actividades para colegios, con cita previa y previo pago, tambi\u00e9n durante el periodo de cierre, poni\u00e9ndose en contacto con los servicios educativos del Museo en el siguiente n\u00famero de tel\u00e9fono m\u00f3vil 349.4118779 o por correo electr\u00f3nico en didattica@accademiatadini.it<\/p>\n<p>\u00a0<\/p>\n<p>Librer\u00eda &#8211; Ofrece una selecci\u00f3n de cat\u00e1logos de exposiciones organizadas por la Academia, publicaciones sobre la cultura neocl\u00e1sica y postales.<\/p>\n","slides":[{"image":{"ID":7144,"id":7144,"title":"da87a60a69af97093fb2ea386e2f404f_a0f47928.png","filename":"da87a60a69af97093fb2ea386e2f404f_a0f47928.png","filesize":1227677,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/da87a60a69af97093fb2ea386e2f404f_a0f47928.png","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/academia-de-bellas-artes-tadini\/da87a60a69af97093fb2ea386e2f404f_a0f47928-png-2\/","alt":"","author":"0","description":"","caption":"","name":"da87a60a69af97093fb2ea386e2f404f_a0f47928-png-2","status":"inherit","uploaded_to":19620,"date":"2024-05-08 08:43:30","modified":"2024-05-08 12:22:37","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":560,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/da87a60a69af97093fb2ea386e2f404f_a0f47928-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/da87a60a69af97093fb2ea386e2f404f_a0f47928-300x108.png","medium-width":300,"medium-height":108,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/da87a60a69af97093fb2ea386e2f404f_a0f47928-768x277.png","medium_large-width":768,"medium_large-height":277,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/da87a60a69af97093fb2ea386e2f404f_a0f47928-1024x370.png","large-width":1024,"large-height":370,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/da87a60a69af97093fb2ea386e2f404f_a0f47928-1536x555.png","1536x1536-width":1536,"1536x1536-height":555,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/da87a60a69af97093fb2ea386e2f404f_a0f47928.png","2048x2048-width":1550,"2048x2048-height":560,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/da87a60a69af97093fb2ea386e2f404f_a0f47928.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":108,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/da87a60a69af97093fb2ea386e2f404f_a0f47928.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/da87a60a69af97093fb2ea386e2f404f_a0f47928.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"academia tadini lovere","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":7150,"id":7150,"title":"ca852cb1351ef568a82ea1ca1792947d_e33455b5.jpg","filename":"ca852cb1351ef568a82ea1ca1792947d_e33455b5.jpg","filesize":334569,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ca852cb1351ef568a82ea1ca1792947d_e33455b5.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/academia-de-bellas-artes-tadini\/ca852cb1351ef568a82ea1ca1792947d_e33455b5-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ca852cb1351ef568a82ea1ca1792947d_e33455b5-jpg-2","status":"inherit","uploaded_to":19620,"date":"2024-05-08 08:43:32","modified":"2024-05-08 12:22:37","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1550,"height":596,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ca852cb1351ef568a82ea1ca1792947d_e33455b5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ca852cb1351ef568a82ea1ca1792947d_e33455b5-300x115.jpg","medium-width":300,"medium-height":115,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ca852cb1351ef568a82ea1ca1792947d_e33455b5-768x295.jpg","medium_large-width":768,"medium_large-height":295,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ca852cb1351ef568a82ea1ca1792947d_e33455b5-1024x394.jpg","large-width":1024,"large-height":394,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ca852cb1351ef568a82ea1ca1792947d_e33455b5-1536x591.jpg","1536x1536-width":1536,"1536x1536-height":591,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ca852cb1351ef568a82ea1ca1792947d_e33455b5.jpg","2048x2048-width":1550,"2048x2048-height":596,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ca852cb1351ef568a82ea1ca1792947d_e33455b5.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":115,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ca852cb1351ef568a82ea1ca1792947d_e33455b5.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":154,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ca852cb1351ef568a82ea1ca1792947d_e33455b5.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":231}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"academia tadini lovere","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":7156,"id":7156,"title":"307b4c304615cf0ce30cf022977224ee_cf587904.jpg","filename":"307b4c304615cf0ce30cf022977224ee_cf587904.jpg","filesize":454811,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/307b4c304615cf0ce30cf022977224ee_cf587904.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/academia-de-bellas-artes-tadini\/307b4c304615cf0ce30cf022977224ee_cf587904-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"307b4c304615cf0ce30cf022977224ee_cf587904-jpg-2","status":"inherit","uploaded_to":19620,"date":"2024-05-08 08:43:33","modified":"2024-05-08 12:22:37","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":779,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/307b4c304615cf0ce30cf022977224ee_cf587904-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/307b4c304615cf0ce30cf022977224ee_cf587904-300x148.jpg","medium-width":300,"medium-height":148,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/307b4c304615cf0ce30cf022977224ee_cf587904-768x379.jpg","medium_large-width":768,"medium_large-height":379,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/307b4c304615cf0ce30cf022977224ee_cf587904-1024x505.jpg","large-width":1024,"large-height":505,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/307b4c304615cf0ce30cf022977224ee_cf587904-1536x757.jpg","1536x1536-width":1536,"1536x1536-height":757,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/307b4c304615cf0ce30cf022977224ee_cf587904.jpg","2048x2048-width":1580,"2048x2048-height":779,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/307b4c304615cf0ce30cf022977224ee_cf587904.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":148,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/307b4c304615cf0ce30cf022977224ee_cf587904.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":197,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/307b4c304615cf0ce30cf022977224ee_cf587904.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":296}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"tadini","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.accademiatadini.it","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","filotto_fill":"manual","url":"http:\/\/www.accademiatadini.it","hero_title":"Academia de Bellas Artes Tadini","hero_text":"<p>Luigi Tadini (nacido en Verona en 1745 y fallecido en Lovere en 1829) encarna la figura del &#8220;noble aficionado&#8221;, amante del progreso, el arte y la ciencia y comprometido personalmente con el bienestar de la comunidad en los \u00e1mbitos pol\u00edtico, social y cultural.<\/p>\n","iu_website":"http:\/\/www.accademiatadini.it","size":"full","filotto_items":false,"hero_type":"images","accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Ficha t\u00e9cnica"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"poi_data":{"description":"<p>El proyecto cultural del conde se inscrib\u00eda en el animado debate sobre la funci\u00f3n educativa del museo, apoyado por instancias de tipo ilustrado y un fuerte sentido del deber c\u00edvico, que vio nacer, entre los siglos XVIII y XIX, &#8220;establecimientos&#8221; o &#8220;institutos&#8221; privados de bellas artes: la Accademia Carrara de B\u00e9rgamo (1795), la Pinacoteca di Paolo Tosio de Brescia (1832), el Stabilimento di belle arti Malaspina de Pav\u00eda (1833), el Istituto Ala Ponzone de Cremona (1842), que est\u00e1n en el origen del actual sistema muse\u00edstico de Lombard\u00eda.<br \/>\nDe todos ellos, la Accademia es el \u00fanico que ha conservado sus colecciones, biblioteca y archivos hist\u00f3ricos en su emplazamiento original, lo que, unido a su ubicaci\u00f3n panor\u00e1mica a orillas del lago, le confiere un encanto \u00fanico. <\/p>\n<p>\u00a0<\/p>\n<p>El conde Tadini frecuentaba Lovere con su familia como lugar de vacaciones.<br \/>\nTras la tr\u00e1gica muerte de su hijo Faustino, arrastrado por el derrumbe de un edificio en 1799, estuvo ausente de la ciudad durante mucho tiempo, a la que regres\u00f3 en 1818 con la intenci\u00f3n de construir un palacio para albergar sus ricas colecciones de arte.<br \/>\nEl encargo fue confiado a Sebastiano Salimbeni, arquitecto aficionado, que dise\u00f1\u00f3 un palacio en torno a la capilla consagrada a la memoria de Faustino Tadini (celebrada por una Estela esculpida por Antonio Canova) que servir\u00eda tanto de exposici\u00f3n de las colecciones como de sede de la escuela de dibujo y m\u00fasica, importante punto de referencia para la zona Sebino-Camuno.  <\/p>\n<p>\u00a0<\/p>\n<p>El nuevo edificio, construido entre 1821 y 1824, ya pod\u00eda albergar las colecciones de arte, que hasta entonces se expon\u00edan en las diez salas de la residencia privada del conde en Crema.<br \/>\nLa Academia de Bellas Artes Tadini, creada formalmente en 1829 a la muerte de su fundador, es uno de los museos m\u00e1s antiguos de Lombard\u00eda, fiel testigo del gusto de la \u00e9poca neocl\u00e1sica.<br \/>\nTodav\u00eda hoy est\u00e1 activa la Escuela de M\u00fasica, con un curso escolar regular y cursos de especializaci\u00f3n en verano para violinistas, violonchelistas y cantantes de \u00f3pera.<br \/>\nLa Sala de Conciertos acoge cada a\u00f1o, desde 1927, en abril y mayo, una prestigiosa temporada de conciertos de m\u00fasica de c\u00e1mara con int\u00e9rpretes de renombre internacional.   <\/p>\n<p>\u00a0<\/p>\n<h2>Criterios de exposici\u00f3n &#8211; Itinerario de visita<\/h2>\n<p>\u00a0<\/p>\n<p>El solemne palacio con vistas al lago ha conservado el encanto del antiguo museo.<br \/>\nLa colecci\u00f3n reunida por el conde Luigi Tadini refleja la variedad de intereses de un arist\u00f3crata que creci\u00f3 en el clima de la Ilustraci\u00f3n lombarda y que coleccion\u00f3 en su biblioteca obras de literatura, filosof\u00eda, historia y ciencia.<br \/>\nDe hecho, sus intereses se dirig\u00edan hacia las m\u00e1s variadas expresiones del arte, la t\u00e9cnica y la naturaleza: junto a pinturas, esculturas, dibujos y grabados, coleccionaba porcelana, y despu\u00e9s minerales, f\u00f3siles y animales.<br \/>\nUn resumen de su pensamiento parece expresarse en el sencillo ep\u00edgrafe dedicatorio que dict\u00f3, colocado en la escalera de entrada: A. MDCCCXXVI \/ LITTERIS ARTIBUS NATURAE \/ DICATUM.   <\/p>\n<p>\u00a0<\/p>\n<p>El coraz\u00f3n de la colecci\u00f3n son las obras de Antonio Canova, que mantuvo constantes relaciones amistosas con la familia: la Religi\u00f3n, un raro boceto en terracota para el monumento a Clemente XIII, y la Estela Tadini, consagrada a la memoria de Faustino, el hijo del conde, en el silencio de la capilla, que figura entre las \u00faltimas obras maestras del gran escultor.<br \/>\nLa Galer\u00eda, a la que se accede por una amplia escalera de tres tramos, est\u00e1 dispuesta a lo largo de 23 salas interconectadas que reproponen la antigua distribuci\u00f3n: el Gabinete Arqueol\u00f3gico es uno de los pocos de Lombard\u00eda que conserva su mobiliario del siglo XIX, y todas las salas lucen techos pintados por el trevigliese Luigi Dell&#8217;Era (1826). <\/p>\n<p>\u00a0<\/p>\n<p>La exposici\u00f3n incluye una fina selecci\u00f3n de objetos de arte de gusto neocl\u00e1sico, entre ellos una importante colecci\u00f3n de porcelana de las m\u00e1s importantes manufacturas italianas y europeas: Meissen, Sevres, la Real F\u00e1brica de N\u00e1poles.<br \/>\nEntre las obras maestras que no debes perderte se encuentran una Virgen con el Ni\u00f1o de Jacopo Bellini, un San Antonio de Padua de Antonio y Bartolomeo Vivarini, un hermoso retablo de Paris Bordon, un Retrato de hombre como posadero de Giacomo Ceruti conocido como il Pitocchetto, tres importantes cuadros de Francesco Hayez (Ecce Homo, Autorretrato, Virgen) una secci\u00f3n destinada a exponer, en rotaci\u00f3n, ejemplos significativos de arte moderno y contempor\u00e1neo adquiridos a lo largo del tiempo. <\/p>\n<p>\u00a0<\/p>\n<p>Las adquisiciones posteriores, tras las exposiciones en el Atelier Tadini, fueron constituyendo la colecci\u00f3n de la secci\u00f3n de arte moderno y contempor\u00e1neo.<br \/>\nEspecialmente importante a este respecto fue la exposici\u00f3n Europars, por el alto nivel de los artistas presentados.<br \/>\nVarios frescos del siglo XVI, desprendidos en distintas \u00e9pocas de los exteriores de casas de Lovere, y recogidos en el Aula Magna, documentan el compromiso de la Academia con la protecci\u00f3n y valorizaci\u00f3n de la zona.  <\/p>\n<p>\u00a0<\/p>\n<p>Tasa de entrada.<br \/>\nReducciones previstas. <\/p>\n<p>\u00a0<\/p>\n<p>Informaci\u00f3n sobre visitas &#8211; Se pueden organizar visitas guiadas para grupos y actividades para colegios, con cita previa y previo pago, tambi\u00e9n durante el periodo de cierre, poni\u00e9ndose en contacto con los servicios educativos del Museo en el siguiente n\u00famero de tel\u00e9fono m\u00f3vil 349.4118779 o por correo electr\u00f3nico en didattica@accademiatadini.it<\/p>\n<p>\u00a0<\/p>\n<p>Librer\u00eda &#8211; Ofrece una selecci\u00f3n de cat\u00e1logos de exposiciones organizadas por la Academia, publicaciones sobre la cultura neocl\u00e1sica y postales.<\/p>\n","indepth":"","howtogetthere":"","price":"","time":"","latitude":"45.815399","longitude":"10.073900","id_visit_manza":"6062","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"","iu_addr_city":"","iu_addr_province":"","iu_phone":"+39035962780","iu_cell":"349 411 8779","iu_website":"http:\/\/www.accademiatadini.it","iu_email":"didattica@accademiatadini.it","iu_document_label":"","iu_document":false,"iu_timetable":false},"hero_buttons_group":{"buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.accademiatadini.it","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}]},"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":"","modules":false,"hero_buttons":false,"iu_kids":false,"iu_cell":"349 411 8779","iu_email":"didattica@accademiatadini.it","is_an_ambassador":false,"accessibilityicons":[],"hero_random_sort":false,"filotto_no_overlay":false,"scheda_accessibilita":[{"ID":209198,"post_author":"3","post_date":"2025-10-11 14:55:47","post_date_gmt":"2025-10-11 12:55:47","post_content":"","post_title":"Accademia di Belle Arti Tadini","post_excerpt":"","post_status":"publish","comment_status":"closed","ping_status":"closed","post_password":"","post_name":"accademia-di-belle-arti-tadini","to_ping":"","pinged":"","post_modified":"2025-10-11 14:55:47","post_modified_gmt":"2025-10-11 12:55:47","post_content_filtered":"","post_parent":0,"guid":"https:\/\/visit.valueservice.cloud\/?post_type=accessibility&#038;p=209198","menu_order":0,"post_type":"accessibility","post_mime_type":"","comment_count":"0","filter":"raw"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/19620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/19620\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/7144"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=19620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=19620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=19620"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=19620"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=19620"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=19620"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=19620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}