{"id":19700,"date":"2024-05-08T11:05:18","date_gmt":"2024-05-08T09:05:18","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/san-pellegrino-terme\/"},"modified":"2025-02-16T10:01:42","modified_gmt":"2025-02-16T09:01:42","slug":"san-pellegrino-terme","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/san-pellegrino-terme\/","title":{"rendered":"San Pellegrino Terme"},"excerpt":{"rendered":"<p>Impresionantes edificios modernistas, balneario, centro de bienestar, una de las aguas minerales m\u00e1s famosas del mundo: no es un sue\u00f1o, \u00a1ven a Val Brembana!<\/p>\n","protected":false},"author":3,"featured_media":8512,"template":"","categories":[],"tags":[],"aggr":[17639],"area":[],"kind":[18679],"zona":[],"class_list":["post-19700","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","aggr-imperdibile-es","kind-poi-es"],"acf":{"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","latitude":"45.838146","longitude":"9.664217","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"","iu_addr_city":"","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"http:\/\/www.sanpellegrinoterme.gov.it\/","iu_email":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"3030","url_youtube":"","iu_timetable":false,"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Ficha t\u00e9cnica"},{"acf_fc_layout":"text","text":""}],"description":"<p>San Pellegrino Terme -la perla de la <strong>Val Brembana-<\/strong> es una renombrada ciudad situada a lo largo del curso del r\u00edo Brembo, mundialmente conocido por su <strong>agua<\/strong>, la famosa <strong>San Pellegrino<\/strong>. Los edificios Art Nouveau, el hist\u00f3rico centro termal, el famoso <strong>Gran Hotel<\/strong> y la planta de agua de <strong>San P <\/strong>ellegrino hacen de esta ciudad un destino fascinante.<\/p>\n<p><strong>Balneario de San Pellegrino: arquitectura Art Nouveau y dise\u00f1o moderno<\/strong><\/p>\n<p><strong>Los ba\u00f1os termales<\/strong>, construidos en 1840, transformaron un peque\u00f1o pueblo del valle en un renombrado lugar de vacaciones para la rica burgues\u00eda internacional. Las instalaciones se ampliaron a\u00fan m\u00e1s a finales del siglo XIX, con edificios construidos en <strong>estilo<\/strong> Art <strong>Nouveau<\/strong>, el movimiento art\u00edstico que favorec\u00eda las l\u00edneas curvas y arabescas. En pocos a\u00f1os este movimiento conquist\u00f3 San Pellegrino, pobl\u00e1ndolo con algunos de los ejemplos m\u00e1s ecl\u00e9cticos de este estilo en el mundo, como el majestuoso <strong>Casino<\/strong> Municipal, el <strong>Gran Hotel<\/strong> y la <strong>f\u00e1brica embotelladora de agua<\/strong>. La mayor\u00eda de estas obras pueden visitarse ahora; algunas han sido restauradas recientemente y reabiertas al p\u00fablico. Las <strong>termas<\/strong>, por ejemplo, forman ahora parte de un elegante centro de bienestar que combina la arquitectura Art Nouveau y un refinado dise\u00f1o moderno. <\/p>\n","slides":[{"image":false,"video":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/IMP-San-Pellegrino-Terme.mp4","video_mobile":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/IMP-San-Pellegrino-Terme-V.mp4","video_with_audio":false,"duration_ms":"","title":"gran hotel san pellegrino","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"filotto_layout":"scroll","filotto_fill":"manual","url":"http:\/\/www.sanpellegrinoterme.gov.it\/","hero_title":"San Pellegrino Terme","hero_text":"<p>Encantadores edificios modernistas, balnearios y una de las aguas minerales m\u00e1s famosas del mundo.<\/p>\n","indepth":"<h3>Historia<\/h3>\n<p><strong>San Pellegrino<\/strong> <strong>Terme<\/strong> floreci\u00f3 a finales del siglo XIX y principios del XX, incorporando plenamente los dictados de la <strong><em>Belle <\/em><\/strong><em><strong>\u00c9poque<\/strong>,<\/em> a saber, un optimismo generalizado y un renovado deseo de diversi\u00f3n y ligereza.<br \/>\nDurante unos veinte a\u00f1os se convirti\u00f3 en el fulcro de la vida social bergamasca y no s\u00f3lo, ayudado sin duda por la presencia del <strong>Balneario<\/strong>,<strong> el Casino <\/strong>y<strong> el Gran Hotel<\/strong>, refinadas guaridas de la rica burgues\u00eda industrial que quer\u00eda divertirse.<br \/>\nLas infraestructuras tambi\u00e9n se beneficiaron de estas condiciones positivas: adem\u00e1s del ferrocarril que conectaba la ciudad con B\u00e9rgamo, en 1909 se construy\u00f3 un funicular para salvar el desnivel de 300 metros que la separaba de la estaci\u00f3n de Vetta.<br \/>\nFue la Primera Guerra Mundial la que trajo consigo una disminuci\u00f3n inicial del flujo de veraneantes, que continu\u00f3 en los a\u00f1os posteriores a la Segunda Guerra Mundial y condujo al cierre del Gran Hotel.<br \/>\nLa industria del agua, en cambio, no conoce el declive y<strong> San Pellegrino<\/strong> sigue invirtiendo mucho en ella a trav\u00e9s del embotellado, creando una etiqueta exportada y famosa en todo el mundo.<br \/>\nHoy puedes sumergirte en el pasado y revivir el mismo esplendor de principios del siglo XX en el<strong> nuevo centro termal<\/strong>, recientemente restaurado y realizado seg\u00fan un proyecto que incluye tambi\u00e9n la recuperaci\u00f3n del suntuoso Casino, donde puedes alojarte.<\/p>\n","size":"full","filotto_items":false,"hero_type":"images","accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Ficha t\u00e9cnica"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"poi_data":{"description":"<p>San Pellegrino Terme -la perla de la <strong>Val Brembana-<\/strong> es una renombrada ciudad situada a lo largo del curso del r\u00edo Brembo, mundialmente conocido por su <strong>agua<\/strong>, la famosa <strong>San Pellegrino<\/strong>. Los edificios Art Nouveau, el hist\u00f3rico centro termal, el famoso <strong>Gran Hotel<\/strong> y la planta de agua de <strong>San P <\/strong>ellegrino hacen de esta ciudad un destino fascinante.<\/p>\n<p><strong>Balneario de San Pellegrino: arquitectura Art Nouveau y dise\u00f1o moderno<\/strong><\/p>\n<p><strong>Los ba\u00f1os termales<\/strong>, construidos en 1840, transformaron un peque\u00f1o pueblo del valle en un renombrado lugar de vacaciones para la rica burgues\u00eda internacional. Las instalaciones se ampliaron a\u00fan m\u00e1s a finales del siglo XIX, con edificios construidos en <strong>estilo<\/strong> Art <strong>Nouveau<\/strong>, el movimiento art\u00edstico que favorec\u00eda las l\u00edneas curvas y arabescas. En pocos a\u00f1os este movimiento conquist\u00f3 San Pellegrino, pobl\u00e1ndolo con algunos de los ejemplos m\u00e1s ecl\u00e9cticos de este estilo en el mundo, como el majestuoso <strong>Casino<\/strong> Municipal, el <strong>Gran Hotel<\/strong> y la <strong>f\u00e1brica embotelladora de agua<\/strong>. La mayor\u00eda de estas obras pueden visitarse ahora; algunas han sido restauradas recientemente y reabiertas al p\u00fablico. Las <strong>termas<\/strong>, por ejemplo, forman ahora parte de un elegante centro de bienestar que combina la arquitectura Art Nouveau y un refinado dise\u00f1o moderno. <\/p>\n","indepth":"<h3>Historia<\/h3>\n<p><strong>San Pellegrino<\/strong> <strong>Terme<\/strong> floreci\u00f3 a finales del siglo XIX y principios del XX, incorporando plenamente los dictados de la <strong><em>Belle <\/em><\/strong><em><strong>\u00c9poque<\/strong>,<\/em> a saber, un optimismo generalizado y un renovado deseo de diversi\u00f3n y ligereza.<br \/>\nDurante unos veinte a\u00f1os se convirti\u00f3 en el fulcro de la vida social bergamasca y no s\u00f3lo, ayudado sin duda por la presencia del <strong>Balneario<\/strong>,<strong> el Casino <\/strong>y<strong> el Gran Hotel<\/strong>, refinadas guaridas de la rica burgues\u00eda industrial que quer\u00eda divertirse.<br \/>\nLas infraestructuras tambi\u00e9n se beneficiaron de estas condiciones positivas: adem\u00e1s del ferrocarril que conectaba la ciudad con B\u00e9rgamo, en 1909 se construy\u00f3 un funicular para salvar el desnivel de 300 metros que la separaba de la estaci\u00f3n de Vetta.<br \/>\nFue la Primera Guerra Mundial la que trajo consigo una disminuci\u00f3n inicial del flujo de veraneantes, que continu\u00f3 en los a\u00f1os posteriores a la Segunda Guerra Mundial y condujo al cierre del Gran Hotel.<br \/>\nLa industria del agua, en cambio, no conoce el declive y<strong> San Pellegrino<\/strong> sigue invirtiendo mucho en ella a trav\u00e9s del embotellado, creando una etiqueta exportada y famosa en todo el mundo.<br \/>\nHoy puedes sumergirte en el pasado y revivir el mismo esplendor de principios del siglo XX en el<strong> nuevo centro termal<\/strong>, recientemente restaurado y realizado seg\u00fan un proyecto que incluye tambi\u00e9n la recuperaci\u00f3n del suntuoso Casino, donde puedes alojarte.<\/p>\n","howtogetthere":"","price":"","time":"","latitude":"45.838146","longitude":"9.664217","id_visit_manza":"3030","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"","iu_addr_city":"","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"http:\/\/www.sanpellegrinoterme.gov.it\/","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":false},"hero_buttons_group":{"buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.sanpellegrinoterme.gov.it\/","select_post":null,"target":"_self","url_youtube":"","target_modal":""},{"style":false,"text":"","icon":{"button_icon":"none"},"function":false,"url":"","select_post":null,"target":false,"url_youtube":"","target_modal":""}]},"buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.sanpellegrinoterme.gov.it\/","select_post":null,"target":"_self","url_youtube":"","target_modal":""},{"style":false,"text":"","icon":{"button_icon":"none"},"function":false,"url":"","select_post":null,"target":false,"url_youtube":"","target_modal":""}],"modules":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"iu_document_label":"","hero_buttons":[{"style":"primary","text":"Ponte en contacto con","icon":{"button_icon":"none"},"function":"link","url":"http:\/\/www.sanpellegrinoterme.gov.it\/","select_post":null,"target":"_self","url_youtube":"","target_modal":""}],"iu_kids":false,"is_an_ambassador":false,"featured_video":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/06\/IMP-San-Pellegrino-Terme_SH.mp4"},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/19700","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/19700\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/8512"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=19700"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=19700"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=19700"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=19700"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=19700"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=19700"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=19700"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}