{"id":36031,"date":"2025-06-08T14:56:25","date_gmt":"2025-06-08T12:56:25","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/visitas-guiadas-de-bergamo-alta-domingo\/"},"modified":"2025-05-12T19:56:34","modified_gmt":"2025-05-12T17:56:34","slug":"visitas-guiadas-de-bergamo-alta-domingos-y-dias-festivos","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/visitas-guiadas-de-bergamo-alta-domingos-y-dias-festivos\/","title":{"rendered":"Visitas guiadas de B\u00e9rgamo Alta &#8211; Domingos y d\u00edas festivos"},"excerpt":{"rendered":"<p>D\u00e9janos llevarte en una visita guiada de dos horas para descubrir la ciudad.<br \/>\nVisita del domingo y en los d\u00edas festivos a las 10:30 horas<\/p>\n","protected":false},"author":0,"featured_media":184055,"template":"","categories":[521,525],"tags":[],"aggr":[],"area":[],"kind":[18702],"zona":[],"class_list":["post-36031","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-esperienze","category-experiencias","kind-esperienza-es"],"acf":{"buttons":[{"style":"primary","text":"Comprar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contactar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Visitas guiadas de B\u00e9rgamo Alta - Domingos y d\u00edas festivos","hero_text":"<p>D\u00e9janos llevarte en una visita guiada de dos horas para descubrir la ciudad.<br \/>\nVisita del domingo y en los d\u00edas festivos a las 10:30 horas<\/p>\n","slides":[{"image":{"ID":184055,"id":184055,"title":"ec_service_2574_12","filename":"ec_service_2574_12.jpg","filesize":94459,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2574_12.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/visitas-guiadas-de-bergamo-alta-domingos-y-dias-festivos\/ec_service_2574_12-2-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2574_12-2-2","status":"inherit","uploaded_to":36031,"date":"2025-04-22 17:48:37","modified":"2025-05-12 17:56:35","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":543,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2574_12-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2574_12-300x136.jpg","medium-width":300,"medium-height":136,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2574_12-768x348.jpg","medium_large-width":768,"medium_large-height":348,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2574_12-1024x463.jpg","large-width":1024,"large-height":463,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2574_12.jpg","1536x1536-width":1200,"1536x1536-height":543,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2574_12.jpg","2048x2048-width":1200,"2048x2048-height":543,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2574_12.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":136,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2574_12.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":181,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2574_12.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":272}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":[{"style":"primary","text":"Comprar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contactar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>B\u00e9rgamo merece una visita, pero no una cualquiera!<br \/>\nLa ciudad esconde sorpresas e historias por descubrir y los gu\u00edas de la ciudad te har\u00e1n admirar lo esencial a trav\u00e9s de un itinerario que recorre las calles y mayores monumentos de la ciudad vieja.<\/p>\n<p>La cita es en la Torre del Gombito (Via Gombito, 13), una antigua torre que ahora acoge el punto de informaci\u00f3n tur\u00edstica, todos los domingos y en los d\u00edas festivos a las 10.30 horas.<\/p>\n<p>Conocer\u00e1s a tu gu\u00eda autorizado que te acompa\u00f1ar\u00e1 en un viaje por la historia, la cultura, el arte y las tradiciones de B\u00e9rgamo.<br \/>\nEl tour de los domingos y en los d\u00edas festivos es en italiano.<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Todos los domingos y en los d\u00edas festivos con salida a las 10.30 horas<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>En caso de no presentarse, se cargar\u00e1 el importe total.<\/p>\n","moredetails":"<p>Visita gratuita para ni\u00f1os hasta 12 a\u00f1os (es necesario comunicar su presencia con antelaci\u00f3n).<\/p>\n<p>Punto de encuentro: frente al punto de informaci\u00f3n tur\u00edstica de B\u00e9rgamo Alta en Via Gombito, 13.<\/p>\n<p>Duraci\u00f3n: 2 horas<\/p>\n","whatsincluded":"<p>Visita guiada de dos horas con gu\u00eda tur\u00edstico autorizado<\/p>\n","whatsnotincluded":"<p>-Transporte para llegar al lugar del tour.<br \/>\n-Cualquier entrada (opcional)<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.70364710","longitude":"9.66417920","startingprice":"12.00","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Gombito, 13","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"Ass. Guide Turistiche Citt\u00e0 di Bergamo, Bergamo, Bergamo","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=esp&no_qr=si&styleid=3073&ecomid=2574&serviceid=12","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"2h","iu_languages":"italiano","iu_minpeople":"M\u00ednimo 1 persona","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_2574_12","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"04\/03\/2023","validto":"31\/12\/2025","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":[{"stars":"5","text":"<p>Passeggiata molto interessante ,la guida e&#8217;stata molto brava a far conoscere e raccontare la storia di Bergamo alta.<\/p>\n","date":"01\/05\/2025","author":"Luigi"},{"stars":"5","text":"","date":"30\/04\/2025","author":"Dario"},{"stars":"4","text":"<p>Ottima visita guidata con Elisabetta che ci fa fatto scoprire le perle nascoste di Bergamo Alta!<\/p>\n","date":"28\/04\/2025","author":"Giovanni"},{"stars":"5","text":"<p>Ciao, complimenti a Elisabetta, guida attenta, professionale, preparata, \u00e8 stata eccezzionale, per un milanese come me, che non aveva mai visitato Bergamo, mi ha sorpreso, bravi tutti, Gianfranco<\/p>\n","date":"04\/04\/2025","author":"ANNA"},{"stars":"5","text":"<p>Citt\u00e0 molto bella, apprezzata la visita guidata nella citt\u00e0 alta molto brava la guida.  Musei ben strutturati . Da consigliare.<\/p>\n","date":"02\/04\/2025","author":"Gianfranco"},{"stars":"5","text":"<p>Guida molto preparata e piacevole da seguire anche con piccoli scorci  da scoprire<\/p>\n","date":"26\/03\/2025","author":"Paola"},{"stars":"5","text":"<p>La guida era molto brava e preparata<\/p>\n","date":"19\/03\/2025","author":"Patrizia"},{"stars":"5","text":"<p>Visita guidata molto bella &#8211; la signora che ci ha fatto da guida e\u0092 molto preparata, si sentiva che ama la sua citt\u00e0! Esperienza super consigliata<\/p>\n","date":"05\/03\/2025","author":"Stefania"},{"stars":"5","text":"<p>Tutto bene<\/p>\n","date":"19\/02\/2025","author":"katya"},{"stars":"5","text":"<p>X Elisabetta la nostra guida tantissimi complimenti per averci fatto scoprire anche un itinerario al di fuori del solito.. giro.. ben preparata e disponibile<\/p>\n","date":"15\/01\/2025","author":"Pia"},{"stars":"5","text":"<p>La guida veramente eccezionale ,molto competente e preparata ,professionale al massimo ,la visita e&#8217; durata h.2&#8243;30 .Siamo rimasti veramente contenti,complimenti Bergamo ci rimarr\u00e0 nel cuore!!!Luisella Luigi<\/p>\n","date":"09\/01\/2025","author":"Stefano"},{"stars":"5","text":"<p>Guida fantastica. Esposizione delle cose e dei fatti in maniera chiara ed interessante e soprattutto udibile (altoparlante perfetto).<\/p>\n","date":"01\/01\/2025","author":"Alberto"},{"stars":"5","text":"<p>ottima esperienza<\/p>\n","date":"05\/12\/2024","author":"Luisella"},{"stars":"5","text":"<p>Bellissima gita e bellissima citt\u00e0&#8230;.Bergamo alta mi ha colpita in tutto,tantissimo verde consiglio a tutti una carina passeggiata con la guida che sono stati fantastici!!!<\/p>\n","date":"04\/12\/2024","author":"Samuele"},{"stars":"5","text":"<p>Ottima visita con ottima guida<\/p>\n","date":"21\/11\/2024","author":"Simonetta"},{"stars":"5","text":"<p>Experiencia fant\u00e1stica y totalmente recomendable.<\/p>\n","date":"20\/11\/2024","author":"Caterina"},{"stars":"5","text":"<p>Visita guidata molto interessante ad un prezzo contenuto!<\/p>\n","date":"02\/10\/2024","author":"Mirco"},{"stars":"5","text":"<p>Non pensavo che Bergamo fosse una Citt\u00e0  cos\u00ec bella.  Gente simpatica, gentile e molto disponibile. La visita guidata della Citt\u00e0 \u00e8  stata super. Grazie per l&#8217;accoglienza.<\/p>\n","date":"28\/08\/2024","author":"eligio"},{"stars":"5","text":"<p>Visita turistica molto interessante. La guida molto preparata e appassionata. Purtroppo non \u00e8 stato possibile visitare la basilica. Il pagamento aggiuntivo di 5 euro per la visita degli interni mi sembra possa essere regolamentato meglio, magari organizzando un percorso alternativo. Grazie<\/p>\n","date":"19\/07\/2024","author":"Nuria"},{"stars":"5","text":"","date":"17\/07\/2024","author":"Raffaella"},{"stars":"5","text":"","date":"08\/05\/2024","author":"Elena"},{"stars":"5","text":"","date":"03\/05\/2024","author":"Claudia"},{"stars":"4","text":"","date":"12\/04\/2024","author":"Cristiana"}],"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_auditory_accessibility":"no","iu_cognitive_accessibility":"yes","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","featured_video":false,"is_an_ambassador":false,"only_ambassadors":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/36031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/36031\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/184055"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=36031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=36031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=36031"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=36031"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=36031"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=36031"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=36031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}