{"id":36088,"date":"2025-06-08T14:57:49","date_gmt":"2025-06-08T12:57:49","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/tour-gastronomico-de-bergamo-por-la-manana\/"},"modified":"2025-05-12T19:58:31","modified_gmt":"2025-05-12T17:58:31","slug":"tour-gastronomico-de-bergamo-por-la-manana","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/tour-gastronomico-de-bergamo-por-la-manana\/","title":{"rendered":"Tour gastron\u00f3mico de B\u00e9rgamo &#8211; por la ma\u00f1ana"},"excerpt":{"rendered":"<p>Te espera un recorrido a pie lleno de sabor y tradici\u00f3n.<br \/>\nConoce las especialidades de B\u00e9rgamo de la mano de un experto en gastronom\u00eda local.<\/p>\n","protected":false},"author":0,"featured_media":184300,"template":"","categories":[521,525],"tags":[],"aggr":[17644],"area":[],"kind":[18702],"zona":[],"class_list":["post-36088","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-esperienze","category-experiencias","aggr-freschi-di-stagione-es","kind-esperienza-es"],"acf":{"buttons":[{"style":"primary","text":"Comprar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contactar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Tour gastron\u00f3mico de B\u00e9rgamo - por la ma\u00f1ana","hero_text":"<p>Te espera un recorrido a pie lleno de sabor y tradici\u00f3n.<br \/>\nConoce las especialidades de B\u00e9rgamo de la mano de un experto en gastronom\u00eda local.<\/p>\n","slides":[{"image":{"ID":184300,"id":184300,"title":"ec_service_4032_1","filename":"ec_service_4032_1.jpg","filesize":73518,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4032_1.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/tour-gastronomico-de-bergamo-por-la-manana\/ec_service_4032_1-2-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4032_1-2-2","status":"inherit","uploaded_to":36088,"date":"2025-04-22 17:49:43","modified":"2025-05-12 17:58:32","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":497,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4032_1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4032_1-300x124.jpg","medium-width":300,"medium-height":124,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4032_1-768x318.jpg","medium_large-width":768,"medium_large-height":318,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4032_1-1024x424.jpg","large-width":1024,"large-height":424,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4032_1.jpg","1536x1536-width":1200,"1536x1536-height":497,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4032_1.jpg","2048x2048-width":1200,"2048x2048-height":497,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4032_1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":124,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4032_1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":166,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4032_1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":249}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":35482,"id":35482,"title":"ec_service_4032_1_2.jpg","filename":"ec_service_4032_1_2.jpg","filesize":75434,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_4032_1_2.jpg","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/tour-gastronomico-de-bergamo-por-la-manana\/ec_service_4032_1_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4032_1_2-jpg-2","status":"inherit","uploaded_to":36088,"date":"2024-05-21 11:43:01","modified":"2025-05-12 17:58:32","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":500,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_4032_1_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_4032_1_2-300x125.jpg","medium-width":300,"medium-height":125,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_4032_1_2-768x320.jpg","medium_large-width":768,"medium_large-height":320,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_4032_1_2-1024x427.jpg","large-width":1024,"large-height":427,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_4032_1_2.jpg","1536x1536-width":1200,"1536x1536-height":500,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_4032_1_2.jpg","2048x2048-width":1200,"2048x2048-height":500,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_4032_1_2.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":125,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_4032_1_2.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":167,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ec_service_4032_1_2.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":250}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":[{"style":"primary","text":"Comprar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contactar","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>&#8211; 4 paradas enogastron\u00f3micas por la ciudad<br \/>\n&#8211; Te acompa\u00f1ar\u00e1 un experto culinario local<br \/>\n&#8211; Conocer\u00e1s a gente nueva <\/p>\n<p>LO QUE TE ESPERA<br \/>\nCon esta experiencia har\u00e1s un recorrido a pie por B\u00e9rgamo Alta: el coraz\u00f3n hist\u00f3rico de la ciudad. Te acompa\u00f1ar\u00e1 un experto culinario local y conocer\u00e1s a gente nueva que, como t\u00fa, quiere conocer las especialidades locales.<br \/>\nTambi\u00e9n te detendr\u00e1s en lugares emblem\u00e1ticos de la ciudad, aquellos que suelen frecuentar los bergamascos, y degustar\u00e1s las mejores especialidades de B\u00e9rgamo.<br \/>\nPrep\u00e1rate para un d\u00eda lleno de sabor! Habr\u00e1 al menos cuatro paradas gastron\u00f3micas. <\/p>\n<p>Las degustaciones dependen de la estacionalidad, pero te dejamos una lista de lo que podr\u00e1s probar durante el recorrido: <\/p>\n<p>Aperitivo con una copa de Valcalepio &#8211; rebanadas de pan tostado con la adici\u00f3n de ingredientes locales junto con una copa de vino tinto Valcalepio, el DOC de B\u00e9rgamo, producido en la zona colindante con el lago Iseo. <\/p>\n<p>Casoncelli: el primer plato t\u00edpico por excelencia. Se trata de una pasta rellena de queso parmesano y carne aderezada con tocino crujiente, mantequilla y salvia. <\/p>\n<p>Foiade &#8211; otro primer plato tradicional, normalmente acompa\u00f1ado de una salsa de setas, que a veces se encuentra con salsa de carne o de queso.  <\/p>\n<p>Polenta con manteca de cerdo y queso &#8211; plato tradicional bergamasco elaborado con harina de ma\u00edz. La polenta se sirve con lonchas de manteca de cerdo que se deshacen en la boca o con los famosos y sabrosos quesos de los valles bergamascos.<\/p>\n<p>Pan tostado con Taleggio &#8211; un pan r\u00fastico adornado con sabroso Taleggio DOP y cebollas caramelizadas.<\/p>\n<p>Helado de Stracciatella &#8211; leche y nata con copos de chocolate negro: un sabor muy apreciado por todos, inventado en B\u00e9rgamo en los a\u00f1os 60: visite la misma helader\u00eda que vio nacer esta excepcional delicia.  <\/p>\n<p>Caf\u00e9 espresso &#8211; un buen caf\u00e9 espresso es la conclusi\u00f3n tradicional e indispensable de cualquier comida italiana que se precie.<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Todo el a\u00f1o<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>Cancelaci\u00f3n gratuita si se realiza en las 24 horas anteriores al inicio del viaje que haya reservado con al menos 2 d\u00edas de antelaci\u00f3n.<\/p>\n","moredetails":"<p>Punto de encuentro: Piazza Mercato delle Scarpe en B\u00e9rgamo Alta<br \/>\nD\u00edas y horarios:<br \/>\nDe martes a domingo a las 11.30 horas<br \/>\nDe martes a jueves y domingo a las 18.30 horas.<br \/>\nPres\u00e9ntate en el punto de encuentro 10 minutos antes del comienzo de la visita. <\/p>\n<p>El recorrido dura 3 horas.<br \/>\nTodo se hace a pie: se recomienda llevar ropa c\u00f3moda y calzado plano (la citt\u00e0 alta tiene adoquines hist\u00f3ricos).<\/p>\n<p>Es necesario reservar para un m\u00ednimo de 2 personas.<br \/>\nEl grupo al que te unas estar\u00e1 formado por un m\u00e1ximo de 12 personas. <\/p>\n<p>TARIFAS<br \/>\nAdulto: 85 euros<br \/>\nNi\u00f1o de 6 a 10 a\u00f1os: 43 euros<br \/>\nNi\u00f1o menor de 5 a\u00f1os: gratis<\/p>\n","whatsincluded":"<p>&#8211; Acompa\u00f1ado por un experto culinario local<br \/>\n&#8211; 1 degustaci\u00f3n en cada parada<\/p>\n","whatsnotincluded":"<p>&#8211; Transporte hasta\/desde el punto de encuentro<br \/>\n&#8211; Propinas<br \/>\n&#8211; Todo lo que no se mencione expl\u00edcitamente en la secci\u00f3n &#8220;Qu\u00e9 incluye&#8221;<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.70310210","longitude":"9.66510250","startingprice":"85.00","gpxmap":"","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Piazza Mercato delle Scarpe","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"Do Eat Better srl, Via Gabriele d'Annunzio, 2\/88, Genova","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=esp&no_qr=si&styleid=3073&ecomid=4032&serviceid=1","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"3h 30 min","iu_languages":"Ingl\u00e9s - italiano","iu_minpeople":"M\u00ednimo 2 personas","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_4032_1","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"24\/11\/2023","validto":"31\/12\/2025","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"tcm_content":false,"accessibilitycontent":{"tcm_content":false},"gallery":{"gallery_items":false},"poi_data":{"description":"<p>&#8211; 4 paradas enogastron\u00f3micas por la ciudad<br \/>\n&#8211; Te acompa\u00f1ar\u00e1 un experto culinario local<br \/>\n&#8211; Conocer\u00e1s a gente nueva <\/p>\n<p>LO QUE TE ESPERA<br \/>\nCon esta experiencia har\u00e1s un recorrido a pie por B\u00e9rgamo Alta: el coraz\u00f3n hist\u00f3rico de la ciudad. Te acompa\u00f1ar\u00e1 un experto culinario local y conocer\u00e1s a gente nueva que, como t\u00fa, quiere conocer las especialidades locales.<br \/>\nTambi\u00e9n te detendr\u00e1s en lugares emblem\u00e1ticos de la ciudad, aquellos que suelen frecuentar los bergamascos, y degustar\u00e1s las mejores especialidades de B\u00e9rgamo.<br \/>\nPrep\u00e1rate para un d\u00eda lleno de sabor! Habr\u00e1 al menos cuatro paradas gastron\u00f3micas. <\/p>\n<p>Las degustaciones dependen de la estacionalidad, pero te dejamos una lista de lo que podr\u00e1s probar durante el recorrido: <\/p>\n<p>Aperitivo con una copa de Valcalepio &#8211; rebanadas de pan tostado con la adici\u00f3n de ingredientes locales junto con una copa de vino tinto Valcalepio, el DOC de B\u00e9rgamo, producido en la zona colindante con el lago Iseo. <\/p>\n<p>Casoncelli: el primer plato t\u00edpico por excelencia. Se trata de una pasta rellena de queso parmesano y carne aderezada con tocino crujiente, mantequilla y salvia. <\/p>\n<p>Foiade &#8211; otro primer plato tradicional, normalmente acompa\u00f1ado de una salsa de setas, que a veces se encuentra con salsa de carne o de queso.  <\/p>\n<p>Polenta con manteca de cerdo y queso &#8211; plato tradicional bergamasco elaborado con harina de ma\u00edz. La polenta se sirve con lonchas de manteca de cerdo que se deshacen en la boca o con los famosos y sabrosos quesos de los valles bergamascos.<\/p>\n<p>Pan tostado con Taleggio &#8211; un pan r\u00fastico adornado con sabroso Taleggio DOP y cebollas caramelizadas.<\/p>\n<p>Helado de Stracciatella &#8211; leche y nata con copos de chocolate negro: un sabor muy apreciado por todos, inventado en B\u00e9rgamo en los a\u00f1os 60: visite la misma helader\u00eda que vio nacer esta excepcional delicia.  <\/p>\n<p>Caf\u00e9 espresso &#8211; un buen caf\u00e9 espresso es la conclusi\u00f3n tradicional e indispensable de cualquier comida italiana que se precie.<\/p>\n","indepth":"","howtogetthere":"","price":"","time":"","latitude":"45.70310210","longitude":"9.66510250","id_visit_manza":"","iu_motor_accessibility":"no","iu_visual_accessibility":"yes","iu_auditory_accessibility":"yes","iu_cognitive_accessibility":"yes","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"Piazza Mercato delle Scarpe","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":false},"iu_motor_accessibility":"no","iu_visual_accessibility":"yes","iu_auditory_accessibility":"yes","iu_cognitive_accessibility":"yes","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","featured_video":false,"is_an_ambassador":false,"only_ambassadors":false,"object_id":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/36088","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/36088\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/184300"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=36088"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=36088"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=36088"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=36088"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=36088"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=36088"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=36088"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}