{"id":92566,"date":"2024-09-11T09:40:59","date_gmt":"2024-09-11T07:40:59","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/los-quesos-principe-de-la-orobie\/"},"modified":"2024-10-08T15:14:23","modified_gmt":"2024-10-08T13:14:23","slug":"los-quesos-principe-de-la-orobie","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/es\/oggetto\/los-quesos-principe-de-la-orobie\/","title":{"rendered":"Los quesos pr\u00edncipe de la Orobie"},"excerpt":{"rendered":"","protected":false},"author":7,"featured_media":42002,"template":"","categories":[],"tags":[],"aggr":[],"area":[],"kind":[18693],"zona":[],"class_list":["post-92566","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","kind-editoriale-es"],"acf":{"iu_shortprice":"","iu_timetable":false,"latitude":"","longitude":"","iu_kids":false,"iu_addr_postalcode":"","iu_addr_city":"","iu_phone":"","iu_cell":"","iu_email":"","id_visit_manza":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","slides":[{"image":false,"video":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/POI-I-principi-delle-Orobie.mp4","video_mobile":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/POI-I-principi-delle-Orobie-V.mp4","video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"modules":[{"acf_fc_layout":"one_column_module","ctac_title":"","ctac_text":"<p>Con 30 quesos tradicionales, 9 quesos DOP y 3 baluartes slow-food, B\u00e9rgamo ostenta el t\u00edtulo de Capital Europea del Queso.<br \/>\nHasta nueve quesos bergamascos han obtenido oficialmente el estatus de Denominaci\u00f3n de Origen Protegida<strong>(<\/strong>DOP), pero pronto tambi\u00e9n podr\u00e1 presumir de la prestigiosa etiqueta el<strong>&#8220;Strachitunt<\/strong>&#8220;, un queso muy antiguo (cuya primera prueba se encuentra en un pergamino que data de 1380) que se ha salvado y ha saltado a la fama internacional gracias a la tenacidad de unos cuantos agricultores y productores del <strong>valle de Taleggio<\/strong>.<br \/>\nHoy en d\u00eda, la zona de B\u00e9rgamo ocupa el primer lugar en Italia por el n\u00famero de <strong>quesos DOP<\/strong>; se calcula que hay unos 150 pastos de monta\u00f1a a\u00fan activos.<br \/>\nTambi\u00e9n hay que tener en cuenta la cr\u00eda de cabras y la creciente popularidad de los sabrosos quesos de cabra.<br \/>\nDesde 2019, B\u00e9rgamo forma parte de la red de Ciudades Creativas de la Gastronom\u00eda y el Vino de la Unesco, gracias a la producci\u00f3n quesera de su Valle del Queso.<\/p>\n","ctac_buttons":{"buttons":false},"ctac_buttons_new":false},{"acf_fc_layout":"filotto","filotto_title":"Quesos de B\u00e9rgamo","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":[{"object":70743,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":70735,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":70745,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":70734,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":70744,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":70747,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""}],"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},{"acf_fc_layout":"filotto","filotto_title":"D\u00f3nde probarlos","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":[{"object":38643,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":38679,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":38418,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":38650,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":39121,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":38530,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":38404,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""},{"object":38552,"title":"","image":false,"youtubeurl":"","label_cta":"","url":"","target":"_self","preview":""}],"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}}],"filotto_layout":"scroll","filotto_fill":"manual","hero_title":"Los quesos pr\u00edncipe de la Orobie","size":"full","tcm_content":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"filotto_items":false,"hero_type":"images","accessibilitycontent":{"tcm_content":false},"gallery":{"gallery_items":false},"iu_addr_province":"","poi_data":{"description":"","indepth":"","howtogetthere":"","price":"","time":"","latitude":"","longitude":"","id_visit_manza":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"","iu_addr_city":"","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":false},"hero_buttons_group":{"buttons":false},"filotto_title":"","filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"description":"","indepth":"","howtogetthere":"","price":"","time":"","iu_addr_streetnumber":"","iu_website":"","iu_document_label":"","iu_document":false,"buttons":false,"hero_buttons":false,"featured_video":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/09\/POI-I-principi-delle-Orobie_SH.mp4","is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/92566","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/users\/7"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/oggetto\/92566\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media\/42002"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/media?parent=92566"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/categories?post=92566"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/tags?post=92566"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/aggr?post=92566"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/area?post=92566"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/kind?post=92566"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/es\/wp-json\/wp\/v2\/zona?post=92566"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}