{"id":112816,"date":"2025-06-08T14:59:18","date_gmt":"2025-06-08T12:59:18","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/112816\/"},"modified":"2025-05-12T20:07:59","modified_gmt":"2025-05-12T18:07:59","slug":"parcs-aventure-suspendus","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/parcs-aventure-suspendus\/","title":{"rendered":"Parcs aventure suspendus"},"excerpt":{"rendered":"<p>Vivez une aventure suspendue dans la for\u00eat!<\/p>\n","protected":false},"author":0,"featured_media":184555,"template":"","categories":[521,523],"tags":[17243],"aggr":[],"area":[],"kind":[18704],"zona":[],"class_list":["post-112816","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-esperienze","category-experience","tag-amusant-fr","kind-esperienza-fr"],"acf":{"buttons":[{"style":"primary","text":"Acheter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contacter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Parcs aventure suspendus","hero_text":"<p>Vivez une aventure suspendue dans la for\u00eat!<\/p>\n","slides":[{"image":{"ID":184555,"id":184555,"title":"ec_service_4401_1","filename":"ec_service_4401_1.jpg","filesize":169108,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/parcs-aventure-suspendus\/ec_service_4401_1-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4401_1-2","status":"inherit","uploaded_to":112816,"date":"2025-04-22 17:51:02","modified":"2025-05-12 18:08:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":557,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1-300x139.jpg","medium-width":300,"medium-height":139,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1-768x356.jpg","medium_large-width":768,"medium_large-height":356,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1-1024x475.jpg","large-width":1024,"large-height":475,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1.jpg","1536x1536-width":1200,"1536x1536-height":557,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1.jpg","2048x2048-width":1200,"2048x2048-height":557,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":139,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":186,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4401_1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":279}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":112848,"id":112848,"title":"ec_service_4401_1_2.jpg","filename":"ec_service_4401_1_2.jpg","filesize":133363,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/parcs-aventure-suspendus\/ec_service_4401_1_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4401_1_2-jpg-2","status":"inherit","uploaded_to":112816,"date":"2024-12-17 17:01:01","modified":"2025-05-12 18:08:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":585,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2-300x146.jpg","medium-width":300,"medium-height":146,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2-768x374.jpg","medium_large-width":768,"medium_large-height":374,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2-1024x499.jpg","large-width":1024,"large-height":499,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2.jpg","1536x1536-width":1200,"1536x1536-height":585,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2.jpg","2048x2048-width":1200,"2048x2048-height":585,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_2-600x585.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":585}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":112849,"id":112849,"title":"ec_service_4401_1_3.jpg","filename":"ec_service_4401_1_3.jpg","filesize":74142,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/parcs-aventure-suspendus\/ec_service_4401_1_3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4401_1_3-jpg-2","status":"inherit","uploaded_to":112816,"date":"2024-12-17 17:01:02","modified":"2025-05-12 18:08:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":584,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3-300x146.jpg","medium-width":300,"medium-height":146,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3-768x374.jpg","medium_large-width":768,"medium_large-height":374,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3-1024x498.jpg","large-width":1024,"large-height":498,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3.jpg","1536x1536-width":1200,"1536x1536-height":584,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3.jpg","2048x2048-width":1200,"2048x2048-height":584,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_3-600x584.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":584}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":112850,"id":112850,"title":"ec_service_4401_1_4.jpg","filename":"ec_service_4401_1_4.jpg","filesize":169108,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/parcs-aventure-suspendus\/ec_service_4401_1_4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4401_1_4-jpg-2","status":"inherit","uploaded_to":112816,"date":"2024-12-17 17:01:03","modified":"2025-05-12 18:08:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":557,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4-300x139.jpg","medium-width":300,"medium-height":139,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4-768x356.jpg","medium_large-width":768,"medium_large-height":356,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4-1024x475.jpg","large-width":1024,"large-height":475,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4.jpg","1536x1536-width":1200,"1536x1536-height":557,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4.jpg","2048x2048-width":1200,"2048x2048-height":557,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_4-600x557.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":557}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":112851,"id":112851,"title":"ec_service_4401_1_5.jpg","filename":"ec_service_4401_1_5.jpg","filesize":192650,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/parcs-aventure-suspendus\/ec_service_4401_1_5-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4401_1_5-jpg-2","status":"inherit","uploaded_to":112816,"date":"2024-12-17 17:01:04","modified":"2025-05-12 18:08:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":553,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5-300x138.jpg","medium-width":300,"medium-height":138,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5-768x354.jpg","medium_large-width":768,"medium_large-height":354,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5-1024x472.jpg","large-width":1024,"large-height":472,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5.jpg","1536x1536-width":1200,"1536x1536-height":553,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5.jpg","2048x2048-width":1200,"2048x2048-height":553,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_5-600x553.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":553}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":112852,"id":112852,"title":"ec_service_4401_1_6.jpg","filename":"ec_service_4401_1_6.jpg","filesize":108708,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/parcs-aventure-suspendus\/ec_service_4401_1_6-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4401_1_6-jpg-2","status":"inherit","uploaded_to":112816,"date":"2024-12-17 17:01:05","modified":"2025-05-12 18:08:00","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":486,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6-300x122.jpg","medium-width":300,"medium-height":122,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6-768x311.jpg","medium_large-width":768,"medium_large-height":311,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6-1024x415.jpg","large-width":1024,"large-height":415,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6.jpg","1536x1536-width":1200,"1536x1536-height":486,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6.jpg","2048x2048-width":1200,"2048x2048-height":486,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/12\/ec_service_4401_1_6-600x486.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":486}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":[{"style":"primary","text":"Acheter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contacter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>CE QUE TU FERAS:<br \/>\n&#8211; Une immersion dans la nature gr\u00e2ce aux parcours suspendus.<br \/>\n&#8211; Tu exploreras une for\u00eat en hauteur gr\u00e2ce aux diff\u00e9rents passages reliant un arbre \u00e0 lautre. \u00c0 travers des ponts tib\u00e9tains, des tyroliennes, des lianes, des troncs suspendus et bien dautres encore, tu mettras ton courage \u00e0 l\u00e9preuve.<br \/>\n&#8211; Avec le m\u00eame billet, tu pourras choisir de te rendre au parc de Torre Boldone, \u00e0 quelques minutes de Bergame, ou \u00e0 celui de Roncola, au pied de la vall\u00e9e de lImagna.<br \/>\n&#8211; En fonction de la dur\u00e9e choisie, tu vivras des aventures passionnantes suspendues dans la for\u00eat, en toute s\u00e9curit\u00e9 et sous l\u009cil attentif de l\u00e9quipe du parc.<\/p>\n<p>CE QUI T&#8217;ATTEND:<br \/>\nAvec Parchi Avventura Bergamo, le plaisir est doubl\u00e9 ! Tu pourras choisir entre le parc de Roncola, dans le cadre enchanteur de la vall\u00e9e de lImagna, immerg\u00e9 parmi des arbres centenaires, ou celui de Torre Boldone, un grand poumon vert \u00e0 quelques pas de la ville de Bergame, facilement accessible depuis le centre-ville en quelques minutes gr\u00e2ce au tram \u00e9lectrique TEB ou au bus ATB de la ville. En franchissant une s\u00e9rie de parcours et en marchant au c\u009cur de la nature, tu resteras suspendu entre les arbres, traverseras des passerelles en bois et te lanceras sur des tyroliennes : tout cela en toute s\u00e9curit\u00e9 et dans le respect total de la nature. Dans le parc de Torre Boldone, les plus jeunes pourront \u00e9galement samuser dans laire de jeux et se rafra\u00eechir dans la fontaine avec des jets deau, tout en d\u00e9gustant des sp\u00e9cialit\u00e9s au restaurant Into The Woods.<\/p>\n<p>Lentr\u00e9e dans les deux parcs est GRATUITE, tu ne payes que si tu acc\u00e8des aux parcours suspendus.<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>De mars \u00e0 novembre 2025<br \/>\n(v\u00e9rifie le calendrier sur parchiavventurabergamo.it)<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>Le billet est ouvert et valable pour n&#8217;importe quel jour d&#8217;ouverture des parcours suspendus pendant toute la saison 2025.<\/p>\n","moredetails":"<p>Types et prix des billets :<\/p>\n<p>ADULTES au-dessus de 140 cm<br \/>\n1 heure : 17 euros<br \/>\n2 heures : 22 euros<br \/>\n3 heures : 27 euros<br \/>\nBillet journalier : 35 euros  <\/p>\n<p>ENFANTS de 110 cm \u00e0 140 cm<br \/>\n1 heure : 13 euros<br \/>\n2 heures : 17 euros<br \/>\n3 heures : 21 euros<br \/>\nBillet journalier : 30 euros  <\/p>\n<p>ENFANTS moins de 110 cm<br \/>\n1 heure : 9,50 euros<br \/>\n2 heures : 11,50 euros<br \/>\nBillet journalier : 20 euros  <\/p>\n<p>LIEU ET P\u00c9RIODE :<br \/>\nAvec le billet achet\u00e9, tu peux choisir la date \u00e0 laquelle tu souhaites l&#8217;utiliser  de mars \u00e0 novembre, selon louverture du parc aventure  et tu peux choisir dans quel parc aventure vivre ton exp\u00e9rience.<br \/>\n&#8211; PARCO AVVENTURA DELLA RONCOLA<br \/>\nVia Canale 19<br \/>\n24030 Roncola (BG)<br \/>\n&#8211; PARCO AVVENTURA DI TORRE BOLDONE<br \/>\nVia Ugo Foscolo 10<br \/>\n24020 Torre Boldone (BG)<br \/>\nAu parc aventure de Torre Boldone, d\u00e9couvre le restaurant Into The Woods.  <\/p>\n<p>PARCOURS<br \/>\n3 parcours faciles pour les plus jeunes<br \/>\n4 parcours adapt\u00e9s \u00e0 la fois pour les enfants de plus de 140 cm et ceux entre 110 et 140 cm : 1 facile, 2 moyens\/faciles et 1 moyen<br \/>\n3 parcours adapt\u00e9s uniquement aux enfants de plus de 140 cm, tous les 3 moyens\/difficiles  <\/p>\n<p>L&#8217;entr\u00e9e dans les parcs est GRATUITE, tu payes uniquement si tu acc\u00e8des aux parcours suspendus.<br \/>\nLes parcours sont adapt\u00e9s aux grands et aux petits, \u00e0 partir de 3 ans jusqu&#8217;\u00e0 un maximum de 100 kg de poids.  <\/p>\n<p>V\u00caTEMENTS<br \/>\nIl est recommand\u00e9 de porter des v\u00eatements confortables et sportifs avec des chaussures de tennis ou de randonn\u00e9e !<br \/>\nPour des raisons de s\u00e9curit\u00e9, les tongs ou sandales ouvertes sont INTERDITES.<\/p>\n","whatsincluded":"<p>&#8211; Acc\u00e8s au parc<br \/>\n&#8211; Acc\u00e8s aux parcours suspendus entre les arbres<br \/>\n&#8211; Une \u00e9quipe compos\u00e9e d&#8217;instructeurs form\u00e9s et qualifi\u00e9s pour l&#8217;assistance<br \/>\n&#8211; Harnais et \u00e9quipements n\u00e9cessaires pour acc\u00e9der aux attractions<\/p>\n","whatsnotincluded":"<p>&#8211; Transport vers et depuis les lieux de l&#8217;exp\u00e9rience<br \/>\n&#8211; Repas<br \/>\n&#8211; Tout ce qui n&#8217;est pas explicitement mentionn\u00e9 dans &#8220;Ce qui est inclus&#8221;<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.71302760","longitude":"9.70447610","startingprice":"17.00","gpxmap":"","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Ugo Foscolo","iu_addr_postalcode":"24020","iu_addr_city":"Torre Boldone","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"Parco Avventura Bergamo , Via Nelson Mandela, Treviolo","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=fra&no_qr=si&styleid=3073&ecomid=4401&serviceid=1","iu_videourl":"","iu_difficulty":"En fonction des parcours, de facile \u00e0 moyen\/difficile.","iu_accessibility":"","iu_duration":"1h - 2h - 3h - journ\u00e9e enti\u00e8re","iu_languages":"anglais - italien","iu_minpeople":"Minimum 1 personne","iu_maxpeople":"Maximum 50 personnes","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_4401_1","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"01\/03\/2025","validto":"30\/11\/2025","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","experience_data":{"description":"<p>CE QUE TU FERAS:<br \/>\n&#8211; Une immersion dans la nature gr\u00e2ce aux parcours suspendus.<br \/>\n&#8211; Tu exploreras une for\u00eat en hauteur gr\u00e2ce aux diff\u00e9rents passages reliant un arbre \u00e0 lautre. \u00c0 travers des ponts tib\u00e9tains, des tyroliennes, des lianes, des troncs suspendus et bien dautres encore, tu mettras ton courage \u00e0 l\u00e9preuve.<br \/>\n&#8211; Avec le m\u00eame billet, tu pourras choisir de te rendre au parc de Torre Boldone, \u00e0 quelques minutes de Bergame, ou \u00e0 celui de Roncola, au pied de la vall\u00e9e de lImagna.<br \/>\n&#8211; En fonction de la dur\u00e9e choisie, tu vivras des aventures passionnantes suspendues dans la for\u00eat, en toute s\u00e9curit\u00e9 et sous l\u009cil attentif de l\u00e9quipe du parc.<\/p>\n<p>CE QUI T&#8217;ATTEND:<br \/>\nAvec Parchi Avventura Bergamo, le plaisir est doubl\u00e9 ! Tu pourras choisir entre le parc de Roncola, dans le cadre enchanteur de la vall\u00e9e de lImagna, immerg\u00e9 parmi des arbres centenaires, ou celui de Torre Boldone, un grand poumon vert \u00e0 quelques pas de la ville de Bergame, facilement accessible depuis le centre-ville en quelques minutes gr\u00e2ce au tram \u00e9lectrique TEB ou au bus ATB de la ville. En franchissant une s\u00e9rie de parcours et en marchant au c\u009cur de la nature, tu resteras suspendu entre les arbres, traverseras des passerelles en bois et te lanceras sur des tyroliennes : tout cela en toute s\u00e9curit\u00e9 et dans le respect total de la nature. Dans le parc de Torre Boldone, les plus jeunes pourront \u00e9galement samuser dans laire de jeux et se rafra\u00eechir dans la fontaine avec des jets deau, tout en d\u00e9gustant des sp\u00e9cialit\u00e9s au restaurant Into The Woods.<\/p>\n<p>Lentr\u00e9e dans les deux parcs est GRATUITE, tu ne payes que si tu acc\u00e8des aux parcours suspendus.<\/p>\n","indepth":"","latitude":"45.71302760","longitude":"9.70447610","iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","iu_cognitive_accessibility":"notsure","iu_addr_streetnumber":"Via Ugo Foscolo","iu_addr_postalcode":"24020","iu_addr_city":"Torre Boldone","iu_addr_province":"Bergamo","timerange":"<p>De mars \u00e0 novembre 2025<br \/>\n(v\u00e9rifie le calendrier sur parchiavventurabergamo.it)<\/p>\n","cancellationpolicy":"<p>Le billet est ouvert et valable pour n&#8217;importe quel jour d&#8217;ouverture des parcours suspendus pendant toute la saison 2025.<\/p>\n","moredetails":"<p>Types et prix des billets :<\/p>\n<p>ADULTES au-dessus de 140 cm<br \/>\n1 heure : 17 euros<br \/>\n2 heures : 22 euros<br \/>\n3 heures : 27 euros<br \/>\nBillet journalier : 35 euros  <\/p>\n<p>ENFANTS de 110 cm \u00e0 140 cm<br \/>\n1 heure : 13 euros<br \/>\n2 heures : 17 euros<br \/>\n3 heures : 21 euros<br \/>\nBillet journalier : 30 euros  <\/p>\n<p>ENFANTS moins de 110 cm<br \/>\n1 heure : 9,50 euros<br \/>\n2 heures : 11,50 euros<br \/>\nBillet journalier : 20 euros  <\/p>\n<p>LIEU ET P\u00c9RIODE :<br \/>\nAvec le billet achet\u00e9, tu peux choisir la date \u00e0 laquelle tu souhaites l&#8217;utiliser  de mars \u00e0 novembre, selon louverture du parc aventure  et tu peux choisir dans quel parc aventure vivre ton exp\u00e9rience.<br \/>\n&#8211; PARCO AVVENTURA DELLA RONCOLA<br \/>\nVia Canale 19<br \/>\n24030 Roncola (BG)<br \/>\n&#8211; PARCO AVVENTURA DI TORRE BOLDONE<br \/>\nVia Ugo Foscolo 10<br \/>\n24020 Torre Boldone (BG)<br \/>\nAu parc aventure de Torre Boldone, d\u00e9couvre le restaurant Into The Woods.  <\/p>\n<p>PARCOURS<br \/>\n3 parcours faciles pour les plus jeunes<br \/>\n4 parcours adapt\u00e9s \u00e0 la fois pour les enfants de plus de 140 cm et ceux entre 110 et 140 cm : 1 facile, 2 moyens\/faciles et 1 moyen<br \/>\n3 parcours adapt\u00e9s uniquement aux enfants de plus de 140 cm, tous les 3 moyens\/difficiles  <\/p>\n<p>L&#8217;entr\u00e9e dans les parcs est GRATUITE, tu payes uniquement si tu acc\u00e8des aux parcours suspendus.<br \/>\nLes parcours sont adapt\u00e9s aux grands et aux petits, \u00e0 partir de 3 ans jusqu&#8217;\u00e0 un maximum de 100 kg de poids.  <\/p>\n<p>V\u00caTEMENTS<br \/>\nIl est recommand\u00e9 de porter des v\u00eatements confortables et sportifs avec des chaussures de tennis ou de randonn\u00e9e !<br \/>\nPour des raisons de s\u00e9curit\u00e9, les tongs ou sandales ouvertes sont INTERDITES.<\/p>\n","whatsincluded":"<p>&#8211; Acc\u00e8s au parc<br \/>\n&#8211; Acc\u00e8s aux parcours suspendus entre les arbres<br \/>\n&#8211; Une \u00e9quipe compos\u00e9e d&#8217;instructeurs form\u00e9s et qualifi\u00e9s pour l&#8217;assistance<br \/>\n&#8211; Harnais et \u00e9quipements n\u00e9cessaires pour acc\u00e9der aux attractions<\/p>\n","whatsnotincluded":"<p>&#8211; Transport vers et depuis les lieux de l&#8217;exp\u00e9rience<br \/>\n&#8211; Repas<br \/>\n&#8211; Tout ce qui n&#8217;est pas explicitement mentionn\u00e9 dans &#8220;Ce qui est inclus&#8221;<\/p>\n","startingprice":"17.00","id_madeep":"652_4401_1","iu_minpeople":"Minimum 1 personne","iu_maxpeople":"Maximum 50 personnes","iu_languages":"anglais - italien","iu_duration":"1h - 2h - 3h - journ\u00e9e enti\u00e8re","iu_difficulty":"En fonction des parcours, de facile \u00e0 moyen\/difficile.","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=fra&no_qr=si&styleid=3073&ecomid=4401&serviceid=1","iu_manager":"Parco Avventura Bergamo , Via Nelson Mandela, Treviolo","review":false,"validfrom":"01\/03\/2025","validto":"30\/11\/2025"},"featured_video":false,"is_an_ambassador":false,"only_ambassadors":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/112816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/112816\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/184555"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=112816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=112816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=112816"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=112816"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=112816"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=112816"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=112816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}