{"id":113750,"date":"2025-06-08T14:56:08","date_gmt":"2025-06-08T12:56:08","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/113750\/"},"modified":"2025-05-12T20:02:48","modified_gmt":"2025-05-12T18:02:48","slug":"peche-a-la-mouche-dans-les-rivieres-serio-et-brembo-vallees-de-bergame","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/peche-a-la-mouche-dans-les-rivieres-serio-et-brembo-vallees-de-bergame\/","title":{"rendered":"P\u00eache \u00e0 la mouche dans les rivi\u00e8res Serio et Brembo, vall\u00e9es de Bergame."},"excerpt":{"rendered":"<p>Vivez une exp\u00e9rience unique, accompagn\u00e9 par du personnel expert, dans les Pr\u00e9alpes de Bergame. Essayez la technique de p\u00eache \u00e0 la mouche pour les truites fario et marmor\u00e9es!<\/p>\n","protected":false},"author":0,"featured_media":184009,"template":"","categories":[523],"tags":[17225],"aggr":[],"area":[],"kind":[18704],"zona":[],"class_list":["post-113750","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-experience","tag-de-plein-air-fr","kind-esperienza-fr"],"acf":{"buttons":[{"style":"primary","text":"Acheter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contacter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"P\u00eache \u00e0 la mouche dans les rivi\u00e8res Serio et Brembo, vall\u00e9es de Bergame.","hero_text":"<p>Vivez une exp\u00e9rience unique, accompagn\u00e9 par du personnel expert, dans les Pr\u00e9alpes de Bergame. Essayez la technique de p\u00eache \u00e0 la mouche pour les truites fario et marmor\u00e9es!<\/p>\n","slides":[{"image":{"ID":184009,"id":184009,"title":"ec_service_2549_1","filename":"ec_service_2549_1.jpg","filesize":59516,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_1.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/peche-a-la-mouche-dans-les-rivieres-serio-et-brembo-vallees-de-bergame\/ec_service_2549_1-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2549_1-2","status":"inherit","uploaded_to":113750,"date":"2025-04-22 17:48:26","modified":"2025-05-12 18:02:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":606,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_1-300x152.jpg","medium-width":300,"medium-height":152,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_1-768x388.jpg","medium_large-width":768,"medium_large-height":388,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_1-1024x517.jpg","large-width":1024,"large-height":517,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_1.jpg","1536x1536-width":1200,"1536x1536-height":606,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_1.jpg","2048x2048-width":1200,"2048x2048-height":606,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":152,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":202,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_2549_1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":303}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":113752,"id":113752,"title":"ec_service_2549_1_2.jpg","filename":"ec_service_2549_1_2.jpg","filesize":210571,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_2.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/peche-a-la-mouche-dans-les-rivieres-serio-et-brembo-vallees-de-bergame\/ec_service_2549_1_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2549_1_2-jpg-2","status":"inherit","uploaded_to":113750,"date":"2025-01-15 11:00:32","modified":"2025-05-12 18:02:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":748,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_2-300x187.jpg","medium-width":300,"medium-height":187,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_2-768x479.jpg","medium_large-width":768,"medium_large-height":479,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_2-1024x638.jpg","large-width":1024,"large-height":638,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_2.jpg","1536x1536-width":1200,"1536x1536-height":748,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_2.jpg","2048x2048-width":1200,"2048x2048-height":748,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_2-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_2-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_2-600x600.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":113753,"id":113753,"title":"ec_service_2549_1_3.jpg","filename":"ec_service_2549_1_3.jpg","filesize":237958,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_3.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/peche-a-la-mouche-dans-les-rivieres-serio-et-brembo-vallees-de-bergame\/ec_service_2549_1_3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2549_1_3-jpg-2","status":"inherit","uploaded_to":113750,"date":"2025-01-15 11:00:33","modified":"2025-05-12 18:02:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":966,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_3-300x183.jpg","medium-width":300,"medium-height":183,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_3-768x470.jpg","medium_large-width":768,"medium_large-height":470,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_3-1024x626.jpg","large-width":1024,"large-height":626,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_3-1536x939.jpg","1536x1536-width":1536,"1536x1536-height":939,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_3.jpg","2048x2048-width":1580,"2048x2048-height":966,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_3-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_3-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_3-600x600.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":113754,"id":113754,"title":"ec_service_2549_1_4.jpg","filename":"ec_service_2549_1_4.jpg","filesize":353571,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_4.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/peche-a-la-mouche-dans-les-rivieres-serio-et-brembo-vallees-de-bergame\/ec_service_2549_1_4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_2549_1_4-jpg-2","status":"inherit","uploaded_to":113750,"date":"2025-01-15 11:00:34","modified":"2025-05-12 18:02:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1580,"height":968,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_4-300x184.jpg","medium-width":300,"medium-height":184,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_4-768x471.jpg","medium_large-width":768,"medium_large-height":471,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_4-1024x627.jpg","large-width":1024,"large-height":627,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_4-1536x941.jpg","1536x1536-width":1536,"1536x1536-height":941,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_4.jpg","2048x2048-width":1580,"2048x2048-height":968,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_4-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_4-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_2549_1_4-600x600.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":[{"style":"primary","text":"Acheter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contacter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>CE QUE TU FERAS:<br \/>\n&#8211; P\u00eache \u00e0 la mouche dans le fleuve Serio et le fleuve Brembo pour attraper de grandes truites marmor\u00e9es et des truites fario.<br \/>\n&#8211; Avec toi, un guide de p\u00eache qualifi\u00e9 et accr\u00e9dit\u00e9 par l&#8217;Associazione Italiana Guide Professionali di Pesca (AIGUPP).  <\/p>\n<p>CE QUI T&#8217;ATTEND:<br \/>\nLes Alpes italiennes, avec leurs montagnes, torrents, rivi\u00e8res et vall\u00e9es du nord de l&#8217;Italie, offrent une opportunit\u00e9 unique pour les passionn\u00e9s de p\u00eache \u00e0 la mouche ou pour les p\u00eacheurs souhaitant vivre un voyage m\u00e9morable.<br \/>\nLa p\u00eache dans les Alpes italiennes, \u00e0 Bergame, se d\u00e9roule dans certaines des vall\u00e9es les plus belles et \u00e9vocatrices des Alpes. Le fleuve Serio et le fleuve Brembo sont c\u00e9l\u00e8bres pour la grande pr\u00e9sence de truites fario et de truites marmor\u00e9es.<br \/>\nDes paysages enchanteurs de vall\u00e9es alpines, dans un environnement montagnard \u00e0 couper le souffle, la culture et les traditions typiques de cette r\u00e9gion, ainsi que le mode de vie et la culture italienne, sont des \u00e9l\u00e9ments essentiels pour offrir \u00e0 nos clients une exp\u00e9rience unique et extraordinaire.  <\/p>\n<p>L&#8217;exp\u00e9rience de p\u00eache \u00e0 la mouche sur les rivi\u00e8res Serio et Brembo s&#8217;adresse aux p\u00eacheurs \u00e0 la recherche de poissons importants comme la truite marmor\u00e9e et la truite fario.<\/p>\n<p>La journ\u00e9e sera guid\u00e9e par des guides de p\u00eache \u00e0 la mouche, qualifi\u00e9s par l&#8217;AIGUPP (Associazione Italiana Guide Professionali di Pesca) et l&#8217;IGFA (International Game Fishing Association), qui t&#8217;accompagneront tout au long de la journ\u00e9e de la meilleure mani\u00e8re possible.<\/p>\n<p>Points forts de l&#8217;exp\u00e9rience :<br \/>\n&#8211; P\u00eache \u00e0 la mouche de truites fario et de truites marmor\u00e9es.<br \/>\n&#8211; La nature des vall\u00e9es de Bergame.<br \/>\n&#8211; Suggestions et conseils sur la meilleure fa\u00e7on de passer une journ\u00e9e dans les vall\u00e9es pour les familles et les accompagnateurs non p\u00eacheurs.<br \/>\n&#8211; Service de guide de p\u00eache offert aux p\u00eacheurs individuels ou aux petits groupes (maximum 4 p\u00eacheurs), avec un guide expert pour chaque 2 p\u00eacheurs.<br \/>\n&#8211; Service photo semi-professionnel inclus.<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Saison de p\u00eache : Mars, Avril, Mai, Juin, Juillet, Ao\u00fbt, Septembre, Octobre<br \/>\nTous les jours de la semaine, de 8h00 \u00e0 19h00 : les heures de p\u00eache sont de 7 heures.<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>En cas de &#8220;no show&#8221;, 100 % du montant sera retenu.<\/p>\n<p>Annulation avant la date pr\u00e9vue :<br \/>\n&#8211; 10 jours : Remboursement de 100 % de l&#8217;acompte<br \/>\n&#8211; 5 jours : Remboursement de 50 % de l&#8217;acompte<br \/>\n&#8211; 0\/5 jours : Aucun remboursement<\/p>\n<p>L&#8217;organisateur de l&#8217;exp\u00e9rience se r\u00e9serve le droit de modifier l&#8217;itin\u00e9raire en cas de circonstances d\u00e9favorables, telles que des conditions m\u00e9t\u00e9orologiques d\u00e9favorables ou des conditions des cours d&#8217;eau.<\/p>\n","moredetails":"<p>Point de rencontre :<br \/>\nSelon que la journ\u00e9e de p\u00eache se d\u00e9roule dans la vall\u00e9e Seriana ou la vall\u00e9e Brembana, le point de rencontre sera situ\u00e9 \u00e0 un endroit le long de la route menant \u00e0 la vall\u00e9e. Le point de rencontre exact sera d\u00e9fini avec les organisateurs de l&#8217;exp\u00e9rience apr\u00e8s la r\u00e9servation.<\/p>\n<p>Il est recommand\u00e9 de porter des v\u00eatements adapt\u00e9s \u00e0 la vie en plein air.<\/p>\n<p>Conditions de r\u00e9servation :<br \/>\nR\u00e9servation jusqu&#8217;\u00e0 5 jours avant la date pr\u00e9vue.<\/p>\n","whatsincluded":"<p>&#8211; Service de guide de p\u00eache avec accompagnement<br \/>\n(La dur\u00e9e de la journ\u00e9e de p\u00eache varie en fonction des saisons, mais elle n&#8217;est pas inf\u00e9rieure \u00e0 7\/8 heures)<br \/>\n&#8211; Gestion des proc\u00e9dures d&#8217;autorisation (licence de p\u00eache et permis d&#8217;acc\u00e8s aux eaux)<br \/>\n&#8211; Service photo semi-professionnel<\/p>\n","whatsnotincluded":"<p>&#8211; Licence de p\u00eache italienne (co\u00fbt de 23,00 euros par p\u00eacheur, valable pendant un an)<br \/>\n&#8211; Co\u00fbt du permis d&#8217;acc\u00e8s aux eaux &#8211; variable \u00e0 partir de 20,00 euros par p\u00eacheur et par jour<br \/>\n&#8211; Transfert vers et depuis le point de p\u00eache (peut toutefois \u00eatre demand\u00e9 lors de la r\u00e9servation)<br \/>\n&#8211; Tout autre \u00e9l\u00e9ment non indiqu\u00e9 dans la section &#8220;ce qui est inclus&#8221;<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.83728990","longitude":"9.66370160","startingprice":"190.00","gpxmap":"","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"via san carlo 4","iu_addr_postalcode":"24016","iu_addr_city":"San Pellegrino Terme","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"Alps Store & Fishing Service, Via Martin Luther King, 4, Grassobbio","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=fra&no_qr=si&styleid=3073&ecomid=2549&serviceid=1","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"journ\u00e9e enti\u00e8re","iu_languages":"anglais - italien","iu_minpeople":"Minimum 1 personne","iu_maxpeople":"Maximum 4 personnes","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_2549_1","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"15\/01\/2025","validto":"31\/10\/2025","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"yes","iu_cognitive_accessibility":"no","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","experience_data":{"description":"<p>CE QUE TU FERAS:<br \/>\n&#8211; P\u00eache \u00e0 la mouche dans le fleuve Serio et le fleuve Brembo pour attraper de grandes truites marmor\u00e9es et des truites fario.<br \/>\n&#8211; Avec toi, un guide de p\u00eache qualifi\u00e9 et accr\u00e9dit\u00e9 par l&#8217;Associazione Italiana Guide Professionali di Pesca (AIGUPP).  <\/p>\n<p>CE QUI T&#8217;ATTEND:<br \/>\nLes Alpes italiennes, avec leurs montagnes, torrents, rivi\u00e8res et vall\u00e9es du nord de l&#8217;Italie, offrent une opportunit\u00e9 unique pour les passionn\u00e9s de p\u00eache \u00e0 la mouche ou pour les p\u00eacheurs souhaitant vivre un voyage m\u00e9morable.<br \/>\nLa p\u00eache dans les Alpes italiennes, \u00e0 Bergame, se d\u00e9roule dans certaines des vall\u00e9es les plus belles et \u00e9vocatrices des Alpes. Le fleuve Serio et le fleuve Brembo sont c\u00e9l\u00e8bres pour la grande pr\u00e9sence de truites fario et de truites marmor\u00e9es.<br \/>\nDes paysages enchanteurs de vall\u00e9es alpines, dans un environnement montagnard \u00e0 couper le souffle, la culture et les traditions typiques de cette r\u00e9gion, ainsi que le mode de vie et la culture italienne, sont des \u00e9l\u00e9ments essentiels pour offrir \u00e0 nos clients une exp\u00e9rience unique et extraordinaire.  <\/p>\n<p>L&#8217;exp\u00e9rience de p\u00eache \u00e0 la mouche sur les rivi\u00e8res Serio et Brembo s&#8217;adresse aux p\u00eacheurs \u00e0 la recherche de poissons importants comme la truite marmor\u00e9e et la truite fario.<\/p>\n<p>La journ\u00e9e sera guid\u00e9e par des guides de p\u00eache \u00e0 la mouche, qualifi\u00e9s par l&#8217;AIGUPP (Associazione Italiana Guide Professionali di Pesca) et l&#8217;IGFA (International Game Fishing Association), qui t&#8217;accompagneront tout au long de la journ\u00e9e de la meilleure mani\u00e8re possible.<\/p>\n<p>Points forts de l&#8217;exp\u00e9rience :<br \/>\n&#8211; P\u00eache \u00e0 la mouche de truites fario et de truites marmor\u00e9es.<br \/>\n&#8211; La nature des vall\u00e9es de Bergame.<br \/>\n&#8211; Suggestions et conseils sur la meilleure fa\u00e7on de passer une journ\u00e9e dans les vall\u00e9es pour les familles et les accompagnateurs non p\u00eacheurs.<br \/>\n&#8211; Service de guide de p\u00eache offert aux p\u00eacheurs individuels ou aux petits groupes (maximum 4 p\u00eacheurs), avec un guide expert pour chaque 2 p\u00eacheurs.<br \/>\n&#8211; Service photo semi-professionnel inclus.<\/p>\n","indepth":"","latitude":"45.83728990","longitude":"9.66370160","iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"yes","iu_cognitive_accessibility":"no","iu_addr_streetnumber":"via san carlo 4","iu_addr_postalcode":"24016","iu_addr_city":"San Pellegrino Terme","iu_addr_province":"Bergamo","timerange":"<p>Saison de p\u00eache : Mars, Avril, Mai, Juin, Juillet, Ao\u00fbt, Septembre, Octobre<br \/>\nTous les jours de la semaine, de 8h00 \u00e0 19h00 : les heures de p\u00eache sont de 7 heures.<\/p>\n","cancellationpolicy":"<p>En cas de &#8220;no show&#8221;, 100 % du montant sera retenu.<\/p>\n<p>Annulation avant la date pr\u00e9vue :<br \/>\n&#8211; 10 jours : Remboursement de 100 % de l&#8217;acompte<br \/>\n&#8211; 5 jours : Remboursement de 50 % de l&#8217;acompte<br \/>\n&#8211; 0\/5 jours : Aucun remboursement<\/p>\n<p>L&#8217;organisateur de l&#8217;exp\u00e9rience se r\u00e9serve le droit de modifier l&#8217;itin\u00e9raire en cas de circonstances d\u00e9favorables, telles que des conditions m\u00e9t\u00e9orologiques d\u00e9favorables ou des conditions des cours d&#8217;eau.<\/p>\n","moredetails":"<p>Point de rencontre :<br \/>\nSelon que la journ\u00e9e de p\u00eache se d\u00e9roule dans la vall\u00e9e Seriana ou la vall\u00e9e Brembana, le point de rencontre sera situ\u00e9 \u00e0 un endroit le long de la route menant \u00e0 la vall\u00e9e. Le point de rencontre exact sera d\u00e9fini avec les organisateurs de l&#8217;exp\u00e9rience apr\u00e8s la r\u00e9servation.<\/p>\n<p>Il est recommand\u00e9 de porter des v\u00eatements adapt\u00e9s \u00e0 la vie en plein air.<\/p>\n<p>Conditions de r\u00e9servation :<br \/>\nR\u00e9servation jusqu&#8217;\u00e0 5 jours avant la date pr\u00e9vue.<\/p>\n","whatsincluded":"<p>&#8211; Service de guide de p\u00eache avec accompagnement<br \/>\n(La dur\u00e9e de la journ\u00e9e de p\u00eache varie en fonction des saisons, mais elle n&#8217;est pas inf\u00e9rieure \u00e0 7\/8 heures)<br \/>\n&#8211; Gestion des proc\u00e9dures d&#8217;autorisation (licence de p\u00eache et permis d&#8217;acc\u00e8s aux eaux)<br \/>\n&#8211; Service photo semi-professionnel<\/p>\n","whatsnotincluded":"<p>&#8211; Licence de p\u00eache italienne (co\u00fbt de 23,00 euros par p\u00eacheur, valable pendant un an)<br \/>\n&#8211; Co\u00fbt du permis d&#8217;acc\u00e8s aux eaux &#8211; variable \u00e0 partir de 20,00 euros par p\u00eacheur et par jour<br \/>\n&#8211; Transfert vers et depuis le point de p\u00eache (peut toutefois \u00eatre demand\u00e9 lors de la r\u00e9servation)<br \/>\n&#8211; Tout autre \u00e9l\u00e9ment non indiqu\u00e9 dans la section &#8220;ce qui est inclus&#8221;<\/p>\n","startingprice":"190.00","id_madeep":"652_2549_1","iu_minpeople":"Minimum 1 personne","iu_maxpeople":"Maximum 4 personnes","iu_languages":"anglais - italien","iu_duration":"journ\u00e9e enti\u00e8re","iu_difficulty":"","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=fra&no_qr=si&styleid=3073&ecomid=2549&serviceid=1","iu_manager":"Alps Store & Fishing Service, Via Martin Luther King, 4, Grassobbio","review":false,"validfrom":"15\/01\/2025","validto":"31\/10\/2025"},"featured_video":false,"is_an_ambassador":false,"only_ambassadors":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/113750","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/113750\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/184009"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=113750"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=113750"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=113750"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=113750"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=113750"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=113750"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=113750"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}