{"id":114252,"date":"2025-06-08T14:58:08","date_gmt":"2025-06-08T12:58:08","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/copia\/"},"modified":"2025-05-12T20:06:02","modified_gmt":"2025-05-12T18:06:02","slug":"pont-suspendu-dejeuner-typique-et-parc-speleologique-a-dossena-dans-la-vallee-brembana","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/pont-suspendu-dejeuner-typique-et-parc-speleologique-a-dossena-dans-la-vallee-brembana\/","title":{"rendered":"Pont suspendu, d\u00e9jeuner typique et parc sp\u00e9l\u00e9ologique \u00e0 Dossena dans la vall\u00e9e Brembana"},"excerpt":{"rendered":"<p>Parcourez le pont tib\u00e9tain le plus haut d&#8217;Europe, d\u00e9gustez un d\u00e9jeuner typique de Bergamasque et d\u00e9couvrez le parc sp\u00e9l\u00e9ologique de Dossena pour une journ\u00e9e plac\u00e9e sous le signe de l&#8217;adr\u00e9naline!<\/p>\n","protected":false},"author":0,"featured_media":184338,"template":"","categories":[521,523],"tags":[17225],"aggr":[],"area":[],"kind":[18704],"zona":[],"class_list":["post-114252","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-esperienze","category-experience","tag-de-plein-air-fr","kind-esperienza-fr"],"acf":{"buttons":[{"style":"primary","text":"Acheter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contacter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}],"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Pont suspendu, d\u00e9jeuner typique et parc sp\u00e9l\u00e9ologique \u00e0 Dossena dans la vall\u00e9e Brembana","hero_text":"<p>Parcourez le pont tib\u00e9tain le plus haut d&#8217;Europe, d\u00e9gustez un d\u00e9jeuner typique de Bergamasque et d\u00e9couvrez le parc sp\u00e9l\u00e9ologique de Dossena pour une journ\u00e9e plac\u00e9e sous le signe de l&#8217;adr\u00e9naline!<\/p>\n","slides":[{"image":{"ID":184338,"id":184338,"title":"ec_service_4140_5","filename":"ec_service_4140_5.jpg","filesize":144278,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_5.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/pont-suspendu-dejeuner-typique-et-parc-speleologique-a-dossena-dans-la-vallee-brembana\/ec_service_4140_5-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4140_5-2","status":"inherit","uploaded_to":114252,"date":"2025-04-22 17:49:54","modified":"2025-05-12 18:06:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":451,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_5-300x113.jpg","medium-width":300,"medium-height":113,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_5-768x289.jpg","medium_large-width":768,"medium_large-height":289,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_5-1024x385.jpg","large-width":1024,"large-height":385,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_5.jpg","1536x1536-width":1200,"1536x1536-height":451,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_5.jpg","2048x2048-width":1200,"2048x2048-height":451,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_5.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":113,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_5.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":150,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ec_service_4140_5.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":226}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":114477,"id":114477,"title":"ec_service_4140_5_2.jpg","filename":"ec_service_4140_5_2.jpg","filesize":176371,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_2.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/pont-suspendu-dejeuner-typique-et-parc-speleologique-a-dossena-dans-la-vallee-brembana\/ec_service_4140_5_2-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4140_5_2-jpg-2","status":"inherit","uploaded_to":114252,"date":"2025-01-22 09:00:48","modified":"2025-05-12 18:06:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":505,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_2-300x126.jpg","medium-width":300,"medium-height":126,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_2-768x323.jpg","medium_large-width":768,"medium_large-height":323,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_2-1024x431.jpg","large-width":1024,"large-height":431,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_2.jpg","1536x1536-width":1200,"1536x1536-height":505,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_2.jpg","2048x2048-width":1200,"2048x2048-height":505,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_2-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_2-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_2-600x505.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":505}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":114478,"id":114478,"title":"ec_service_4140_5_3.jpg","filename":"ec_service_4140_5_3.jpg","filesize":77680,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_3.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/pont-suspendu-dejeuner-typique-et-parc-speleologique-a-dossena-dans-la-vallee-brembana\/ec_service_4140_5_3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4140_5_3-jpg-2","status":"inherit","uploaded_to":114252,"date":"2025-01-22 09:00:49","modified":"2025-05-12 18:06:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":397,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_3-300x99.jpg","medium-width":300,"medium-height":99,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_3-768x254.jpg","medium_large-width":768,"medium_large-height":254,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_3-1024x339.jpg","large-width":1024,"large-height":339,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_3.jpg","1536x1536-width":1200,"1536x1536-height":397,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_3.jpg","2048x2048-width":1200,"2048x2048-height":397,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_3-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_3-400x397.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":397,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_3-600x397.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":397}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":114479,"id":114479,"title":"ec_service_4140_5_4.jpg","filename":"ec_service_4140_5_4.jpg","filesize":144398,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_4.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/pont-suspendu-dejeuner-typique-et-parc-speleologique-a-dossena-dans-la-vallee-brembana\/ec_service_4140_5_4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ec_service_4140_5_4-jpg-2","status":"inherit","uploaded_to":114252,"date":"2025-01-22 09:00:50","modified":"2025-05-12 18:06:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":537,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_4-300x134.jpg","medium-width":300,"medium-height":134,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_4-768x344.jpg","medium_large-width":768,"medium_large-height":344,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_4-1024x458.jpg","large-width":1024,"large-height":458,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_4.jpg","1536x1536-width":1200,"1536x1536-height":537,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_4.jpg","2048x2048-width":1200,"2048x2048-height":537,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_4-300x300.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_4-400x400.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/01\/ec_service_4140_5_4-600x537.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":537}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"hero_buttons_group":{"buttons":[{"style":"primary","text":"Acheter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"buyExp"},{"style":"primary","text":"Contacter","icon":{"button_icon":"none"},"function":"content","url":"","select_post":"","target":"_self","url_youtube":"","target_modal":"modalContact"}]},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"}},"description":"<p>D\u00e9couvrez la vall\u00e9e de Brembana de mani\u00e8re unique et captivante, en traversant le &#8220;Ponte nel Sole&#8221; et en vous immergeant dans le sous-sol !<\/p>\n<p>Les points forts de la journ\u00e9e :<br \/>\n&#8211; Le pont tib\u00e9tain le plus long au monde sans tirants lat\u00e9raux et \u00e0 p\u00e9dales discontinues ;<br \/>\n&#8211; 120 m\u00e8tres de hauteur maximale ;<br \/>\n&#8211; 3,5 km de c\u00e2bles en acier ;<br \/>\n&#8211; Le seul parc sp\u00e9l\u00e9ologique en Europe ;<br \/>\n&#8211; 100 m\u00e8tres de profondeur ;<br \/>\n&#8211; Un m\u00e9lange de via ferrata et de parc aventure au c\u009cur de la Terre !<\/p>\n<p>Ponte nel Sole :<br \/>\nVivez une exp\u00e9rience unique sur le pont tib\u00e9tain le plus long du monde \u00e0 p\u00e9dale discontinue et sans tirants lat\u00e9raux ! L&#8217;exp\u00e9rience consiste \u00e0 atteindre le d\u00e9part du pont gr\u00e2ce \u00e0 un sentier qui part du centre du village ; le retour dans le village se fera en traversant l&#8217;infrastructure. L&#8217;itin\u00e9raire est donc con\u00e7u comme un parcours en boucle : l&#8217;aller sur le sentier et le retour sur le pont.<\/p>\n<p>Arrivez directement au centre du village de Dossena et garez votre voiture dans l&#8217;un des parkings gratuits.<\/p>\n<p>parc sp\u00e9l\u00e9ologique:<br \/>\nPlongez dans les entrailles de la Terre et visitez le Parc Sp\u00e9l\u00e9ologique de Dossena, au c\u009cur de la vall\u00e9e de Brembana ! Il s&#8217;agit d&#8217;un parcours am\u00e9nag\u00e9 \u00e0 vivre sous un angle ludique et culturel pour explorer les anciennes galeries des mines de Dossena \u00e0 travers des tyroliennes, des ponts, des passages suspendus au-dessus de grottes naturelles, des chemin\u00e9es artificielles et bien plus encore. Une aventure inoubliable \u00e0 la d\u00e9couverte de l&#8217;histoire et des beaut\u00e9s de nos mines, m\u00eame en cas de mauvais temps. N&#8217;oubliez pas de porter des v\u00eatements sportifs et chauds avec des chaussures appropri\u00e9es.<\/p>\n<p>Une fois votre voiture gar\u00e9e \u00e0 l&#8217;emplacement indiqu\u00e9 sur la carte (ou selon les instructions du personnel de VisitDossena), empruntez le sentier qui vous conduira au point d&#8217;accueil \u00e0 l&#8217;ext\u00e9rieur des galeries ; avec l&#8217;aide de notre personnel, r\u00e9cup\u00e9rez votre titre d&#8217;acc\u00e8s, remplissez le &#8220;registre des visites&#8221; et portez votre casque, vos gants et votre harnais ! En groupes de 15 personnes par visite, apr\u00e8s un court briefing, vous serez accompagn\u00e9 par un guide exp\u00e9riment\u00e9 et un serre-file.<\/p>\n<p>PROGRAMME :<br \/>\n&#8211; Rendez-vous \u00e0 l&#8217;Infopoint de Dossena, Piazzale Alpini, 1 pour un briefing sur le Pont Suspendu. Pr\u00e9sentez-vous 15 minutes avant l&#8217;heure choisie.<br \/>\n&#8211; Transfert autonome vers le Ponte del Sole.<br \/>\n&#8211; PONTE DEL SOLE &#8211; Le parcours dure environ 1 heure et 30 minutes.<br \/>\n&#8211; \u00c0 partir de 12h00, d\u00e9jeuner \u00e0 la Trattoria Alpina de Dossena, via Don Pietro Rigoli, 30 \u00e0 Dossena.<br \/>\n&#8211; Transfert autonome vers le parc sp\u00e9l\u00e9ologique.<br \/>\n&#8211; Rendez-vous \u00e0 la localit\u00e9 Paglio-Pignolino, 15 minutes avant l&#8217;heure choisie.<br \/>\n&#8211; parc sp\u00e9l\u00e9ologique: Le parcours dans le parc sp\u00e9l\u00e9ologique dure 1 heure et 15 minutes.<br \/>\nIl est conseill\u00e9 de visiter ensuite le BECCO DI DOSSENA, une terrasse panoramique avec un acc\u00e8s libre et gratuit, surplombant une falaise d&#8217;environ 250 m\u00e8tres, offrant une vue imprenable sur la vall\u00e9e de Parina.<br \/>\nPour conclure la journ\u00e9e en beaut\u00e9, il est possible de r\u00e9server un APERITIVO du territoire \u00e0 l&#8217;H\u00f4tel Moderno de Serina, non inclus dans le prix du forfait, \u00e0 15 euros par personne.<\/p>\n","indepth":"","howtogetthere":"","timerange":"<p>Toute l&#8217;ann\u00e9e.<br \/>\nLUN : Pont \u00e0 11h30, parc \u00e0 14h00<br \/>\nVEN : Pont \u00e0 11h30, parc \u00e0 14h00<br \/>\nSAM : Pont \u00e0 10h00, 10h30, 11h00 ; Parc \u00e0 15h00, 16h30<br \/>\nDIM : Pont \u00e0 10h00, 10h30, 11h00 ; Parc \u00e0 15h00, 16h30<\/p>\n","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"<p>3. MODIFICATION\/ANNULATION DU SERVICE<br \/>\n3.1 ASD se r\u00e9serve le droit de communiquer (par SMS, t\u00e9l\u00e9phone et\/ou e-mail aux coordonn\u00e9es fournies lors de la r\u00e9servation) au Consommateur l&#8217;impossibilit\u00e9 de fournir le Service \u00e0 la date et \u00e0 l&#8217;heure convenues ou la n\u00e9cessit\u00e9 de modifier le Service convenu jusqu&#8217;\u00e0 dix-huit (18) heures avant la prestation du Service, m\u00eame en l&#8217;absence de causes de force majeure. Dans ce cas, le Consommateur aura droit \u00e0 un bon d&#8217;un montant d\u00e9termin\u00e9 par ASD correspondant \u00e0 la partie du Service non fourni, ou pourra reprogrammer la date et l&#8217;heure du Service ainsi que son contenu selon les disponibilit\u00e9s du moment ; le Consommateur devra communiquer son choix dans un d\u00e9lai de quarante-huit (48) heures \u00e0 partir du moment o\u00f9 ASD l&#8217;informe qu&#8217;elle ne peut pas fournir le Service dans les conditions initialement convenues. En tout \u00e9tat de cause, ASD ne sera pas tenue de rembourser les frais de voyage, de transport, d&#8217;h\u00e9bergement, etc., que le Consommateur pourrait avoir d\u00e9j\u00e0 engag\u00e9s pour la fourniture du Service annul\u00e9 ou modifi\u00e9.<br \/>\n3.2 ASD se r\u00e9serve le droit, \u00e0 sa seule discr\u00e9tion, de modifier les horaires et les modalit\u00e9s de prestation du Service, si des causes de force majeure, telles que de mauvaises conditions m\u00e9t\u00e9orologiques (pluie ou vent fort) et\/ou des situations environnementales et\/ou des conditions des installations et des structures ne permettant pas la r\u00e9alisation du Service en toute s\u00e9curit\u00e9, surviennent, m\u00eame pour des p\u00e9riodes de temps limit\u00e9es au cours de la journ\u00e9e. Dans ce cas, le Consommateur aura droit \u00e0 un bon d&#8217;un montant d\u00e9termin\u00e9 par ASD correspondant \u00e0 la partie du Service non fourni, ou pourra reprogrammer la date et l&#8217;heure du Service ainsi que son contenu selon les disponibilit\u00e9s du moment. En tout \u00e9tat de cause, ASD ne sera pas tenue de rembourser les frais de voyage, de transport, d&#8217;h\u00e9bergement, etc., que le Consommateur pourrait avoir d\u00e9j\u00e0 engag\u00e9s pour la fourniture du Service annul\u00e9 ou modifi\u00e9.<br \/>\n3.3 Si, apr\u00e8s la prestation d&#8217;une partie du Service convenu, la partie restante du Service ne peut pas \u00eatre fournie, m\u00eame en l&#8217;absence de causes de force majeure, ASD proposera, dans la mesure du possible, des solutions alternatives, compatibles avec les exigences techniques et de s\u00e9curit\u00e9, sans frais suppl\u00e9mentaires pour le Consommateur.<br \/>\n3.4 Si le Consommateur souhaite modifier la date et\/ou l&#8217;heure du Service pr\u00e9c\u00e9demment achet\u00e9, cette modification pourra \u00eatre effectu\u00e9e selon les modalit\u00e9s d\u00e9finies sur le site web www.visitdossena.it et selon les disponibilit\u00e9s des six (6) mois suivants, uniquement dans un d\u00e9lai ne d\u00e9passant pas 2 (deux) jours calendaires avant la date initialement choisie, aux conditions suivantes : avec un co\u00fbt de gestion suppl\u00e9mentaire de 5,00 euros si la modification a lieu entre 2 (deux) et 5 (cinq) jours calendaires avant la date initialement choisie, gratuitement si la modification a lieu plus de 5 (cinq) jours calendaires avant la date initialement choisie. De plus, si la modification entra\u00eene un prix du Service sup\u00e9rieur \u00e0 celui initialement achet\u00e9, le Consommateur devra verser la diff\u00e9rence \u00e0 ASD lors de la demande de modification.<br \/>\n3.5 Si le Consommateur ne se pr\u00e9sente pas au check-in \u00e0 Piazzale degli Alpini n.1 (Infopoint) ou au point d&#8217;accueil des mines \u00e0 l&#8217;heure fix\u00e9e, ASD pourra lui refuser l&#8217;acc\u00e8s au Service, le billet correspondant \u00e9tant consid\u00e9r\u00e9 comme utilis\u00e9 et ne pouvant en aucun cas \u00eatre rembours\u00e9.<\/p>\n","moredetails":"<p>R\u00c9SERVATION: Lors de la r\u00e9servation, veuillez indiquer dans le champ &#8220;notes&#8221; l&#8217;heure \u00e0 laquelle vous vous rendrez au pont le matin et au parc sp\u00e9l\u00e9ologique l&#8217;apr\u00e8s-midi.<\/p>\n<p>HORAIRES:<br \/>\nLUN : Pont 11h30, parc 14h00<br \/>\nVEN : Pont 11h30, parc 14h00<br \/>\nSAM : Pont 10h00, 10h30, 11h00 ; Parc 15h00, 16h30<br \/>\nDIM : Pont 10h00, 10h30, 11h00 ; Parc 15h00, 16h30  <\/p>\n<p>Conditions du Ponte nel Sole<br \/>\n&#8211; Les visiteurs doivent \u00eatre en bonne sant\u00e9 ;<br \/>\n&#8211; Les visiteurs doivent retirer le titre d&#8217;acc\u00e8s \u00e0 l&#8217;INFOPOINT, situ\u00e9 via Piazzale degli Alpini 1, pour pouvoir profiter de l&#8217;attraction ;  <\/p>\n<p>Retirez le titre d&#8217;acc\u00e8s \u00e0 l&#8217;INFOPOINT (via Piazzale degli Alpini 1) pour pouvoir profiter de l&#8217;attraction. Continuez votre promenade dans le centre et suivez le sentier derri\u00e8re l&#8217;\u00e9glise Arciprebiterale, signal\u00e9 par des panneaux jaunes et bleus ; vous atteindrez l&#8217;ex-zone de tir \u00e0 la vol\u00e9e Roccolo Corna Bianca \u00e0 pied, avec un temps estim\u00e9 \u00e0 environ 25 minutes. Apr\u00e8s un bref briefing d&#8217;environ 10 minutes sur l&#8217;utilisation des mousquetons et du harnais, vous pourrez vivre l&#8217;exp\u00e9rience du &#8220;Ponte nel Sole&#8221; en direction du village. N&#8217;oubliez pas de porter des v\u00eatements et des chaussures de sport !<\/p>\n<p>Parc Sp\u00e9l\u00e9ologique:<br \/>\nLe parcours ne peut pas \u00eatre effectu\u00e9 par des personnes ayant des probl\u00e8mes cardiaques, de mobilit\u00e9, ou signalant des probl\u00e8mes de vertige ou de claustrophobie ; les invit\u00e9s ne doivent pas avoir consomm\u00e9 d&#8217;alcool, de substances psychoactives ou de m\u00e9dicaments susceptibles de limiter leur lucidit\u00e9. N&#8217;oubliez pas, si vous avez les cheveux longs, de les attacher correctement afin qu&#8217;ils ne risquent pas de se coincer sur le parcours. N&#8217;oubliez pas d&#8217;apporter vos gants : ils sont obligatoires ! L&#8217;\u00e2ge minimum est de 12 ans et la taille minimale de 140 cm.<\/p>\n","whatsincluded":"<p>&#8211; D\u00e9jeuner typique avec casoncelli \u00e0 la bergamasque, plateau de charcuteries et fromages locaux, et fromages affin\u00e9s en mine, dessert de la maison, 1\/2 litre d&#8217;eau, caf\u00e9 et couvert ;<br \/>\n&#8211; Location de harnais et casque ;<br \/>\n&#8211; Assistance par du personnel qualifi\u00e9.<br \/>\n&#8211; Assurance.<br \/>\n&#8211; Place de parking (suivez les indications du &#8220;point de rencontre&#8221; indiqu\u00e9es sur le billet) ;<br \/>\n&#8211; Navette (si pr\u00e9vue par VisitDossena) ;<\/p>\n","whatsnotincluded":"<p>&#8211; Transfert de \/ vers le lieu de l&#8217;exp\u00e9rience<br \/>\n&#8211; Autres attractions de VisitDossena;<br \/>\n&#8211; Gants anti-salissures;<br \/>\n&#8211; Outils pour services photographiques;<\/p>\n","price":"","time":"","service_icons":[],"services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.87962570","longitude":"9.69818230","startingprice":"79.00","gpxmap":"","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Piazzale Alpini, 1","iu_addr_postalcode":"24010","iu_addr_city":"Dossena","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"VIsit Dossena, Via Chiesa, 6, Dossena","iu_bookingurl":"https:\/\/back-services.com\/newfront\/services.htm?channelid=652&lang=fra&no_qr=si&styleid=3073&ecomid=4140&serviceid=5","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"journ\u00e9e enti\u00e8re","iu_languages":"italien - anglais","iu_minpeople":"Minimum 1 personne","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"652_4140_5","id_visit_manza":"","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"20\/01\/2025","validto":"20\/01\/2026","hours":"","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","review":false,"modules":false,"filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"iu_motor_accessibility":"no","iu_visual_accessibility":"no","iu_auditory_accessibility":"no","iu_cognitive_accessibility":"no","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"random","order_way":"asc"},"or_filter":false,"max_elements":"","show_total":false,"see_all":false,"order_by":"random","order_way":"asc","only_ambassadors":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/114252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/114252\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/184338"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=114252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=114252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=114252"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=114252"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=114252"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=114252"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=114252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}