{"id":16235,"date":"2024-05-08T11:03:23","date_gmt":"2024-05-08T09:03:23","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/chateau-de-san-vigilio\/"},"modified":"2025-02-16T09:14:45","modified_gmt":"2025-02-16T08:14:45","slug":"chateau-de-san-vigilio","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/chateau-de-san-vigilio\/","title":{"rendered":"Ch\u00e2teau de San Vigilio"},"excerpt":{"rendered":"<p>Les ruines d&#8217;un ch\u00e2teau grandiose, avec des tours, des embrasures et des meurtri\u00e8res, construit sur un r\u00e9seau souterrain complexe de tunnels et de passages secrets. Le dernier poste de garde de Bergame et de son territoire. <\/p>\n","protected":false},"author":3,"featured_media":2769,"template":"","categories":[152],"tags":[],"aggr":[],"area":[867],"kind":[18678],"zona":[18758],"class_list":["post-16235","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-ou-aller","area-bergamo","kind-poi-fr","zona-bergamo-fr"],"acf":{"hero_buttons":false,"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","latitude":"45.708436","longitude":"9.650390","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_postalcode":"24100","iu_addr_city":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"20","url":"","url_youtube":"","iu_timetable":false,"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Fiche technique"},{"acf_fc_layout":"text","text":""}],"description":"<p><span style=\"font-weight: 400;\">D\u00e9couvrez le <strong>ch\u00e2teau de San Vigilio \u00e0 Bergame<\/strong>: un monument historique avec des vues panoramiques \u00e0 couper le souffle.<br \/>\nExplorez son histoire fascinante, ses donjons secrets et profitez d&#8217;un d\u00eener romantique dans l&#8217;un des restaurants de luxe situ\u00e9s sur la colline.<br \/>\nVisites guid\u00e9es disponibles.  <\/span><\/p>\n<h3>Caract\u00e9ristiques<\/h3>\n<p>Symbole tr\u00e8s visible du pouvoir, le <strong>ch\u00e2teau de San Vigilio<\/strong> a \u00e9t\u00e9 pendant des si\u00e8cles la r\u00e9sidence des diff\u00e9rents souverains qui se sont succ\u00e9d\u00e9 \u00e0 Bergame. Situ\u00e9 \u00e0 <strong>496 m\u00e8tres au-dessus du niveau de la mer<\/strong> sur la colline qui lui donne son nom, il domine la <strong>ville haute<\/strong>, ce qui explique le r\u00f4le strat\u00e9gique qu&#8217;il a jou\u00e9 dans le pass\u00e9 en cas d&#8217;attaques ennemies. De son sommet, en effet, on peut apercevoir le <strong>Mont Bastia<\/strong> tout proche et les villages en contrebas de l&#8217;ancien <strong>Val Breno<\/strong> (aujourd&#8217;hui <strong>Valbrembo<\/strong> et <strong>Paladina<\/strong>), l&#8217;<strong>esplanade d&#8217;Almenno<\/strong>, dite <strong>Lemine<\/strong>, autrefois zone de grande importance commerciale, et les villages situ\u00e9s le long de la route menant \u00e0 l&#8217;entr\u00e9e du <strong>Val Brembana<\/strong>. Ce panorama, aussi spectaculaire qu&#8217;infini, embrasse \u00e9galement une vaste partie des <strong>Pr\u00e9alpes<\/strong>.<\/p>\n<p> Le plan de l&#8217;\u00e9difice, qui rappelle la forme d&#8217;une \u00e9toile, est tr\u00e8s frappant, avec les quatre tours annexes appel\u00e9es <em>Castagneta<\/em>, <em>Belvedere<\/em>, <em>Del Ponte<\/em> et <em><strong>San Vigilio<\/strong><\/em>.<br \/>\nSes souterrains sont \u00e9galement tr\u00e8s complexes : un tunnel a \u00e9t\u00e9 d\u00e9couvert, dont une partie est praticable, qui relie directement le ch\u00e2teau \u00e0 la partie nord de la muraille de la colline, \u00e0 l&#8217;int\u00e9rieur du <strong>Fort San Marco<\/strong>.<\/p>\n","slides":[{"image":{"ID":2769,"id":2769,"title":"30c450ea41dc233ceb7add1dec6cd64e_9a7042bc.jpg","filename":"30c450ea41dc233ceb7add1dec6cd64e_9a7042bc.jpg","filesize":1124116,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/30c450ea41dc233ceb7add1dec6cd64e_9a7042bc.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/chateau-de-san-vigilio\/30c450ea41dc233ceb7add1dec6cd64e_9a7042bc-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"30c450ea41dc233ceb7add1dec6cd64e_9a7042bc-jpg-2","status":"inherit","uploaded_to":16235,"date":"2024-05-08 08:34:55","modified":"2024-05-08 12:11:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1036,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/30c450ea41dc233ceb7add1dec6cd64e_9a7042bc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/30c450ea41dc233ceb7add1dec6cd64e_9a7042bc-300x162.jpg","medium-width":300,"medium-height":162,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/30c450ea41dc233ceb7add1dec6cd64e_9a7042bc-768x414.jpg","medium_large-width":768,"medium_large-height":414,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/30c450ea41dc233ceb7add1dec6cd64e_9a7042bc-1024x553.jpg","large-width":1024,"large-height":553,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/30c450ea41dc233ceb7add1dec6cd64e_9a7042bc-1536x829.jpg","1536x1536-width":1536,"1536x1536-height":829,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/30c450ea41dc233ceb7add1dec6cd64e_9a7042bc.jpg","2048x2048-width":1920,"2048x2048-height":1036,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/30c450ea41dc233ceb7add1dec6cd64e_9a7042bc.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":162,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/30c450ea41dc233ceb7add1dec6cd64e_9a7042bc.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":216,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/30c450ea41dc233ceb7add1dec6cd64e_9a7042bc.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":324}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"ch\u00e2teau de san vigilio","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":33935,"id":33935,"title":"San Vigilio 1","filename":"San-Vigilio-1.jpg","filesize":955712,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-Vigilio-1.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/chateau-de-san-vigilio\/san-vigilio-1-2\/","alt":"","author":"6","description":"","caption":"","name":"san-vigilio-1-2","status":"inherit","uploaded_to":16235,"date":"2024-05-20 12:53:22","modified":"2024-05-20 12:53:22","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":720,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-Vigilio-1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-Vigilio-1-300x138.jpg","medium-width":300,"medium-height":138,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-Vigilio-1-768x354.jpg","medium_large-width":768,"medium_large-height":354,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-Vigilio-1-1024x473.jpg","large-width":1024,"large-height":473,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-Vigilio-1-1536x709.jpg","1536x1536-width":1536,"1536x1536-height":709,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-Vigilio-1.jpg","2048x2048-width":1560,"2048x2048-height":720,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-Vigilio-1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":138,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-Vigilio-1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":185,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-Vigilio-1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":277}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"ch\u00e2teau de san vigilio 2 collines","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":33941,"id":33941,"title":"San vigilio","filename":"San-vigilio.jpg","filesize":826580,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-vigilio.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/chateau-de-san-vigilio\/san-vigilio-2-2\/","alt":"","author":"6","description":"","caption":"","name":"san-vigilio-2-2","status":"inherit","uploaded_to":16235,"date":"2024-05-20 12:53:23","modified":"2024-05-20 12:53:23","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":720,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-vigilio-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-vigilio-300x138.jpg","medium-width":300,"medium-height":138,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-vigilio-768x354.jpg","medium_large-width":768,"medium_large-height":354,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-vigilio-1024x473.jpg","large-width":1024,"large-height":473,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-vigilio-1536x709.jpg","1536x1536-width":1536,"1536x1536-height":709,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-vigilio.jpg","2048x2048-width":1560,"2048x2048-height":720,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-vigilio.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":138,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-vigilio.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":185,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/San-vigilio.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":277}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":33947,"id":33947,"title":"Parco Castello S. Vigilio","filename":"Parco-Castello-S.-Vigilio-scaled.jpg","filesize":1440888,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Parco-Castello-S.-Vigilio-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/chateau-de-san-vigilio\/parco-castello-s-vigilio-2\/","alt":"","author":"6","description":"","caption":"","name":"parco-castello-s-vigilio-2","status":"inherit","uploaded_to":16235,"date":"2024-05-20 12:53:25","modified":"2024-05-20 12:53:25","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1713,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Parco-Castello-S.-Vigilio-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Parco-Castello-S.-Vigilio-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Parco-Castello-S.-Vigilio-768x514.jpg","medium_large-width":768,"medium_large-height":514,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Parco-Castello-S.-Vigilio-1024x685.jpg","large-width":1024,"large-height":685,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Parco-Castello-S.-Vigilio-1536x1028.jpg","1536x1536-width":1536,"1536x1536-height":1028,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Parco-Castello-S.-Vigilio-2048x1370.jpg","2048x2048-width":2048,"2048x2048-height":1370,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Parco-Castello-S.-Vigilio-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Parco-Castello-S.-Vigilio-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/Parco-Castello-S.-Vigilio-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":2775,"id":2775,"title":"1ac4f44f9e2055dccd5768c42f16e77a_54666e63.jpg","filename":"1ac4f44f9e2055dccd5768c42f16e77a_54666e63.jpg","filesize":1164643,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1ac4f44f9e2055dccd5768c42f16e77a_54666e63.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/chateau-de-san-vigilio\/1ac4f44f9e2055dccd5768c42f16e77a_54666e63-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1ac4f44f9e2055dccd5768c42f16e77a_54666e63-jpg-2","status":"inherit","uploaded_to":16235,"date":"2024-05-08 08:34:56","modified":"2024-05-08 12:11:42","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1277,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1ac4f44f9e2055dccd5768c42f16e77a_54666e63-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1ac4f44f9e2055dccd5768c42f16e77a_54666e63-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1ac4f44f9e2055dccd5768c42f16e77a_54666e63-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1ac4f44f9e2055dccd5768c42f16e77a_54666e63-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1ac4f44f9e2055dccd5768c42f16e77a_54666e63-1536x1022.jpg","1536x1536-width":1536,"1536x1536-height":1022,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1ac4f44f9e2055dccd5768c42f16e77a_54666e63.jpg","2048x2048-width":1920,"2048x2048-height":1277,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1ac4f44f9e2055dccd5768c42f16e77a_54666e63.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1ac4f44f9e2055dccd5768c42f16e77a_54666e63.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/1ac4f44f9e2055dccd5768c42f16e77a_54666e63.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Contact","icon":{"button_icon":"none"},"function":"link","url":"","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","hero_type":"images","hero_title":"Ch\u00e2teau de San Vigilio","hero_text":"<p>Les ruines d&#8217;un ch\u00e2teau grandiose, avec des tours, des embrasures et des meurtri\u00e8res, construit sur un r\u00e9seau complexe de souterrains et de passages secrets.<br \/>\nLe dernier poste de garde de Bergame et de son territoire. <\/p>\n","indepth":"<h3>Histoire du ch\u00e2teau<\/h3>\n<p>Les premi\u00e8res traces d&#8217;une fortification sur la colline remontent aux alentours du VIe si\u00e8cle apr\u00e8s J.-C., bien que la pr\u00e9sence de b\u00e2timents datant de l&#8217;\u00e9poque romaine ne soit pas exclue. En 889, le futur roi d&#8217;Italie, Arnolfo de Carinthie, d\u00e9cida de conqu\u00e9rir la colline en la prenant \u00e0 la communaut\u00e9 religieuse qui y \u00e9tait install\u00e9e depuis le VIe si\u00e8cle et qui y avait construit une petite forteresse appel\u00e9e Castello della Cappella (du nom de la chapelle d\u00e9di\u00e9e \u00e0 Sainte Marie-Madeleine). Le lieu devint ensuite une garnison militaire d&#8217;une grande importance strat\u00e9gique, \u00e0 tel point qu&#8217;en 1166, le conseil municipal de la ville de Bergame d\u00e9cida de construire un ch\u00e2teau plus grand que le pr\u00e9c\u00e9dent. Gr\u00e2ce aux interventions du duch\u00e9 de Milan au XIVe si\u00e8cle et surtout de la R\u00e9publique de Venise au XVe si\u00e8cle, le <strong>ch\u00e2teau de San Vigilio<\/strong> a \u00e9t\u00e9 agrandi et renforc\u00e9. De nombreuses modifications ont \u00e9t\u00e9 apport\u00e9es, notamment quatre tours \u00e9quip\u00e9es d&#8217;embrasures et de meurtri\u00e8res, reli\u00e9es par un mur d&#8217;enceinte de forme polygonale, et un foss\u00e9 de protection. Au cours du XVIe si\u00e8cle, les si\u00e8ges r\u00e9p\u00e9t\u00e9s des Fran\u00e7ais et des Espagnols ont conduit \u00e0 la construction d&#8217;un imposant mur d&#8217;enceinte. La tour centrale d&#8217;origine m\u00e9di\u00e9vale a \u00e9t\u00e9 d\u00e9molie pour permettre un plus grand afflux de garnisons militaires, et des logements de soldats et la maison du ch\u00e2telain ont \u00e9t\u00e9 construits. <\/p>\n<h3>\u00c9v\u00e9nements et visites<\/h3>\n<p>D\u00e8s la fin du XIXe si\u00e8cle, le ch\u00e2teau a montr\u00e9 sa vocation touristique : l&#8217;ensemble de la structure a \u00e9t\u00e9 achet\u00e9 par la famille Soregaroli, qui y a ouvert un restaurant. Une sorte de pr\u00e9monition, puisqu&#8217;aujourd&#8217;hui la <strong>colline de San Vigilio<\/strong>, avec ses deux restaurants de luxe, est consid\u00e9r\u00e9e comme l&#8217;une des destinations id\u00e9ales pour s&#8217;offrir un d\u00eener en t\u00eate-\u00e0-t\u00eate. Le <strong>funiculaire de San Vigilio<\/strong>, construit en 1912 pour relier la colline \u00e0 Porta Sant&#8217;Alessandro, fait \u00e9galement partie de l&#8217;atmosph\u00e8re amoureuse que vous respirerez. Le ch\u00e2teau est ensuite devenu la propri\u00e9t\u00e9 de la municipalit\u00e9 de Bergame, qui l&#8217;a ouvert au public en 1962, tandis que le funiculaire, \u00e0 l&#8217;arr\u00eat depuis 1976, a \u00e9t\u00e9 restaur\u00e9 en 1991. Aujourd&#8217;hui, il est encore possible de visiter le passage secret qui relie la <strong>forteresse de San Marco<\/strong> au ch\u00e2teau lui-m\u00eame, gr\u00e2ce aux activit\u00e9s du groupe sp\u00e9l\u00e9ologique Le Nottole, qui propose des <strong>visites guid\u00e9es sur rendez-vous.<\/strong>  <\/p>\n","time":"<p>Du 1er novembre au 31 mars 8 &#8211; 17 Du 1er avril au 31 octobre 7 &#8211; 21<\/p>\n","iu_addr_streetnumber":"Via al Castello, 1","filotto_fill":"manual","filotto_items":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Fiche technique"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"iu_addr_province":"Bergamo","poi_data":{"description":"<p><span style=\"font-weight: 400;\">D\u00e9couvrez le <strong>ch\u00e2teau de San Vigilio \u00e0 Bergame<\/strong>: un monument historique avec des vues panoramiques \u00e0 couper le souffle.<br \/>\nExplorez son histoire fascinante, ses donjons secrets et profitez d&#8217;un d\u00eener romantique dans l&#8217;un des restaurants de luxe situ\u00e9s sur la colline.<br \/>\nVisites guid\u00e9es disponibles.  <\/span><\/p>\n<h3>Caract\u00e9ristiques<\/h3>\n<p>Symbole tr\u00e8s visible du pouvoir, le <strong>ch\u00e2teau de San Vigilio<\/strong> a \u00e9t\u00e9 pendant des si\u00e8cles la r\u00e9sidence des diff\u00e9rents souverains qui se sont succ\u00e9d\u00e9 \u00e0 Bergame. Situ\u00e9 \u00e0 <strong>496 m\u00e8tres au-dessus du niveau de la mer<\/strong> sur la colline qui lui donne son nom, il domine la <strong>ville haute<\/strong>, ce qui explique le r\u00f4le strat\u00e9gique qu&#8217;il a jou\u00e9 dans le pass\u00e9 en cas d&#8217;attaques ennemies. De son sommet, en effet, on peut apercevoir le <strong>Mont Bastia<\/strong> tout proche et les villages en contrebas de l&#8217;ancien <strong>Val Breno<\/strong> (aujourd&#8217;hui <strong>Valbrembo<\/strong> et <strong>Paladina<\/strong>), l&#8217;<strong>esplanade d&#8217;Almenno<\/strong>, dite <strong>Lemine<\/strong>, autrefois zone de grande importance commerciale, et les villages situ\u00e9s le long de la route menant \u00e0 l&#8217;entr\u00e9e du <strong>Val Brembana<\/strong>. Ce panorama, aussi spectaculaire qu&#8217;infini, embrasse \u00e9galement une vaste partie des <strong>Pr\u00e9alpes<\/strong>.<\/p>\n<p> Le plan de l&#8217;\u00e9difice, qui rappelle la forme d&#8217;une \u00e9toile, est tr\u00e8s frappant, avec les quatre tours annexes appel\u00e9es <em>Castagneta<\/em>, <em>Belvedere<\/em>, <em>Del Ponte<\/em> et <em><strong>San Vigilio<\/strong><\/em>.<br \/>\nSes souterrains sont \u00e9galement tr\u00e8s complexes : un tunnel a \u00e9t\u00e9 d\u00e9couvert, dont une partie est praticable, qui relie directement le ch\u00e2teau \u00e0 la partie nord de la muraille de la colline, \u00e0 l&#8217;int\u00e9rieur du <strong>Fort San Marco<\/strong>.<\/p>\n","indepth":"<h3>Histoire du ch\u00e2teau<\/h3>\n<p>Les premi\u00e8res traces d&#8217;une fortification sur la colline remontent aux alentours du VIe si\u00e8cle apr\u00e8s J.-C., bien que la pr\u00e9sence de b\u00e2timents datant de l&#8217;\u00e9poque romaine ne soit pas exclue. En 889, le futur roi d&#8217;Italie, Arnolfo de Carinthie, d\u00e9cida de conqu\u00e9rir la colline en la prenant \u00e0 la communaut\u00e9 religieuse qui y \u00e9tait install\u00e9e depuis le VIe si\u00e8cle et qui y avait construit une petite forteresse appel\u00e9e Castello della Cappella (du nom de la chapelle d\u00e9di\u00e9e \u00e0 Sainte Marie-Madeleine). Le lieu devint ensuite une garnison militaire d&#8217;une grande importance strat\u00e9gique, \u00e0 tel point qu&#8217;en 1166, le conseil municipal de la ville de Bergame d\u00e9cida de construire un ch\u00e2teau plus grand que le pr\u00e9c\u00e9dent. Gr\u00e2ce aux interventions du duch\u00e9 de Milan au XIVe si\u00e8cle et surtout de la R\u00e9publique de Venise au XVe si\u00e8cle, le <strong>ch\u00e2teau de San Vigilio<\/strong> a \u00e9t\u00e9 agrandi et renforc\u00e9. De nombreuses modifications ont \u00e9t\u00e9 apport\u00e9es, notamment quatre tours \u00e9quip\u00e9es d&#8217;embrasures et de meurtri\u00e8res, reli\u00e9es par un mur d&#8217;enceinte de forme polygonale, et un foss\u00e9 de protection. Au cours du XVIe si\u00e8cle, les si\u00e8ges r\u00e9p\u00e9t\u00e9s des Fran\u00e7ais et des Espagnols ont conduit \u00e0 la construction d&#8217;un imposant mur d&#8217;enceinte. La tour centrale d&#8217;origine m\u00e9di\u00e9vale a \u00e9t\u00e9 d\u00e9molie pour permettre un plus grand afflux de garnisons militaires, et des logements de soldats et la maison du ch\u00e2telain ont \u00e9t\u00e9 construits. <\/p>\n<h3>\u00c9v\u00e9nements et visites<\/h3>\n<p>D\u00e8s la fin du XIXe si\u00e8cle, le ch\u00e2teau a montr\u00e9 sa vocation touristique : l&#8217;ensemble de la structure a \u00e9t\u00e9 achet\u00e9 par la famille Soregaroli, qui y a ouvert un restaurant. Une sorte de pr\u00e9monition, puisqu&#8217;aujourd&#8217;hui la <strong>colline de San Vigilio<\/strong>, avec ses deux restaurants de luxe, est consid\u00e9r\u00e9e comme l&#8217;une des destinations id\u00e9ales pour s&#8217;offrir un d\u00eener en t\u00eate-\u00e0-t\u00eate. Le <strong>funiculaire de San Vigilio<\/strong>, construit en 1912 pour relier la colline \u00e0 Porta Sant&#8217;Alessandro, fait \u00e9galement partie de l&#8217;atmosph\u00e8re amoureuse que vous respirerez. Le ch\u00e2teau est ensuite devenu la propri\u00e9t\u00e9 de la municipalit\u00e9 de Bergame, qui l&#8217;a ouvert au public en 1962, tandis que le funiculaire, \u00e0 l&#8217;arr\u00eat depuis 1976, a \u00e9t\u00e9 restaur\u00e9 en 1991. Aujourd&#8217;hui, il est encore possible de visiter le passage secret qui relie la <strong>forteresse de San Marco<\/strong> au ch\u00e2teau lui-m\u00eame, gr\u00e2ce aux activit\u00e9s du groupe sp\u00e9l\u00e9ologique Le Nottole, qui propose des <strong>visites guid\u00e9es sur rendez-vous.<\/strong>  <\/p>\n","howtogetthere":"","price":"","time":"<p>Du 1er novembre au 31 mars 8 &#8211; 17 Du 1er avril au 31 octobre 7 &#8211; 21<\/p>\n","latitude":"45.708436","longitude":"9.650390","id_visit_manza":"20","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"Via al Castello, 1","iu_addr_postalcode":"24100","iu_addr_city":"Bergamo","iu_addr_province":"Bergamo","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":false},"size":"full","featured_video":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"iu_document_label":"","modules":false,"iu_kids":false,"is_an_ambassador":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/16235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/16235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/2769"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=16235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=16235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=16235"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=16235"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=16235"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=16235"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=16235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}