{"id":16448,"date":"2024-05-08T11:04:38","date_gmt":"2024-05-08T09:04:38","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/porta-san-giacomo\/"},"modified":"2025-02-16T09:18:54","modified_gmt":"2025-02-16T08:18:54","slug":"porta-san-giacomo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/porta-san-giacomo\/","title":{"rendered":"Porte de Saint-Jacques"},"excerpt":{"rendered":"<p>La seule br\u00e8che dans les murailles visible depuis la basse Bergame, la seule en marbre blanc poli, la seule pr\u00e9c\u00e9d\u00e9e d&#8217;un viaduc en pierre surplombant la plaine.  <\/p>\n","protected":false},"author":3,"featured_media":6619,"template":"","categories":[],"tags":[],"aggr":[],"area":[867],"kind":[18678],"zona":[18758],"class_list":["post-16448","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","area-bergamo","kind-poi-fr","zona-bergamo-fr"],"acf":{"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","latitude":"45.701325","longitude":"9.662940","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"6560","url":"","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"","target":"","url_youtube":"","target_modal":""},"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Fiche technique"},{"acf_fc_layout":"text","text":""}],"description":"<p>Autrefois, la Porta San Giacomo \u00e9tait l&#8217;entr\u00e9e de la Citt\u00e0 Alta pour ceux qui arrivaient de Milan.<br \/>\nC&#8217;est le seul acc\u00e8s aux remparts qui soit parfaitement visible depuis le Viale Vittorio Emanuele, l&#8217;axe qui traverse le bas Bergame du sud au nord, tant par sa position que par sa couleur.<br \/>\nLe marbre blanc avec lequel il est construit, extrait des carri\u00e8res de Zandobbio, dans la proche Val Cavallina, le distingue de la pierre grise des murs de d\u00e9fense.<br \/>\nGr\u00e2ce \u00e0 ces caract\u00e9ristiques, en plus d&#8217;\u00eatre l&#8217;un des lieux les plus photographi\u00e9s de Bergame, il constitue une toile de fond id\u00e9ale pour projeter des lumi\u00e8res color\u00e9es lors d&#8217;\u00e9v\u00e9nements sp\u00e9ciaux (par exemple, le tricolore du drapeau italien lors de c\u00e9l\u00e9brations li\u00e9es \u00e0 des anniversaires nationaux).<br \/>\nEn vous appuyant sur la balustrade, vous b\u00e9n\u00e9ficierez, d&#8217;une part, d&#8217;une belle vue sur les fortifications v\u00e9nitiennes et, d&#8217;autre part, d&#8217;un splendide panorama sur la ville basse et la plaine jusqu&#8217;aux Apennins !    <\/p>\n","slides":[{"image":{"ID":6619,"id":6619,"title":"c987f17a0c75c3e6aa776d824750c376_fc5b6281.jpg","filename":"c987f17a0c75c3e6aa776d824750c376_fc5b6281.jpg","filesize":667602,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/porta-san-giacomo\/c987f17a0c75c3e6aa776d824750c376_fc5b6281-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c987f17a0c75c3e6aa776d824750c376_fc5b6281-jpg-2","status":"inherit","uploaded_to":16448,"date":"2024-05-08 08:42:41","modified":"2024-05-08 12:13:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1285,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281-300x201.jpg","medium-width":300,"medium-height":201,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281-768x514.jpg","medium_large-width":768,"medium_large-height":514,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281-1024x685.jpg","large-width":1024,"large-height":685,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281-1536x1028.jpg","1536x1536-width":1536,"1536x1536-height":1028,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281.jpg","2048x2048-width":1920,"2048x2048-height":1285,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":201,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":268,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/c987f17a0c75c3e6aa776d824750c376_fc5b6281.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":402}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"porta san giacomo 1","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":6625,"id":6625,"title":"0487d66663ce51306fa12250ffedcc07_3638c838.jpg","filename":"0487d66663ce51306fa12250ffedcc07_3638c838.jpg","filesize":766538,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/porta-san-giacomo\/0487d66663ce51306fa12250ffedcc07_3638c838-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"0487d66663ce51306fa12250ffedcc07_3638c838-jpg-2","status":"inherit","uploaded_to":16448,"date":"2024-05-08 08:42:42","modified":"2024-05-08 12:13:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1277,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838-1536x1022.jpg","1536x1536-width":1536,"1536x1536-height":1022,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838.jpg","2048x2048-width":1920,"2048x2048-height":1277,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/0487d66663ce51306fa12250ffedcc07_3638c838.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"porta san giacomo d\u00e9tail","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":6631,"id":6631,"title":"17d7eb37fd6a5fce963059c933588665_e9f539eb.jpg","filename":"17d7eb37fd6a5fce963059c933588665_e9f539eb.jpg","filesize":463730,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/porta-san-giacomo\/17d7eb37fd6a5fce963059c933588665_e9f539eb-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"17d7eb37fd6a5fce963059c933588665_e9f539eb-jpg-2","status":"inherit","uploaded_to":16448,"date":"2024-05-08 08:42:42","modified":"2024-05-08 12:13:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":743,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb-300x116.jpg","medium-width":300,"medium-height":116,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb-768x297.jpg","medium_large-width":768,"medium_large-height":297,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb-1024x396.jpg","large-width":1024,"large-height":396,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb-1536x594.jpg","1536x1536-width":1536,"1536x1536-height":594,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb.jpg","2048x2048-width":1920,"2048x2048-height":743,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":116,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":155,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/17d7eb37fd6a5fce963059c933588665_e9f539eb.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":232}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"porta san giacomo retro","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Contact","icon":{"button_icon":"none"},"function":"link","url":"","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","hero_type":"images","hero_title":"Porte de Saint-Jacques","hero_text":"<p><span id=\"docs-internal-guid-83cf3d0d-7d5b-d56e-4e7d-c7895f4875e7\"><span>La seule br\u00e8che dans les murailles visible depuis la basse Bergame, la seule en marbre blanc poli, la seule pr\u00e9c\u00e9d\u00e9e d&#8217;un viaduc en pierre surplombant la plaine.<\/span><span><br class=\"kix-line-break\"><\/span><\/span><\/p>\n","indepth":"<p>Cette porte est form\u00e9e d&#8217;un fronton triangulaire soutenu par des demi-colonnes de style classique ; comme les autres entr\u00e9es de la ville, celle-ci est domin\u00e9e par le lion sculpt\u00e9 de Saint-Marc, symbole de la domination v\u00e9nitienne.<br \/>\nL&#8217;aspect de la Porta San Giacomo n&#8217;a pas toujours \u00e9t\u00e9 celui que l&#8217;on conna\u00eet aujourd&#8217;hui : l&#8217;ancien pont-levis en bois, qui fermait l&#8217;entr\u00e9e en cas de danger, a \u00e9t\u00e9 d\u00e9moli \u00e0 la fin du XVIIIe si\u00e8cle sur ordre du gouverneur v\u00e9nitien Alvise Contarini.<br \/>\n\u00c0 sa place fut construite la route en ma\u00e7onnerie que l&#8217;on peut encore emprunter aujourd&#8217;hui.<br \/>\nLa beaut\u00e9 de la Porta San Giacomo provient du romantique viaduc d&#8217;acc\u00e8s mais aussi de l&#8217;\u00e9clat du marbre avec lequel elle a \u00e9t\u00e9 r\u00e9alis\u00e9e : ce min\u00e9ral est extrait depuis l&#8217;antiquit\u00e9 \u00e0 Zandobbio, dans la province de Bergame.<br \/>\nLes Bergamasques l&#8217;ont \u00e9galement utilis\u00e9 pour la construction d&#8217;autres b\u00e2timents importants de la ville, tels que le Palazzo Nuovo (aujourd&#8217;hui la biblioth\u00e8que Angelo Mai) et la fontaine Contarini sur la Piazza Vecchia.    <\/p>\n<h3>Curiosit\u00e9 :<\/h3>\n<p>Comme les autres portes des remparts, la Porta San Giacomo \u00e9tait ferm\u00e9e tous les soirs \u00e0 22 heures pour assurer la s\u00e9curit\u00e9 de la ville.<\/p>\n","filotto_fill":"manual","filotto_items":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Fiche technique"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"iu_kids":false,"iu_timetable":false,"poi_data":{"description":"<p>Autrefois, la Porta San Giacomo \u00e9tait l&#8217;entr\u00e9e de la Citt\u00e0 Alta pour ceux qui arrivaient de Milan.<br \/>\nC&#8217;est le seul acc\u00e8s aux remparts qui soit parfaitement visible depuis le Viale Vittorio Emanuele, l&#8217;axe qui traverse le bas Bergame du sud au nord, tant par sa position que par sa couleur.<br \/>\nLe marbre blanc avec lequel il est construit, extrait des carri\u00e8res de Zandobbio, dans la proche Val Cavallina, le distingue de la pierre grise des murs de d\u00e9fense.<br \/>\nGr\u00e2ce \u00e0 ces caract\u00e9ristiques, en plus d&#8217;\u00eatre l&#8217;un des lieux les plus photographi\u00e9s de Bergame, il constitue une toile de fond id\u00e9ale pour projeter des lumi\u00e8res color\u00e9es lors d&#8217;\u00e9v\u00e9nements sp\u00e9ciaux (par exemple, le tricolore du drapeau italien lors de c\u00e9l\u00e9brations li\u00e9es \u00e0 des anniversaires nationaux).<br \/>\nEn vous appuyant sur la balustrade, vous b\u00e9n\u00e9ficierez, d&#8217;une part, d&#8217;une belle vue sur les fortifications v\u00e9nitiennes et, d&#8217;autre part, d&#8217;un splendide panorama sur la ville basse et la plaine jusqu&#8217;aux Apennins !    <\/p>\n","indepth":"<p>Cette porte est form\u00e9e d&#8217;un fronton triangulaire soutenu par des demi-colonnes de style classique ; comme les autres entr\u00e9es de la ville, celle-ci est domin\u00e9e par le lion sculpt\u00e9 de Saint-Marc, symbole de la domination v\u00e9nitienne.<br \/>\nL&#8217;aspect de la Porta San Giacomo n&#8217;a pas toujours \u00e9t\u00e9 celui que l&#8217;on conna\u00eet aujourd&#8217;hui : l&#8217;ancien pont-levis en bois, qui fermait l&#8217;entr\u00e9e en cas de danger, a \u00e9t\u00e9 d\u00e9moli \u00e0 la fin du XVIIIe si\u00e8cle sur ordre du gouverneur v\u00e9nitien Alvise Contarini.<br \/>\n\u00c0 sa place fut construite la route en ma\u00e7onnerie que l&#8217;on peut encore emprunter aujourd&#8217;hui.<br \/>\nLa beaut\u00e9 de la Porta San Giacomo provient du romantique viaduc d&#8217;acc\u00e8s mais aussi de l&#8217;\u00e9clat du marbre avec lequel elle a \u00e9t\u00e9 r\u00e9alis\u00e9e : ce min\u00e9ral est extrait depuis l&#8217;antiquit\u00e9 \u00e0 Zandobbio, dans la province de Bergame.<br \/>\nLes Bergamasques l&#8217;ont \u00e9galement utilis\u00e9 pour la construction d&#8217;autres b\u00e2timents importants de la ville, tels que le Palazzo Nuovo (aujourd&#8217;hui la biblioth\u00e8que Angelo Mai) et la fontaine Contarini sur la Piazza Vecchia.    <\/p>\n<h3>Curiosit\u00e9 :<\/h3>\n<p>Comme les autres portes des remparts, la Porta San Giacomo \u00e9tait ferm\u00e9e tous les soirs \u00e0 22 heures pour assurer la s\u00e9curit\u00e9 de la ville.<\/p>\n","howtogetthere":"","price":"","time":"","latitude":"45.701325","longitude":"9.662940","id_visit_manza":"6560","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":false},"size":"full","featured_video":false,"is_an_ambassador":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/16448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/16448\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/6619"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=16448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=16448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=16448"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=16448"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=16448"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=16448"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=16448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}