{"id":16506,"date":"2024-05-08T11:05:01","date_gmt":"2024-05-08T09:05:01","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/bourg-pignolo\/"},"modified":"2025-02-16T09:20:10","modified_gmt":"2025-02-16T08:20:10","slug":"borgo-pignolo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/borgo-pignolo\/","title":{"rendered":"Borgo Pignolo"},"excerpt":{"rendered":"<p>Ce village enchanteur, situ\u00e9 au pied des remparts v\u00e9nitiens, est un joyau qui allie art, architecture raffin\u00e9e et tradition, offrant des aper\u00e7us d&#8217;une beaut\u00e9 unique.<\/p>\n","protected":false},"author":3,"featured_media":7879,"template":"","categories":[152],"tags":[],"aggr":[],"area":[867],"kind":[18678],"zona":[18758],"class_list":["post-16506","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-ou-aller","area-bergamo","kind-poi-fr","zona-bergamo-fr"],"acf":{"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","latitude":"45.700747","longitude":"9.673895","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_postalcode":"","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"3010","url":"","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"","target":"","url_youtube":"","target_modal":""},"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Fiche technique"},{"acf_fc_layout":"text","text":""}],"description":"<p><strong>Borgo Pignolo<\/strong> est situ\u00e9 entre Bergamo Alta et Bergamo Bassa.<\/p>\n<p>En remontant le Borgo par le bas, vous serez progressivement conduit vers la Porta Sant&#8217;Agostino, le long d&#8217;un itin\u00e9raire incroyablement \u00e9vocateur : \u00e0 la succession de demeures Renaissance et n\u00e9oclassiques s&#8217;ajoutent des ateliers d&#8217;artisans, dont celui d&#8217;un luthier de renomm\u00e9e internationale, et de nombreux restaurateurs.<br \/>\nLes demeures historiques comprennent \u00e9galement l&#8217;un des lieux les plus prestigieux de la ville, le merveilleux Palazzo Agliardi. <\/p>\n<p>La particularit\u00e9 de<strong> Borgo Pignolo<\/strong> est de permettre \u00e0 l&#8217;art ancien de rencontrer l&#8217;art contemporain, en op\u00e9rant cette petite magie dans la succession harmonieuse des galeries d&#8217;art et des magasins d&#8217;antiquit\u00e9s.<\/p>\n<p>Enfin, le parcours s&#8217;enrichit des nombreux petits \u00e9tablissements qui jalonnent la rue principale, la Via Pignolo.<br \/>\nSoudain, la merveilleuse succession de palais majestueux c\u00e8de la place \u00e0 une vue tout aussi spectaculaire : la Porta di Sant&#8217;Agostino, qui ouvre une br\u00e8che dans les murailles v\u00e9nitiennes, le Parco della Fara et l&#8217;incroyable panorama du paysage environnant.   <\/p>\n","slides":[{"image":{"ID":7879,"id":7879,"title":"a413d6d33e11fdafe414600183218273_2b178841.jpg","filename":"a413d6d33e11fdafe414600183218273_2b178841.jpg","filesize":186553,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a413d6d33e11fdafe414600183218273_2b178841.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/borgo-pignolo\/a413d6d33e11fdafe414600183218273_2b178841-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a413d6d33e11fdafe414600183218273_2b178841-jpg-2","status":"inherit","uploaded_to":16506,"date":"2024-05-08 08:45:19","modified":"2024-09-28 13:30:25","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":915,"height":528,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a413d6d33e11fdafe414600183218273_2b178841-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a413d6d33e11fdafe414600183218273_2b178841-300x173.jpg","medium-width":300,"medium-height":173,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a413d6d33e11fdafe414600183218273_2b178841-768x443.jpg","medium_large-width":768,"medium_large-height":443,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a413d6d33e11fdafe414600183218273_2b178841.jpg","large-width":915,"large-height":528,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a413d6d33e11fdafe414600183218273_2b178841.jpg","1536x1536-width":915,"1536x1536-height":528,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a413d6d33e11fdafe414600183218273_2b178841.jpg","2048x2048-width":915,"2048x2048-height":528,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a413d6d33e11fdafe414600183218273_2b178841.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":173,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a413d6d33e11fdafe414600183218273_2b178841.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":231,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/a413d6d33e11fdafe414600183218273_2b178841.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":346}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Borgo Pignolo","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":7885,"id":7885,"title":"d8b36ec6a608d7089b5dbbb72b987a7a_0f24b35f.jpg","filename":"d8b36ec6a608d7089b5dbbb72b987a7a_0f24b35f.jpg","filesize":196792,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d8b36ec6a608d7089b5dbbb72b987a7a_0f24b35f.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/borgo-pignolo\/d8b36ec6a608d7089b5dbbb72b987a7a_0f24b35f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d8b36ec6a608d7089b5dbbb72b987a7a_0f24b35f-jpg-2","status":"inherit","uploaded_to":16506,"date":"2024-05-08 08:45:20","modified":"2024-09-28 13:30:32","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":915,"height":528,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d8b36ec6a608d7089b5dbbb72b987a7a_0f24b35f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d8b36ec6a608d7089b5dbbb72b987a7a_0f24b35f-300x173.jpg","medium-width":300,"medium-height":173,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d8b36ec6a608d7089b5dbbb72b987a7a_0f24b35f-768x443.jpg","medium_large-width":768,"medium_large-height":443,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d8b36ec6a608d7089b5dbbb72b987a7a_0f24b35f.jpg","large-width":915,"large-height":528,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d8b36ec6a608d7089b5dbbb72b987a7a_0f24b35f.jpg","1536x1536-width":915,"1536x1536-height":528,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d8b36ec6a608d7089b5dbbb72b987a7a_0f24b35f.jpg","2048x2048-width":915,"2048x2048-height":528,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d8b36ec6a608d7089b5dbbb72b987a7a_0f24b35f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":173,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d8b36ec6a608d7089b5dbbb72b987a7a_0f24b35f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":231,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/d8b36ec6a608d7089b5dbbb72b987a7a_0f24b35f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":346}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Borgo","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":7891,"id":7891,"title":"ab9e2cfc5dcbcff0ae5dff873ec93940_87bdadac.jpg","filename":"ab9e2cfc5dcbcff0ae5dff873ec93940_87bdadac.jpg","filesize":136831,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ab9e2cfc5dcbcff0ae5dff873ec93940_87bdadac.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/borgo-pignolo\/ab9e2cfc5dcbcff0ae5dff873ec93940_87bdadac-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ab9e2cfc5dcbcff0ae5dff873ec93940_87bdadac-jpg-2","status":"inherit","uploaded_to":16506,"date":"2024-05-08 08:45:20","modified":"2024-09-28 13:30:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":915,"height":528,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ab9e2cfc5dcbcff0ae5dff873ec93940_87bdadac-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ab9e2cfc5dcbcff0ae5dff873ec93940_87bdadac-300x173.jpg","medium-width":300,"medium-height":173,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ab9e2cfc5dcbcff0ae5dff873ec93940_87bdadac-768x443.jpg","medium_large-width":768,"medium_large-height":443,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ab9e2cfc5dcbcff0ae5dff873ec93940_87bdadac.jpg","large-width":915,"large-height":528,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ab9e2cfc5dcbcff0ae5dff873ec93940_87bdadac.jpg","1536x1536-width":915,"1536x1536-height":528,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ab9e2cfc5dcbcff0ae5dff873ec93940_87bdadac.jpg","2048x2048-width":915,"2048x2048-height":528,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ab9e2cfc5dcbcff0ae5dff873ec93940_87bdadac.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":173,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ab9e2cfc5dcbcff0ae5dff873ec93940_87bdadac.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":231,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/ab9e2cfc5dcbcff0ae5dff873ec93940_87bdadac.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":346}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Borgo Pignolo","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":7897,"id":7897,"title":"7f7c1beedee0c8e587079cc7087e2c31_1bc55818.jpg","filename":"7f7c1beedee0c8e587079cc7087e2c31_1bc55818.jpg","filesize":185756,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/7f7c1beedee0c8e587079cc7087e2c31_1bc55818.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/borgo-pignolo\/7f7c1beedee0c8e587079cc7087e2c31_1bc55818-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"7f7c1beedee0c8e587079cc7087e2c31_1bc55818-jpg-2","status":"inherit","uploaded_to":16506,"date":"2024-05-08 08:45:20","modified":"2024-09-28 13:30:44","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":915,"height":528,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/7f7c1beedee0c8e587079cc7087e2c31_1bc55818-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/7f7c1beedee0c8e587079cc7087e2c31_1bc55818-300x173.jpg","medium-width":300,"medium-height":173,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/7f7c1beedee0c8e587079cc7087e2c31_1bc55818-768x443.jpg","medium_large-width":768,"medium_large-height":443,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/7f7c1beedee0c8e587079cc7087e2c31_1bc55818.jpg","large-width":915,"large-height":528,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/7f7c1beedee0c8e587079cc7087e2c31_1bc55818.jpg","1536x1536-width":915,"1536x1536-height":528,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/7f7c1beedee0c8e587079cc7087e2c31_1bc55818.jpg","2048x2048-width":915,"2048x2048-height":528,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/7f7c1beedee0c8e587079cc7087e2c31_1bc55818.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":173,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/7f7c1beedee0c8e587079cc7087e2c31_1bc55818.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":231,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/7f7c1beedee0c8e587079cc7087e2c31_1bc55818.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":346}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Borgo Pignolo","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Contact","icon":{"button_icon":"none"},"function":"link","url":"","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","hero_type":"images","hero_title":"Borgo Pignolo","hero_text":"<p>Ce village enchanteur, situ\u00e9 au pied des remparts v\u00e9nitiens, est un joyau qui allie art, architecture raffin\u00e9e et tradition, offrant des aper\u00e7us d&#8217;une beaut\u00e9 unique.<\/p>\n","indepth":"<p>En visitant cet ancien village, vous ne manquerez pas de remarquer l&#8217;alternance de splendides demeures aristocratiques du XVIe si\u00e8cle, qui entourent de belles cours, tandis que votre regard se porte sur la majest\u00e9 des murs v\u00e9nitiens qui en marquent les limites.<\/p>\n<p><strong>Borgo Pignolo<\/strong> est \u00e9galement surnomm\u00e9 &#8220;Borgo del Sapere&#8221; (village du savoir) par les habitants de Bergame : en effet, la partie sup\u00e9rieure abrite aujourd&#8217;hui le si\u00e8ge du d\u00e9partement de litt\u00e9rature et de philosophie de l&#8217;universit\u00e9 de Bergame, le long des rues autrefois emprunt\u00e9es par d&#8217;illustres personnalit\u00e9s de Venise : d&#8217;\u00e9minents recteurs ou autorit\u00e9s municipales, qui traversaient le village pour se rendre dans la ville haute.<\/p>\n<p>Parmi les palais majestueux qui offrent une s\u00e9quence parfaite de la Renaissance et de l&#8217;art n\u00e9oclassique, l&#8217;un d&#8217;entre eux a appartenu plus tard \u00e0 la famille Tasso, dans laquelle le c\u00e9l\u00e8bre po\u00e8te Torquato \u00e9tait invit\u00e9 !<br \/>\nD&#8217;autres abritent d&#8217;incroyables fresques dans leurs vastes salles. <\/p>\n<p>En vous promenant dans les rues pav\u00e9es du Borgo, ne manquez pas d&#8217;entrer dans l&#8217;\u00e9glise de S. Bernardino, qui abrite un magnifique retable de Lorenzo Lotto, datant de 1521.<\/p>\n<p>Enfin, dans la Via Pignolo se trouve l&#8217;int\u00e9ressant mus\u00e9e Bernareggi, 20 salles consacr\u00e9es \u00e0 l&#8217;art sacr\u00e9 qui abritent, entre autres, des \u0153uvres de L. Lotto, G. B. Moroni et C. Ceresa.  <\/p>\n","iu_addr_streetnumber":"Via Pignolo","filotto_fill":"manual","filotto_items":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Fiche technique"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"iu_timetable":false,"poi_data":{"description":"<p><strong>Borgo Pignolo<\/strong> est situ\u00e9 entre Bergamo Alta et Bergamo Bassa.<\/p>\n<p>En remontant le Borgo par le bas, vous serez progressivement conduit vers la Porta Sant&#8217;Agostino, le long d&#8217;un itin\u00e9raire incroyablement \u00e9vocateur : \u00e0 la succession de demeures Renaissance et n\u00e9oclassiques s&#8217;ajoutent des ateliers d&#8217;artisans, dont celui d&#8217;un luthier de renomm\u00e9e internationale, et de nombreux restaurateurs.<br \/>\nLes demeures historiques comprennent \u00e9galement l&#8217;un des lieux les plus prestigieux de la ville, le merveilleux Palazzo Agliardi. <\/p>\n<p>La particularit\u00e9 de<strong> Borgo Pignolo<\/strong> est de permettre \u00e0 l&#8217;art ancien de rencontrer l&#8217;art contemporain, en op\u00e9rant cette petite magie dans la succession harmonieuse des galeries d&#8217;art et des magasins d&#8217;antiquit\u00e9s.<\/p>\n<p>Enfin, le parcours s&#8217;enrichit des nombreux petits \u00e9tablissements qui jalonnent la rue principale, la Via Pignolo.<br \/>\nSoudain, la merveilleuse succession de palais majestueux c\u00e8de la place \u00e0 une vue tout aussi spectaculaire : la Porta di Sant&#8217;Agostino, qui ouvre une br\u00e8che dans les murailles v\u00e9nitiennes, le Parco della Fara et l&#8217;incroyable panorama du paysage environnant.   <\/p>\n","indepth":"<p>En visitant cet ancien village, vous ne manquerez pas de remarquer l&#8217;alternance de splendides demeures aristocratiques du XVIe si\u00e8cle, qui entourent de belles cours, tandis que votre regard se porte sur la majest\u00e9 des murs v\u00e9nitiens qui en marquent les limites.<\/p>\n<p><strong>Borgo Pignolo<\/strong> est \u00e9galement surnomm\u00e9 &#8220;Borgo del Sapere&#8221; (village du savoir) par les habitants de Bergame : en effet, la partie sup\u00e9rieure abrite aujourd&#8217;hui le si\u00e8ge du d\u00e9partement de litt\u00e9rature et de philosophie de l&#8217;universit\u00e9 de Bergame, le long des rues autrefois emprunt\u00e9es par d&#8217;illustres personnalit\u00e9s de Venise : d&#8217;\u00e9minents recteurs ou autorit\u00e9s municipales, qui traversaient le village pour se rendre dans la ville haute.<\/p>\n<p>Parmi les palais majestueux qui offrent une s\u00e9quence parfaite de la Renaissance et de l&#8217;art n\u00e9oclassique, l&#8217;un d&#8217;entre eux a appartenu plus tard \u00e0 la famille Tasso, dans laquelle le c\u00e9l\u00e8bre po\u00e8te Torquato \u00e9tait invit\u00e9 !<br \/>\nD&#8217;autres abritent d&#8217;incroyables fresques dans leurs vastes salles. <\/p>\n<p>En vous promenant dans les rues pav\u00e9es du Borgo, ne manquez pas d&#8217;entrer dans l&#8217;\u00e9glise de S. Bernardino, qui abrite un magnifique retable de Lorenzo Lotto, datant de 1521.<\/p>\n<p>Enfin, dans la Via Pignolo se trouve l&#8217;int\u00e9ressant mus\u00e9e Bernareggi, 20 salles consacr\u00e9es \u00e0 l&#8217;art sacr\u00e9 qui abritent, entre autres, des \u0153uvres de L. Lotto, G. B. Moroni et C. Ceresa.  <\/p>\n","howtogetthere":"","price":"","time":"","latitude":"45.700747","longitude":"9.673895","id_visit_manza":"3010","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"Via Pignolo","iu_addr_postalcode":"","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":false},"size":"full","featured_video":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":"","modules":false,"hero_buttons":false,"iu_kids":false,"is_an_ambassador":false,"accessibilityicons":[]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/16506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/16506\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/7879"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=16506"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=16506"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=16506"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=16506"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=16506"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=16506"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=16506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}