{"id":16510,"date":"2024-05-08T11:05:03","date_gmt":"2024-05-08T09:05:03","guid":{"rendered":"https:\/\/visitstg2.visitbergamo.net\/oggetto\/bourg-canale\/"},"modified":"2025-02-16T09:20:16","modified_gmt":"2025-02-16T08:20:16","slug":"borgo-canale","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/borgo-canale\/","title":{"rendered":"Borgo Canale"},"excerpt":{"rendered":"<p>Le village le plus pittoresque et le plus relaxant de Bergame !<br \/>\nNe manquez pas les vues magnifiques qui s&#8217;offrent \u00e0 vous, mais n&#8217;oubliez pas non plus la ville natale de Donizetti ! <\/p>\n","protected":false},"author":3,"featured_media":7951,"template":"","categories":[152],"tags":[],"aggr":[],"area":[867],"kind":[18678],"zona":[18758],"class_list":["post-16510","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-ou-aller","area-bergamo","kind-poi-fr","zona-bergamo-fr"],"acf":{"filotto_title":"","filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":"scroll","filotto_fill":"manual","filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""}},"howtogetthere":"","timerange":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","time":"","latitude":"45.706538","longitude":"9.652143","startingprice":"","gpxmap":"","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_shortprice":"","iu_addr_postalcode":"","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","id_madeep":"","id_visit_manza":"3012","url":"","url_youtube":"","cta":{"style":"","text":"","icon":{"button_icon":"none"},"function":"","url":"","target":"","url_youtube":"","target_modal":""},"button_icon":"none","tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Fiche technique"},{"acf_fc_layout":"text","text":""}],"description":"<p>Sa situation la rend riche en points de vue.<br \/>\nD&#8217;un c\u00f4t\u00e9, vous pourrez profiter d&#8217;une vue \u00e0 perte de vue sur la plaine et de l&#8217;autre, d&#8217;une vue particuli\u00e8re sur la ville haute, o\u00f9 ses nombreuses tours, clochers et d\u00f4mes appara\u00eetront dans une succession \u00e0 vous couper le souffle. <\/p>\n<p>Ce coin de Bergame est une v\u00e9ritable petite oasis de paix et de romantisme o\u00f9 l&#8217;on peut s&#8217;arr\u00eater pour contempler la vue sans \u00eatre d\u00e9rang\u00e9 par la circulation et se promener dans les rues \u00e9troites et historiques.<\/p>\n<p>C&#8217;est dans l&#8217;une d&#8217;entre elles qu&#8217;est n\u00e9 le c\u00e9l\u00e8bre compositeur bergamasque Gaetano Donizetti.<\/p>\n","slides":[{"image":{"ID":7951,"id":7951,"title":"4fb72f4a2405457e854fe4111429e4dc_567ada5e.jpg","filename":"4fb72f4a2405457e854fe4111429e4dc_567ada5e.jpg","filesize":207969,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4fb72f4a2405457e854fe4111429e4dc_567ada5e.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/borgo-canale\/4fb72f4a2405457e854fe4111429e4dc_567ada5e-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4fb72f4a2405457e854fe4111429e4dc_567ada5e-jpg-2","status":"inherit","uploaded_to":16510,"date":"2024-05-08 08:45:26","modified":"2024-08-30 13:30:06","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":915,"height":528,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4fb72f4a2405457e854fe4111429e4dc_567ada5e-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4fb72f4a2405457e854fe4111429e4dc_567ada5e-300x173.jpg","medium-width":300,"medium-height":173,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4fb72f4a2405457e854fe4111429e4dc_567ada5e-768x443.jpg","medium_large-width":768,"medium_large-height":443,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4fb72f4a2405457e854fe4111429e4dc_567ada5e.jpg","large-width":915,"large-height":528,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4fb72f4a2405457e854fe4111429e4dc_567ada5e.jpg","1536x1536-width":915,"1536x1536-height":528,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4fb72f4a2405457e854fe4111429e4dc_567ada5e.jpg","2048x2048-width":915,"2048x2048-height":528,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4fb72f4a2405457e854fe4111429e4dc_567ada5e.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":173,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4fb72f4a2405457e854fe4111429e4dc_567ada5e.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":231,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2024\/05\/4fb72f4a2405457e854fe4111429e4dc_567ada5e.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":346}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"Borgo Canale","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":[{"style":"primary","text":"Contact","icon":{"button_icon":"none"},"function":"link","url":"","select_post":null,"target":"_blank","url_youtube":"","target_modal":""}],"filotto_layout":"scroll","hero_type":"images","hero_title":"Borgo Canale","hero_text":"<p>Le village le plus pittoresque et le plus relaxant de Bergame !<br \/>\nNe manquez pas les vues magnifiques qui s&#8217;offrent \u00e0 vous, mais n&#8217;oubliez pas non plus la ville natale de Donizetti ! <\/p>\n","indepth":"<p>Vous pourrez en effet y visiter la maison natale du musicien, mondialement connu pour ses compositions d&#8217;op\u00e9ra, aujourd&#8217;hui transform\u00e9e en un mus\u00e9e intimiste qui rassemble de nombreux t\u00e9moignages de cet illustre Bergamasque et vous plongera \u00e9galement dans la vie quotidienne d&#8217;une famille bourgeoise du XIXe si\u00e8cle.<\/p>\n<p>Le funiculaire date du m\u00eame si\u00e8cle !<br \/>\n\u00c0 la fin de la journ\u00e9e, nous vous recommandons de vous offrir un tour dans ce moyen de transport, qui se trouve \u00e0 l&#8217;entr\u00e9e de Borgo Canale et vous emm\u00e8ne sur la colline de San Vigilio.<br \/>\nVous pourrez y d\u00e9guster un ap\u00e9ritif, tandis que le panorama s&#8217;illumine de la chaude lumi\u00e8re du coucher du soleil et que Bergame s&#8217;illumine peu \u00e0 peu.  <\/p>\n","iu_addr_streetnumber":"Via Borgo Canale","filotto_fill":"manual","filotto_items":false,"accessibilitycontent":{"tcm_content":[{"acf_fc_layout":"title","title_tag":"h3","title_text":"Fiche technique"},{"acf_fc_layout":"text","text":""}]},"gallery":{"gallery_items":false},"iu_kids":false,"iu_timetable":false,"poi_data":{"description":"<p>Sa situation la rend riche en points de vue.<br \/>\nD&#8217;un c\u00f4t\u00e9, vous pourrez profiter d&#8217;une vue \u00e0 perte de vue sur la plaine et de l&#8217;autre, d&#8217;une vue particuli\u00e8re sur la ville haute, o\u00f9 ses nombreuses tours, clochers et d\u00f4mes appara\u00eetront dans une succession \u00e0 vous couper le souffle. <\/p>\n<p>Ce coin de Bergame est une v\u00e9ritable petite oasis de paix et de romantisme o\u00f9 l&#8217;on peut s&#8217;arr\u00eater pour contempler la vue sans \u00eatre d\u00e9rang\u00e9 par la circulation et se promener dans les rues \u00e9troites et historiques.<\/p>\n<p>C&#8217;est dans l&#8217;une d&#8217;entre elles qu&#8217;est n\u00e9 le c\u00e9l\u00e8bre compositeur bergamasque Gaetano Donizetti.<\/p>\n","indepth":"<p>Vous pourrez en effet y visiter la maison natale du musicien, mondialement connu pour ses compositions d&#8217;op\u00e9ra, aujourd&#8217;hui transform\u00e9e en un mus\u00e9e intimiste qui rassemble de nombreux t\u00e9moignages de cet illustre Bergamasque et vous plongera \u00e9galement dans la vie quotidienne d&#8217;une famille bourgeoise du XIXe si\u00e8cle.<\/p>\n<p>Le funiculaire date du m\u00eame si\u00e8cle !<br \/>\n\u00c0 la fin de la journ\u00e9e, nous vous recommandons de vous offrir un tour dans ce moyen de transport, qui se trouve \u00e0 l&#8217;entr\u00e9e de Borgo Canale et vous emm\u00e8ne sur la colline de San Vigilio.<br \/>\nVous pourrez y d\u00e9guster un ap\u00e9ritif, tandis que le panorama s&#8217;illumine de la chaude lumi\u00e8re du coucher du soleil et que Bergame s&#8217;illumine peu \u00e0 peu.  <\/p>\n","howtogetthere":"","price":"","time":"","latitude":"45.706538","longitude":"9.652143","id_visit_manza":"3012","iu_motor_accessibility":"no","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_addr_streetnumber":"Via Borgo Canale","iu_addr_postalcode":"","iu_addr_city":"Bergamo","iu_addr_province":"","iu_phone":"","iu_cell":"","iu_website":"","iu_email":"","iu_document_label":"","iu_document":false,"iu_timetable":false},"size":"full","featured_video":false,"is_an_ambassador":false,"filotto_sub":"","or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"order_by":"","order_way":"","filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":"0","show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":"","order_way":""},"style":"","text":"","icon":{"button_icon":"none"},"function":"","target":"","target_modal":"","iu_document_label":""},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/16510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/users\/3"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/16510\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/7951"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=16510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=16510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=16510"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=16510"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=16510"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=16510"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=16510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}