{"id":177600,"date":"2025-04-18T13:04:38","date_gmt":"2025-04-18T11:04:38","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/bb-san-francesco-class\/"},"modified":"2025-04-18T14:29:51","modified_gmt":"2025-04-18T12:29:51","slug":"bb-san-francesco-class","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bb-san-francesco-class\/","title":{"rendered":"B&#038;B SAN FRANCESCO CLASS"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":148715,"template":"","categories":[1000],"tags":[],"aggr":[],"area":[],"kind":[18724],"zona":[],"class_list":["post-177600","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sommeil","kind-strutturaricettiva-fr"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"B&B SAN FRANCESCO CLASS","hero_text":"<p class='normal'>Nouveau B&#038;B \u00e9l\u00e9gant, id\u00e9alement situ\u00e9 \u00e0 6 minutes \u00e0 pied du funiculaire et \u00e0 8 minutes \u00e0 pied de la station thermale QC Terme. Commerces \u00e0 proximit\u00e9 pour tous les besoins.<\/p>\n","slides":[{"image":{"ID":148715,"id":148715,"title":"f9277359b5ca34beae4bf82dd77d74f9_a3b096ef.jpg","filename":"f9277359b5ca34beae4bf82dd77d74f9_a3b096ef.jpg","filesize":559154,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bb-san-francesco-class\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"f9277359b5ca34beae4bf82dd77d74f9_a3b096ef-jpg-2","status":"inherit","uploaded_to":177600,"date":"2025-04-17 14:39:51","modified":"2025-04-18 12:29:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1152,"height":2048,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef-169x300.jpg","medium-width":169,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef-768x1365.jpg","medium_large-width":768,"medium_large-height":1365,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef-576x1024.jpg","large-width":576,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef-864x1536.jpg","1536x1536-width":864,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef.jpg","2048x2048-width":1152,"2048x2048-height":2048,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef.jpg","gform-image-choice-sm-width":169,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef.jpg","gform-image-choice-md-width":225,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f9277359b5ca34beae4bf82dd77d74f9_a3b096ef.jpg","gform-image-choice-lg-width":338,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148722,"id":148722,"title":"cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","filename":"cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","filesize":130289,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bb-san-francesco-class\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488-jpg-2","status":"inherit","uploaded_to":177600,"date":"2025-04-17 14:39:52","modified":"2025-04-18 12:29:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cd7b63e3d7fa1ba9bd23990450e4ec51_71d7d488.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148729,"id":148729,"title":"9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","filename":"9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","filesize":116686,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bb-san-francesco-class\/9acfcfbe54398a525299b4b24b588b22_d2244fd3-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"9acfcfbe54398a525299b4b24b588b22_d2244fd3-jpg-2","status":"inherit","uploaded_to":177600,"date":"2025-04-17 14:39:53","modified":"2025-04-18 12:29:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9acfcfbe54398a525299b4b24b588b22_d2244fd3.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148736,"id":148736,"title":"8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","filename":"8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","filesize":112218,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bb-san-francesco-class\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"8d9355bd02b7c311ad10fa9826f01158_7a985d3a-jpg-2","status":"inherit","uploaded_to":177600,"date":"2025-04-17 14:39:54","modified":"2025-04-18 12:29:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8d9355bd02b7c311ad10fa9826f01158_7a985d3a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148743,"id":148743,"title":"5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de.jpg","filename":"5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de.jpg","filesize":277737,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bb-san-francesco-class\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de-jpg-2","status":"inherit","uploaded_to":177600,"date":"2025-04-17 14:39:55","modified":"2025-04-18 12:29:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":900,"height":1600,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de-169x300.jpg","medium-width":169,"medium-height":300,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de-768x1365.jpg","medium_large-width":768,"medium_large-height":1365,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de-576x1024.jpg","large-width":576,"large-height":1024,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de-864x1536.jpg","1536x1536-width":864,"1536x1536-height":1536,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de.jpg","2048x2048-width":900,"2048x2048-height":1600,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de.jpg","gform-image-choice-sm-width":169,"gform-image-choice-sm-height":300,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de.jpg","gform-image-choice-md-width":225,"gform-image-choice-md-height":400,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5128ba3e18c0f0a98c3efceb2b05926f_42b1d9de.jpg","gform-image-choice-lg-width":338,"gform-image-choice-lg-height":600}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148750,"id":148750,"title":"3c78e9861a0a123e06217d69263d568d_45745c24.jpg","filename":"3c78e9861a0a123e06217d69263d568d_45745c24.jpg","filesize":139322,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bb-san-francesco-class\/3c78e9861a0a123e06217d69263d568d_45745c24-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3c78e9861a0a123e06217d69263d568d_45745c24-jpg-2","status":"inherit","uploaded_to":177600,"date":"2025-04-17 14:39:56","modified":"2025-04-18 12:29:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3c78e9861a0a123e06217d69263d568d_45745c24.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148757,"id":148757,"title":"c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","filename":"c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","filesize":200484,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bb-san-francesco-class\/c15af13143f5ea124fa282d477ea64ca_c71cecdc-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c15af13143f5ea124fa282d477ea64ca_c71cecdc-jpg-2","status":"inherit","uploaded_to":177600,"date":"2025-04-17 14:39:57","modified":"2025-04-18 12:29:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c15af13143f5ea124fa282d477ea64ca_c71cecdc.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148764,"id":148764,"title":"27f95e83868ef558f9172416bed60717_29080259.jpg","filename":"27f95e83868ef558f9172416bed60717_29080259.jpg","filesize":462973,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bb-san-francesco-class\/27f95e83868ef558f9172416bed60717_29080259-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"27f95e83868ef558f9172416bed60717_29080259-jpg-2","status":"inherit","uploaded_to":177600,"date":"2025-04-17 14:39:58","modified":"2025-04-18 12:29:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":942,"height":628,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259.jpg","large-width":942,"large-height":628,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259.jpg","1536x1536-width":942,"1536x1536-height":628,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259.jpg","2048x2048-width":942,"2048x2048-height":628,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/27f95e83868ef558f9172416bed60717_29080259.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148771,"id":148771,"title":"65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","filename":"65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","filesize":85949,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bb-san-francesco-class\/65dc678186e843de51a1cade5e09a93a_5b77e816-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"65dc678186e843de51a1cade5e09a93a_5b77e816-jpg-2","status":"inherit","uploaded_to":177600,"date":"2025-04-17 14:39:59","modified":"2025-04-18 12:29:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/65dc678186e843de51a1cade5e09a93a_5b77e816.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148778,"id":148778,"title":"063467b628d5723bee3c66434054386e_f3518747.jpg","filename":"063467b628d5723bee3c66434054386e_f3518747.jpg","filesize":259703,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bb-san-francesco-class\/063467b628d5723bee3c66434054386e_f3518747-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"063467b628d5723bee3c66434054386e_f3518747-jpg-2","status":"inherit","uploaded_to":177600,"date":"2025-04-17 14:39:59","modified":"2025-04-18 12:29:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":800,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747.jpg","1536x1536-width":1200,"1536x1536-height":800,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747.jpg","2048x2048-width":1200,"2048x2048-height":800,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/063467b628d5723bee3c66434054386e_f3518747.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":148785,"id":148785,"title":"dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","filename":"dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","filesize":156093,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bb-san-francesco-class\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b-jpg-2","status":"inherit","uploaded_to":177600,"date":"2025-04-17 14:40:00","modified":"2025-04-18 12:29:53","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1024,"height":768,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","1536x1536-width":1024,"1536x1536-height":768,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","2048x2048-width":1024,"2048x2048-height":768,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/dc7f6da1b1a32b83865f6f0a5eb93e6d_c861a12b.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Structure de deux chambres avec salle de bain priv\u00e9e, kit de bienvenue et de courtoisie, parking int\u00e9rieur pour motos et v\u00e9los, utilisation de la cuisine, TV, wifi, air conditionn\u00e9, petit d\u00e9jeuner, taxe de s\u00e9jour et nettoyage final inclus.<\/p>\n","indepth":"<p>B\u00e2timents historiques Art nouveau, source d&#8217;eau San Pellegrino mondialement connue, point de d\u00e9part de nombreuses randonn\u00e9es p\u00e9destres et cyclistes ; le casino et le Gran H\u00f4tel peuvent \u00eatre visit\u00e9s sur rendez-vous. Possibilit\u00e9 d&#8217;activit\u00e9s sportives telles que l&#8217;\u00e9quitation, le cano\u00eb, l&#8217;escalade, le tennis.<\/p>\n","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"<p>Chambre Arlequin : 128,00 \u20ac (possibilit\u00e9 d&#8217;un troisi\u00e8me lit 50,00 \u20ac)&#13;<br \/>\nChambre P\u00f2ta : 118,00 \u20ac (chambre double avec possibilit\u00e9 de s\u00e9parer les lits)<\/p>\n","services":"","parking":"<p>Parking gratuit ou payant devant l&#8217;\u00e9tablissement<\/p>\n","restaurant":"<p>Non pr\u00e9sent<\/p>\n","breakfast":"<p>Petit d\u00e9jeuner excellent et copieux<\/p>\n","internet":"<p>Wifi disponible<\/p>\n","children":"","pets":"<p>non admis<\/p>\n","latitude":"45.833123","longitude":"9.665365","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"B&B SAN FRANCESCO CLASS","registered_office":"MANNELLO ANDREA VIA MONTE ZUCCO 1 SAN PELLEGRINO TERME (BG)","iu_addr_streetnumber":"Via Monte Zucco, 1","iu_addr_postalcode":"24016","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"3402584538","iu_cell":"3402584538","iu_website":"http:\/\/www.bebsanfrancescoclass.it","iu_email":"sanfrancescobeb@gmail.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"2","iu_beds":"5","id_madeep":"","id_visit_manza":"10506","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","time":"<p>Check in ore 14:00\/16:00&#13;<br \/>\nCheck out ore 10:00&#13;<br \/>\nSolitamente sempre aperto, bisogna informarsi per\u00f2 sui periodi di chiusura obbligatori per legge.<\/p>\n","service_icons":[{"value":"laundry","label":"Lavanderia"},{"value":"tv_lounge","label":"Sala TV"},{"value":"tennis","label":"Tennis"},{"value":"wifi","label":"Wi-Fi"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"balcony","label":"Balcone"},{"value":"tv_room","label":"TV in camera"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"eurocard","label":"Eurocard \/ Mastercard"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177600\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/148715"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=177600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=177600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=177600"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=177600"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=177600"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=177600"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=177600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}