{"id":177747,"date":"2025-04-18T13:09:41","date_gmt":"2025-04-18T11:09:41","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/villa-sancelso\/"},"modified":"2025-04-18T14:35:21","modified_gmt":"2025-04-18T12:35:21","slug":"villa-sancelso","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/villa-sancelso\/","title":{"rendered":"Villa Sancelso"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":152774,"template":"","categories":[1000],"tags":[],"aggr":[],"area":[],"kind":[18724],"zona":[],"class_list":["post-177747","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sommeil","kind-strutturaricettiva-fr"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Villa Sancelso","hero_text":"<p>La <strong>Villa Sancelso<\/strong> est situ\u00e9e \u00e0 Castione della Presolana, un charmant village de la Val Seriana, \u00e0 900 m d&#8217;altitude, au pied du <strong>massif de la Presolana<\/strong> et du <strong>Monte Pora<\/strong>. La villa se trouve \u00e0 c\u00f4t\u00e9 du <strong>Parc R\u00e9gional des Orobie Bergamasques<\/strong>, un magnifique parc de montagne qui compte des sommets de plus de 3 000 m, de vastes vall\u00e9es et des for\u00eats.<\/p>\n<p>&#13;<\/p>\n<p>C&#8217;est la plus grande zone prot\u00e9g\u00e9e de haute naturalit\u00e9 de toute la Lombardie, un espace vert magnifique et de grand charme.<\/p>\n","slides":[{"image":{"ID":152774,"id":152774,"title":"0531d7924401f1a6e676a817a28a9446_486ac021.jpg","filename":"0531d7924401f1a6e676a817a28a9446_486ac021.jpg","filesize":822304,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0531d7924401f1a6e676a817a28a9446_486ac021.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/villa-sancelso\/0531d7924401f1a6e676a817a28a9446_486ac021-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"0531d7924401f1a6e676a817a28a9446_486ac021-jpg-2","status":"inherit","uploaded_to":177747,"date":"2025-04-17 14:55:53","modified":"2025-04-18 12:35:23","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1477,"height":984,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0531d7924401f1a6e676a817a28a9446_486ac021-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0531d7924401f1a6e676a817a28a9446_486ac021-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0531d7924401f1a6e676a817a28a9446_486ac021-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0531d7924401f1a6e676a817a28a9446_486ac021-1024x682.jpg","large-width":1024,"large-height":682,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0531d7924401f1a6e676a817a28a9446_486ac021.jpg","1536x1536-width":1477,"1536x1536-height":984,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0531d7924401f1a6e676a817a28a9446_486ac021.jpg","2048x2048-width":1477,"2048x2048-height":984,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0531d7924401f1a6e676a817a28a9446_486ac021.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0531d7924401f1a6e676a817a28a9446_486ac021.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0531d7924401f1a6e676a817a28a9446_486ac021.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152781,"id":152781,"title":"413c48441063d7eb5d0ebf86f78e4f71_847e865c.jpg","filename":"413c48441063d7eb5d0ebf86f78e4f71_847e865c.jpg","filesize":436800,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/413c48441063d7eb5d0ebf86f78e4f71_847e865c.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/villa-sancelso\/413c48441063d7eb5d0ebf86f78e4f71_847e865c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"413c48441063d7eb5d0ebf86f78e4f71_847e865c-jpg-2","status":"inherit","uploaded_to":177747,"date":"2025-04-17 14:55:54","modified":"2025-04-18 12:35:23","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1339,"height":893,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/413c48441063d7eb5d0ebf86f78e4f71_847e865c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/413c48441063d7eb5d0ebf86f78e4f71_847e865c-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/413c48441063d7eb5d0ebf86f78e4f71_847e865c-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/413c48441063d7eb5d0ebf86f78e4f71_847e865c-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/413c48441063d7eb5d0ebf86f78e4f71_847e865c.jpg","1536x1536-width":1339,"1536x1536-height":893,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/413c48441063d7eb5d0ebf86f78e4f71_847e865c.jpg","2048x2048-width":1339,"2048x2048-height":893,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/413c48441063d7eb5d0ebf86f78e4f71_847e865c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/413c48441063d7eb5d0ebf86f78e4f71_847e865c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/413c48441063d7eb5d0ebf86f78e4f71_847e865c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152788,"id":152788,"title":"ca285d1de3899ab008766b55228b5c41_55b0fc24.jpg","filename":"ca285d1de3899ab008766b55228b5c41_55b0fc24.jpg","filesize":445215,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca285d1de3899ab008766b55228b5c41_55b0fc24.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/villa-sancelso\/ca285d1de3899ab008766b55228b5c41_55b0fc24-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ca285d1de3899ab008766b55228b5c41_55b0fc24-jpg-2","status":"inherit","uploaded_to":177747,"date":"2025-04-17 14:55:55","modified":"2025-04-18 12:35:23","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1309,"height":873,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca285d1de3899ab008766b55228b5c41_55b0fc24-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca285d1de3899ab008766b55228b5c41_55b0fc24-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca285d1de3899ab008766b55228b5c41_55b0fc24-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca285d1de3899ab008766b55228b5c41_55b0fc24-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca285d1de3899ab008766b55228b5c41_55b0fc24.jpg","1536x1536-width":1309,"1536x1536-height":873,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca285d1de3899ab008766b55228b5c41_55b0fc24.jpg","2048x2048-width":1309,"2048x2048-height":873,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca285d1de3899ab008766b55228b5c41_55b0fc24.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca285d1de3899ab008766b55228b5c41_55b0fc24.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ca285d1de3899ab008766b55228b5c41_55b0fc24.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152795,"id":152795,"title":"df7228399106512e1f0cdf31398f13a5_f101b60f.jpg","filename":"df7228399106512e1f0cdf31398f13a5_f101b60f.jpg","filesize":503217,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/df7228399106512e1f0cdf31398f13a5_f101b60f.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/villa-sancelso\/df7228399106512e1f0cdf31398f13a5_f101b60f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"df7228399106512e1f0cdf31398f13a5_f101b60f-jpg-2","status":"inherit","uploaded_to":177747,"date":"2025-04-17 14:55:56","modified":"2025-04-18 12:35:23","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1697,"height":953,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/df7228399106512e1f0cdf31398f13a5_f101b60f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/df7228399106512e1f0cdf31398f13a5_f101b60f-300x168.jpg","medium-width":300,"medium-height":168,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/df7228399106512e1f0cdf31398f13a5_f101b60f-768x431.jpg","medium_large-width":768,"medium_large-height":431,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/df7228399106512e1f0cdf31398f13a5_f101b60f-1024x575.jpg","large-width":1024,"large-height":575,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/df7228399106512e1f0cdf31398f13a5_f101b60f-1536x863.jpg","1536x1536-width":1536,"1536x1536-height":863,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/df7228399106512e1f0cdf31398f13a5_f101b60f.jpg","2048x2048-width":1697,"2048x2048-height":953,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/df7228399106512e1f0cdf31398f13a5_f101b60f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":168,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/df7228399106512e1f0cdf31398f13a5_f101b60f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/df7228399106512e1f0cdf31398f13a5_f101b60f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152802,"id":152802,"title":"762abd6d63c36d7b06c89d07835f0dd1_3e2249a7.jpg","filename":"762abd6d63c36d7b06c89d07835f0dd1_3e2249a7.jpg","filesize":487631,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/762abd6d63c36d7b06c89d07835f0dd1_3e2249a7.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/villa-sancelso\/762abd6d63c36d7b06c89d07835f0dd1_3e2249a7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"762abd6d63c36d7b06c89d07835f0dd1_3e2249a7-jpg-2","status":"inherit","uploaded_to":177747,"date":"2025-04-17 14:55:58","modified":"2025-04-18 12:35:23","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1928,"height":1082,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/762abd6d63c36d7b06c89d07835f0dd1_3e2249a7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/762abd6d63c36d7b06c89d07835f0dd1_3e2249a7-300x168.jpg","medium-width":300,"medium-height":168,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/762abd6d63c36d7b06c89d07835f0dd1_3e2249a7-768x431.jpg","medium_large-width":768,"medium_large-height":431,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/762abd6d63c36d7b06c89d07835f0dd1_3e2249a7-1024x575.jpg","large-width":1024,"large-height":575,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/762abd6d63c36d7b06c89d07835f0dd1_3e2249a7-1536x862.jpg","1536x1536-width":1536,"1536x1536-height":862,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/762abd6d63c36d7b06c89d07835f0dd1_3e2249a7.jpg","2048x2048-width":1928,"2048x2048-height":1082,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/762abd6d63c36d7b06c89d07835f0dd1_3e2249a7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":168,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/762abd6d63c36d7b06c89d07835f0dd1_3e2249a7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":224,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/762abd6d63c36d7b06c89d07835f0dd1_3e2249a7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152809,"id":152809,"title":"37dd673d41021591300cf7218653e57c_4103e9c0.jpg","filename":"37dd673d41021591300cf7218653e57c_4103e9c0-scaled.jpg","filesize":241135,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37dd673d41021591300cf7218653e57c_4103e9c0-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/villa-sancelso\/37dd673d41021591300cf7218653e57c_4103e9c0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"37dd673d41021591300cf7218653e57c_4103e9c0-jpg-2","status":"inherit","uploaded_to":177747,"date":"2025-04-17 14:55:59","modified":"2025-04-18 12:35:23","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1439,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37dd673d41021591300cf7218653e57c_4103e9c0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37dd673d41021591300cf7218653e57c_4103e9c0-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37dd673d41021591300cf7218653e57c_4103e9c0-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37dd673d41021591300cf7218653e57c_4103e9c0-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37dd673d41021591300cf7218653e57c_4103e9c0-1536x863.jpg","1536x1536-width":1536,"1536x1536-height":863,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37dd673d41021591300cf7218653e57c_4103e9c0-2048x1151.jpg","2048x2048-width":2048,"2048x2048-height":1151,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37dd673d41021591300cf7218653e57c_4103e9c0-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":169,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37dd673d41021591300cf7218653e57c_4103e9c0-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37dd673d41021591300cf7218653e57c_4103e9c0-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152816,"id":152816,"title":"a4e5941957d9231f4f09de118401c320_b8b75997.jpg","filename":"a4e5941957d9231f4f09de118401c320_b8b75997.jpg","filesize":509900,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a4e5941957d9231f4f09de118401c320_b8b75997.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/villa-sancelso\/a4e5941957d9231f4f09de118401c320_b8b75997-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"a4e5941957d9231f4f09de118401c320_b8b75997-jpg-2","status":"inherit","uploaded_to":177747,"date":"2025-04-17 14:56:01","modified":"2025-04-18 12:35:23","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1642,"height":1232,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a4e5941957d9231f4f09de118401c320_b8b75997-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a4e5941957d9231f4f09de118401c320_b8b75997-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a4e5941957d9231f4f09de118401c320_b8b75997-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a4e5941957d9231f4f09de118401c320_b8b75997-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a4e5941957d9231f4f09de118401c320_b8b75997-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a4e5941957d9231f4f09de118401c320_b8b75997.jpg","2048x2048-width":1642,"2048x2048-height":1232,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a4e5941957d9231f4f09de118401c320_b8b75997.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a4e5941957d9231f4f09de118401c320_b8b75997.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/a4e5941957d9231f4f09de118401c320_b8b75997.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152823,"id":152823,"title":"2696b21f99af1bb2266a47ad72ae7ab5_c424cd61.jpg","filename":"2696b21f99af1bb2266a47ad72ae7ab5_c424cd61-scaled.jpg","filesize":302196,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2696b21f99af1bb2266a47ad72ae7ab5_c424cd61-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/villa-sancelso\/2696b21f99af1bb2266a47ad72ae7ab5_c424cd61-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"2696b21f99af1bb2266a47ad72ae7ab5_c424cd61-jpg-2","status":"inherit","uploaded_to":177747,"date":"2025-04-17 14:56:02","modified":"2025-04-18 12:35:23","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1437,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2696b21f99af1bb2266a47ad72ae7ab5_c424cd61-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2696b21f99af1bb2266a47ad72ae7ab5_c424cd61-300x168.jpg","medium-width":300,"medium-height":168,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2696b21f99af1bb2266a47ad72ae7ab5_c424cd61-768x431.jpg","medium_large-width":768,"medium_large-height":431,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2696b21f99af1bb2266a47ad72ae7ab5_c424cd61-1024x575.jpg","large-width":1024,"large-height":575,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2696b21f99af1bb2266a47ad72ae7ab5_c424cd61-1536x862.jpg","1536x1536-width":1536,"1536x1536-height":862,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2696b21f99af1bb2266a47ad72ae7ab5_c424cd61-2048x1150.jpg","2048x2048-width":2048,"2048x2048-height":1150,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2696b21f99af1bb2266a47ad72ae7ab5_c424cd61-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":168,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2696b21f99af1bb2266a47ad72ae7ab5_c424cd61-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":225,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2696b21f99af1bb2266a47ad72ae7ab5_c424cd61-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":337}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152830,"id":152830,"title":"d6905d6ce5158e2231ee1f848b63c918_b9d8a756.jpg","filename":"d6905d6ce5158e2231ee1f848b63c918_b9d8a756.jpg","filesize":500096,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d6905d6ce5158e2231ee1f848b63c918_b9d8a756.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/villa-sancelso\/d6905d6ce5158e2231ee1f848b63c918_b9d8a756-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d6905d6ce5158e2231ee1f848b63c918_b9d8a756-jpg-2","status":"inherit","uploaded_to":177747,"date":"2025-04-17 14:56:04","modified":"2025-04-18 12:35:23","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1296,"height":972,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d6905d6ce5158e2231ee1f848b63c918_b9d8a756-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d6905d6ce5158e2231ee1f848b63c918_b9d8a756-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d6905d6ce5158e2231ee1f848b63c918_b9d8a756-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d6905d6ce5158e2231ee1f848b63c918_b9d8a756-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d6905d6ce5158e2231ee1f848b63c918_b9d8a756.jpg","1536x1536-width":1296,"1536x1536-height":972,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d6905d6ce5158e2231ee1f848b63c918_b9d8a756.jpg","2048x2048-width":1296,"2048x2048-height":972,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d6905d6ce5158e2231ee1f848b63c918_b9d8a756.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d6905d6ce5158e2231ee1f848b63c918_b9d8a756.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d6905d6ce5158e2231ee1f848b63c918_b9d8a756.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152837,"id":152837,"title":"4e5874f568c65a43a50395fccc0925f9_f511481d.jpg","filename":"4e5874f568c65a43a50395fccc0925f9_f511481d.jpg","filesize":434820,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4e5874f568c65a43a50395fccc0925f9_f511481d.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/villa-sancelso\/4e5874f568c65a43a50395fccc0925f9_f511481d-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4e5874f568c65a43a50395fccc0925f9_f511481d-jpg-2","status":"inherit","uploaded_to":177747,"date":"2025-04-17 14:56:05","modified":"2025-04-18 12:35:23","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1302,"height":868,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4e5874f568c65a43a50395fccc0925f9_f511481d-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4e5874f568c65a43a50395fccc0925f9_f511481d-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4e5874f568c65a43a50395fccc0925f9_f511481d-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4e5874f568c65a43a50395fccc0925f9_f511481d-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4e5874f568c65a43a50395fccc0925f9_f511481d.jpg","1536x1536-width":1302,"1536x1536-height":868,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4e5874f568c65a43a50395fccc0925f9_f511481d.jpg","2048x2048-width":1302,"2048x2048-height":868,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4e5874f568c65a43a50395fccc0925f9_f511481d.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4e5874f568c65a43a50395fccc0925f9_f511481d.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4e5874f568c65a43a50395fccc0925f9_f511481d.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\nLa Villa Sancelso est ouverte toute l\u2019ann\u00e9e et pr\u00eate \u00e0 accueillir des groupes sportifs, familiaux, scolaires et universitaires ; elle est disponible pour des s\u00e9minaires et des conf\u00e9rences r\u00e9sidentielles, des groupes paroissiaux et des groupes d&#8217;autres confessions. L&#8217;\u00e9tablissement convient \u00e9galement aux cours de formation, de mise \u00e0 jour et aux MasterClasses \u00e0 des prix tr\u00e8s abordables.&#13;<br \/>\nLa formule que nous proposons est une location courte dur\u00e9e, en autogestion, avec possibilit\u00e9 de service traiteur sur demande.&#13;<br \/>\nSitu\u00e9e \u00e0 l&#8217;entr\u00e9e du village, elle b\u00e9n\u00e9ficie d&#8217;un emplacement paisible tout en \u00e9tant tr\u00e8s proche du centre, reli\u00e9 par un chemin pi\u00e9ton s\u00e9curis\u00e9 au milieu de la verdure. La Villa Sancelso est entour\u00e9e d&#8217;un parc priv\u00e9 de 14 000 m\u00b2, \u00e9quip\u00e9 pour diverses activit\u00e9s sportives.&#13;<br \/>\nLa Villa est facilement accessible depuis les principales villes du nord de l&#8217;Italie : elle se trouve \u00e0 90 km de Milan, 70 km de Brescia, seulement 40 km de la ville de Bergame et 45 km de l&#8217;a\u00e9roport international Caravaggio Orio al Serio (BG).&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n&#13;<br \/>\n\u00a0&#13;<br \/>\n&#13;<br \/>\n&#13;<\/p>\n","indepth":"<p>La Villa a \u00e9t\u00e9 construite en 1968, sur les plans du Dr Renato Asti, et con\u00e7ue pour offrir des semaines de ski et des s\u00e9jours d\u2019\u00e9t\u00e9 aux jeunes \u00e9tudiants de l\u2019Institut San Celso, \u00e0 Milan, dans un magnifique lieu proche de la ville, Castione della Presolana. La famille Asti, d\u00e9sormais \u00e0 sa quatri\u00e8me g\u00e9n\u00e9ration, a choisi de poursuivre cette philosophie et a \u00e9largi l\u2019hospitalit\u00e9 \u00e0 divers groupes, accueillant tous ceux qui souhaitent passer des vacances dans un endroit proche des grandes villes et en pleine nature.&#13;<br \/>\nCe qui impressionne dans la Villa, ce sont les espaces, qui permettent d\u2019accueillir confortablement de grands groupes dans un environnement \u00e9l\u00e9gant et confortable. Le hall d\u2019entr\u00e9e, le salon et la salle \u00e0 manger sont reli\u00e9s par des portes vitr\u00e9es, et ce choix architectural renforce cette impression de grandeur et de luminosit\u00e9.&#13;<br \/>\nCIN:IT016064B4NOFQPLCS<\/p>\n","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"<p>Dates et co\u00fbts:\u00a0https:\/\/www.villasancelso.it\/date-e-costi\/<\/p>\n","services":"","parking":"<p>Parking priv\u00e9 accessible aux bus, avec environ 40 places de stationnement et \u00e9ventuellement un espace vert pouvant \u00eatre utilis\u00e9 comme parking.<\/p>\n","restaurant":"","breakfast":"","internet":"","children":"","pets":"<p>Animaux accept\u00e9s<\/p>\n","latitude":"45.904872","longitude":"10.028997","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"Sancelso srl","registered_office":"Via Pinamonte da Vimercate, 6&#13;\n20121 - Milano (MI)","iu_addr_streetnumber":"Via Risorgimento, 42","iu_addr_postalcode":"24020","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 0346 60051","iu_cell":"+39 339 7504406","iu_website":"https:\/\/www.villasancelso.it","iu_email":"castione@sancelso.com","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"42","iu_beds":"135","id_madeep":"","id_visit_manza":"5420","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"time":"<p>La struttura \u00e8 accessibile dalle ore 17:00 del giorno d\u2019arrivo alle ore 10:00 del giorno di partenza.<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"disabled_access","label":"Accessibile disabili"},{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"elevator","label":"Ascensore"},{"value":"bar","label":"Bar"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"banquet_hall","label":"Sala banchetti"},{"value":"conference_hall","label":"Sala congressi"},{"value":"meeting_room","label":"Sala riunioni"},{"value":"wifi","label":"Wi-Fi"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"balcony","label":"Balcone"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177747\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/152774"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=177747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=177747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=177747"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=177747"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=177747"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=177747"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=177747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}