{"id":177748,"date":"2025-04-18T13:09:41","date_gmt":"2025-04-18T11:09:41","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/mammamia\/"},"modified":"2025-04-28T22:50:14","modified_gmt":"2025-04-28T20:50:14","slug":"mammamia","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/mammamia\/","title":{"rendered":"MammaMia"},"excerpt":{"rendered":"","protected":false},"author":48,"featured_media":152845,"template":"","categories":[1000],"tags":[],"aggr":[],"area":[],"kind":[18724],"zona":[],"class_list":["post-177748","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sommeil","kind-strutturaricettiva-fr"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"MammaMia","hero_text":"<p lang='fr-FR'>Id\u00e9alement situ\u00e9 le long de la Corsarola, la rue principale de la ville haute, \u00e0 proximit\u00e9 de l\u2019arr\u00eat de bus reliant Colle Aperto \u00e0 l&#8217;a\u00e9roport de Bergame, l&#8217;appartement MammaMia a tout pour vous charmer.<\/p>\n","slides":[{"image":{"ID":152845,"id":152845,"title":"d683115ee1e1487e38a6cfffb1b86984_3fc1d692.jpg","filename":"d683115ee1e1487e38a6cfffb1b86984_3fc1d692.jpg","filesize":550253,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d683115ee1e1487e38a6cfffb1b86984_3fc1d692.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/mammamia\/d683115ee1e1487e38a6cfffb1b86984_3fc1d692-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d683115ee1e1487e38a6cfffb1b86984_3fc1d692-jpg-2","status":"inherit","uploaded_to":177748,"date":"2025-04-17 14:56:09","modified":"2025-04-18 12:35:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d683115ee1e1487e38a6cfffb1b86984_3fc1d692-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d683115ee1e1487e38a6cfffb1b86984_3fc1d692-300x109.jpg","medium-width":300,"medium-height":109,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d683115ee1e1487e38a6cfffb1b86984_3fc1d692-768x278.jpg","medium_large-width":768,"medium_large-height":278,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d683115ee1e1487e38a6cfffb1b86984_3fc1d692-1024x371.jpg","large-width":1024,"large-height":371,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d683115ee1e1487e38a6cfffb1b86984_3fc1d692-1536x556.jpg","1536x1536-width":1536,"1536x1536-height":556,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d683115ee1e1487e38a6cfffb1b86984_3fc1d692.jpg","2048x2048-width":1560,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d683115ee1e1487e38a6cfffb1b86984_3fc1d692.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":109,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d683115ee1e1487e38a6cfffb1b86984_3fc1d692.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d683115ee1e1487e38a6cfffb1b86984_3fc1d692.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152852,"id":152852,"title":"23851176ec5539b846b26064f9e2e038_82da3ec5.jpg","filename":"23851176ec5539b846b26064f9e2e038_82da3ec5.jpg","filesize":416483,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23851176ec5539b846b26064f9e2e038_82da3ec5.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/mammamia\/23851176ec5539b846b26064f9e2e038_82da3ec5-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"23851176ec5539b846b26064f9e2e038_82da3ec5-jpg-2","status":"inherit","uploaded_to":177748,"date":"2025-04-17 14:56:10","modified":"2025-04-18 12:35:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23851176ec5539b846b26064f9e2e038_82da3ec5-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23851176ec5539b846b26064f9e2e038_82da3ec5-300x109.jpg","medium-width":300,"medium-height":109,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23851176ec5539b846b26064f9e2e038_82da3ec5-768x278.jpg","medium_large-width":768,"medium_large-height":278,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23851176ec5539b846b26064f9e2e038_82da3ec5-1024x371.jpg","large-width":1024,"large-height":371,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23851176ec5539b846b26064f9e2e038_82da3ec5-1536x556.jpg","1536x1536-width":1536,"1536x1536-height":556,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23851176ec5539b846b26064f9e2e038_82da3ec5.jpg","2048x2048-width":1560,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23851176ec5539b846b26064f9e2e038_82da3ec5.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":109,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23851176ec5539b846b26064f9e2e038_82da3ec5.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/23851176ec5539b846b26064f9e2e038_82da3ec5.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152859,"id":152859,"title":"570d1c2089f44302bf19f98971e66486_53fbe918.jpg","filename":"570d1c2089f44302bf19f98971e66486_53fbe918.jpg","filesize":339586,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/570d1c2089f44302bf19f98971e66486_53fbe918.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/mammamia\/570d1c2089f44302bf19f98971e66486_53fbe918-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"570d1c2089f44302bf19f98971e66486_53fbe918-jpg-2","status":"inherit","uploaded_to":177748,"date":"2025-04-17 14:56:11","modified":"2025-04-18 12:35:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/570d1c2089f44302bf19f98971e66486_53fbe918-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/570d1c2089f44302bf19f98971e66486_53fbe918-300x109.jpg","medium-width":300,"medium-height":109,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/570d1c2089f44302bf19f98971e66486_53fbe918-768x278.jpg","medium_large-width":768,"medium_large-height":278,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/570d1c2089f44302bf19f98971e66486_53fbe918-1024x371.jpg","large-width":1024,"large-height":371,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/570d1c2089f44302bf19f98971e66486_53fbe918-1536x556.jpg","1536x1536-width":1536,"1536x1536-height":556,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/570d1c2089f44302bf19f98971e66486_53fbe918.jpg","2048x2048-width":1560,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/570d1c2089f44302bf19f98971e66486_53fbe918.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":109,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/570d1c2089f44302bf19f98971e66486_53fbe918.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/570d1c2089f44302bf19f98971e66486_53fbe918.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152866,"id":152866,"title":"c2bcffde958e0fa7ec6597dd6135d75b_e2e2126c.jpg","filename":"c2bcffde958e0fa7ec6597dd6135d75b_e2e2126c.jpg","filesize":314822,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c2bcffde958e0fa7ec6597dd6135d75b_e2e2126c.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/mammamia\/c2bcffde958e0fa7ec6597dd6135d75b_e2e2126c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c2bcffde958e0fa7ec6597dd6135d75b_e2e2126c-jpg-2","status":"inherit","uploaded_to":177748,"date":"2025-04-17 14:56:12","modified":"2025-04-18 12:35:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c2bcffde958e0fa7ec6597dd6135d75b_e2e2126c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c2bcffde958e0fa7ec6597dd6135d75b_e2e2126c-300x109.jpg","medium-width":300,"medium-height":109,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c2bcffde958e0fa7ec6597dd6135d75b_e2e2126c-768x278.jpg","medium_large-width":768,"medium_large-height":278,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c2bcffde958e0fa7ec6597dd6135d75b_e2e2126c-1024x371.jpg","large-width":1024,"large-height":371,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c2bcffde958e0fa7ec6597dd6135d75b_e2e2126c-1536x556.jpg","1536x1536-width":1536,"1536x1536-height":556,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c2bcffde958e0fa7ec6597dd6135d75b_e2e2126c.jpg","2048x2048-width":1560,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c2bcffde958e0fa7ec6597dd6135d75b_e2e2126c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":109,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c2bcffde958e0fa7ec6597dd6135d75b_e2e2126c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c2bcffde958e0fa7ec6597dd6135d75b_e2e2126c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152873,"id":152873,"title":"9a1ef7c2104f8e95743b21e8d0d7b5b6_d43498ce.jpg","filename":"9a1ef7c2104f8e95743b21e8d0d7b5b6_d43498ce.jpg","filesize":320059,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a1ef7c2104f8e95743b21e8d0d7b5b6_d43498ce.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/mammamia\/9a1ef7c2104f8e95743b21e8d0d7b5b6_d43498ce-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"9a1ef7c2104f8e95743b21e8d0d7b5b6_d43498ce-jpg-2","status":"inherit","uploaded_to":177748,"date":"2025-04-17 14:56:13","modified":"2025-04-18 12:35:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a1ef7c2104f8e95743b21e8d0d7b5b6_d43498ce-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a1ef7c2104f8e95743b21e8d0d7b5b6_d43498ce-300x109.jpg","medium-width":300,"medium-height":109,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a1ef7c2104f8e95743b21e8d0d7b5b6_d43498ce-768x278.jpg","medium_large-width":768,"medium_large-height":278,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a1ef7c2104f8e95743b21e8d0d7b5b6_d43498ce-1024x371.jpg","large-width":1024,"large-height":371,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a1ef7c2104f8e95743b21e8d0d7b5b6_d43498ce-1536x556.jpg","1536x1536-width":1536,"1536x1536-height":556,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a1ef7c2104f8e95743b21e8d0d7b5b6_d43498ce.jpg","2048x2048-width":1560,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a1ef7c2104f8e95743b21e8d0d7b5b6_d43498ce.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":109,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a1ef7c2104f8e95743b21e8d0d7b5b6_d43498ce.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/9a1ef7c2104f8e95743b21e8d0d7b5b6_d43498ce.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152880,"id":152880,"title":"3f9352c551c4b94c27c18d1e53171d72_676c35bd.jpg","filename":"3f9352c551c4b94c27c18d1e53171d72_676c35bd.jpg","filesize":345497,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9352c551c4b94c27c18d1e53171d72_676c35bd.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/mammamia\/3f9352c551c4b94c27c18d1e53171d72_676c35bd-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"3f9352c551c4b94c27c18d1e53171d72_676c35bd-jpg-2","status":"inherit","uploaded_to":177748,"date":"2025-04-17 14:56:15","modified":"2025-04-18 12:35:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9352c551c4b94c27c18d1e53171d72_676c35bd-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9352c551c4b94c27c18d1e53171d72_676c35bd-300x109.jpg","medium-width":300,"medium-height":109,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9352c551c4b94c27c18d1e53171d72_676c35bd-768x278.jpg","medium_large-width":768,"medium_large-height":278,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9352c551c4b94c27c18d1e53171d72_676c35bd-1024x371.jpg","large-width":1024,"large-height":371,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9352c551c4b94c27c18d1e53171d72_676c35bd-1536x556.jpg","1536x1536-width":1536,"1536x1536-height":556,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9352c551c4b94c27c18d1e53171d72_676c35bd.jpg","2048x2048-width":1560,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9352c551c4b94c27c18d1e53171d72_676c35bd.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":109,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9352c551c4b94c27c18d1e53171d72_676c35bd.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/3f9352c551c4b94c27c18d1e53171d72_676c35bd.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152887,"id":152887,"title":"fec0cbcdb67eea483316dbdf0a2d11a8_530044ac.jpg","filename":"fec0cbcdb67eea483316dbdf0a2d11a8_530044ac.jpg","filesize":374856,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fec0cbcdb67eea483316dbdf0a2d11a8_530044ac.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/mammamia\/fec0cbcdb67eea483316dbdf0a2d11a8_530044ac-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"fec0cbcdb67eea483316dbdf0a2d11a8_530044ac-jpg-2","status":"inherit","uploaded_to":177748,"date":"2025-04-17 14:56:16","modified":"2025-04-18 12:35:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fec0cbcdb67eea483316dbdf0a2d11a8_530044ac-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fec0cbcdb67eea483316dbdf0a2d11a8_530044ac-300x109.jpg","medium-width":300,"medium-height":109,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fec0cbcdb67eea483316dbdf0a2d11a8_530044ac-768x278.jpg","medium_large-width":768,"medium_large-height":278,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fec0cbcdb67eea483316dbdf0a2d11a8_530044ac-1024x371.jpg","large-width":1024,"large-height":371,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fec0cbcdb67eea483316dbdf0a2d11a8_530044ac-1536x556.jpg","1536x1536-width":1536,"1536x1536-height":556,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fec0cbcdb67eea483316dbdf0a2d11a8_530044ac.jpg","2048x2048-width":1560,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fec0cbcdb67eea483316dbdf0a2d11a8_530044ac.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":109,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fec0cbcdb67eea483316dbdf0a2d11a8_530044ac.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fec0cbcdb67eea483316dbdf0a2d11a8_530044ac.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152894,"id":152894,"title":"0a24c1cd9c5f7c909ca07b613c2fcf00_715751e6.jpg","filename":"0a24c1cd9c5f7c909ca07b613c2fcf00_715751e6.jpg","filesize":383509,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a24c1cd9c5f7c909ca07b613c2fcf00_715751e6.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/mammamia\/0a24c1cd9c5f7c909ca07b613c2fcf00_715751e6-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"0a24c1cd9c5f7c909ca07b613c2fcf00_715751e6-jpg-2","status":"inherit","uploaded_to":177748,"date":"2025-04-17 14:56:17","modified":"2025-04-18 12:35:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a24c1cd9c5f7c909ca07b613c2fcf00_715751e6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a24c1cd9c5f7c909ca07b613c2fcf00_715751e6-300x109.jpg","medium-width":300,"medium-height":109,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a24c1cd9c5f7c909ca07b613c2fcf00_715751e6-768x278.jpg","medium_large-width":768,"medium_large-height":278,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a24c1cd9c5f7c909ca07b613c2fcf00_715751e6-1024x371.jpg","large-width":1024,"large-height":371,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a24c1cd9c5f7c909ca07b613c2fcf00_715751e6-1536x556.jpg","1536x1536-width":1536,"1536x1536-height":556,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a24c1cd9c5f7c909ca07b613c2fcf00_715751e6.jpg","2048x2048-width":1560,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a24c1cd9c5f7c909ca07b613c2fcf00_715751e6.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":109,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a24c1cd9c5f7c909ca07b613c2fcf00_715751e6.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0a24c1cd9c5f7c909ca07b613c2fcf00_715751e6.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152901,"id":152901,"title":"043f09fa7e3793a0722cc6cad042bceb_b117d675.jpg","filename":"043f09fa7e3793a0722cc6cad042bceb_b117d675.jpg","filesize":481843,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/043f09fa7e3793a0722cc6cad042bceb_b117d675.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/mammamia\/043f09fa7e3793a0722cc6cad042bceb_b117d675-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"043f09fa7e3793a0722cc6cad042bceb_b117d675-jpg-2","status":"inherit","uploaded_to":177748,"date":"2025-04-17 14:56:18","modified":"2025-04-18 12:35:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/043f09fa7e3793a0722cc6cad042bceb_b117d675-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/043f09fa7e3793a0722cc6cad042bceb_b117d675-300x109.jpg","medium-width":300,"medium-height":109,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/043f09fa7e3793a0722cc6cad042bceb_b117d675-768x278.jpg","medium_large-width":768,"medium_large-height":278,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/043f09fa7e3793a0722cc6cad042bceb_b117d675-1024x371.jpg","large-width":1024,"large-height":371,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/043f09fa7e3793a0722cc6cad042bceb_b117d675-1536x556.jpg","1536x1536-width":1536,"1536x1536-height":556,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/043f09fa7e3793a0722cc6cad042bceb_b117d675.jpg","2048x2048-width":1560,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/043f09fa7e3793a0722cc6cad042bceb_b117d675.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":109,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/043f09fa7e3793a0722cc6cad042bceb_b117d675.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/043f09fa7e3793a0722cc6cad042bceb_b117d675.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152908,"id":152908,"title":"fca765eb366dbd9822be32f5e14ec2a3_e1d6b2d8.jpg","filename":"fca765eb366dbd9822be32f5e14ec2a3_e1d6b2d8.jpg","filesize":411689,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fca765eb366dbd9822be32f5e14ec2a3_e1d6b2d8.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/mammamia\/fca765eb366dbd9822be32f5e14ec2a3_e1d6b2d8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"fca765eb366dbd9822be32f5e14ec2a3_e1d6b2d8-jpg-2","status":"inherit","uploaded_to":177748,"date":"2025-04-17 14:56:19","modified":"2025-04-18 12:35:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fca765eb366dbd9822be32f5e14ec2a3_e1d6b2d8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fca765eb366dbd9822be32f5e14ec2a3_e1d6b2d8-300x109.jpg","medium-width":300,"medium-height":109,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fca765eb366dbd9822be32f5e14ec2a3_e1d6b2d8-768x278.jpg","medium_large-width":768,"medium_large-height":278,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fca765eb366dbd9822be32f5e14ec2a3_e1d6b2d8-1024x371.jpg","large-width":1024,"large-height":371,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fca765eb366dbd9822be32f5e14ec2a3_e1d6b2d8-1536x556.jpg","1536x1536-width":1536,"1536x1536-height":556,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fca765eb366dbd9822be32f5e14ec2a3_e1d6b2d8.jpg","2048x2048-width":1560,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fca765eb366dbd9822be32f5e14ec2a3_e1d6b2d8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":109,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fca765eb366dbd9822be32f5e14ec2a3_e1d6b2d8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/fca765eb366dbd9822be32f5e14ec2a3_e1d6b2d8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152929,"id":152929,"title":"faa3ce109a054111e52848e308d9675a_e2792e16","filename":"faa3ce109a054111e52848e308d9675a_e2792e16.jpg","filesize":391185,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faa3ce109a054111e52848e308d9675a_e2792e16.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/mammamia\/faa3ce109a054111e52848e308d9675a_e2792e16-2-2\/","alt":"","author":"0","description":"","caption":"","name":"faa3ce109a054111e52848e308d9675a_e2792e16-2-2","status":"inherit","uploaded_to":177748,"date":"2025-04-17 14:56:23","modified":"2025-04-18 12:35:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faa3ce109a054111e52848e308d9675a_e2792e16-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faa3ce109a054111e52848e308d9675a_e2792e16-300x109.jpg","medium-width":300,"medium-height":109,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faa3ce109a054111e52848e308d9675a_e2792e16-768x278.jpg","medium_large-width":768,"medium_large-height":278,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faa3ce109a054111e52848e308d9675a_e2792e16-1024x371.jpg","large-width":1024,"large-height":371,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faa3ce109a054111e52848e308d9675a_e2792e16-1536x556.jpg","1536x1536-width":1536,"1536x1536-height":556,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faa3ce109a054111e52848e308d9675a_e2792e16.jpg","2048x2048-width":1560,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faa3ce109a054111e52848e308d9675a_e2792e16.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":109,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faa3ce109a054111e52848e308d9675a_e2792e16.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/faa3ce109a054111e52848e308d9675a_e2792e16.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152915,"id":152915,"title":"277cf770eeb4dd6e89dd01947aff1f6a_cc1ea049.jpg","filename":"277cf770eeb4dd6e89dd01947aff1f6a_cc1ea049.jpg","filesize":264226,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/277cf770eeb4dd6e89dd01947aff1f6a_cc1ea049.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/mammamia\/277cf770eeb4dd6e89dd01947aff1f6a_cc1ea049-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"277cf770eeb4dd6e89dd01947aff1f6a_cc1ea049-jpg-2","status":"inherit","uploaded_to":177748,"date":"2025-04-17 14:56:21","modified":"2025-04-18 12:35:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/277cf770eeb4dd6e89dd01947aff1f6a_cc1ea049-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/277cf770eeb4dd6e89dd01947aff1f6a_cc1ea049-300x109.jpg","medium-width":300,"medium-height":109,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/277cf770eeb4dd6e89dd01947aff1f6a_cc1ea049-768x278.jpg","medium_large-width":768,"medium_large-height":278,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/277cf770eeb4dd6e89dd01947aff1f6a_cc1ea049-1024x371.jpg","large-width":1024,"large-height":371,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/277cf770eeb4dd6e89dd01947aff1f6a_cc1ea049-1536x556.jpg","1536x1536-width":1536,"1536x1536-height":556,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/277cf770eeb4dd6e89dd01947aff1f6a_cc1ea049.jpg","2048x2048-width":1560,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/277cf770eeb4dd6e89dd01947aff1f6a_cc1ea049.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":109,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/277cf770eeb4dd6e89dd01947aff1f6a_cc1ea049.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/277cf770eeb4dd6e89dd01947aff1f6a_cc1ea049.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":152922,"id":152922,"title":"339d0f5c527b4ca71a13e4db8845d4a5_9c4e5aa9.jpg","filename":"339d0f5c527b4ca71a13e4db8845d4a5_9c4e5aa9.jpg","filesize":415598,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/339d0f5c527b4ca71a13e4db8845d4a5_9c4e5aa9.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/mammamia\/339d0f5c527b4ca71a13e4db8845d4a5_9c4e5aa9-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"339d0f5c527b4ca71a13e4db8845d4a5_9c4e5aa9-jpg-2","status":"inherit","uploaded_to":177748,"date":"2025-04-17 14:56:22","modified":"2025-04-18 12:35:28","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1560,"height":565,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/339d0f5c527b4ca71a13e4db8845d4a5_9c4e5aa9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/339d0f5c527b4ca71a13e4db8845d4a5_9c4e5aa9-300x109.jpg","medium-width":300,"medium-height":109,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/339d0f5c527b4ca71a13e4db8845d4a5_9c4e5aa9-768x278.jpg","medium_large-width":768,"medium_large-height":278,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/339d0f5c527b4ca71a13e4db8845d4a5_9c4e5aa9-1024x371.jpg","large-width":1024,"large-height":371,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/339d0f5c527b4ca71a13e4db8845d4a5_9c4e5aa9-1536x556.jpg","1536x1536-width":1536,"1536x1536-height":556,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/339d0f5c527b4ca71a13e4db8845d4a5_9c4e5aa9.jpg","2048x2048-width":1560,"2048x2048-height":565,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/339d0f5c527b4ca71a13e4db8845d4a5_9c4e5aa9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":109,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/339d0f5c527b4ca71a13e4db8845d4a5_9c4e5aa9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":145,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/339d0f5c527b4ca71a13e4db8845d4a5_9c4e5aa9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":217}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>MammaMia se trouve dans la rue principale du centre ancien de la ville haute, \u00e0 deux pas de la magnifique Piazza Vecchia.&#13;<br \/>\nIl se compose de deux chambres\u00a0: une parentale et une double, avec possibilit\u00e9 d&#8217;ajouter un cinqui\u00e8me lit.&#13;<br \/>\nIl est dot\u00e9 d&#8217;un bureaux pour travailler, une table pour les repas et un canap\u00e9 pour passer un s\u00e9jour tous conforts. Le t\u00e9l\u00e9viseur avec USB et le Wifi haut d\u00e9bit compl\u00e8tent l&#8217;offre de l&#8217;appartement.&#13;<br \/>\nLa salle de bain est dot\u00e9e d&#8217;une petite v\u00e9randa avec vue sur les cours int\u00e9rieurs des demeures et les toits de la ville haute.Cuisine enti\u00e8rement \u00e9quip\u00e9e.\u00c0 disposition des h\u00f4tes\u00a0: caf\u00e9, th\u00e9, lait, confiture, miel, biscuits et viennoiseries. Pour vos caf\u00e9s, vous pourrez choisir entre la machine \u00e0 dosettes ou la cafeti\u00e8re italienne traditionnelle \u00e0 savoir la moka. Une bouilloire est \u00e9galement pr\u00e9sente pour vos th\u00e9s et infusions.&#13;<br \/>\nLe linge de chambre est inclus, ainsi que les produits d\u2019hygi\u00e8ne de la salle de bain.&#13;<br \/>\nIl est interdit de fumer dans tout l&#8217;appartement.&#13;<br \/>\nUne attention toute particuli\u00e8re est port\u00e9e \u00e0 l&#8217;accueil des h\u00f4tes et \u00e0 la propret\u00e9 de la structure, pour garantir un parfait s\u00e9jour.<\/p>\n","indepth":"","howtogetthere":"<p>L&#8217;entr\u00e9e se trouve en face de l&#8217;\u00e9glise du Carmine, \u00e0 c\u00f4t\u00e9 de la Latteria di zia Manu.<\/p>\n","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"<p>\u00c0 partir de 120\u00a0\u20ac pour deux personnes.&#13;<br \/>\nHors taxe de s\u00e9jour (2,50\u00a0\u20ac)&#13;<br \/>\nR\u00e9servation d&#8217;une seule nuit accept\u00e9e.<\/p>\n","services":"<p>M\u00e9nage 30\u00a0\u20ac\/s\u00e9jour<\/p>\n","parking":"<p>La structure se trouve \u00e0 l&#8217;int\u00e9rieure de la zone pi\u00e9tonne.&#13;<br \/>\nPour acc\u00e9der et se garer, il est n\u00e9cessaire de communiquer la plaque d&#8217;immatriculation.<\/p>\n","restaurant":"<p>Cuisine enti\u00e8rement \u00e9quip\u00e9e.<\/p>\n","breakfast":"<p>Petit d\u00e9jeuner inclus\u00a0: caf\u00e9, th\u00e9, lait, biscuits, biscottes, miel, confiture et viennoiseries.<\/p>\n","internet":"<p>Le Wifi haut d\u00e9bit est inclus.<\/p>\n","children":"<p>L&#8217;agencement de l&#8217;appartement convient aux enfants de plus de trois ans.<\/p>\n","pets":"<p>Animaux accept\u00e9s.<\/p>\n","latitude":"45.705230","longitude":"9.660370","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"Renata Amigoni","registered_office":"Via San Giacomo, 14 - 24129 - BERGAMO","iu_addr_streetnumber":"Via Bartolomeo Colleoni, 38","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 035 224333","iu_cell":"+39 348 8553363","iu_website":"http:\/\/www.mammamiahome.it","iu_email":"renami@mac.com","iu_vat":"02009280161","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"1","iu_beds":"5","id_madeep":"","id_visit_manza":"7724","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","time":"<p>Check-in dalle 15:00 alle 20:00&#13;<br \/>\nCheck-out entro le 11:00&#13;<br \/>\nPrevio accordo siamo flessibili su un piccolo spostamento di orario.&#13;<br \/>\nVi preghiamo di comunicare l&#8217;orario di arrivo il giorno prima.<\/p>\n","service_icons":[{"value":"laundry","label":"Lavanderia"},{"value":"tv_lounge","label":"Sala TV"},{"value":"wifi","label":"Wi-Fi"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"balcony","label":"Balcone"},{"value":"mini_bar","label":"Frigo bar"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"author":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/users\/48"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177748\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/152845"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=177748"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=177748"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=177748"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=177748"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=177748"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=177748"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=177748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}