{"id":177781,"date":"2025-04-18T13:11:04","date_gmt":"2025-04-18T11:11:04","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/bergamo-alta-suite\/"},"modified":"2025-04-18T14:36:47","modified_gmt":"2025-04-18T12:36:47","slug":"bergamo-alta-suite","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bergamo-alta-suite\/","title":{"rendered":"Bergamo Alta Suite"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":153536,"template":"","categories":[1000],"tags":[],"aggr":[],"area":[],"kind":[18724],"zona":[],"class_list":["post-177781","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sommeil","kind-strutturaricettiva-fr"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"Bergamo Alta Suite","hero_text":"","slides":[{"image":{"ID":153536,"id":153536,"title":"0f96b45fddc989f7f573b26fcf86e7f8_e1f17cc4.jpg","filename":"0f96b45fddc989f7f573b26fcf86e7f8_e1f17cc4.jpg","filesize":188204,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f96b45fddc989f7f573b26fcf86e7f8_e1f17cc4.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bergamo-alta-suite\/0f96b45fddc989f7f573b26fcf86e7f8_e1f17cc4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"0f96b45fddc989f7f573b26fcf86e7f8_e1f17cc4-jpg-2","status":"inherit","uploaded_to":177781,"date":"2025-04-17 14:59:10","modified":"2025-04-18 12:36:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1399,"height":930,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f96b45fddc989f7f573b26fcf86e7f8_e1f17cc4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f96b45fddc989f7f573b26fcf86e7f8_e1f17cc4-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f96b45fddc989f7f573b26fcf86e7f8_e1f17cc4-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f96b45fddc989f7f573b26fcf86e7f8_e1f17cc4-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f96b45fddc989f7f573b26fcf86e7f8_e1f17cc4.jpg","1536x1536-width":1399,"1536x1536-height":930,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f96b45fddc989f7f573b26fcf86e7f8_e1f17cc4.jpg","2048x2048-width":1399,"2048x2048-height":930,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f96b45fddc989f7f573b26fcf86e7f8_e1f17cc4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f96b45fddc989f7f573b26fcf86e7f8_e1f17cc4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/0f96b45fddc989f7f573b26fcf86e7f8_e1f17cc4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153543,"id":153543,"title":"8fd4bfb58f36ddb7ce3e68b677e138b3_3eefd3bc.jpg","filename":"8fd4bfb58f36ddb7ce3e68b677e138b3_3eefd3bc.jpg","filesize":174104,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fd4bfb58f36ddb7ce3e68b677e138b3_3eefd3bc.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bergamo-alta-suite\/8fd4bfb58f36ddb7ce3e68b677e138b3_3eefd3bc-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"8fd4bfb58f36ddb7ce3e68b677e138b3_3eefd3bc-jpg-2","status":"inherit","uploaded_to":177781,"date":"2025-04-17 14:59:11","modified":"2025-04-18 12:36:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1246,"height":930,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fd4bfb58f36ddb7ce3e68b677e138b3_3eefd3bc-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fd4bfb58f36ddb7ce3e68b677e138b3_3eefd3bc-300x224.jpg","medium-width":300,"medium-height":224,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fd4bfb58f36ddb7ce3e68b677e138b3_3eefd3bc-768x573.jpg","medium_large-width":768,"medium_large-height":573,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fd4bfb58f36ddb7ce3e68b677e138b3_3eefd3bc-1024x764.jpg","large-width":1024,"large-height":764,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fd4bfb58f36ddb7ce3e68b677e138b3_3eefd3bc.jpg","1536x1536-width":1246,"1536x1536-height":930,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fd4bfb58f36ddb7ce3e68b677e138b3_3eefd3bc.jpg","2048x2048-width":1246,"2048x2048-height":930,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fd4bfb58f36ddb7ce3e68b677e138b3_3eefd3bc.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":224,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fd4bfb58f36ddb7ce3e68b677e138b3_3eefd3bc.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":299,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/8fd4bfb58f36ddb7ce3e68b677e138b3_3eefd3bc.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":448}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153550,"id":153550,"title":"37aa9ab97dacadbaae50c4a0967f847a_2cf962f4.jpg","filename":"37aa9ab97dacadbaae50c4a0967f847a_2cf962f4.jpg","filesize":179323,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37aa9ab97dacadbaae50c4a0967f847a_2cf962f4.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bergamo-alta-suite\/37aa9ab97dacadbaae50c4a0967f847a_2cf962f4-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"37aa9ab97dacadbaae50c4a0967f847a_2cf962f4-jpg-2","status":"inherit","uploaded_to":177781,"date":"2025-04-17 14:59:12","modified":"2025-04-18 12:36:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1246,"height":930,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37aa9ab97dacadbaae50c4a0967f847a_2cf962f4-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37aa9ab97dacadbaae50c4a0967f847a_2cf962f4-300x224.jpg","medium-width":300,"medium-height":224,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37aa9ab97dacadbaae50c4a0967f847a_2cf962f4-768x573.jpg","medium_large-width":768,"medium_large-height":573,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37aa9ab97dacadbaae50c4a0967f847a_2cf962f4-1024x764.jpg","large-width":1024,"large-height":764,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37aa9ab97dacadbaae50c4a0967f847a_2cf962f4.jpg","1536x1536-width":1246,"1536x1536-height":930,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37aa9ab97dacadbaae50c4a0967f847a_2cf962f4.jpg","2048x2048-width":1246,"2048x2048-height":930,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37aa9ab97dacadbaae50c4a0967f847a_2cf962f4.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":224,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37aa9ab97dacadbaae50c4a0967f847a_2cf962f4.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":299,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/37aa9ab97dacadbaae50c4a0967f847a_2cf962f4.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":448}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153557,"id":153557,"title":"26add2fa1ce02997a16033961cafa663_7aea0808.jpg","filename":"26add2fa1ce02997a16033961cafa663_7aea0808.jpg","filesize":171956,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/26add2fa1ce02997a16033961cafa663_7aea0808.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bergamo-alta-suite\/26add2fa1ce02997a16033961cafa663_7aea0808-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"26add2fa1ce02997a16033961cafa663_7aea0808-jpg-2","status":"inherit","uploaded_to":177781,"date":"2025-04-17 14:59:13","modified":"2025-04-18 12:36:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1399,"height":930,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/26add2fa1ce02997a16033961cafa663_7aea0808-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/26add2fa1ce02997a16033961cafa663_7aea0808-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/26add2fa1ce02997a16033961cafa663_7aea0808-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/26add2fa1ce02997a16033961cafa663_7aea0808-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/26add2fa1ce02997a16033961cafa663_7aea0808.jpg","1536x1536-width":1399,"1536x1536-height":930,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/26add2fa1ce02997a16033961cafa663_7aea0808.jpg","2048x2048-width":1399,"2048x2048-height":930,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/26add2fa1ce02997a16033961cafa663_7aea0808.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/26add2fa1ce02997a16033961cafa663_7aea0808.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/26add2fa1ce02997a16033961cafa663_7aea0808.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153564,"id":153564,"title":"42a45537ee34ad3076855d1ebff3e0a9_c3946f42.jpg","filename":"42a45537ee34ad3076855d1ebff3e0a9_c3946f42.jpg","filesize":183774,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42a45537ee34ad3076855d1ebff3e0a9_c3946f42.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bergamo-alta-suite\/42a45537ee34ad3076855d1ebff3e0a9_c3946f42-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"42a45537ee34ad3076855d1ebff3e0a9_c3946f42-jpg-2","status":"inherit","uploaded_to":177781,"date":"2025-04-17 14:59:14","modified":"2025-04-18 12:36:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1399,"height":930,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42a45537ee34ad3076855d1ebff3e0a9_c3946f42-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42a45537ee34ad3076855d1ebff3e0a9_c3946f42-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42a45537ee34ad3076855d1ebff3e0a9_c3946f42-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42a45537ee34ad3076855d1ebff3e0a9_c3946f42-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42a45537ee34ad3076855d1ebff3e0a9_c3946f42.jpg","1536x1536-width":1399,"1536x1536-height":930,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42a45537ee34ad3076855d1ebff3e0a9_c3946f42.jpg","2048x2048-width":1399,"2048x2048-height":930,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42a45537ee34ad3076855d1ebff3e0a9_c3946f42.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42a45537ee34ad3076855d1ebff3e0a9_c3946f42.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/42a45537ee34ad3076855d1ebff3e0a9_c3946f42.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153571,"id":153571,"title":"633465617464b06cd025813d8708d5af_c3946f42.jpg","filename":"633465617464b06cd025813d8708d5af_c3946f42.jpg","filesize":183774,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/633465617464b06cd025813d8708d5af_c3946f42.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bergamo-alta-suite\/633465617464b06cd025813d8708d5af_c3946f42-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"633465617464b06cd025813d8708d5af_c3946f42-jpg-2","status":"inherit","uploaded_to":177781,"date":"2025-04-17 14:59:15","modified":"2025-04-18 12:36:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1399,"height":930,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/633465617464b06cd025813d8708d5af_c3946f42-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/633465617464b06cd025813d8708d5af_c3946f42-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/633465617464b06cd025813d8708d5af_c3946f42-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/633465617464b06cd025813d8708d5af_c3946f42-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/633465617464b06cd025813d8708d5af_c3946f42.jpg","1536x1536-width":1399,"1536x1536-height":930,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/633465617464b06cd025813d8708d5af_c3946f42.jpg","2048x2048-width":1399,"2048x2048-height":930,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/633465617464b06cd025813d8708d5af_c3946f42.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/633465617464b06cd025813d8708d5af_c3946f42.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/633465617464b06cd025813d8708d5af_c3946f42.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153578,"id":153578,"title":"6a311e1d9b7da50f82dae1a5d2440e3f_eae96f57.jpg","filename":"6a311e1d9b7da50f82dae1a5d2440e3f_eae96f57.jpg","filesize":233436,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6a311e1d9b7da50f82dae1a5d2440e3f_eae96f57.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bergamo-alta-suite\/6a311e1d9b7da50f82dae1a5d2440e3f_eae96f57-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"6a311e1d9b7da50f82dae1a5d2440e3f_eae96f57-jpg-2","status":"inherit","uploaded_to":177781,"date":"2025-04-17 14:59:16","modified":"2025-04-18 12:36:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1399,"height":930,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6a311e1d9b7da50f82dae1a5d2440e3f_eae96f57-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6a311e1d9b7da50f82dae1a5d2440e3f_eae96f57-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6a311e1d9b7da50f82dae1a5d2440e3f_eae96f57-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6a311e1d9b7da50f82dae1a5d2440e3f_eae96f57-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6a311e1d9b7da50f82dae1a5d2440e3f_eae96f57.jpg","1536x1536-width":1399,"1536x1536-height":930,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6a311e1d9b7da50f82dae1a5d2440e3f_eae96f57.jpg","2048x2048-width":1399,"2048x2048-height":930,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6a311e1d9b7da50f82dae1a5d2440e3f_eae96f57.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6a311e1d9b7da50f82dae1a5d2440e3f_eae96f57.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/6a311e1d9b7da50f82dae1a5d2440e3f_eae96f57.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153585,"id":153585,"title":"b9740899811d07ba108e569aff78f5c2_382e5f29.jpg","filename":"b9740899811d07ba108e569aff78f5c2_382e5f29.jpg","filesize":276342,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9740899811d07ba108e569aff78f5c2_382e5f29.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bergamo-alta-suite\/b9740899811d07ba108e569aff78f5c2_382e5f29-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"b9740899811d07ba108e569aff78f5c2_382e5f29-jpg-2","status":"inherit","uploaded_to":177781,"date":"2025-04-17 14:59:17","modified":"2025-04-18 12:36:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1399,"height":930,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9740899811d07ba108e569aff78f5c2_382e5f29-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9740899811d07ba108e569aff78f5c2_382e5f29-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9740899811d07ba108e569aff78f5c2_382e5f29-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9740899811d07ba108e569aff78f5c2_382e5f29-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9740899811d07ba108e569aff78f5c2_382e5f29.jpg","1536x1536-width":1399,"1536x1536-height":930,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9740899811d07ba108e569aff78f5c2_382e5f29.jpg","2048x2048-width":1399,"2048x2048-height":930,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9740899811d07ba108e569aff78f5c2_382e5f29.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9740899811d07ba108e569aff78f5c2_382e5f29.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b9740899811d07ba108e569aff78f5c2_382e5f29.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153592,"id":153592,"title":"c5b5736605a5245db15f9309d43ad5d2_c0801ec1.jpg","filename":"c5b5736605a5245db15f9309d43ad5d2_c0801ec1.jpg","filesize":165417,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5b5736605a5245db15f9309d43ad5d2_c0801ec1.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bergamo-alta-suite\/c5b5736605a5245db15f9309d43ad5d2_c0801ec1-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c5b5736605a5245db15f9309d43ad5d2_c0801ec1-jpg-2","status":"inherit","uploaded_to":177781,"date":"2025-04-17 14:59:18","modified":"2025-04-18 12:36:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1399,"height":930,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5b5736605a5245db15f9309d43ad5d2_c0801ec1-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5b5736605a5245db15f9309d43ad5d2_c0801ec1-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5b5736605a5245db15f9309d43ad5d2_c0801ec1-768x511.jpg","medium_large-width":768,"medium_large-height":511,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5b5736605a5245db15f9309d43ad5d2_c0801ec1-1024x681.jpg","large-width":1024,"large-height":681,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5b5736605a5245db15f9309d43ad5d2_c0801ec1.jpg","1536x1536-width":1399,"1536x1536-height":930,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5b5736605a5245db15f9309d43ad5d2_c0801ec1.jpg","2048x2048-width":1399,"2048x2048-height":930,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5b5736605a5245db15f9309d43ad5d2_c0801ec1.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5b5736605a5245db15f9309d43ad5d2_c0801ec1.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c5b5736605a5245db15f9309d43ad5d2_c0801ec1.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153599,"id":153599,"title":"e6e38cf5475c501bfd99a48743229ee9_2209f2b9.jpg","filename":"e6e38cf5475c501bfd99a48743229ee9_2209f2b9.jpg","filesize":203564,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6e38cf5475c501bfd99a48743229ee9_2209f2b9.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bergamo-alta-suite\/e6e38cf5475c501bfd99a48743229ee9_2209f2b9-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e6e38cf5475c501bfd99a48743229ee9_2209f2b9-jpg-2","status":"inherit","uploaded_to":177781,"date":"2025-04-17 14:59:19","modified":"2025-04-18 12:36:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":797,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6e38cf5475c501bfd99a48743229ee9_2209f2b9-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6e38cf5475c501bfd99a48743229ee9_2209f2b9-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6e38cf5475c501bfd99a48743229ee9_2209f2b9-768x510.jpg","medium_large-width":768,"medium_large-height":510,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6e38cf5475c501bfd99a48743229ee9_2209f2b9-1024x680.jpg","large-width":1024,"large-height":680,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6e38cf5475c501bfd99a48743229ee9_2209f2b9.jpg","1536x1536-width":1200,"1536x1536-height":797,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6e38cf5475c501bfd99a48743229ee9_2209f2b9.jpg","2048x2048-width":1200,"2048x2048-height":797,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6e38cf5475c501bfd99a48743229ee9_2209f2b9.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6e38cf5475c501bfd99a48743229ee9_2209f2b9.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6e38cf5475c501bfd99a48743229ee9_2209f2b9.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153606,"id":153606,"title":"e6dca7829e20c4f3553e8c5fb3805369_aa292ddd.jpg","filename":"e6dca7829e20c4f3553e8c5fb3805369_aa292ddd.jpg","filesize":174595,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6dca7829e20c4f3553e8c5fb3805369_aa292ddd.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bergamo-alta-suite\/e6dca7829e20c4f3553e8c5fb3805369_aa292ddd-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e6dca7829e20c4f3553e8c5fb3805369_aa292ddd-jpg-2","status":"inherit","uploaded_to":177781,"date":"2025-04-17 14:59:20","modified":"2025-04-18 12:36:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":797,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6dca7829e20c4f3553e8c5fb3805369_aa292ddd-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6dca7829e20c4f3553e8c5fb3805369_aa292ddd-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6dca7829e20c4f3553e8c5fb3805369_aa292ddd-768x510.jpg","medium_large-width":768,"medium_large-height":510,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6dca7829e20c4f3553e8c5fb3805369_aa292ddd-1024x680.jpg","large-width":1024,"large-height":680,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6dca7829e20c4f3553e8c5fb3805369_aa292ddd.jpg","1536x1536-width":1200,"1536x1536-height":797,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6dca7829e20c4f3553e8c5fb3805369_aa292ddd.jpg","2048x2048-width":1200,"2048x2048-height":797,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6dca7829e20c4f3553e8c5fb3805369_aa292ddd.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6dca7829e20c4f3553e8c5fb3805369_aa292ddd.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e6dca7829e20c4f3553e8c5fb3805369_aa292ddd.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153613,"id":153613,"title":"4045cdfed0d9557174682f12114ff68e_5cd82276.jpg","filename":"4045cdfed0d9557174682f12114ff68e_5cd82276.jpg","filesize":199212,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4045cdfed0d9557174682f12114ff68e_5cd82276.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/bergamo-alta-suite\/4045cdfed0d9557174682f12114ff68e_5cd82276-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4045cdfed0d9557174682f12114ff68e_5cd82276-jpg-2","status":"inherit","uploaded_to":177781,"date":"2025-04-17 14:59:21","modified":"2025-04-18 12:36:49","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1200,"height":797,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4045cdfed0d9557174682f12114ff68e_5cd82276-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4045cdfed0d9557174682f12114ff68e_5cd82276-300x199.jpg","medium-width":300,"medium-height":199,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4045cdfed0d9557174682f12114ff68e_5cd82276-768x510.jpg","medium_large-width":768,"medium_large-height":510,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4045cdfed0d9557174682f12114ff68e_5cd82276-1024x680.jpg","large-width":1024,"large-height":680,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4045cdfed0d9557174682f12114ff68e_5cd82276.jpg","1536x1536-width":1200,"1536x1536-height":797,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4045cdfed0d9557174682f12114ff68e_5cd82276.jpg","2048x2048-width":1200,"2048x2048-height":797,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4045cdfed0d9557174682f12114ff68e_5cd82276.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":199,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4045cdfed0d9557174682f12114ff68e_5cd82276.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":266,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4045cdfed0d9557174682f12114ff68e_5cd82276.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":399}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"","indepth":"","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"","parking":"","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.704582","longitude":"9.662070","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"Michela Marrone","registered_office":"via S.Tomaso, 57 - 24121 Bergamo","iu_addr_streetnumber":"Via Bartolomeo Colleoni, 10","iu_addr_postalcode":"24129","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"","iu_cell":"+39 3475947151","iu_website":"http:\/\/www.bergamoaltasuite.it","iu_email":"bergamoaltasuite@gmail.com","iu_vat":"MRRMHL62H68A794V","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"1","iu_beds":"10","id_madeep":"","id_visit_manza":"8500","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"time":"<p>CHECK IN dalle 14.00 alle 22.00&#13;<br \/>\nCHECK OUT entro le 10.00<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"groups_welcome","label":"Accettazione gruppi"},{"value":"safe","label":"safe"},{"value":"audiovisual_equipment","label":"Impianti audiovisivi"},{"value":"wifi","label":"Wi-Fi"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms_with_tub","label":"Bagni con idromassaggio"},{"value":"safe_deposit_box","label":"Cassetta di sicurezza"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177781","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177781\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/153536"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=177781"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=177781"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=177781"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=177781"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=177781"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=177781"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=177781"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}