{"id":177790,"date":"2025-04-18T13:11:04","date_gmt":"2025-04-18T11:11:04","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/57-reshotel-orio\/"},"modified":"2025-04-18T14:37:01","modified_gmt":"2025-04-18T12:37:01","slug":"57-reshotel-orio","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/57-reshotel-orio\/","title":{"rendered":"57 RESHOTEL ORIO"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":153629,"template":"","categories":[1000],"tags":[],"aggr":[],"area":[],"kind":[18724],"zona":[],"class_list":["post-177790","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sommeil","kind-strutturaricettiva-fr"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"57 RESHOTEL ORIO","hero_text":"<p>Situ\u00e9 \u00e0 seulement 5 minutes de voiture de l\u2019a\u00e9roport d\u2019Orio al Serio, le 57 Reshotel offre de modernes appartements une-chambre avec r\u00e9seau internet gratuit, une cafeteria e un restaurant \u00e0 la carte sp\u00e9cialis\u00e9 en cuisine nationale et pizza.<\/p>\n","slides":[{"image":{"ID":153629,"id":153629,"title":"d7aa6165c68817fbc9191b3dc7450cb2_7ef6f5e7.jpg","filename":"d7aa6165c68817fbc9191b3dc7450cb2_7ef6f5e7.jpg","filesize":214134,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7aa6165c68817fbc9191b3dc7450cb2_7ef6f5e7.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/57-reshotel-orio\/d7aa6165c68817fbc9191b3dc7450cb2_7ef6f5e7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d7aa6165c68817fbc9191b3dc7450cb2_7ef6f5e7-jpg-2","status":"inherit","uploaded_to":177790,"date":"2025-04-17 14:59:31","modified":"2025-04-18 12:37:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1298,"height":865,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7aa6165c68817fbc9191b3dc7450cb2_7ef6f5e7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7aa6165c68817fbc9191b3dc7450cb2_7ef6f5e7-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7aa6165c68817fbc9191b3dc7450cb2_7ef6f5e7-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7aa6165c68817fbc9191b3dc7450cb2_7ef6f5e7-1024x682.jpg","large-width":1024,"large-height":682,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7aa6165c68817fbc9191b3dc7450cb2_7ef6f5e7.jpg","1536x1536-width":1298,"1536x1536-height":865,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7aa6165c68817fbc9191b3dc7450cb2_7ef6f5e7.jpg","2048x2048-width":1298,"2048x2048-height":865,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7aa6165c68817fbc9191b3dc7450cb2_7ef6f5e7.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7aa6165c68817fbc9191b3dc7450cb2_7ef6f5e7.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d7aa6165c68817fbc9191b3dc7450cb2_7ef6f5e7.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153636,"id":153636,"title":"c1e729e57bad8e97f0adea5f7543fca7_a98cef0f.jpg","filename":"c1e729e57bad8e97f0adea5f7543fca7_a98cef0f.jpg","filesize":246933,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c1e729e57bad8e97f0adea5f7543fca7_a98cef0f.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/57-reshotel-orio\/c1e729e57bad8e97f0adea5f7543fca7_a98cef0f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c1e729e57bad8e97f0adea5f7543fca7_a98cef0f-jpg-2","status":"inherit","uploaded_to":177790,"date":"2025-04-17 14:59:32","modified":"2025-04-18 12:37:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1310,"height":873,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c1e729e57bad8e97f0adea5f7543fca7_a98cef0f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c1e729e57bad8e97f0adea5f7543fca7_a98cef0f-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c1e729e57bad8e97f0adea5f7543fca7_a98cef0f-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c1e729e57bad8e97f0adea5f7543fca7_a98cef0f-1024x682.jpg","large-width":1024,"large-height":682,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c1e729e57bad8e97f0adea5f7543fca7_a98cef0f.jpg","1536x1536-width":1310,"1536x1536-height":873,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c1e729e57bad8e97f0adea5f7543fca7_a98cef0f.jpg","2048x2048-width":1310,"2048x2048-height":873,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c1e729e57bad8e97f0adea5f7543fca7_a98cef0f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c1e729e57bad8e97f0adea5f7543fca7_a98cef0f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c1e729e57bad8e97f0adea5f7543fca7_a98cef0f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":153643,"id":153643,"title":"b86c63f0be304b3a62d2e7788d3c7ca9_c1ca2f1f.jpg","filename":"b86c63f0be304b3a62d2e7788d3c7ca9_c1ca2f1f.jpg","filesize":309385,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b86c63f0be304b3a62d2e7788d3c7ca9_c1ca2f1f.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/57-reshotel-orio\/b86c63f0be304b3a62d2e7788d3c7ca9_c1ca2f1f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"b86c63f0be304b3a62d2e7788d3c7ca9_c1ca2f1f-jpg-2","status":"inherit","uploaded_to":177790,"date":"2025-04-17 14:59:33","modified":"2025-04-18 12:37:03","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1920,"height":1517,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b86c63f0be304b3a62d2e7788d3c7ca9_c1ca2f1f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b86c63f0be304b3a62d2e7788d3c7ca9_c1ca2f1f-300x237.jpg","medium-width":300,"medium-height":237,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b86c63f0be304b3a62d2e7788d3c7ca9_c1ca2f1f-768x607.jpg","medium_large-width":768,"medium_large-height":607,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b86c63f0be304b3a62d2e7788d3c7ca9_c1ca2f1f-1024x809.jpg","large-width":1024,"large-height":809,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b86c63f0be304b3a62d2e7788d3c7ca9_c1ca2f1f-1536x1214.jpg","1536x1536-width":1536,"1536x1536-height":1214,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b86c63f0be304b3a62d2e7788d3c7ca9_c1ca2f1f.jpg","2048x2048-width":1920,"2048x2048-height":1517,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b86c63f0be304b3a62d2e7788d3c7ca9_c1ca2f1f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":237,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b86c63f0be304b3a62d2e7788d3c7ca9_c1ca2f1f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":316,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/b86c63f0be304b3a62d2e7788d3c7ca9_c1ca2f1f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":474}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Tous les locations disposent de climatisation, de salon\/salle de diner avec coin cuisine et tv satellitaire \u00e0 \u00e9cran plat, et d\u2019une salle de bain priv\u00e9e avec serviettes de courtoisie et s\u00e8che-cheveux. Vous pourrez vous d\u00e9tendre dans le salon en commun que vous trouverez pr\u00eat du hall de r\u00e9ception.Situ\u00e9 pr\u00eat de pistes cyclables et de jogging, le Reshotel se dresse \u00e0 moins de 4 kilom\u00e8tres de la gare ferroviaire et du centre-ville de Bergame, et \u00e0 5 minutes de voiture du centre commercial Oriocenter.<\/p>\n","indepth":"<p>\u00a0&#13;<br \/>\n\u00a0<\/p>\n","howtogetthere":"","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"<p>Proche de l\u2019A\u00e9roport d\u2019Orio al Serio, Bergamo Fiera, centre-ville de Bergame, gare ferroviaire, Milan.<\/p>\n","parking":"<p>Gratuit et couvert.<\/p>\n","restaurant":"","breakfast":"<p>Le petit d\u00e9jeuner italien est compris dans le prix \u00e0 partir de 6.00 heures jusqu\u2019\u00e0 10.00.<\/p>\n","internet":"<p>R\u00e9seau internet gratuit dans toute la structure.<\/p>\n","children":"<p>0-2 ans gratuit.<\/p>\n","pets":"<p>Seulement de petite taille (supplement de 5 \u20ac).<\/p>\n","latitude":"45.674220","longitude":"9.688660","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via Europa, 4","iu_addr_postalcode":"24050","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+390356661001","iu_cell":"+393356125580","iu_website":"http:\/\/www.57reshotel.it\/","iu_email":"info@57reshotel.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"5430","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"time":"<p>La nostra reception \u00e8 aperta 24h.<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"disabled_access","label":"Accessibile disabili"},{"value":"elevator","label":"Ascensore"},{"value":"bar","label":"Bar"},{"value":"safe","label":"safe"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"restaurant","label":"Ristorante"},{"value":"wifi","label":"Wi-Fi"},{"value":"pets_allowed","label":"Ammessi piccoli animali"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"balcony","label":"Balcone"},{"value":"safe_deposit_box","label":"Cassetta di sicurezza"},{"value":"electronic_key","label":"Chiave elettronica"},{"value":"mini_bar","label":"Frigo bar"},{"value":"room_service","label":"Servizio in camera"},{"value":"tv_room","label":"TV in camera"},{"value":"satellite_tv","label":"TV satellitare"},{"value":"bancomat","label":"Bancomat"},{"value":"visa","label":"Visa"},{"value":"mastercard","label":"Mastercard"},{"value":"amex","label":"American Express"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177790","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177790\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/153629"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=177790"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=177790"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=177790"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=177790"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=177790"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=177790"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=177790"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}