{"id":177834,"date":"2025-04-18T13:12:18","date_gmt":"2025-04-18T11:12:18","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/casa-g-palazzolo\/"},"modified":"2025-04-18T14:38:36","modified_gmt":"2025-04-18T12:38:36","slug":"casa-g-palazzolo","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-g-palazzolo\/","title":{"rendered":"CASA G. PALAZZOLO"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":154500,"template":"","categories":[1000],"tags":[],"aggr":[],"area":[],"kind":[18724],"zona":[],"class_list":["post-177834","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sommeil","kind-strutturaricettiva-fr"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"CASA G. PALAZZOLO","hero_text":"<p lang='fr-FR'>Un b\u00e2timent historique con\u00e7u et r\u00e9nov\u00e9 afin de pouvoir accueillir des personnes \u00e0 mobilit\u00e9 r\u00e9duite<\/p>\n","buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Casa G. Palazzolo est un \u00e9difice d&#8217;\u00e9poque situ\u00e9 au c\u0153ur de San Pellegrino Terme, compos\u00e9 de 10 appartements con\u00e7us et adapt\u00e9s aux personnes \u00e0 mobilit\u00e9 r\u00e9duite.&#13;<br \/>\nDirig\u00e9 par l&#8217;Istituto Clinico Quarenghi, il est conform\u00e9ment \u00e9quip\u00e9 pour les patients qui sont r\u00e9int\u00e9gr\u00e9s progressivement avant leur retour au domicile, avec le soutien de l&#8217;\u00e9tablissement de soins et de sant\u00e9 \u00e0 proximit\u00e9.&#13;<br \/>\nIl est \u00e9galement con\u00e7u pour les proches des patients\u00a0: les appartements sont \u00e9quip\u00e9s tout confort et permettent d\u2019\u00eatre \u00e0 deux pas de leurs proches.&#13;<br \/>\nCasa G. Palazzolo s&#8217;adresse aussi \u00e0 ceux qui veulent profiter du climat doux de San Pellegrino Terme, en effet dans l&#8217;un des nombreux appartements, vous pourrez compter sur les soins de l&#8217;institut clinique voisine. Pour ceux qui souhaitent aller plus loin, San Pellegrino propose \u00e9galement de nombreuses aventures sportives adapt\u00e9es aux personnes pr\u00e9sentant un handicap.<\/p>\n","indepth":"","howtogetthere":"<p>Entr\u00e9e de la structure par Viale della Vittoria.<\/p>\n","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"","services":"<p>TAXE DE S\u00c9JOUR&#13;<br \/>\n1\u00a0\u20ac par jour et par personne&#13;<br \/>\njusqu&#8217;\u00e0 un maximum de 20 nuits par an.&#13;<br \/>\n&#13;<br \/>\nR\u00e8glement et formulaire d&#8217;exemption\u00a0:&#13;<br \/>\nhttp:\/\/www.casagpalazzolo.com\/listinoprezzi.aspx<\/p>\n","parking":"<p>Possibilit\u00e9 de parking non couvert dans le jardin de la maison, sous r\u00e9serve de disponibilit\u00e9 (pas plus d&#8217;une voiture par appartement)<\/p>\n","restaurant":"","breakfast":"","internet":"","children":"","pets":"","latitude":"45.837617","longitude":"9.663336","startingprice":"","gpxmap":"","iu_motor_accessibility":"yes","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":false,"iu_shortprice":"","iu_company_name":"","registered_office":"","iu_addr_streetnumber":"Via S. Carlo, 68","iu_addr_postalcode":"24016","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39034525111 clinica","iu_cell":"","iu_website":"http:\/\/www.casagpalazzolo.com\/","iu_email":"info@casagpalazzolo.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"5440","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"time":"<p>Il sabato dalle ore 13:30 alle 15:30,\u00a0alla partenza\u00a0devono essere liberati il sabato entro le ore 10.00.\u00a0Check-in presso l&#8217;Istituto Clinico Quarenghi.\u00a0<\/p>\n","service_icons":[],"ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","slides":false},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177834\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/154500"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=177834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=177834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=177834"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=177834"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=177834"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=177834"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=177834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}