{"id":177910,"date":"2025-04-18T13:15:42","date_gmt":"2025-04-18T11:15:42","guid":{"rendered":"https:\/\/visit.valueservice.cloud\/oggetto\/casa-san-giorgio\/"},"modified":"2025-04-18T14:41:27","modified_gmt":"2025-04-18T12:41:27","slug":"casa-san-giorgio","status":"publish","type":"oggetto","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/","title":{"rendered":"CASA SAN GIORGIO"},"excerpt":{"rendered":"","protected":false},"author":0,"featured_media":156221,"template":"","categories":[1000],"tags":[],"aggr":[],"area":[],"kind":[18724],"zona":[],"class_list":["post-177910","oggetto","type-oggetto","status-publish","has-post-thumbnail","hentry","category-sommeil","kind-strutturaricettiva-fr"],"acf":{"hero_type":"images","video_youtube_url":"","video_vimeo_url":"","size":"full","hero_title":"CASA SAN GIORGIO","hero_text":"<p lang='fr-FR'>Faites un break\u00a0!<\/p>\n<p>&#13;<\/p>\n<p>\u00a0<\/p>\n","slides":[{"image":{"ID":156221,"id":156221,"title":"1c158b6172752d78c9ecd49064222dbe_0feb877b.jpg","filename":"1c158b6172752d78c9ecd49064222dbe_0feb877b.jpg","filesize":896506,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1c158b6172752d78c9ecd49064222dbe_0feb877b.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/1c158b6172752d78c9ecd49064222dbe_0feb877b-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1c158b6172752d78c9ecd49064222dbe_0feb877b-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:06","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1709,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1c158b6172752d78c9ecd49064222dbe_0feb877b-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1c158b6172752d78c9ecd49064222dbe_0feb877b-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1c158b6172752d78c9ecd49064222dbe_0feb877b-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1c158b6172752d78c9ecd49064222dbe_0feb877b-1024x684.jpg","large-width":1024,"large-height":684,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1c158b6172752d78c9ecd49064222dbe_0feb877b-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1c158b6172752d78c9ecd49064222dbe_0feb877b-2048x1367.jpg","2048x2048-width":2048,"2048x2048-height":1367,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1c158b6172752d78c9ecd49064222dbe_0feb877b.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1c158b6172752d78c9ecd49064222dbe_0feb877b.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1c158b6172752d78c9ecd49064222dbe_0feb877b.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156228,"id":156228,"title":"79ecc4ec70af8f986849bb41e5e3c773_e73a7b18.jpg","filename":"79ecc4ec70af8f986849bb41e5e3c773_e73a7b18.jpg","filesize":1062995,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/79ecc4ec70af8f986849bb41e5e3c773_e73a7b18.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/79ecc4ec70af8f986849bb41e5e3c773_e73a7b18-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"79ecc4ec70af8f986849bb41e5e3c773_e73a7b18-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:07","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/79ecc4ec70af8f986849bb41e5e3c773_e73a7b18-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/79ecc4ec70af8f986849bb41e5e3c773_e73a7b18-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/79ecc4ec70af8f986849bb41e5e3c773_e73a7b18-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/79ecc4ec70af8f986849bb41e5e3c773_e73a7b18-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/79ecc4ec70af8f986849bb41e5e3c773_e73a7b18-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/79ecc4ec70af8f986849bb41e5e3c773_e73a7b18-2048x1366.jpg","2048x2048-width":2048,"2048x2048-height":1366,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/79ecc4ec70af8f986849bb41e5e3c773_e73a7b18.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/79ecc4ec70af8f986849bb41e5e3c773_e73a7b18.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/79ecc4ec70af8f986849bb41e5e3c773_e73a7b18.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156235,"id":156235,"title":"eba36c7f025ea0c8a1b4cd63c5277d18_ac079a9a.jpg","filename":"eba36c7f025ea0c8a1b4cd63c5277d18_ac079a9a.jpg","filesize":968156,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eba36c7f025ea0c8a1b4cd63c5277d18_ac079a9a.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/eba36c7f025ea0c8a1b4cd63c5277d18_ac079a9a-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"eba36c7f025ea0c8a1b4cd63c5277d18_ac079a9a-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:09","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eba36c7f025ea0c8a1b4cd63c5277d18_ac079a9a-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eba36c7f025ea0c8a1b4cd63c5277d18_ac079a9a-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eba36c7f025ea0c8a1b4cd63c5277d18_ac079a9a-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eba36c7f025ea0c8a1b4cd63c5277d18_ac079a9a-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eba36c7f025ea0c8a1b4cd63c5277d18_ac079a9a-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eba36c7f025ea0c8a1b4cd63c5277d18_ac079a9a-2048x1366.jpg","2048x2048-width":2048,"2048x2048-height":1366,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eba36c7f025ea0c8a1b4cd63c5277d18_ac079a9a.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eba36c7f025ea0c8a1b4cd63c5277d18_ac079a9a.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/eba36c7f025ea0c8a1b4cd63c5277d18_ac079a9a.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156242,"id":156242,"title":"f0362069f9a10a7ebbd6c9919d92683b_3bc2adaa.jpg","filename":"f0362069f9a10a7ebbd6c9919d92683b_3bc2adaa.jpg","filesize":1000323,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0362069f9a10a7ebbd6c9919d92683b_3bc2adaa.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/f0362069f9a10a7ebbd6c9919d92683b_3bc2adaa-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"f0362069f9a10a7ebbd6c9919d92683b_3bc2adaa-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:10","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0362069f9a10a7ebbd6c9919d92683b_3bc2adaa-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0362069f9a10a7ebbd6c9919d92683b_3bc2adaa-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0362069f9a10a7ebbd6c9919d92683b_3bc2adaa-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0362069f9a10a7ebbd6c9919d92683b_3bc2adaa-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0362069f9a10a7ebbd6c9919d92683b_3bc2adaa-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0362069f9a10a7ebbd6c9919d92683b_3bc2adaa-2048x1366.jpg","2048x2048-width":2048,"2048x2048-height":1366,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0362069f9a10a7ebbd6c9919d92683b_3bc2adaa.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0362069f9a10a7ebbd6c9919d92683b_3bc2adaa.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/f0362069f9a10a7ebbd6c9919d92683b_3bc2adaa.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156249,"id":156249,"title":"2584f18bb76ec01dd1477cbfc24c8f0e_7063b9f8.jpg","filename":"2584f18bb76ec01dd1477cbfc24c8f0e_7063b9f8.jpg","filesize":1308832,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2584f18bb76ec01dd1477cbfc24c8f0e_7063b9f8.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/2584f18bb76ec01dd1477cbfc24c8f0e_7063b9f8-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"2584f18bb76ec01dd1477cbfc24c8f0e_7063b9f8-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:12","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1706,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2584f18bb76ec01dd1477cbfc24c8f0e_7063b9f8-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2584f18bb76ec01dd1477cbfc24c8f0e_7063b9f8-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2584f18bb76ec01dd1477cbfc24c8f0e_7063b9f8-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2584f18bb76ec01dd1477cbfc24c8f0e_7063b9f8-1024x682.jpg","large-width":1024,"large-height":682,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2584f18bb76ec01dd1477cbfc24c8f0e_7063b9f8-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2584f18bb76ec01dd1477cbfc24c8f0e_7063b9f8-2048x1365.jpg","2048x2048-width":2048,"2048x2048-height":1365,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2584f18bb76ec01dd1477cbfc24c8f0e_7063b9f8.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2584f18bb76ec01dd1477cbfc24c8f0e_7063b9f8.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2584f18bb76ec01dd1477cbfc24c8f0e_7063b9f8.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156256,"id":156256,"title":"88a52024bf91684ac80142c6617e18ac_d41b5547.jpg","filename":"88a52024bf91684ac80142c6617e18ac_d41b5547.jpg","filesize":966062,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a52024bf91684ac80142c6617e18ac_d41b5547.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/88a52024bf91684ac80142c6617e18ac_d41b5547-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"88a52024bf91684ac80142c6617e18ac_d41b5547-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:14","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a52024bf91684ac80142c6617e18ac_d41b5547-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a52024bf91684ac80142c6617e18ac_d41b5547-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a52024bf91684ac80142c6617e18ac_d41b5547-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a52024bf91684ac80142c6617e18ac_d41b5547-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a52024bf91684ac80142c6617e18ac_d41b5547-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a52024bf91684ac80142c6617e18ac_d41b5547-2048x1366.jpg","2048x2048-width":2048,"2048x2048-height":1366,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a52024bf91684ac80142c6617e18ac_d41b5547.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a52024bf91684ac80142c6617e18ac_d41b5547.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/88a52024bf91684ac80142c6617e18ac_d41b5547.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156263,"id":156263,"title":"c509e88584a29b5995a6bafe75b84bb9_36e9e86c.jpg","filename":"c509e88584a29b5995a6bafe75b84bb9_36e9e86c.jpg","filesize":847021,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c509e88584a29b5995a6bafe75b84bb9_36e9e86c.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/c509e88584a29b5995a6bafe75b84bb9_36e9e86c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"c509e88584a29b5995a6bafe75b84bb9_36e9e86c-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:15","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c509e88584a29b5995a6bafe75b84bb9_36e9e86c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c509e88584a29b5995a6bafe75b84bb9_36e9e86c-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c509e88584a29b5995a6bafe75b84bb9_36e9e86c-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c509e88584a29b5995a6bafe75b84bb9_36e9e86c-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c509e88584a29b5995a6bafe75b84bb9_36e9e86c-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c509e88584a29b5995a6bafe75b84bb9_36e9e86c-2048x1366.jpg","2048x2048-width":2048,"2048x2048-height":1366,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c509e88584a29b5995a6bafe75b84bb9_36e9e86c.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c509e88584a29b5995a6bafe75b84bb9_36e9e86c.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/c509e88584a29b5995a6bafe75b84bb9_36e9e86c.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156270,"id":156270,"title":"4ae12d2941d69fcbc0f0cb19cabe9f92_9eb7b5ea.jpg","filename":"4ae12d2941d69fcbc0f0cb19cabe9f92_9eb7b5ea.jpg","filesize":1137123,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ae12d2941d69fcbc0f0cb19cabe9f92_9eb7b5ea.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/4ae12d2941d69fcbc0f0cb19cabe9f92_9eb7b5ea-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"4ae12d2941d69fcbc0f0cb19cabe9f92_9eb7b5ea-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:17","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1709,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ae12d2941d69fcbc0f0cb19cabe9f92_9eb7b5ea-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ae12d2941d69fcbc0f0cb19cabe9f92_9eb7b5ea-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ae12d2941d69fcbc0f0cb19cabe9f92_9eb7b5ea-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ae12d2941d69fcbc0f0cb19cabe9f92_9eb7b5ea-1024x684.jpg","large-width":1024,"large-height":684,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ae12d2941d69fcbc0f0cb19cabe9f92_9eb7b5ea-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ae12d2941d69fcbc0f0cb19cabe9f92_9eb7b5ea-2048x1367.jpg","2048x2048-width":2048,"2048x2048-height":1367,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ae12d2941d69fcbc0f0cb19cabe9f92_9eb7b5ea.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ae12d2941d69fcbc0f0cb19cabe9f92_9eb7b5ea.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/4ae12d2941d69fcbc0f0cb19cabe9f92_9eb7b5ea.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156277,"id":156277,"title":"e3aba087579f17b2a2e07c979bb0ea27_be73bb39.jpg","filename":"e3aba087579f17b2a2e07c979bb0ea27_be73bb39.jpg","filesize":1160175,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3aba087579f17b2a2e07c979bb0ea27_be73bb39.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/e3aba087579f17b2a2e07c979bb0ea27_be73bb39-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"e3aba087579f17b2a2e07c979bb0ea27_be73bb39-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:19","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1709,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3aba087579f17b2a2e07c979bb0ea27_be73bb39-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3aba087579f17b2a2e07c979bb0ea27_be73bb39-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3aba087579f17b2a2e07c979bb0ea27_be73bb39-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3aba087579f17b2a2e07c979bb0ea27_be73bb39-1024x684.jpg","large-width":1024,"large-height":684,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3aba087579f17b2a2e07c979bb0ea27_be73bb39-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3aba087579f17b2a2e07c979bb0ea27_be73bb39-2048x1367.jpg","2048x2048-width":2048,"2048x2048-height":1367,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3aba087579f17b2a2e07c979bb0ea27_be73bb39.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3aba087579f17b2a2e07c979bb0ea27_be73bb39.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/e3aba087579f17b2a2e07c979bb0ea27_be73bb39.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156284,"id":156284,"title":"857d8d73e377c4865c194c6c11a3d2fc_d17f1eb0.jpg","filename":"857d8d73e377c4865c194c6c11a3d2fc_d17f1eb0.jpg","filesize":949155,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/857d8d73e377c4865c194c6c11a3d2fc_d17f1eb0.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/857d8d73e377c4865c194c6c11a3d2fc_d17f1eb0-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"857d8d73e377c4865c194c6c11a3d2fc_d17f1eb0-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:20","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1709,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/857d8d73e377c4865c194c6c11a3d2fc_d17f1eb0-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/857d8d73e377c4865c194c6c11a3d2fc_d17f1eb0-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/857d8d73e377c4865c194c6c11a3d2fc_d17f1eb0-768x513.jpg","medium_large-width":768,"medium_large-height":513,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/857d8d73e377c4865c194c6c11a3d2fc_d17f1eb0-1024x684.jpg","large-width":1024,"large-height":684,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/857d8d73e377c4865c194c6c11a3d2fc_d17f1eb0-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/857d8d73e377c4865c194c6c11a3d2fc_d17f1eb0-2048x1367.jpg","2048x2048-width":2048,"2048x2048-height":1367,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/857d8d73e377c4865c194c6c11a3d2fc_d17f1eb0.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/857d8d73e377c4865c194c6c11a3d2fc_d17f1eb0.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/857d8d73e377c4865c194c6c11a3d2fc_d17f1eb0.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":401}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156291,"id":156291,"title":"1ec2c0e93b249a59058f3e85b192a36d_34044406.jpg","filename":"1ec2c0e93b249a59058f3e85b192a36d_34044406.jpg","filesize":703430,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1ec2c0e93b249a59058f3e85b192a36d_34044406.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/1ec2c0e93b249a59058f3e85b192a36d_34044406-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"1ec2c0e93b249a59058f3e85b192a36d_34044406-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:22","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1ec2c0e93b249a59058f3e85b192a36d_34044406-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1ec2c0e93b249a59058f3e85b192a36d_34044406-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1ec2c0e93b249a59058f3e85b192a36d_34044406-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1ec2c0e93b249a59058f3e85b192a36d_34044406-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1ec2c0e93b249a59058f3e85b192a36d_34044406-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1ec2c0e93b249a59058f3e85b192a36d_34044406-2048x1366.jpg","2048x2048-width":2048,"2048x2048-height":1366,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1ec2c0e93b249a59058f3e85b192a36d_34044406.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1ec2c0e93b249a59058f3e85b192a36d_34044406.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/1ec2c0e93b249a59058f3e85b192a36d_34044406.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156298,"id":156298,"title":"5a188d95e6bb312003ae8ac00ad7b671_8f53c27f.jpg","filename":"5a188d95e6bb312003ae8ac00ad7b671_8f53c27f.jpg","filesize":2643498,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a188d95e6bb312003ae8ac00ad7b671_8f53c27f.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/5a188d95e6bb312003ae8ac00ad7b671_8f53c27f-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"5a188d95e6bb312003ae8ac00ad7b671_8f53c27f-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:24","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1707,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a188d95e6bb312003ae8ac00ad7b671_8f53c27f-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a188d95e6bb312003ae8ac00ad7b671_8f53c27f-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a188d95e6bb312003ae8ac00ad7b671_8f53c27f-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a188d95e6bb312003ae8ac00ad7b671_8f53c27f-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a188d95e6bb312003ae8ac00ad7b671_8f53c27f-1536x1024.jpg","1536x1536-width":1536,"1536x1536-height":1024,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a188d95e6bb312003ae8ac00ad7b671_8f53c27f-2048x1366.jpg","2048x2048-width":2048,"2048x2048-height":1366,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a188d95e6bb312003ae8ac00ad7b671_8f53c27f.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":200,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a188d95e6bb312003ae8ac00ad7b671_8f53c27f.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":267,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/5a188d95e6bb312003ae8ac00ad7b671_8f53c27f.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":400}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156305,"id":156305,"title":"d01b9dedc23a40218ede7a84247010f6_a908ddde.jpg","filename":"d01b9dedc23a40218ede7a84247010f6_a908ddde.jpg","filesize":1327198,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d01b9dedc23a40218ede7a84247010f6_a908ddde.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/d01b9dedc23a40218ede7a84247010f6_a908ddde-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"d01b9dedc23a40218ede7a84247010f6_a908ddde-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:25","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2498,"height":801,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d01b9dedc23a40218ede7a84247010f6_a908ddde-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d01b9dedc23a40218ede7a84247010f6_a908ddde-300x96.jpg","medium-width":300,"medium-height":96,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d01b9dedc23a40218ede7a84247010f6_a908ddde-768x246.jpg","medium_large-width":768,"medium_large-height":246,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d01b9dedc23a40218ede7a84247010f6_a908ddde-1024x328.jpg","large-width":1024,"large-height":328,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d01b9dedc23a40218ede7a84247010f6_a908ddde-1536x493.jpg","1536x1536-width":1536,"1536x1536-height":493,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d01b9dedc23a40218ede7a84247010f6_a908ddde-2048x657.jpg","2048x2048-width":2048,"2048x2048-height":657,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d01b9dedc23a40218ede7a84247010f6_a908ddde.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":96,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d01b9dedc23a40218ede7a84247010f6_a908ddde.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":128,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/d01b9dedc23a40218ede7a84247010f6_a908ddde.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":192}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156312,"id":156312,"title":"ee7b297bc438a9c90e98425267408337_2ac267c6.jpg","filename":"ee7b297bc438a9c90e98425267408337_2ac267c6-scaled.jpg","filesize":910571,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ee7b297bc438a9c90e98425267408337_2ac267c6-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/ee7b297bc438a9c90e98425267408337_2ac267c6-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"ee7b297bc438a9c90e98425267408337_2ac267c6-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:26","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ee7b297bc438a9c90e98425267408337_2ac267c6-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ee7b297bc438a9c90e98425267408337_2ac267c6-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ee7b297bc438a9c90e98425267408337_2ac267c6-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ee7b297bc438a9c90e98425267408337_2ac267c6-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ee7b297bc438a9c90e98425267408337_2ac267c6-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ee7b297bc438a9c90e98425267408337_2ac267c6-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ee7b297bc438a9c90e98425267408337_2ac267c6-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ee7b297bc438a9c90e98425267408337_2ac267c6-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/ee7b297bc438a9c90e98425267408337_2ac267c6-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156319,"id":156319,"title":"cf980c84b89b238b67fae62d1bd44e3a_f47d2eb7.jpg","filename":"cf980c84b89b238b67fae62d1bd44e3a_f47d2eb7-scaled.jpg","filesize":341658,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cf980c84b89b238b67fae62d1bd44e3a_f47d2eb7-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/cf980c84b89b238b67fae62d1bd44e3a_f47d2eb7-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"cf980c84b89b238b67fae62d1bd44e3a_f47d2eb7-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:28","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cf980c84b89b238b67fae62d1bd44e3a_f47d2eb7-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cf980c84b89b238b67fae62d1bd44e3a_f47d2eb7-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cf980c84b89b238b67fae62d1bd44e3a_f47d2eb7-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cf980c84b89b238b67fae62d1bd44e3a_f47d2eb7-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cf980c84b89b238b67fae62d1bd44e3a_f47d2eb7-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cf980c84b89b238b67fae62d1bd44e3a_f47d2eb7-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cf980c84b89b238b67fae62d1bd44e3a_f47d2eb7-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cf980c84b89b238b67fae62d1bd44e3a_f47d2eb7-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/cf980c84b89b238b67fae62d1bd44e3a_f47d2eb7-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156326,"id":156326,"title":"2b7ade3537da77b395dbb7556ada5fec_1843e56c.jpg","filename":"2b7ade3537da77b395dbb7556ada5fec_1843e56c-scaled.jpg","filesize":1063627,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b7ade3537da77b395dbb7556ada5fec_1843e56c-scaled.jpg","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/2b7ade3537da77b395dbb7556ada5fec_1843e56c-jpg-2\/","alt":"","author":"0","description":"","caption":"","name":"2b7ade3537da77b395dbb7556ada5fec_1843e56c-jpg-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:31","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b7ade3537da77b395dbb7556ada5fec_1843e56c-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b7ade3537da77b395dbb7556ada5fec_1843e56c-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b7ade3537da77b395dbb7556ada5fec_1843e56c-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b7ade3537da77b395dbb7556ada5fec_1843e56c-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b7ade3537da77b395dbb7556ada5fec_1843e56c-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b7ade3537da77b395dbb7556ada5fec_1843e56c-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b7ade3537da77b395dbb7556ada5fec_1843e56c-scaled.jpg","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b7ade3537da77b395dbb7556ada5fec_1843e56c-scaled.jpg","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/2b7ade3537da77b395dbb7556ada5fec_1843e56c-scaled.jpg","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}},{"image":{"ID":156333,"id":156333,"title":"48a5985609ac2348b28f5ecedffbea67_07ff78e7.png","filename":"48a5985609ac2348b28f5ecedffbea67_07ff78e7.png","filesize":2616317,"url":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48a5985609ac2348b28f5ecedffbea67_07ff78e7.png","link":"https:\/\/visit.valueservice.cloud\/fr\/oggetto\/casa-san-giorgio\/48a5985609ac2348b28f5ecedffbea67_07ff78e7-png-2\/","alt":"","author":"0","description":"","caption":"","name":"48a5985609ac2348b28f5ecedffbea67_07ff78e7-png-2","status":"inherit","uploaded_to":177910,"date":"2025-04-17 15:11:33","modified":"2025-04-18 12:41:29","menu_order":0,"mime_type":"image\/png","type":"image","subtype":"png","icon":"https:\/\/visit.valueservice.cloud\/wp-includes\/images\/media\/default.png","width":1248,"height":936,"sizes":{"thumbnail":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48a5985609ac2348b28f5ecedffbea67_07ff78e7-150x150.png","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48a5985609ac2348b28f5ecedffbea67_07ff78e7-300x225.png","medium-width":300,"medium-height":225,"medium_large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48a5985609ac2348b28f5ecedffbea67_07ff78e7-768x576.png","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48a5985609ac2348b28f5ecedffbea67_07ff78e7-1024x768.png","large-width":1024,"large-height":768,"1536x1536":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48a5985609ac2348b28f5ecedffbea67_07ff78e7.png","1536x1536-width":1248,"1536x1536-height":936,"2048x2048":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48a5985609ac2348b28f5ecedffbea67_07ff78e7.png","2048x2048-width":1248,"2048x2048-height":936,"gform-image-choice-sm":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48a5985609ac2348b28f5ecedffbea67_07ff78e7.png","gform-image-choice-sm-width":300,"gform-image-choice-sm-height":225,"gform-image-choice-md":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48a5985609ac2348b28f5ecedffbea67_07ff78e7.png","gform-image-choice-md-width":400,"gform-image-choice-md-height":300,"gform-image-choice-lg":"https:\/\/visit.valueservice.cloud\/wp-content\/uploads\/2025\/04\/48a5985609ac2348b28f5ecedffbea67_07ff78e7.png","gform-image-choice-lg-width":600,"gform-image-choice-lg-height":450}},"video":false,"video_mobile":false,"video_with_audio":false,"duration_ms":"","title":"","text":"","hero_slide_buttons":{"buttons":false},"slide_buttons":false,"b2b_register_button":false,"formb2b":{"button_text":"","form_b2b":false}}],"buttons":false,"hero_buttons_group":{"buttons":false},"hero_buttons":false,"filotto":{"filotto_title":"","filotto_sub":"","filotto_layout":false,"filotto_fill":false,"filotto_items":false,"filotto_fill_conditions":{"or_filter":false,"only_ambassadors":false,"max_elements":0,"show_total":false,"see_all":false,"custom_show_all_page":null,"order_by":false,"order_way":false}},"description":"<p>Une magnifique maison de vacances situ\u00e9e en colline avec vue panoramique sur la ville de Bergame.&#13;<br \/>\nFace \u00e0 la structure, dans le beau jardin \u00e0 l&#8217;anglaise, vous trouverez un espace pique-nique et un barbecue \u00e0 disposition pour vos moments de convivialit\u00e9.&#13;<br \/>\nChaque chambre est enti\u00e8rement \u00e9quip\u00e9e et dot\u00e9e de lits king\u00a0size, ce qui rend cette maison une parfaite alternative \u00e0 l\u2019h\u00f4tel.&#13;<br \/>\nCasa san Giorgio se trouve sur le c\u00f4t\u00e9 ensoleill\u00e9 de la colline, au c\u0153ur du parc naturel (PLIS) des vall\u00e9es d&#8217;Argon. Le domaine de propri\u00e9t\u00e9 de la maison s&#8217;\u00e9tend jusqu&#8217;au sommet, sur quatre hectares, comprenant un territoire riche en chemins p\u00e9destres ou \u00e0 emprunter en VTT.&#13;<br \/>\nFace \u00e0 l&#8217;entr\u00e9e de la maison, un imposant m\u00fbrier centenaire offre son ombre, un abri id\u00e9al pendant les p\u00e9riodes estivales de canicule.&#13;<br \/>\nCasa san Giorgio dispose d&#8217;une salle de sport \u00e9quip\u00e9e avec sauna, machines multifonctions, tapis de course et v\u00e9lo elliptiques.&#13;<br \/>\n\u00a0&#13;<br \/>\n\u00a0Casa San Giorgio: Virtual Tour&#13;<br \/>\n\u00a0&#13;<br \/>\nCasa san Giorgio se trouve au c\u0153ur de la Route du vin et des saveurs de la Valcalepio.<\/p>\n","indepth":"<p>Casa san Giorgio se trouve au c\u0153ur de la Route du vin et des saveurs de la Valcalepio.&#13;<br \/>\n\u2026 Casa San Giorgio fut construite il y a quelques ann\u00e9es \u00e0 l&#8217;endroit pr\u00e9cis o\u00f9 autrefois \u00e9tait actif un ancien vigneron producteur de la colline de San Giorgio.&#13;<br \/>\nCette ancienne ferme abandonn\u00e9e, \u00e9tait compl\u00e8tement en ruine dans les ann\u00e9es 1980. Arm\u00e9 d&#8217;une bonne dose de courage, mon p\u00e8re entreprit de la reconstruire dans le respect de la tradition des fermes locales, sans d\u00e9naturer le lieu, n&#8217;utilisant que des mat\u00e9riaux issus de ce lieu magique&#8230;&#13;<br \/>\nOggi la custodiamo e come lui avrebbe voluto, abbiamo deciso di condividere cos\u00ec tanta bellezza con persone provenienti da tutto il mondo che amano la bellezza della natura e il relax e che vogliono conoscere la vera ospitalit\u00e0 italiana&#13;<br \/>\nAujourd&#8217;hui nous nous effor\u00e7ons de la conserver comme il aurait aim\u00e9 et de la partager avec les voyageurs provenant du monde entier, ceux qui aiment les tr\u00e9sors de la nature et son calme et qui souhaitent conna\u00eetre l&#8217;art de l&#8217;accueil \u00e0 l&#8217;italienne&#8230;&#13;<br \/>\nFaites un break&#8230; \u00e0 la Casa San Giorgio.<\/p>\n","howtogetthere":"<p>Il est conseill\u00e9 de nous rejoindre en voiture, puisque la maison est en colline. La Casa san Giorgio se trouve dans une route au calme. Si votre gps ne trouve pas le n. 50, vous pouvez suivre vers le n. 40.Coordonn\u00e9es\u00a0:GPS Coordinates: 45.687458, 9.779567&#13;<br \/>\nLa maison se trouve \u00e0 seulement 10 minutes de l&#8217;a\u00e9roport Bergame \u2013 Orio al Serio et \u00e0 15 minutes du centre-ville de Bergame, 50 minutes de Milan, 40 minutes de Brescia, 90 minutes de Verone, 30 minutes de San Pellegrino et \u00e0 une petite heure du lac de Garde.&#13;<br \/>\nBergame est c\u00e9l\u00e8bre par ses remparts v\u00e9nitiens, r\u00e9cemment inscrits par l&#8217;Unesco au patrimoine mondial de l&#8217;humanit\u00e9.&#13;<br \/>\n\u00a0<\/p>\n","timerange":"","seasonality":"","pairings":"","curiosities":"","awards":"","cancellationpolicy":"","moredetails":"","whatsincluded":"","whatsnotincluded":"","price":"<p>55-70 \u20ac<\/p>\n","services":"","parking":"<p>Parking gratuit.<\/p>\n","restaurant":"","breakfast":"<p>Petit d\u00e9jeuner buffet.<\/p>\n","internet":"<p>Wifi gratuit.<\/p>\n","children":"<p>La structure convient aux enfants de plus de 3 ans.<\/p>\n","pets":"<p>Les animaux ne sont pas accept\u00e9s.<\/p>\n","latitude":"45.687488","longitude":"9.779763","startingprice":"","gpxmap":"","iu_motor_accessibility":"notsure","iu_visual_accessibility":"notsure","iu_auditory_accessibility":"notsure","iu_cognitive_accessibility":"notsure","iu_kids":true,"iu_shortprice":"","iu_company_name":"Casa San Giorgio","registered_office":"","iu_addr_streetnumber":"Via Monte Grappa 50","iu_addr_postalcode":"24061","iu_addr_city":"Bergamo","iu_addr_province":"BG","iu_phone":"+39 3453484705","iu_cell":"","iu_website":"http:\/\/www.casasangiorgiobergamo.it","iu_email":"info@casasangiorgiobergamo.it","iu_vat":"","iu_document_label":"","iu_document":false,"iu_documents":false,"iu_timetable":false,"iu_startingdate":"","iu_closingdate":"","iu_manager":"","iu_bookingurl":"","iu_videourl":"","iu_difficulty":"","iu_accessibility":"","iu_duration":"","iu_languages":"","iu_minpeople":"","iu_maxpeople":"","iu_lenght":"","iu_positiveheightdiff":"","iu_negativeheightdiff":"","iu_difficultylevel":"","iu_gpxtrack":"","iu_highestpoint":"","iu_lowestpoint":"","iu_suggestedperiod":"","iu_reservation":false,"iu_takeaway":false,"iu_delivery":false,"iu_stars":"","iu_rooms":"","iu_beds":"","id_madeep":"","id_visit_manza":"7763","id_east":"","id_ristora":"","id_eppen":"","style":"primary","text":"","button_icon":"none","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":"","cta":{"style":"primary","text":"","icon":{"button_icon":"none"},"function":"link","url":"","target":"_self","url_youtube":"","target_modal":""},"validfrom":"","validto":"","hours":"","tcm_content":false,"accessibilitycontent":{"tcm_content":false},"accessibilityicons":[],"time":"<p>check-in:\u00a014.00 &#8211; 22.00&#13;<br \/>\ncheck-out :\u00a011.00 am<\/p>\n","ttp":"","hbenchmark":"","management_system":"","cir":"","structure_code":"","service_icons":[{"value":"laundry","label":"Lavanderia"},{"value":"parking","label":"Parcheggio gratuito"},{"value":"park_garden","label":"Parco \/ Giardino"},{"value":"sauna","label":"Sauna"},{"value":"wifi","label":"Wi-Fi"},{"value":"air_conditioner","label":"Aria condizionata"},{"value":"hairdryer","label":"Asciugacapelli"},{"value":"shower","label":"Bagni con doccia"},{"value":"bathrooms_with_tub","label":"Bagni con idromassaggio"},{"value":"bathrooms","label":"Bagni con vasca"},{"value":"tv_room","label":"TV in camera"},{"value":"satellite_tv","label":"TV satellitare"}]},"_links":{"self":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177910","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto"}],"about":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/types\/oggetto"}],"version-history":[{"count":0,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/oggetto\/177910\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media\/156221"}],"wp:attachment":[{"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/media?parent=177910"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/categories?post=177910"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/tags?post=177910"},{"taxonomy":"aggr","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/aggr?post=177910"},{"taxonomy":"area","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/area?post=177910"},{"taxonomy":"kind","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/kind?post=177910"},{"taxonomy":"zona","embeddable":true,"href":"https:\/\/visit.valueservice.cloud\/fr\/wp-json\/wp\/v2\/zona?post=177910"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}